{"id":8381,"count":2,"description":"","link":"https:\/\/blogs.nmz.de\/wm2014\/schlagworte\/sprache\/","name":"Sprache","slug":"sprache","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sprache Archive - Auf dem Sperrsitz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.nmz.de\/wm2014\/schlagworte\/sprache\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sprache Archive - Auf dem Sperrsitz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.nmz.de\/wm2014\/schlagworte\/sprache\/\" \/>\n<meta property=\"og:site_name\" content=\"Auf dem Sperrsitz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@musikzeitung\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/schlagworte\\\/sprache\\\/\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/schlagworte\\\/sprache\\\/\",\"name\":\"Sprache Archive - Auf dem Sperrsitz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/schlagworte\\\/sprache\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/schlagworte\\\/sprache\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sprache\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#website\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/\",\"name\":\"Auf dem Sperrsitz\",\"description\":\"Im Kultur-Zoo der nmz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sprache Archive - Auf dem Sperrsitz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.nmz.de\/wm2014\/schlagworte\/sprache\/","og_locale":"de_DE","og_type":"article","og_title":"Sprache Archive - Auf dem Sperrsitz","og_url":"https:\/\/blogs.nmz.de\/wm2014\/schlagworte\/sprache\/","og_site_name":"Auf dem Sperrsitz","twitter_card":"summary_large_image","twitter_site":"@musikzeitung","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blogs.nmz.de\/wm2014\/schlagworte\/sprache\/","url":"https:\/\/blogs.nmz.de\/wm2014\/schlagworte\/sprache\/","name":"Sprache Archive - Auf dem Sperrsitz","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/#website"},"breadcrumb":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/schlagworte\/sprache\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.nmz.de\/wm2014\/schlagworte\/sprache\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blogs.nmz.de\/wm2014\/"},{"@type":"ListItem","position":2,"name":"Sprache"}]},{"@type":"WebSite","@id":"https:\/\/blogs.nmz.de\/wm2014\/#website","url":"https:\/\/blogs.nmz.de\/wm2014\/","name":"Auf dem Sperrsitz","description":"Im Kultur-Zoo der nmz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.nmz.de\/wm2014\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/tags\/8381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/posts?tags=8381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}