{"id":506,"date":"2014-08-22T10:47:03","date_gmt":"2014-08-22T08:47:03","guid":{"rendered":"http:\/\/blogs.nmz.de\/wm2014\/?p=506"},"modified":"2014-08-22T11:17:14","modified_gmt":"2014-08-22T09:17:14","slug":"ausklang-zum-wochenende","status":"publish","type":"post","link":"https:\/\/blogs.nmz.de\/wm2014\/2014\/08\/22\/ausklang-zum-wochenende\/","title":{"rendered":"Ausklang zum Wochenende"},"content":{"rendered":"<p>Also am Wochenende will ich schon meine Ruhe haben vor der Aufgeregtheit der Welt. Man ist da gewiss privilegiert. F\u00fcr viele Menschen ist das Wochenende nie eines, weil der Kummer, die Sorge, die Angst eine Best\u00e4ndigkeit haben, die nicht vor Zeitstruktur Halt macht. <\/p>\n<p>Unsere WM-Tipperin Lydia Bader mit Debussy.<\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"676\" height=\"381\" src=\"https:\/\/www.youtube.com\/embed\/-E-jXHn1o4Y?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=de-DE&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n<p>PS: Etwas tiefsinniger befasse ich mich im Moment mit der <a href=\"http:\/\/www.jazzzeitung.de\/cms\/2014\/08\/jazz-ist-zeigen-aeh-zeichen-schweigen\/\" title=\"Jazzkritik ist k\u00e4uflich\" target=\"_blank\">K\u00e4uflichkeit der Jazzkritik<\/a> im Blog der JazzZeitung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Also am Wochenende will ich schon meine Ruhe haben vor der Aufgeregtheit der Welt. Man ist da gewiss privilegiert. F\u00fcr viele Menschen ist das Wochenende nie eines, weil der Kummer, die Sorge, die Angst eine Best\u00e4ndigkeit haben, die nicht vor&#8230; <a class=\"more-link\" href=\"https:\/\/blogs.nmz.de\/wm2014\/2014\/08\/22\/ausklang-zum-wochenende\/\">Weiterlesen &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":507,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[385,533],"tags":[11063,11541,13108],"class_list":["post-506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kultur","category-musik","tag-claude-debussy","tag-lydia-maria-bader","tag-musik"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ausklang zum Wochenende - Auf dem Sperrsitz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.nmz.de\/wm2014\/2014\/08\/22\/ausklang-zum-wochenende\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ausklang zum Wochenende - Auf dem Sperrsitz\" \/>\n<meta property=\"og:description\" content=\"Also am Wochenende will ich schon meine Ruhe haben vor der Aufgeregtheit der Welt. Man ist da gewiss privilegiert. F\u00fcr viele Menschen ist das Wochenende nie eines, weil der Kummer, die Sorge, die Angst eine Best\u00e4ndigkeit haben, die nicht vor... Weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.nmz.de\/wm2014\/2014\/08\/22\/ausklang-zum-wochenende\/\" \/>\n<meta property=\"og:site_name\" content=\"Auf dem Sperrsitz\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/musikzeitung\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/hufner\" \/>\n<meta property=\"article:published_time\" content=\"2014-08-22T08:47:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-08-22T09:17:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/blogs.nmz.de\/wm2014\/files\/2014\/08\/nikel_c_hufner.jpg?fit=1200%2C900&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Martin Hufner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@huflaikhan\" \/>\n<meta name=\"twitter:site\" content=\"@musikzeitung\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin Hufner\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2014\\\/08\\\/22\\\/ausklang-zum-wochenende\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2014\\\/08\\\/22\\\/ausklang-zum-wochenende\\\/\"},\"author\":{\"name\":\"Martin Hufner\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#\\\/schema\\\/person\\\/488a80049cf0bbc4cce99951ae91c3b9\"},\"headline\":\"Ausklang zum Wochenende\",\"datePublished\":\"2014-08-22T08:47:03+00:00\",\"dateModified\":\"2014-08-22T09:17:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2014\\\/08\\\/22\\\/ausklang-zum-wochenende\\\/\"},\"wordCount\":81,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2014\\\/08\\\/22\\\/ausklang-zum-wochenende\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/wm2014\\\/files\\\/2014\\\/08\\\/nikel_c_hufner.jpg?fit=1200%2C900&ssl=1\",\"keywords\":[\"Claude Debussy\",\"Lydia Maria Bader\",\"Musik\"],\"articleSection\":[\"Kultur\",\"Musik\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2014\\\/08\\\/22\\\/ausklang-zum-wochenende\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2014\\\/08\\\/22\\\/ausklang-zum-wochenende\\\/\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2014\\\/08\\\/22\\\/ausklang-zum-wochenende\\\/\",\"name\":\"Ausklang zum Wochenende - Auf dem Sperrsitz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2014\\\/08\\\/22\\\/ausklang-zum-wochenende\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2014\\\/08\\\/22\\\/ausklang-zum-wochenende\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/wm2014\\\/files\\\/2014\\\/08\\\/nikel_c_hufner.jpg?fit=1200%2C900&ssl=1\",\"datePublished\":\"2014-08-22T08:47:03+00:00\",\"dateModified\":\"2014-08-22T09:17:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#\\\/schema\\\/person\\\/488a80049cf0bbc4cce99951ae91c3b9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2014\\\/08\\\/22\\\/ausklang-zum-wochenende\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2014\\\/08\\\/22\\\/ausklang-zum-wochenende\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2014\\\/08\\\/22\\\/ausklang-zum-wochenende\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/wm2014\\\/files\\\/2014\\\/08\\\/nikel_c_hufner.jpg?fit=1200%2C900&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/wm2014\\\/files\\\/2014\\\/08\\\/nikel_c_hufner.jpg?fit=1200%2C900&ssl=1\",\"width\":1200,\"height\":900,\"caption\":\"Ensemble Nikel in Fahrt. Foto: Hufner\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2014\\\/08\\\/22\\\/ausklang-zum-wochenende\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ausklang zum Wochenende\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#website\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/\",\"name\":\"Auf dem Sperrsitz\",\"description\":\"Im Kultur-Zoo der nmz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#\\\/schema\\\/person\\\/488a80049cf0bbc4cce99951ae91c3b9\",\"name\":\"Martin Hufner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g\",\"caption\":\"Martin Hufner\"},\"description\":\"seit 1997 chef\u00f6konom der kritischen masse und netzbabysitter der nmz.\",\"sameAs\":[\"https:\\\/\\\/www.musikkritik.org\",\"http:\\\/\\\/www.facebook.com\\\/hufner\",\"https:\\\/\\\/www.linkedin.com\\\/profile\\\/view?id=48050869&trk=spm_pic\",\"https:\\\/\\\/x.com\\\/huflaikhan\"],\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ausklang zum Wochenende - Auf dem Sperrsitz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.nmz.de\/wm2014\/2014\/08\/22\/ausklang-zum-wochenende\/","og_locale":"de_DE","og_type":"article","og_title":"Ausklang zum Wochenende - Auf dem Sperrsitz","og_description":"Also am Wochenende will ich schon meine Ruhe haben vor der Aufgeregtheit der Welt. Man ist da gewiss privilegiert. F\u00fcr viele Menschen ist das Wochenende nie eines, weil der Kummer, die Sorge, die Angst eine Best\u00e4ndigkeit haben, die nicht vor... Weiterlesen &rarr;","og_url":"https:\/\/blogs.nmz.de\/wm2014\/2014\/08\/22\/ausklang-zum-wochenende\/","og_site_name":"Auf dem Sperrsitz","article_publisher":"http:\/\/www.facebook.com\/musikzeitung","article_author":"http:\/\/www.facebook.com\/hufner","article_published_time":"2014-08-22T08:47:03+00:00","article_modified_time":"2014-08-22T09:17:14+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/i1.wp.com\/blogs.nmz.de\/wm2014\/files\/2014\/08\/nikel_c_hufner.jpg?fit=1200%2C900&ssl=1","type":"image\/jpeg"}],"author":"Martin Hufner","twitter_card":"summary_large_image","twitter_creator":"@huflaikhan","twitter_site":"@musikzeitung","twitter_misc":{"Verfasst von":"Martin Hufner"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.nmz.de\/wm2014\/2014\/08\/22\/ausklang-zum-wochenende\/#article","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2014\/08\/22\/ausklang-zum-wochenende\/"},"author":{"name":"Martin Hufner","@id":"https:\/\/blogs.nmz.de\/wm2014\/#\/schema\/person\/488a80049cf0bbc4cce99951ae91c3b9"},"headline":"Ausklang zum Wochenende","datePublished":"2014-08-22T08:47:03+00:00","dateModified":"2014-08-22T09:17:14+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2014\/08\/22\/ausklang-zum-wochenende\/"},"wordCount":81,"commentCount":0,"image":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2014\/08\/22\/ausklang-zum-wochenende\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/wm2014\/files\/2014\/08\/nikel_c_hufner.jpg?fit=1200%2C900&ssl=1","keywords":["Claude Debussy","Lydia Maria Bader","Musik"],"articleSection":["Kultur","Musik"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.nmz.de\/wm2014\/2014\/08\/22\/ausklang-zum-wochenende\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.nmz.de\/wm2014\/2014\/08\/22\/ausklang-zum-wochenende\/","url":"https:\/\/blogs.nmz.de\/wm2014\/2014\/08\/22\/ausklang-zum-wochenende\/","name":"Ausklang zum Wochenende - Auf dem Sperrsitz","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2014\/08\/22\/ausklang-zum-wochenende\/#primaryimage"},"image":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2014\/08\/22\/ausklang-zum-wochenende\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/wm2014\/files\/2014\/08\/nikel_c_hufner.jpg?fit=1200%2C900&ssl=1","datePublished":"2014-08-22T08:47:03+00:00","dateModified":"2014-08-22T09:17:14+00:00","author":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/#\/schema\/person\/488a80049cf0bbc4cce99951ae91c3b9"},"breadcrumb":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2014\/08\/22\/ausklang-zum-wochenende\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.nmz.de\/wm2014\/2014\/08\/22\/ausklang-zum-wochenende\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/wm2014\/2014\/08\/22\/ausklang-zum-wochenende\/#primaryimage","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/wm2014\/files\/2014\/08\/nikel_c_hufner.jpg?fit=1200%2C900&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/wm2014\/files\/2014\/08\/nikel_c_hufner.jpg?fit=1200%2C900&ssl=1","width":1200,"height":900,"caption":"Ensemble Nikel in Fahrt. Foto: Hufner"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.nmz.de\/wm2014\/2014\/08\/22\/ausklang-zum-wochenende\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blogs.nmz.de\/wm2014\/"},{"@type":"ListItem","position":2,"name":"Ausklang zum Wochenende"}]},{"@type":"WebSite","@id":"https:\/\/blogs.nmz.de\/wm2014\/#website","url":"https:\/\/blogs.nmz.de\/wm2014\/","name":"Auf dem Sperrsitz","description":"Im Kultur-Zoo der nmz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.nmz.de\/wm2014\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blogs.nmz.de\/wm2014\/#\/schema\/person\/488a80049cf0bbc4cce99951ae91c3b9","name":"Martin Hufner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g","caption":"Martin Hufner"},"description":"seit 1997 chef\u00f6konom der kritischen masse und netzbabysitter der nmz.","sameAs":["https:\/\/www.musikkritik.org","http:\/\/www.facebook.com\/hufner","https:\/\/www.linkedin.com\/profile\/view?id=48050869&trk=spm_pic","https:\/\/x.com\/huflaikhan"],"url":"https:\/\/blogs.nmz.de\/wm2014\/author\/admin\/"}]}},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","jetpack_shortlink":"https:\/\/wp.me\/p4Gg77-8a","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogs.nmz.de\/wm2014\/files\/2014\/08\/nikel_c_hufner.jpg?fit=1200%2C900&ssl=1","_links":{"self":[{"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/posts\/506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/comments?post=506"}],"version-history":[{"count":3,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/posts\/506\/revisions"}],"predecessor-version":[{"id":510,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/posts\/506\/revisions\/510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/media\/507"}],"wp:attachment":[{"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/media?parent=506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/categories?post=506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/tags?post=506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}