{"id":387,"date":"2014-07-27T09:10:18","date_gmt":"2014-07-27T07:10:18","guid":{"rendered":"http:\/\/blogs.nmz.de\/wm2014\/?p=387"},"modified":"2014-07-27T11:44:17","modified_gmt":"2014-07-27T09:44:17","slug":"stoererhaftung-in-der-kultur","status":"publish","type":"post","link":"https:\/\/blogs.nmz.de\/wm2014\/2014\/07\/27\/stoererhaftung-in-der-kultur\/","title":{"rendered":"St\u00f6rerhaftung in der Kultur"},"content":{"rendered":"<p>Gehen wir kurz zur\u00fcck zum Ursprung des Blogs, den es\u00a0 im Fu\u00dfball hatte. Die Hansestadt Bremen will in Zukunft die Polizeieins\u00e4tze bei Fu\u00dfballveranstaltungen im Weser-Stadion (was ist eigentlich Weser nochmal f\u00fcr ein Sponsor) den Veranstaltern in Rechnung stellen. Ren\u00e9 Pollesch findet, das kann man doch auch prima in der Kulturszene umsetzen.<\/p>\n<blockquote class=\"twitter-tweet\" width=\"550\">\n<p>Fernsehen soll f\u00fcr Bayreuth und Polizeieins\u00e4tze zahlen<\/p>\n<p>&mdash; Ren\u00e9 Pollesch (@renepollesch) <a href=\"https:\/\/twitter.com\/renepollesch\/statuses\/492734614566629376\">July 25, 2014<\/a><\/p><\/blockquote>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Bezahlen sollten die Nutzer und Verursacher dieser Dinge. Sozusagen St\u00f6rerhaftung f\u00fcr Anf\u00e4nger.<\/p>\n<h2>St\u00f6rerhaftung f\u00fcr Profis (Die Sache Schavan)<\/h2>\n<p>Eine andere Angelegenheit scheint dagegen zum Abschluss gekommen zu sein: Die Aberkennung des Doktogrades von Annette Schavan.<\/p>\n<p><!--more--><\/p>\n<p>In der Sache Schavan finden sich erstaunliche Dokumente, die geeignet sind, das Vertrauen in den Wissenschafts- wie Politikbereich erheblich zu st\u00f6ren; wenn man es nicht schon sowieso w\u00fcsste, weil man darin gearbeitet hat.<\/p>\n<p>In diesem <a title=\"Causa Schavan\" href=\"http:\/\/causaschavan.wordpress.com\/2014\/07\/23\/schavangate-komplett-das-vollstandige-dossier-der-bericht-der-uni-dusseldorf-zum-download\/\">Dossier<\/a> sind Anschreiben von hochrangigen Vertretern des Wissensmanagements die f\u00fcr Schavan k\u00e4mpften \u2013 was ja jeder gerne machen kann \u2013 nachzulesen. Die Autoren standen aber in gewisser Hinsicht zugleich unter der Aufsicht der damaligen Bildungsministerin, was auch noch Zufall sein konnte. Aber ihre teils l\u00e4cherlichen und sowieso untauglichen Mittel des Versuchs der Einflussnahme, erzeugen ein f\u00fcr die Institutionen peinliches Bild.<\/p>\n<h2>Barenboim meldet sich zu Wort<\/h2>\n<p>Im <a href=\"http:\/\/www.theguardian.com\/commentisfree\/2014\/jul\/24\/israelis-palestinians-losers-conflict-suffering-rights\" target=\"_blank\">britischen Guardian<\/a> hat sich nun Daniel Barenboim auch zur verh\u00e4rteten Situation in Israel\/Gaza ge\u00e4u\u00dfert (Both Israelis and Palestinians are losers in this conflict). Die deutschsprachige \u00dcbersetzung brachte unter anderem die <a href=\"http:\/\/www.welt.de\/kultur\/buehne-konzert\/article130536258\/Es-gibt-keine-militaerische-Loesung.html\" target=\"_blank\">Welt<\/a> (bezeichnenderweise im Feuilleton) sowie andere Axel-Springer-Organe.<\/p>\n<p>Die Reaktion hierauf ist in der musikalischen Facebook-Welt recht zwiegespalten &#8211; die einen begr\u00fc\u00dfen das Wort, dass eine Person f\u00fchrt, die den Konflikt aus der N\u00e4he kennt und sich auf keine Seite schl\u00e4gt, um der anderen etwas vorzuwerfen. Andere sehen darin wieder nur eine Art Marketing-Aktion. So Genoel Lilienstern:<\/p>\n<blockquote><p>Das idealisierende Medienbild einer Gemeinschaft und die \u00c4sthetisierung des politischen Konflikts n\u00fctzt vor allem Barenboim bei seinem gro\u00dfen Ziel irgendwann den Friedensnobelpreis verliehen zu bekommen. An der Situation der Pal\u00e4stinenser hat es nichts ge\u00e4ndert. (Quelle: <a href=\"https:\/\/www.facebook.com\/genoel.vonlilienstern\/posts\/10152293656698099\" target=\"_blank\">Facebook-Eintrag bei Lilienstern.<\/a>)<\/p><\/blockquote>\n<p>\u00dcberhaupt neigt der deutsche intellektuelle Musikus zu einer gewissen Selbstqu\u00e4lerei, was die Beobachtung fremder Gegenden angeht. Was ihn aber nicht davon abh\u00e4lt, grunds\u00e4tzlich auf einer Seite zu stehen und alle anderen Seiten als mediale Propaganda-Geschichten zu gei\u00dfeln. Da wird manchmal dann doch das Kind im Bad ertr\u00e4nkt..<\/p>\n<h2>Neue Grazer Geschichtsstunden<\/h2>\n<p>Um die Ecke passiert gar Wunderliches.<\/p>\n<div class=\"fb-post\" data-href=\"https:\/\/www.facebook.com\/hufner\/posts\/10152611837704182\" data-width=\"552\" style=\"background-color: #fff; display: inline-block;\"><\/div>\n<p>Man will es ja nicht wirklich glauben. Andererseits wundert einen ja auch nichts mehr.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gehen wir kurz zur\u00fcck zum Ursprung des Blogs, den es\u00a0 im Fu\u00dfball hatte. Die Hansestadt Bremen will in Zukunft die Polizeieins\u00e4tze bei Fu\u00dfballveranstaltungen im Weser-Stadion (was ist eigentlich Weser nochmal f\u00fcr ein Sponsor) den Veranstaltern in Rechnung stellen. Ren\u00e9 Pollesch&#8230; <a class=\"more-link\" href=\"https:\/\/blogs.nmz.de\/wm2014\/2014\/07\/27\/stoererhaftung-in-der-kultur\/\">Weiterlesen &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":397,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[769,385,860],"tags":[11493,1190,10680,11490,11492,13113,8385],"class_list":["post-387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internet","category-kultur","category-politik","tag-annette-schavan","tag-daniel-barenboim","tag-graz","tag-naher-osten","tag-nationalsozialismus","tag-politik","tag-wissenschaft"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>St\u00f6rerhaftung in der Kultur - Auf dem Sperrsitz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.nmz.de\/wm2014\/2014\/07\/27\/stoererhaftung-in-der-kultur\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"St\u00f6rerhaftung in der Kultur - Auf dem Sperrsitz\" \/>\n<meta property=\"og:description\" content=\"Gehen wir kurz zur\u00fcck zum Ursprung des Blogs, den es\u00a0 im Fu\u00dfball hatte. Die Hansestadt Bremen will in Zukunft die Polizeieins\u00e4tze bei Fu\u00dfballveranstaltungen im Weser-Stadion (was ist eigentlich Weser nochmal f\u00fcr ein Sponsor) den Veranstaltern in Rechnung stellen. Ren\u00e9 Pollesch... Weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.nmz.de\/wm2014\/2014\/07\/27\/stoererhaftung-in-der-kultur\/\" \/>\n<meta property=\"og:site_name\" content=\"Auf dem Sperrsitz\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/musikzeitung\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/hufner\" \/>\n<meta property=\"article:published_time\" content=\"2014-07-27T07:10:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-07-27T09:44:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/blogs.nmz.de\/wm2014\/files\/2014\/07\/herrlichkeit_c_hufner.jpg?fit=900%2C675&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Martin Hufner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@huflaikhan\" \/>\n<meta name=\"twitter:site\" content=\"@musikzeitung\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin Hufner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2014\\\/07\\\/27\\\/stoererhaftung-in-der-kultur\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2014\\\/07\\\/27\\\/stoererhaftung-in-der-kultur\\\/\"},\"author\":{\"name\":\"Martin Hufner\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#\\\/schema\\\/person\\\/488a80049cf0bbc4cce99951ae91c3b9\"},\"headline\":\"St\u00f6rerhaftung in der Kultur\",\"datePublished\":\"2014-07-27T07:10:18+00:00\",\"dateModified\":\"2014-07-27T09:44:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2014\\\/07\\\/27\\\/stoererhaftung-in-der-kultur\\\/\"},\"wordCount\":428,\"commentCount\":3,\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2014\\\/07\\\/27\\\/stoererhaftung-in-der-kultur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/wm2014\\\/files\\\/2014\\\/07\\\/herrlichkeit_c_hufner.jpg?fit=900%2C675&ssl=1\",\"keywords\":[\"Annette Schavan\",\"Daniel Barenboim\",\"Graz\",\"Naher Osten\",\"Nationalsozialismus\",\"Politik\",\"Wissenschaft\"],\"articleSection\":[\"Internet\",\"Kultur\",\"Politik\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2014\\\/07\\\/27\\\/stoererhaftung-in-der-kultur\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2014\\\/07\\\/27\\\/stoererhaftung-in-der-kultur\\\/\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2014\\\/07\\\/27\\\/stoererhaftung-in-der-kultur\\\/\",\"name\":\"St\u00f6rerhaftung in der Kultur - Auf dem Sperrsitz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2014\\\/07\\\/27\\\/stoererhaftung-in-der-kultur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2014\\\/07\\\/27\\\/stoererhaftung-in-der-kultur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/wm2014\\\/files\\\/2014\\\/07\\\/herrlichkeit_c_hufner.jpg?fit=900%2C675&ssl=1\",\"datePublished\":\"2014-07-27T07:10:18+00:00\",\"dateModified\":\"2014-07-27T09:44:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#\\\/schema\\\/person\\\/488a80049cf0bbc4cce99951ae91c3b9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2014\\\/07\\\/27\\\/stoererhaftung-in-der-kultur\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2014\\\/07\\\/27\\\/stoererhaftung-in-der-kultur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2014\\\/07\\\/27\\\/stoererhaftung-in-der-kultur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/wm2014\\\/files\\\/2014\\\/07\\\/herrlichkeit_c_hufner.jpg?fit=900%2C675&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/wm2014\\\/files\\\/2014\\\/07\\\/herrlichkeit_c_hufner.jpg?fit=900%2C675&ssl=1\",\"width\":900,\"height\":675,\"caption\":\"Neue Herrlichkeit\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2014\\\/07\\\/27\\\/stoererhaftung-in-der-kultur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"St&#246;rerhaftung in der Kultur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#website\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/\",\"name\":\"Auf dem Sperrsitz\",\"description\":\"Im Kultur-Zoo der nmz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#\\\/schema\\\/person\\\/488a80049cf0bbc4cce99951ae91c3b9\",\"name\":\"Martin Hufner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g\",\"caption\":\"Martin Hufner\"},\"description\":\"seit 1997 chef\u00f6konom der kritischen masse und netzbabysitter der nmz.\",\"sameAs\":[\"https:\\\/\\\/www.musikkritik.org\",\"http:\\\/\\\/www.facebook.com\\\/hufner\",\"https:\\\/\\\/www.linkedin.com\\\/profile\\\/view?id=48050869&trk=spm_pic\",\"https:\\\/\\\/x.com\\\/huflaikhan\"],\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"St\u00f6rerhaftung in der Kultur - Auf dem Sperrsitz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.nmz.de\/wm2014\/2014\/07\/27\/stoererhaftung-in-der-kultur\/","og_locale":"de_DE","og_type":"article","og_title":"St\u00f6rerhaftung in der Kultur - Auf dem Sperrsitz","og_description":"Gehen wir kurz zur\u00fcck zum Ursprung des Blogs, den es\u00a0 im Fu\u00dfball hatte. Die Hansestadt Bremen will in Zukunft die Polizeieins\u00e4tze bei Fu\u00dfballveranstaltungen im Weser-Stadion (was ist eigentlich Weser nochmal f\u00fcr ein Sponsor) den Veranstaltern in Rechnung stellen. Ren\u00e9 Pollesch... Weiterlesen &rarr;","og_url":"https:\/\/blogs.nmz.de\/wm2014\/2014\/07\/27\/stoererhaftung-in-der-kultur\/","og_site_name":"Auf dem Sperrsitz","article_publisher":"http:\/\/www.facebook.com\/musikzeitung","article_author":"http:\/\/www.facebook.com\/hufner","article_published_time":"2014-07-27T07:10:18+00:00","article_modified_time":"2014-07-27T09:44:17+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/i2.wp.com\/blogs.nmz.de\/wm2014\/files\/2014\/07\/herrlichkeit_c_hufner.jpg?fit=900%2C675&ssl=1","type":"image\/jpeg"}],"author":"Martin Hufner","twitter_card":"summary_large_image","twitter_creator":"@huflaikhan","twitter_site":"@musikzeitung","twitter_misc":{"Verfasst von":"Martin Hufner","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.nmz.de\/wm2014\/2014\/07\/27\/stoererhaftung-in-der-kultur\/#article","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2014\/07\/27\/stoererhaftung-in-der-kultur\/"},"author":{"name":"Martin Hufner","@id":"https:\/\/blogs.nmz.de\/wm2014\/#\/schema\/person\/488a80049cf0bbc4cce99951ae91c3b9"},"headline":"St\u00f6rerhaftung in der Kultur","datePublished":"2014-07-27T07:10:18+00:00","dateModified":"2014-07-27T09:44:17+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2014\/07\/27\/stoererhaftung-in-der-kultur\/"},"wordCount":428,"commentCount":3,"image":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2014\/07\/27\/stoererhaftung-in-der-kultur\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/wm2014\/files\/2014\/07\/herrlichkeit_c_hufner.jpg?fit=900%2C675&ssl=1","keywords":["Annette Schavan","Daniel Barenboim","Graz","Naher Osten","Nationalsozialismus","Politik","Wissenschaft"],"articleSection":["Internet","Kultur","Politik"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.nmz.de\/wm2014\/2014\/07\/27\/stoererhaftung-in-der-kultur\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.nmz.de\/wm2014\/2014\/07\/27\/stoererhaftung-in-der-kultur\/","url":"https:\/\/blogs.nmz.de\/wm2014\/2014\/07\/27\/stoererhaftung-in-der-kultur\/","name":"St\u00f6rerhaftung in der Kultur - Auf dem Sperrsitz","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2014\/07\/27\/stoererhaftung-in-der-kultur\/#primaryimage"},"image":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2014\/07\/27\/stoererhaftung-in-der-kultur\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/wm2014\/files\/2014\/07\/herrlichkeit_c_hufner.jpg?fit=900%2C675&ssl=1","datePublished":"2014-07-27T07:10:18+00:00","dateModified":"2014-07-27T09:44:17+00:00","author":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/#\/schema\/person\/488a80049cf0bbc4cce99951ae91c3b9"},"breadcrumb":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2014\/07\/27\/stoererhaftung-in-der-kultur\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.nmz.de\/wm2014\/2014\/07\/27\/stoererhaftung-in-der-kultur\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/wm2014\/2014\/07\/27\/stoererhaftung-in-der-kultur\/#primaryimage","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/wm2014\/files\/2014\/07\/herrlichkeit_c_hufner.jpg?fit=900%2C675&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/wm2014\/files\/2014\/07\/herrlichkeit_c_hufner.jpg?fit=900%2C675&ssl=1","width":900,"height":675,"caption":"Neue Herrlichkeit"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.nmz.de\/wm2014\/2014\/07\/27\/stoererhaftung-in-der-kultur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blogs.nmz.de\/wm2014\/"},{"@type":"ListItem","position":2,"name":"St&#246;rerhaftung in der Kultur"}]},{"@type":"WebSite","@id":"https:\/\/blogs.nmz.de\/wm2014\/#website","url":"https:\/\/blogs.nmz.de\/wm2014\/","name":"Auf dem Sperrsitz","description":"Im Kultur-Zoo der nmz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.nmz.de\/wm2014\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blogs.nmz.de\/wm2014\/#\/schema\/person\/488a80049cf0bbc4cce99951ae91c3b9","name":"Martin Hufner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g","caption":"Martin Hufner"},"description":"seit 1997 chef\u00f6konom der kritischen masse und netzbabysitter der nmz.","sameAs":["https:\/\/www.musikkritik.org","http:\/\/www.facebook.com\/hufner","https:\/\/www.linkedin.com\/profile\/view?id=48050869&trk=spm_pic","https:\/\/x.com\/huflaikhan"],"url":"https:\/\/blogs.nmz.de\/wm2014\/author\/admin\/"}]}},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","jetpack_shortlink":"https:\/\/wp.me\/p4Gg77-6f","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogs.nmz.de\/wm2014\/files\/2014\/07\/herrlichkeit_c_hufner.jpg?fit=900%2C675&ssl=1","_links":{"self":[{"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/posts\/387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/comments?post=387"}],"version-history":[{"count":10,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/posts\/387\/revisions"}],"predecessor-version":[{"id":399,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/posts\/387\/revisions\/399"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/media\/397"}],"wp:attachment":[{"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/media?parent=387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/categories?post=387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/tags?post=387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}