{"id":2340,"date":"2016-09-14T12:56:10","date_gmt":"2016-09-14T10:56:10","guid":{"rendered":"http:\/\/blogs.nmz.de\/wm2014\/?p=2340"},"modified":"2016-09-14T12:56:10","modified_gmt":"2016-09-14T10:56:10","slug":"horst-seehofers-medienpolitischer-sondermuell","status":"publish","type":"post","link":"https:\/\/blogs.nmz.de\/wm2014\/2016\/09\/14\/horst-seehofers-medienpolitischer-sondermuell\/","title":{"rendered":"Horst Seehofers medienpolitischer Sonderm\u00fcll"},"content":{"rendered":"<p>Vor ein paar Tagen soll der CSU-Horst gesagt haben: &#8222;Wir sind der Auffassung, dass die Grundversorgung auch von einer Fernsehanstalt geleistet werden k\u00f6nnte.&#8220; Und zwar gegen\u00fcber der BILD-Zeitung. In dem n\u00e4chsten Grund<del>hatz<\/del>satzprogramm der CSU soll sich folgende Idee wiederfinden: &#8222;Wir streben langfristig die Beseitigung von Doppelstrukturen und die Zusammenlegung von ARD und ZDF unter einem Dach an.&#8220; Und? Was passiert? Wie bei bestimmten anderen Parteien springen die Kommentare an, man distanziert sich hier, kritisiert dort. Und: Man nimmt das oder den ernst?<\/p>\n<p>Und warum? Weil er wichtig ist! Weil er Ministerpr\u00e4sident in Bayern ist! Weil er die politische Treibjagd zur Bundestagswahl eingeleitet hat und man sich dazu verhalten muss &#8211; genau wie \u00fcber jeden politischen Sonderm\u00fcll einer anderen legalen Partei sogleich eine Sturmflut der Entr\u00fcstung hereinbricht. Allein ein paar Komiker haben die richtige Antwort auf den Aufsto\u00df der CSU gefunden und schlagen im Gegenzug die Zusammenlegung von CSU und AfD vor \u2013 wozu braucht man einen Horst Seehofer, wenn man eine Frauke Petry haben k\u00f6nnte.<\/p>\n<p>Also dieser Seehofer ist auf dem Weg zur Weltherrschaft. Der wird dann schlechterdings \u2013 bei der JazzZeitung kann man es lesen \u2013 <a href=\"http:\/\/www.jazzzeitung.de\/cms\/2016\/09\/news20-festival-frei-improvisierter-musik-horst-seehofer-wird-schirmherr-des-1-bayerische-landesjazzfestivalsjazz-session-im-rahmen-des-kulturherbst-oberstaufen\/\"><u>Schirmherr des 1. Bayerischen Landesjazzfestivals.<\/u><\/a> Eine fatale Wahl. Wenn er den Jazz so gut beschirmt wie seinen Verstand, dann gute Nacht.<\/p>\n<p>Ich vermute ja, dem Seehofer ist das alles eh ziemlich wurscht, er hat nur das Wort &#8222;Herrschaft&#8220; entdeckt. Mehr Ziele verfolgt er ja sowieso nicht.<\/p>\n<div class=\"fb-post\" data-href=\"https:\/\/www.facebook.com\/theo.geissler\/posts\/10154608715949445\" data-width=\"552\" style=\"background-color: #fff; display: inline-block;\"><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vor ein paar Tagen soll der CSU-Horst gesagt haben: &#8222;Wir sind der Auffassung, dass die Grundversorgung auch von einer Fernsehanstalt geleistet werden k\u00f6nnte.&#8220; Und zwar gegen\u00fcber der BILD-Zeitung. In dem n\u00e4chsten Grundhatzsatzprogramm der CSU soll sich folgende Idee wiederfinden: &#8222;Wir&#8230; <a class=\"more-link\" href=\"https:\/\/blogs.nmz.de\/wm2014\/2016\/09\/14\/horst-seehofers-medienpolitischer-sondermuell\/\">Weiterlesen &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":2342,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[385,836,860,665],"tags":[10674,1635,2538,13878,820,13876],"class_list":["post-2340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kultur","category-medien","category-politik","category-radio","tag-afd","tag-bayern","tag-csu","tag-horst-seehofer","tag-jazz","tag-medienpolitik"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Horst Seehofers medienpolitischer Sonderm\u00fcll - Auf dem Sperrsitz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.nmz.de\/wm2014\/2016\/09\/14\/horst-seehofers-medienpolitischer-sondermuell\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Horst Seehofers medienpolitischer Sonderm\u00fcll - Auf dem Sperrsitz\" \/>\n<meta property=\"og:description\" content=\"Vor ein paar Tagen soll der CSU-Horst gesagt haben: &#8222;Wir sind der Auffassung, dass die Grundversorgung auch von einer Fernsehanstalt geleistet werden k\u00f6nnte.&#8220; Und zwar gegen\u00fcber der BILD-Zeitung. In dem n\u00e4chsten Grundhatzsatzprogramm der CSU soll sich folgende Idee wiederfinden: &#8222;Wir... Weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.nmz.de\/wm2014\/2016\/09\/14\/horst-seehofers-medienpolitischer-sondermuell\/\" \/>\n<meta property=\"og:site_name\" content=\"Auf dem Sperrsitz\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/musikzeitung\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/hufner\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-14T10:56:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/blogs.nmz.de\/wm2014\/files\/2016\/09\/frosch_c_hufner.jpg?fit=1600%2C1200&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Martin Hufner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@huflaikhan\" \/>\n<meta name=\"twitter:site\" content=\"@musikzeitung\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin Hufner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2016\\\/09\\\/14\\\/horst-seehofers-medienpolitischer-sondermuell\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2016\\\/09\\\/14\\\/horst-seehofers-medienpolitischer-sondermuell\\\/\"},\"author\":{\"name\":\"Martin Hufner\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#\\\/schema\\\/person\\\/488a80049cf0bbc4cce99951ae91c3b9\"},\"headline\":\"Horst Seehofers medienpolitischer Sonderm\u00fcll\",\"datePublished\":\"2016-09-14T10:56:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2016\\\/09\\\/14\\\/horst-seehofers-medienpolitischer-sondermuell\\\/\"},\"wordCount\":250,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2016\\\/09\\\/14\\\/horst-seehofers-medienpolitischer-sondermuell\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/wm2014\\\/files\\\/2016\\\/09\\\/frosch_c_hufner.jpg?fit=1600%2C1200&ssl=1\",\"keywords\":[\"AfD\",\"Bayern\",\"CSU\",\"Horst Seehofer\",\"Jazz\",\"Medienpolitik\"],\"articleSection\":[\"Kultur\",\"Medien\",\"Politik\",\"Radio\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2016\\\/09\\\/14\\\/horst-seehofers-medienpolitischer-sondermuell\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2016\\\/09\\\/14\\\/horst-seehofers-medienpolitischer-sondermuell\\\/\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2016\\\/09\\\/14\\\/horst-seehofers-medienpolitischer-sondermuell\\\/\",\"name\":\"Horst Seehofers medienpolitischer Sonderm\u00fcll - Auf dem Sperrsitz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2016\\\/09\\\/14\\\/horst-seehofers-medienpolitischer-sondermuell\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2016\\\/09\\\/14\\\/horst-seehofers-medienpolitischer-sondermuell\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/wm2014\\\/files\\\/2016\\\/09\\\/frosch_c_hufner.jpg?fit=1600%2C1200&ssl=1\",\"datePublished\":\"2016-09-14T10:56:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#\\\/schema\\\/person\\\/488a80049cf0bbc4cce99951ae91c3b9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2016\\\/09\\\/14\\\/horst-seehofers-medienpolitischer-sondermuell\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2016\\\/09\\\/14\\\/horst-seehofers-medienpolitischer-sondermuell\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2016\\\/09\\\/14\\\/horst-seehofers-medienpolitischer-sondermuell\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/wm2014\\\/files\\\/2016\\\/09\\\/frosch_c_hufner.jpg?fit=1600%2C1200&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/wm2014\\\/files\\\/2016\\\/09\\\/frosch_c_hufner.jpg?fit=1600%2C1200&ssl=1\",\"width\":1600,\"height\":1200,\"caption\":\"Der Frosch hat mehr Vernunft als die Medienpolitiker der CSU. Foto: Hufner\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2016\\\/09\\\/14\\\/horst-seehofers-medienpolitischer-sondermuell\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Horst Seehofers medienpolitischer Sonderm&#252;ll\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#website\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/\",\"name\":\"Auf dem Sperrsitz\",\"description\":\"Im Kultur-Zoo der nmz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#\\\/schema\\\/person\\\/488a80049cf0bbc4cce99951ae91c3b9\",\"name\":\"Martin Hufner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g\",\"caption\":\"Martin Hufner\"},\"description\":\"seit 1997 chef\u00f6konom der kritischen masse und netzbabysitter der nmz.\",\"sameAs\":[\"https:\\\/\\\/www.musikkritik.org\",\"http:\\\/\\\/www.facebook.com\\\/hufner\",\"https:\\\/\\\/www.linkedin.com\\\/profile\\\/view?id=48050869&trk=spm_pic\",\"https:\\\/\\\/x.com\\\/huflaikhan\"],\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Horst Seehofers medienpolitischer Sonderm\u00fcll - Auf dem Sperrsitz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.nmz.de\/wm2014\/2016\/09\/14\/horst-seehofers-medienpolitischer-sondermuell\/","og_locale":"de_DE","og_type":"article","og_title":"Horst Seehofers medienpolitischer Sonderm\u00fcll - Auf dem Sperrsitz","og_description":"Vor ein paar Tagen soll der CSU-Horst gesagt haben: &#8222;Wir sind der Auffassung, dass die Grundversorgung auch von einer Fernsehanstalt geleistet werden k\u00f6nnte.&#8220; Und zwar gegen\u00fcber der BILD-Zeitung. In dem n\u00e4chsten Grundhatzsatzprogramm der CSU soll sich folgende Idee wiederfinden: &#8222;Wir... Weiterlesen &rarr;","og_url":"https:\/\/blogs.nmz.de\/wm2014\/2016\/09\/14\/horst-seehofers-medienpolitischer-sondermuell\/","og_site_name":"Auf dem Sperrsitz","article_publisher":"http:\/\/www.facebook.com\/musikzeitung","article_author":"http:\/\/www.facebook.com\/hufner","article_published_time":"2016-09-14T10:56:10+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/i2.wp.com\/blogs.nmz.de\/wm2014\/files\/2016\/09\/frosch_c_hufner.jpg?fit=1600%2C1200&ssl=1","type":"image\/jpeg"}],"author":"Martin Hufner","twitter_card":"summary_large_image","twitter_creator":"@huflaikhan","twitter_site":"@musikzeitung","twitter_misc":{"Verfasst von":"Martin Hufner","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.nmz.de\/wm2014\/2016\/09\/14\/horst-seehofers-medienpolitischer-sondermuell\/#article","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2016\/09\/14\/horst-seehofers-medienpolitischer-sondermuell\/"},"author":{"name":"Martin Hufner","@id":"https:\/\/blogs.nmz.de\/wm2014\/#\/schema\/person\/488a80049cf0bbc4cce99951ae91c3b9"},"headline":"Horst Seehofers medienpolitischer Sonderm\u00fcll","datePublished":"2016-09-14T10:56:10+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2016\/09\/14\/horst-seehofers-medienpolitischer-sondermuell\/"},"wordCount":250,"commentCount":0,"image":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2016\/09\/14\/horst-seehofers-medienpolitischer-sondermuell\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/wm2014\/files\/2016\/09\/frosch_c_hufner.jpg?fit=1600%2C1200&ssl=1","keywords":["AfD","Bayern","CSU","Horst Seehofer","Jazz","Medienpolitik"],"articleSection":["Kultur","Medien","Politik","Radio"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.nmz.de\/wm2014\/2016\/09\/14\/horst-seehofers-medienpolitischer-sondermuell\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.nmz.de\/wm2014\/2016\/09\/14\/horst-seehofers-medienpolitischer-sondermuell\/","url":"https:\/\/blogs.nmz.de\/wm2014\/2016\/09\/14\/horst-seehofers-medienpolitischer-sondermuell\/","name":"Horst Seehofers medienpolitischer Sonderm\u00fcll - Auf dem Sperrsitz","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2016\/09\/14\/horst-seehofers-medienpolitischer-sondermuell\/#primaryimage"},"image":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2016\/09\/14\/horst-seehofers-medienpolitischer-sondermuell\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/wm2014\/files\/2016\/09\/frosch_c_hufner.jpg?fit=1600%2C1200&ssl=1","datePublished":"2016-09-14T10:56:10+00:00","author":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/#\/schema\/person\/488a80049cf0bbc4cce99951ae91c3b9"},"breadcrumb":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2016\/09\/14\/horst-seehofers-medienpolitischer-sondermuell\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.nmz.de\/wm2014\/2016\/09\/14\/horst-seehofers-medienpolitischer-sondermuell\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/wm2014\/2016\/09\/14\/horst-seehofers-medienpolitischer-sondermuell\/#primaryimage","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/wm2014\/files\/2016\/09\/frosch_c_hufner.jpg?fit=1600%2C1200&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/wm2014\/files\/2016\/09\/frosch_c_hufner.jpg?fit=1600%2C1200&ssl=1","width":1600,"height":1200,"caption":"Der Frosch hat mehr Vernunft als die Medienpolitiker der CSU. Foto: Hufner"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.nmz.de\/wm2014\/2016\/09\/14\/horst-seehofers-medienpolitischer-sondermuell\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blogs.nmz.de\/wm2014\/"},{"@type":"ListItem","position":2,"name":"Horst Seehofers medienpolitischer Sonderm&#252;ll"}]},{"@type":"WebSite","@id":"https:\/\/blogs.nmz.de\/wm2014\/#website","url":"https:\/\/blogs.nmz.de\/wm2014\/","name":"Auf dem Sperrsitz","description":"Im Kultur-Zoo der nmz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.nmz.de\/wm2014\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blogs.nmz.de\/wm2014\/#\/schema\/person\/488a80049cf0bbc4cce99951ae91c3b9","name":"Martin Hufner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g","caption":"Martin Hufner"},"description":"seit 1997 chef\u00f6konom der kritischen masse und netzbabysitter der nmz.","sameAs":["https:\/\/www.musikkritik.org","http:\/\/www.facebook.com\/hufner","https:\/\/www.linkedin.com\/profile\/view?id=48050869&trk=spm_pic","https:\/\/x.com\/huflaikhan"],"url":"https:\/\/blogs.nmz.de\/wm2014\/author\/admin\/"}]}},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","jetpack_shortlink":"https:\/\/wp.me\/p4Gg77-BK","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogs.nmz.de\/wm2014\/files\/2016\/09\/frosch_c_hufner.jpg?fit=1600%2C1200&ssl=1","_links":{"self":[{"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/posts\/2340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/comments?post=2340"}],"version-history":[{"count":2,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/posts\/2340\/revisions"}],"predecessor-version":[{"id":2343,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/posts\/2340\/revisions\/2343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/media\/2342"}],"wp:attachment":[{"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/media?parent=2340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/categories?post=2340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/tags?post=2340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}