{"id":1495,"date":"2015-05-20T15:55:00","date_gmt":"2015-05-20T13:55:00","guid":{"rendered":"http:\/\/blogs.nmz.de\/wm2014\/?p=1495"},"modified":"2015-05-20T21:35:53","modified_gmt":"2015-05-20T19:35:53","slug":"die-sperrtafel-und-die-presse-youtube-vs-gema","status":"publish","type":"post","link":"https:\/\/blogs.nmz.de\/wm2014\/2015\/05\/20\/die-sperrtafel-und-die-presse-youtube-vs-gema\/","title":{"rendered":"Die Sperrtafel, die Presse und die Sklaverei des \u201edigitalen Zeitalters\u201c (YouTube vs. Gema)"},"content":{"rendered":"<p>Die Sache mit der Wahrheit in der Presseberichterstattung ist nicht immer so einfach. Seit Jahren ist ein Streit zur Lizenzierung von Musik zwischen der Gema und YouTube anh\u00e4ngig. Dabei spielten Sperrtafeln eine gro\u00dfe Rolle, die den meisten YouTube-Nutzern in Deutschland angezeigt wurden. Kurz gesagt waren sie derart, dass YouTube behauptete, die Gema sperre die Wiedergabe in dieser Region. Die Gema zog gegen die Formulierung vor Gericht und gewann in <a href=\"http:\/\/www.nmz.de\/kiz\/nachrichten\/gericht-bestaetigt-alte-gema-sperrtafeln-bei-youtube-sind-unzulaessig\">zwei Instanzen<\/a>. Nat\u00fcrlich vollkommen zu Recht.<\/p>\n<p>Gleichwohl h\u00e4lt sich hartn\u00e4ckig das Ger\u00fccht, die Gema veranlasse die Sperrungen. Das war falsch und ist falsch. Wer die Videos sperrt, ist YouTube. Den schwarzen Peter hat man dennoch mit den merkw\u00fcrdigen Texten der Gema zugeschoben.<\/p>\n<p><strong>Gema-Sperrtafel? YouTube-Sperrtafel?<\/strong><\/p>\n<p>Ein Gro\u00dfteil der Presse hat hierbei leider auch hartn\u00e4ckig versagt und redete immer von Gema-Sperrtafeln, selbst das Oberlandesgericht M\u00fcnchen tut dies und die Gema zitiert sie entsprechend: OLG M\u00fcnchen best\u00e4tigt: <a href=\"https:\/\/www.gema.de\/aktuelles\/olg_muenchen_bestaetigt_gema_sperrtafeln_auf_youtube_sind_rechtswidrig\/\">GEMA-Sperrtafeln auf YouTube sind rechtswidrig.<\/a> Eigentlich sind es aber YouTube-Sperrtafeln, da ja YouTube die Auslieferung sperrt. Eine Ausnahem ist hier die <a href=\"http:\/\/www.mediabiz.de\/musik\/news\/apropos-seniorensaenger-und-youtube-sperrtafeln\/394508\">MusikWoche<\/a>, die eben von YouTube-Sperrtafeln spricht und hier muss man Gillig-Degrave f\u00fcr sein Sprachgef\u00fchl loben.<\/p>\n<p>Das Ger\u00fccht konnte also auch so fest im Bewusstsein sich halten, weil die Begrifflichkeit es nahelegte. Wenn man beispielsweise bei Google die entsprechenden Suchbegriffe eingibt, so kommt man n\u00e4mlich zu folgendem Ergebnis:<\/p>\n<ul>\n<li>GEMA-Sperrtafel = Ungef\u00e4hr 151.000 Ergebnisse<\/li>\n<li>YouTube-Sperrtafel = Ungef\u00e4hr 11.300 Ergebnisse<\/li>\n<\/ul>\n<p>Sprache erzeugt eben auch politisches Verhalten. Wollen wir es mal total fair sehen: Immerhin hat YouTube nach dem Urteil des ersten Instanz den Wortlaut des Textes der Sperrtafel ge\u00e4ndert, obwohl man das Urteil zun\u00e4chst nicht anerkennen mochte. Der Jubel der Gema \u00fcber die zweitinstanzliche Entscheidung sollte gleichwohl nicht zu gro\u00df ausfallen. Bislang ist das Urteil nicht rechtskr\u00e4ftig, auch wenn eine Revision nicht zugelassen wurde. Meines Erachtens hat in dieser Sache auch YouTube nicht die geringste Chance und es w\u00e4re allein eine taktische Finte.<\/p>\n<p><strong>Kramm und das digitale Zeitalter<\/strong><\/p>\n<p>Erstaunlicherweise kann selbst der Themenbeauftrage der Piratenpartei, Bruno Kramm, nicht umhin, zuzugestehen, dass <a href=\"https:\/\/www.piratenpartei.de\/2015\/05\/13\/katz-und-mausspiel-im-gemayoutube-streit-neue-episode\/\">Katz und Mausspiel im GEMA\/Youtube Streit: Neue Episode<\/a>. Ansonsten m\u00fcsste man auch letztg\u00fcltig daran zweifeln, ob er die richtige Mann f\u00fcr diese Position bei der Piratenpartei ist. Freilich ist die lapidare Umformulierung, die er anbietet, zwar populistisch lustig, aber sinnlos:<\/p>\n<p style=\"padding-left: 30px;\">\u00bbDieses Video ist in Deutschland nicht verf\u00fcgbar, weil das Urheberrecht noch immer nicht im digitalen Zeitalter angekommen ist\u2026\u00ab [Bruno Kramm]<\/p>\n<p>Dar\u00fcber kann man eigentlich nicht streiten, weil er dann doch auch mal seine Theorie des \u201edigitalen Zeitalters\u201c vorlegen sollte. Ich habe schon an anderer Stelle betont, es ist, wenn \u00fcberhaupt, umgekehrt. Das \u201edigitale Zeitalter\u201c ist noch nicht im Urheberrecht angekommen. W\u00fcrde man es wie Kramm sehen, dann sollte man auch die Sache konsequent zu ende denken und jede Form subjektiver Handlung als unsinnig ansehen. Man ist dann eben Spielball des Zeitalters und verzichtet auf eine aktive Gestaltung desselben. Anpassung also als die letztg\u00fcltige L\u00f6sung. Die Maschinen und M\u00e4rkte bestimmen dann, was der Fall sein soll. Ich finde das sehr wenig piratig, es ist sklavisch.<\/p>\n<p>Auf dem Weg dahin sind wir allerdings schon. Wir geben unsere Daten an allen Stellen der digitalen Welt weiter, wir nutzen fremdbestimmte Dienste wie Facebook, Twitter und Co. Kontrolle frisst Kontrollverlust. Aber das ist ein anderes Thema \u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Sache mit der Wahrheit in der Presseberichterstattung ist nicht immer so einfach. Seit Jahren ist ein Streit zur Lizenzierung von Musik zwischen der Gema und YouTube anh\u00e4ngig. Dabei spielten Sperrtafeln eine gro\u00dfe Rolle, die den meisten YouTube-Nutzern in Deutschland&#8230; <a class=\"more-link\" href=\"https:\/\/blogs.nmz.de\/wm2014\/2015\/05\/20\/die-sperrtafel-und-die-presse-youtube-vs-gema\/\">Weiterlesen &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":1497,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[769,385,836,860],"tags":[8121,25,13026,13025,8467,13005,282],"class_list":["post-1495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internet","category-kultur","category-medien","category-politik","tag-bruno-kramm","tag-gema","tag-neusprech","tag-objektivitaet","tag-piratenpartei","tag-presse","tag-youtube"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Sperrtafel, die Presse und die Sklaverei des \u201edigitalen Zeitalters\u201c (YouTube vs. Gema) - Auf dem Sperrsitz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.nmz.de\/wm2014\/2015\/05\/20\/die-sperrtafel-und-die-presse-youtube-vs-gema\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Sperrtafel, die Presse und die Sklaverei des \u201edigitalen Zeitalters\u201c (YouTube vs. Gema) - Auf dem Sperrsitz\" \/>\n<meta property=\"og:description\" content=\"Die Sache mit der Wahrheit in der Presseberichterstattung ist nicht immer so einfach. Seit Jahren ist ein Streit zur Lizenzierung von Musik zwischen der Gema und YouTube anh\u00e4ngig. Dabei spielten Sperrtafeln eine gro\u00dfe Rolle, die den meisten YouTube-Nutzern in Deutschland... Weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.nmz.de\/wm2014\/2015\/05\/20\/die-sperrtafel-und-die-presse-youtube-vs-gema\/\" \/>\n<meta property=\"og:site_name\" content=\"Auf dem Sperrsitz\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/musikzeitung\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/hufner\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-20T13:55:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-05-20T19:35:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/blogs.nmz.de\/wm2014\/files\/2015\/05\/smiliie-plattung.jpg?fit=1800%2C400&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Martin Hufner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@huflaikhan\" \/>\n<meta name=\"twitter:site\" content=\"@musikzeitung\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin Hufner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2015\\\/05\\\/20\\\/die-sperrtafel-und-die-presse-youtube-vs-gema\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2015\\\/05\\\/20\\\/die-sperrtafel-und-die-presse-youtube-vs-gema\\\/\"},\"author\":{\"name\":\"Martin Hufner\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#\\\/schema\\\/person\\\/488a80049cf0bbc4cce99951ae91c3b9\"},\"headline\":\"Die Sperrtafel, die Presse und die Sklaverei des \u201edigitalen Zeitalters\u201c (YouTube vs. Gema)\",\"datePublished\":\"2015-05-20T13:55:00+00:00\",\"dateModified\":\"2015-05-20T19:35:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2015\\\/05\\\/20\\\/die-sperrtafel-und-die-presse-youtube-vs-gema\\\/\"},\"wordCount\":564,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2015\\\/05\\\/20\\\/die-sperrtafel-und-die-presse-youtube-vs-gema\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/wm2014\\\/files\\\/2015\\\/05\\\/smiliie-plattung.jpg?fit=1800%2C400&ssl=1\",\"keywords\":[\"Bruno Kramm\",\"GEMA\",\"Neusprech\",\"Objektivit\u00e4t\",\"Piratenpartei\",\"Presse\",\"YouTube\"],\"articleSection\":[\"Internet\",\"Kultur\",\"Medien\",\"Politik\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2015\\\/05\\\/20\\\/die-sperrtafel-und-die-presse-youtube-vs-gema\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2015\\\/05\\\/20\\\/die-sperrtafel-und-die-presse-youtube-vs-gema\\\/\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2015\\\/05\\\/20\\\/die-sperrtafel-und-die-presse-youtube-vs-gema\\\/\",\"name\":\"Die Sperrtafel, die Presse und die Sklaverei des \u201edigitalen Zeitalters\u201c (YouTube vs. Gema) - Auf dem Sperrsitz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2015\\\/05\\\/20\\\/die-sperrtafel-und-die-presse-youtube-vs-gema\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2015\\\/05\\\/20\\\/die-sperrtafel-und-die-presse-youtube-vs-gema\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/wm2014\\\/files\\\/2015\\\/05\\\/smiliie-plattung.jpg?fit=1800%2C400&ssl=1\",\"datePublished\":\"2015-05-20T13:55:00+00:00\",\"dateModified\":\"2015-05-20T19:35:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#\\\/schema\\\/person\\\/488a80049cf0bbc4cce99951ae91c3b9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2015\\\/05\\\/20\\\/die-sperrtafel-und-die-presse-youtube-vs-gema\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2015\\\/05\\\/20\\\/die-sperrtafel-und-die-presse-youtube-vs-gema\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2015\\\/05\\\/20\\\/die-sperrtafel-und-die-presse-youtube-vs-gema\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/wm2014\\\/files\\\/2015\\\/05\\\/smiliie-plattung.jpg?fit=1800%2C400&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/wm2014\\\/files\\\/2015\\\/05\\\/smiliie-plattung.jpg?fit=1800%2C400&ssl=1\",\"width\":1800,\"height\":400,\"caption\":\"Das digitale Zeitalter.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2015\\\/05\\\/20\\\/die-sperrtafel-und-die-presse-youtube-vs-gema\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Sperrtafel, die Presse und die Sklaverei des \u201edigitalen Zeitalters\u201c (YouTube vs. Gema)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#website\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/\",\"name\":\"Auf dem Sperrsitz\",\"description\":\"Im Kultur-Zoo der nmz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#\\\/schema\\\/person\\\/488a80049cf0bbc4cce99951ae91c3b9\",\"name\":\"Martin Hufner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g\",\"caption\":\"Martin Hufner\"},\"description\":\"seit 1997 chef\u00f6konom der kritischen masse und netzbabysitter der nmz.\",\"sameAs\":[\"https:\\\/\\\/www.musikkritik.org\",\"http:\\\/\\\/www.facebook.com\\\/hufner\",\"https:\\\/\\\/www.linkedin.com\\\/profile\\\/view?id=48050869&trk=spm_pic\",\"https:\\\/\\\/x.com\\\/huflaikhan\"],\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Sperrtafel, die Presse und die Sklaverei des \u201edigitalen Zeitalters\u201c (YouTube vs. Gema) - Auf dem Sperrsitz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.nmz.de\/wm2014\/2015\/05\/20\/die-sperrtafel-und-die-presse-youtube-vs-gema\/","og_locale":"de_DE","og_type":"article","og_title":"Die Sperrtafel, die Presse und die Sklaverei des \u201edigitalen Zeitalters\u201c (YouTube vs. Gema) - Auf dem Sperrsitz","og_description":"Die Sache mit der Wahrheit in der Presseberichterstattung ist nicht immer so einfach. Seit Jahren ist ein Streit zur Lizenzierung von Musik zwischen der Gema und YouTube anh\u00e4ngig. Dabei spielten Sperrtafeln eine gro\u00dfe Rolle, die den meisten YouTube-Nutzern in Deutschland... Weiterlesen &rarr;","og_url":"https:\/\/blogs.nmz.de\/wm2014\/2015\/05\/20\/die-sperrtafel-und-die-presse-youtube-vs-gema\/","og_site_name":"Auf dem Sperrsitz","article_publisher":"http:\/\/www.facebook.com\/musikzeitung","article_author":"http:\/\/www.facebook.com\/hufner","article_published_time":"2015-05-20T13:55:00+00:00","article_modified_time":"2015-05-20T19:35:53+00:00","og_image":[{"width":1800,"height":400,"url":"https:\/\/i2.wp.com\/blogs.nmz.de\/wm2014\/files\/2015\/05\/smiliie-plattung.jpg?fit=1800%2C400&ssl=1","type":"image\/jpeg"}],"author":"Martin Hufner","twitter_card":"summary_large_image","twitter_creator":"@huflaikhan","twitter_site":"@musikzeitung","twitter_misc":{"Verfasst von":"Martin Hufner","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.nmz.de\/wm2014\/2015\/05\/20\/die-sperrtafel-und-die-presse-youtube-vs-gema\/#article","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2015\/05\/20\/die-sperrtafel-und-die-presse-youtube-vs-gema\/"},"author":{"name":"Martin Hufner","@id":"https:\/\/blogs.nmz.de\/wm2014\/#\/schema\/person\/488a80049cf0bbc4cce99951ae91c3b9"},"headline":"Die Sperrtafel, die Presse und die Sklaverei des \u201edigitalen Zeitalters\u201c (YouTube vs. Gema)","datePublished":"2015-05-20T13:55:00+00:00","dateModified":"2015-05-20T19:35:53+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2015\/05\/20\/die-sperrtafel-und-die-presse-youtube-vs-gema\/"},"wordCount":564,"commentCount":2,"image":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2015\/05\/20\/die-sperrtafel-und-die-presse-youtube-vs-gema\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/wm2014\/files\/2015\/05\/smiliie-plattung.jpg?fit=1800%2C400&ssl=1","keywords":["Bruno Kramm","GEMA","Neusprech","Objektivit\u00e4t","Piratenpartei","Presse","YouTube"],"articleSection":["Internet","Kultur","Medien","Politik"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.nmz.de\/wm2014\/2015\/05\/20\/die-sperrtafel-und-die-presse-youtube-vs-gema\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.nmz.de\/wm2014\/2015\/05\/20\/die-sperrtafel-und-die-presse-youtube-vs-gema\/","url":"https:\/\/blogs.nmz.de\/wm2014\/2015\/05\/20\/die-sperrtafel-und-die-presse-youtube-vs-gema\/","name":"Die Sperrtafel, die Presse und die Sklaverei des \u201edigitalen Zeitalters\u201c (YouTube vs. Gema) - Auf dem Sperrsitz","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2015\/05\/20\/die-sperrtafel-und-die-presse-youtube-vs-gema\/#primaryimage"},"image":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2015\/05\/20\/die-sperrtafel-und-die-presse-youtube-vs-gema\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/wm2014\/files\/2015\/05\/smiliie-plattung.jpg?fit=1800%2C400&ssl=1","datePublished":"2015-05-20T13:55:00+00:00","dateModified":"2015-05-20T19:35:53+00:00","author":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/#\/schema\/person\/488a80049cf0bbc4cce99951ae91c3b9"},"breadcrumb":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2015\/05\/20\/die-sperrtafel-und-die-presse-youtube-vs-gema\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.nmz.de\/wm2014\/2015\/05\/20\/die-sperrtafel-und-die-presse-youtube-vs-gema\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/wm2014\/2015\/05\/20\/die-sperrtafel-und-die-presse-youtube-vs-gema\/#primaryimage","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/wm2014\/files\/2015\/05\/smiliie-plattung.jpg?fit=1800%2C400&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/wm2014\/files\/2015\/05\/smiliie-plattung.jpg?fit=1800%2C400&ssl=1","width":1800,"height":400,"caption":"Das digitale Zeitalter."},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.nmz.de\/wm2014\/2015\/05\/20\/die-sperrtafel-und-die-presse-youtube-vs-gema\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blogs.nmz.de\/wm2014\/"},{"@type":"ListItem","position":2,"name":"Die Sperrtafel, die Presse und die Sklaverei des \u201edigitalen Zeitalters\u201c (YouTube vs. Gema)"}]},{"@type":"WebSite","@id":"https:\/\/blogs.nmz.de\/wm2014\/#website","url":"https:\/\/blogs.nmz.de\/wm2014\/","name":"Auf dem Sperrsitz","description":"Im Kultur-Zoo der nmz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.nmz.de\/wm2014\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blogs.nmz.de\/wm2014\/#\/schema\/person\/488a80049cf0bbc4cce99951ae91c3b9","name":"Martin Hufner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g","caption":"Martin Hufner"},"description":"seit 1997 chef\u00f6konom der kritischen masse und netzbabysitter der nmz.","sameAs":["https:\/\/www.musikkritik.org","http:\/\/www.facebook.com\/hufner","https:\/\/www.linkedin.com\/profile\/view?id=48050869&trk=spm_pic","https:\/\/x.com\/huflaikhan"],"url":"https:\/\/blogs.nmz.de\/wm2014\/author\/admin\/"}]}},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","jetpack_shortlink":"https:\/\/wp.me\/p4Gg77-o7","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogs.nmz.de\/wm2014\/files\/2015\/05\/smiliie-plattung.jpg?fit=1800%2C400&ssl=1","_links":{"self":[{"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/posts\/1495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/comments?post=1495"}],"version-history":[{"count":4,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/posts\/1495\/revisions"}],"predecessor-version":[{"id":1500,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/posts\/1495\/revisions\/1500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/media\/1497"}],"wp:attachment":[{"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/media?parent=1495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/categories?post=1495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/tags?post=1495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}