{"id":1344,"date":"2015-03-26T10:44:37","date_gmt":"2015-03-26T09:44:37","guid":{"rendered":"http:\/\/blogs.nmz.de\/wm2014\/?p=1344"},"modified":"2015-03-26T10:44:37","modified_gmt":"2015-03-26T09:44:37","slug":"umsonstkultur-und-ehrenamt","status":"publish","type":"post","link":"https:\/\/blogs.nmz.de\/wm2014\/2015\/03\/26\/umsonstkultur-und-ehrenamt\/","title":{"rendered":"Umsonstkultur und Ehrenamt"},"content":{"rendered":"<p>In den vergangenen Jahren wurden gro\u00dfe Teile der Musikindustrie und der Kulturpolitik nicht m\u00fcde, zu betonen, dass die im Internet so verbreitete und sogenannte \u201eKostenlosmentalit\u00e4t\u201c nicht gehe. K\u00fcnstler und kreative m\u00fcssten von ihren Produkten, die sie herstellen oder verbreiten leben k\u00f6nnen. Vorne in der Argumentationskette immer die Musikindustrie, die auf Grund des Zusammenbruchs der CD-Welt schwer ins Schlingern kam, sich aber mittlerweile konsolidiert hat: auf einem Niveau, wie es vor dem Siegeszug der CD der Fall war.<\/p>\n<p>Seit gestern ist bekannt, dass Dieter Gorny vom Bundeswirtschaftsministerium und hier explizit von Minister Sigmar Gabriel zum <a href=\"http:\/\/www.nmz.de\/online\/dieter-gorny-ist-beauftragter-fuer-kreative-und-digitale-oekonomie-im-bundeswirtschaftsminist\" target=\"_blank\">\u201eBeauftragten f\u00fcr Kreative und digitale \u00d6konomie\u201c ernannt worden ist<\/a>. Das allein sorgt schon f\u00fcr Unruhe bei den <a href=\"https:\/\/netzpolitik.org\/2015\/die-musikindustrie-uebernimmt-jetzt-die-netzpolitik\/\" target=\"_blank\">Netzaktivisten und -politikbeobachtern<\/a> und <a href=\"http:\/\/www.hier-luebeck.de\/2015\/03\/zur-berufung-von-dieter-gorny-ein-desaster-fuer-die-kreativ-wirtschaft\/\" target=\"_blank\">Piraten<\/a>. F\u00fcr Unruhe sorgt aber eben auch die F\u00e4higkeit Gornys, in Gespr\u00e4chen und Vortr\u00e4gen sprachvision\u00e4r aufzutreten. Er ist ein gro\u00dfer Rhetoriker. Doch das nur nebenbei.<\/p>\n<p>In der <a href=\"http:\/\/www.heise.de\/newsticker\/meldung\/Musikbranche-will-Netzpolitik-nicht-laenger-den-Nerds-ueberlassen-2584406.html\" target=\"_blank\">Heisemeldung von Gornys Berufung<\/a> findet sich der Hinweis, dass sein Amt im Bundeswirtschaftsministerium \u201eehrenamtlich\u201c sei. Neben der Frage, ob es gut ist, dem Cheflobbyisten der Musikindustrie diese T\u00e4tigkeit zu \u00fcberantworten, rein aus politischer Sicht, muss man doch fragen, wie objektiv er, Gorny, das Amt \u00fcberhaupt wahrnehmen k\u00f6nnte, wenn er wollte. Wenn er sein Einkommen vor allem von denen bezieht, f\u00fcr die er Lobbyist ist, d\u00fcrfte eine gewisse Neutralit\u00e4t eher unwahrscheinlich sein.<\/p>\n<p>Aber ganz zuletzt: Wie war das mit der \u201eKostenlosmentalit\u00e4t\u201c im Netz (und im <em>richtigen<\/em> Leben)? Auch Beauftragte sollen von ihrer Arbeit leben k\u00f6nnen. Sollte man meinen. Das l\u00e4sst sich mit einem Ehrenamt allerdings nur schwer in Einklang bringen. Und man m\u00fcsste mal fragen, ob dies wirklich \u00fcberhaupt ein Ehrenamt ist, was er da aus\u00fcbt \u2013 das ist es n\u00e4mlich nicht, es ist eine unbezahlte Nebent\u00e4tigkeit f\u00fcr Musikindustrie und Co \u2013 bis zum Beweis des Gegenteils. Und ob das in der Politik wirklich eine vern\u00fcnftige L\u00f6sung ist. Der Soziologe Max Weber hat in \u201ePolitik als Beruf\u201c das Problem angerissen:<\/p>\n<p style=\"padding-left: 30px;\">\u201eDie Politik kann entweder \u00bbehrenamtlich\u00ab und dann von, wie man zu sagen pflegt, \u00bbunabh\u00e4ngigen\u00ab, d.h. verm\u00f6genden Leuten, Rentnern vor allem, gef\u00fchrt werden. Oder aber ihre F\u00fchrung wird Verm\u00f6genslosen zug\u00e4nglich gemacht, und dann mu\u00df sie entgolten werden.\u201c [Max Weber: Politik als Beruf. Berlin 1982, S. 17 f.]<\/p>\n<p>Weber hatte da das Problem der Abk\u00f6mmlichkeit im Blick. Gorny w\u00e4re in seinen \u00c4mtern jedoch wirklich abk\u00f6mmlich. Und dann sollte er sich vom Ministerium eben auch so bezahlen lassen, dass er abk\u00f6mmlich ist. Als Lobbyist hat er nichts in der Politik verloren \u2013 auch wenn man wei\u00df, dass kaum je ein Politiker oder Staatsbeamter frei von Lobbyeinfluss ist. Doch w\u00e4re dies Voraussetzung f\u00fcr \u00dcbernahme des Amtes. Kostenlos geht in der Politik schon gleich gar nix. Das Amt ist mit seiner Besetzung durch Gorny automatisch besch\u00e4digt und sinnlos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In den vergangenen Jahren wurden gro\u00dfe Teile der Musikindustrie und der Kulturpolitik nicht m\u00fcde, zu betonen, dass die im Internet so verbreitete und sogenannte \u201eKostenlosmentalit\u00e4t\u201c nicht gehe. K\u00fcnstler und kreative m\u00fcssten von ihren Produkten, die sie herstellen oder verbreiten leben&#8230; <a class=\"more-link\" href=\"https:\/\/blogs.nmz.de\/wm2014\/2015\/03\/26\/umsonstkultur-und-ehrenamt\/\">Weiterlesen &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":1345,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[769,385,860],"tags":[12966,12965,12964,1131,1201,12963],"class_list":["post-1344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internet","category-kultur","category-politik","tag-beauftrager-fuer-kreative-und-digitale-oekonomie","tag-bundesverband-musikindustrie","tag-dieter-gorny","tag-lobbyismus","tag-musikwirtschaft","tag-sigmar-gabriel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Umsonstkultur und Ehrenamt - Auf dem Sperrsitz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.nmz.de\/wm2014\/2015\/03\/26\/umsonstkultur-und-ehrenamt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Umsonstkultur und Ehrenamt - Auf dem Sperrsitz\" \/>\n<meta property=\"og:description\" content=\"In den vergangenen Jahren wurden gro\u00dfe Teile der Musikindustrie und der Kulturpolitik nicht m\u00fcde, zu betonen, dass die im Internet so verbreitete und sogenannte \u201eKostenlosmentalit\u00e4t\u201c nicht gehe. K\u00fcnstler und kreative m\u00fcssten von ihren Produkten, die sie herstellen oder verbreiten leben... Weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.nmz.de\/wm2014\/2015\/03\/26\/umsonstkultur-und-ehrenamt\/\" \/>\n<meta property=\"og:site_name\" content=\"Auf dem Sperrsitz\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/musikzeitung\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/hufner\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-26T09:44:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/blogs.nmz.de\/wm2014\/files\/2015\/03\/huf-cmyk-np-03-25-bvmi2015-panel_mit_gorny.jpg?fit=1200%2C900&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Martin Hufner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@huflaikhan\" \/>\n<meta name=\"twitter:site\" content=\"@musikzeitung\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin Hufner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2015\\\/03\\\/26\\\/umsonstkultur-und-ehrenamt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2015\\\/03\\\/26\\\/umsonstkultur-und-ehrenamt\\\/\"},\"author\":{\"name\":\"Martin Hufner\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#\\\/schema\\\/person\\\/488a80049cf0bbc4cce99951ae91c3b9\"},\"headline\":\"Umsonstkultur und Ehrenamt\",\"datePublished\":\"2015-03-26T09:44:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2015\\\/03\\\/26\\\/umsonstkultur-und-ehrenamt\\\/\"},\"wordCount\":485,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2015\\\/03\\\/26\\\/umsonstkultur-und-ehrenamt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/wm2014\\\/files\\\/2015\\\/03\\\/huf-cmyk-np-03-25-bvmi2015-panel_mit_gorny.jpg?fit=1200%2C900&ssl=1\",\"keywords\":[\"Beauftrager f\u00fcr Kreative und digitale \u00d6konomie\",\"Bundesverband Musikindustrie\",\"Dieter Gorny\",\"Lobbyismus\",\"Musikwirtschaft\",\"Sigmar Gabriel\"],\"articleSection\":[\"Internet\",\"Kultur\",\"Politik\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2015\\\/03\\\/26\\\/umsonstkultur-und-ehrenamt\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2015\\\/03\\\/26\\\/umsonstkultur-und-ehrenamt\\\/\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2015\\\/03\\\/26\\\/umsonstkultur-und-ehrenamt\\\/\",\"name\":\"Umsonstkultur und Ehrenamt - Auf dem Sperrsitz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2015\\\/03\\\/26\\\/umsonstkultur-und-ehrenamt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2015\\\/03\\\/26\\\/umsonstkultur-und-ehrenamt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/wm2014\\\/files\\\/2015\\\/03\\\/huf-cmyk-np-03-25-bvmi2015-panel_mit_gorny.jpg?fit=1200%2C900&ssl=1\",\"datePublished\":\"2015-03-26T09:44:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#\\\/schema\\\/person\\\/488a80049cf0bbc4cce99951ae91c3b9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2015\\\/03\\\/26\\\/umsonstkultur-und-ehrenamt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2015\\\/03\\\/26\\\/umsonstkultur-und-ehrenamt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2015\\\/03\\\/26\\\/umsonstkultur-und-ehrenamt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/wm2014\\\/files\\\/2015\\\/03\\\/huf-cmyk-np-03-25-bvmi2015-panel_mit_gorny.jpg?fit=1200%2C900&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/wm2014\\\/files\\\/2015\\\/03\\\/huf-cmyk-np-03-25-bvmi2015-panel_mit_gorny.jpg?fit=1200%2C900&ssl=1\",\"width\":1200,\"height\":900,\"caption\":\"Gorny in einer Gespr\u00e4chsrunde. Foto: Hufner\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/2015\\\/03\\\/26\\\/umsonstkultur-und-ehrenamt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Umsonstkultur und Ehrenamt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#website\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/\",\"name\":\"Auf dem Sperrsitz\",\"description\":\"Im Kultur-Zoo der nmz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/#\\\/schema\\\/person\\\/488a80049cf0bbc4cce99951ae91c3b9\",\"name\":\"Martin Hufner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g\",\"caption\":\"Martin Hufner\"},\"description\":\"seit 1997 chef\u00f6konom der kritischen masse und netzbabysitter der nmz.\",\"sameAs\":[\"https:\\\/\\\/www.musikkritik.org\",\"http:\\\/\\\/www.facebook.com\\\/hufner\",\"https:\\\/\\\/www.linkedin.com\\\/profile\\\/view?id=48050869&trk=spm_pic\",\"https:\\\/\\\/x.com\\\/huflaikhan\"],\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/wm2014\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Umsonstkultur und Ehrenamt - Auf dem Sperrsitz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.nmz.de\/wm2014\/2015\/03\/26\/umsonstkultur-und-ehrenamt\/","og_locale":"de_DE","og_type":"article","og_title":"Umsonstkultur und Ehrenamt - Auf dem Sperrsitz","og_description":"In den vergangenen Jahren wurden gro\u00dfe Teile der Musikindustrie und der Kulturpolitik nicht m\u00fcde, zu betonen, dass die im Internet so verbreitete und sogenannte \u201eKostenlosmentalit\u00e4t\u201c nicht gehe. K\u00fcnstler und kreative m\u00fcssten von ihren Produkten, die sie herstellen oder verbreiten leben... Weiterlesen &rarr;","og_url":"https:\/\/blogs.nmz.de\/wm2014\/2015\/03\/26\/umsonstkultur-und-ehrenamt\/","og_site_name":"Auf dem Sperrsitz","article_publisher":"http:\/\/www.facebook.com\/musikzeitung","article_author":"http:\/\/www.facebook.com\/hufner","article_published_time":"2015-03-26T09:44:37+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/i2.wp.com\/blogs.nmz.de\/wm2014\/files\/2015\/03\/huf-cmyk-np-03-25-bvmi2015-panel_mit_gorny.jpg?fit=1200%2C900&ssl=1","type":"image\/jpeg"}],"author":"Martin Hufner","twitter_card":"summary_large_image","twitter_creator":"@huflaikhan","twitter_site":"@musikzeitung","twitter_misc":{"Verfasst von":"Martin Hufner","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.nmz.de\/wm2014\/2015\/03\/26\/umsonstkultur-und-ehrenamt\/#article","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2015\/03\/26\/umsonstkultur-und-ehrenamt\/"},"author":{"name":"Martin Hufner","@id":"https:\/\/blogs.nmz.de\/wm2014\/#\/schema\/person\/488a80049cf0bbc4cce99951ae91c3b9"},"headline":"Umsonstkultur und Ehrenamt","datePublished":"2015-03-26T09:44:37+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2015\/03\/26\/umsonstkultur-und-ehrenamt\/"},"wordCount":485,"commentCount":0,"image":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2015\/03\/26\/umsonstkultur-und-ehrenamt\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/wm2014\/files\/2015\/03\/huf-cmyk-np-03-25-bvmi2015-panel_mit_gorny.jpg?fit=1200%2C900&ssl=1","keywords":["Beauftrager f\u00fcr Kreative und digitale \u00d6konomie","Bundesverband Musikindustrie","Dieter Gorny","Lobbyismus","Musikwirtschaft","Sigmar Gabriel"],"articleSection":["Internet","Kultur","Politik"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.nmz.de\/wm2014\/2015\/03\/26\/umsonstkultur-und-ehrenamt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.nmz.de\/wm2014\/2015\/03\/26\/umsonstkultur-und-ehrenamt\/","url":"https:\/\/blogs.nmz.de\/wm2014\/2015\/03\/26\/umsonstkultur-und-ehrenamt\/","name":"Umsonstkultur und Ehrenamt - Auf dem Sperrsitz","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2015\/03\/26\/umsonstkultur-und-ehrenamt\/#primaryimage"},"image":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2015\/03\/26\/umsonstkultur-und-ehrenamt\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/wm2014\/files\/2015\/03\/huf-cmyk-np-03-25-bvmi2015-panel_mit_gorny.jpg?fit=1200%2C900&ssl=1","datePublished":"2015-03-26T09:44:37+00:00","author":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/#\/schema\/person\/488a80049cf0bbc4cce99951ae91c3b9"},"breadcrumb":{"@id":"https:\/\/blogs.nmz.de\/wm2014\/2015\/03\/26\/umsonstkultur-und-ehrenamt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.nmz.de\/wm2014\/2015\/03\/26\/umsonstkultur-und-ehrenamt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/wm2014\/2015\/03\/26\/umsonstkultur-und-ehrenamt\/#primaryimage","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/wm2014\/files\/2015\/03\/huf-cmyk-np-03-25-bvmi2015-panel_mit_gorny.jpg?fit=1200%2C900&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/wm2014\/files\/2015\/03\/huf-cmyk-np-03-25-bvmi2015-panel_mit_gorny.jpg?fit=1200%2C900&ssl=1","width":1200,"height":900,"caption":"Gorny in einer Gespr\u00e4chsrunde. Foto: Hufner"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.nmz.de\/wm2014\/2015\/03\/26\/umsonstkultur-und-ehrenamt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blogs.nmz.de\/wm2014\/"},{"@type":"ListItem","position":2,"name":"Umsonstkultur und Ehrenamt"}]},{"@type":"WebSite","@id":"https:\/\/blogs.nmz.de\/wm2014\/#website","url":"https:\/\/blogs.nmz.de\/wm2014\/","name":"Auf dem Sperrsitz","description":"Im Kultur-Zoo der nmz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.nmz.de\/wm2014\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blogs.nmz.de\/wm2014\/#\/schema\/person\/488a80049cf0bbc4cce99951ae91c3b9","name":"Martin Hufner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/891bbce378eb0bdbf7f71559e53af16afd9e2f8a020e2f876adcfcd437cd011a?s=96&d=mm&r=g","caption":"Martin Hufner"},"description":"seit 1997 chef\u00f6konom der kritischen masse und netzbabysitter der nmz.","sameAs":["https:\/\/www.musikkritik.org","http:\/\/www.facebook.com\/hufner","https:\/\/www.linkedin.com\/profile\/view?id=48050869&trk=spm_pic","https:\/\/x.com\/huflaikhan"],"url":"https:\/\/blogs.nmz.de\/wm2014\/author\/admin\/"}]}},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","jetpack_shortlink":"https:\/\/wp.me\/p4Gg77-lG","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogs.nmz.de\/wm2014\/files\/2015\/03\/huf-cmyk-np-03-25-bvmi2015-panel_mit_gorny.jpg?fit=1200%2C900&ssl=1","_links":{"self":[{"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/posts\/1344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/comments?post=1344"}],"version-history":[{"count":1,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/posts\/1344\/revisions"}],"predecessor-version":[{"id":1346,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/posts\/1344\/revisions\/1346"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/media\/1345"}],"wp:attachment":[{"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/media?parent=1344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/categories?post=1344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.nmz.de\/wm2014\/wp-json\/wp\/v2\/tags?post=1344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}