{"id":9898,"date":"2014-01-26T19:12:14","date_gmt":"2014-01-26T18:12:14","guid":{"rendered":"http:\/\/blogs.nmz.de\/badblog\/?p=9898"},"modified":"2018-01-20T18:58:21","modified_gmt":"2018-01-20T17:58:21","slug":"vom-winde-verweht-droht-das-ende-der-e-musik","status":"publish","type":"post","link":"https:\/\/blogs.nmz.de\/badblog\/2014\/01\/26\/vom-winde-verweht-droht-das-ende-der-e-musik\/","title":{"rendered":"Vom Winde verweht \u2013 droht das Ende der E-Musik?"},"content":{"rendered":"<p>Wie sich die Winde drehen: Der Nachfolger Paul W. Hertin ist das totale Gegenteil des Namensgeber der ehemaligen Urheberrechtskanzlei Wilhelm Nordemann, in die er vor vielen Jahren eintrat und nun mit ihr gegen die GEMA antritt. Sein Vorg&#228;nger Nordemann dagegen ist ein Protagonist eines Urheberrechts, das die Bed&#252;rfnisse der einzelnen Sparten einer Kunstform anerkennt und im Falle von Musikautoren diesen in ihrer Verwertungsgesellschaft den Sachverstand einr&#228;umt, nach den Faktoren \u201ewirtschaftlich, sozial und kulturell\u201c ihre Verteilungspl&#228;ne autonom zu organisieren, was eine gesetzliche Vorschrift ist. Vereinfacht gesagt heisst das z.B. im Falle der GEMA, dass diese von Autoren vereins- und aufsichtsrechtlich geleitete Institution Gesellschaft nach einem Abzug an ihre auf hochkomplexen Feldern agierende Verwaltung ihre Einnahmen aus Lizenzen an u.a. Sender, Musikveranstalter, Musikproduzenten oder Tanzlokale direkt an die Urheber weiter durchreicht. Das ist wohl vor allem der oben angef&#252;hrte Faktor \u201ewirtschaftlich\u201c. \u201eSozial\u201c meint, dass die Gesellschaftsmitglieder mit dem h&#246;chsten Einkommen nicht alles ihrer Einnahmen erhalten, sondern ein Teil davon nach unten verteilt wird. \u201eKulturell\u201c meint, dass zeitlich schnell produzierte Musik f&#252;r meist kleine Besetzungen, im Gros Popularmusik (U-Musik), einen Teil ihrer Einnahmen an die Kunstmusik (E-Musik) abgibt, welche selbst nur bescheidene einen Betrag um die 5% schwankend zu den GEMA-Einnahmen beitr&#228;gt. Kunstmusik selbst wird selbst mit ihren erfolgreichsten St&#252;cken seltener als U-Musik gespielt und gesendet. Anhand von Besetzung und L&#228;nge ihrer meisten Werke und derer einmaliger Sch&#246;pfungsh&#246;he erfordert sie zu einem gewissen Grad wesentlich l&#228;ngere Schreib- und Konzeptionsarbeit als Popularmusik. Dies wird im Wertungsverfahren zum Verteilungsplan zur Durchreichung des von der U-Musik gekappten Betrags an die E-Musik pro Urheber und Werk einzeln durchgef&#252;hrt, denn dies kann bisher kein Rechner: die k&#252;nstlerische Begutachtung und Bewertung. Dies f&#252;hren die entsprechenden Arbeitsgruppen der Autoren der GEMA unter den Augen des Deutschen Patent- und Markenamtes eigenst&#228;ndig durch.<!--more--><\/p>\n<p>Wilhelm Nordemann machte sich um die juristische Durchdringung dieses gesetzlich vorgesehenen Modells h&#246;chst verdient, verfasste gemeinsam mit Karl Fromm den Kommentar zum deutschen Urheberrecht Fromm\/Nordemann und wurde f&#252;r seine Verdienste sogar vom Deutschen Komponistenverband ausgezeichnet. Irgendwann trat der Jurist Paul Hertin der Arbeit an diesem Kommentar bei und wurde Soziet&#228;r in Nordemanns Kanzlei. Seit dem Ausscheiden Nordemanns firmiert die Kanzlei nun unter dem Namen Paul Hertins. Sein Vorg&#228;nger war eine St&#252;tze der Urheber, Hertin erkl&#228;rt nun diesen, speziell denen der Kunstmusik den Krieg. Im Internet kursiert unter Juristen und Urheber derzeit seine <a href=\"http:\/\/www.juris.de\/jportal\/prev\/SBLU000368313\" target=\"_blank\">gutachterliche Streitschrift \u201eDas GEMA-Verteilungssystem auf dem Pr&#252;fstand\u201c<\/a>. Was die inl&#228;ndische Rechtsauffassung betrifft, muss er anerkennen, dass man dem status quo Rechtm&#228;&#223;igkeit aufgrund einschl&#228;giger Kommentare zugestehen muss. Richtige Probleme sieht er nur bei den gesetzlichen Aussch&#252;ttungen, die die Ger&#228;teabgabe als Ausgleich f&#252;r durch Privatkopien entgangene Einnahmen f&#252;r die Urheber vorsieht. Bei deren Verteilung m&#252;sse ohne Abschl&#228;ge verteilt werden, worin er sich von der EU-Gerichtshofrechtsprechung best&#228;tig sieht.<\/p>\n<p>In eine offene Wunde schl&#228;gt er allerdings mit der Beschreibung eines konkreten Falles, der allerdings weniger das Wertungsverfahren, sondern die Beurteilung eines Werkes betrifft. Neben E, U, Film, Werbemusik, etc. gibt es immer wieder Werke, die sich nicht genau einer Sparte &#252;berwiegend zuordnen lassen. Oben genannt wurden Dauer, Besetzung und Aufwand der Herstellung. Dies sind Kriterien, die im Alltag meist ganz gut funktionieren. Um Musik im Streitfalle f&#252;r die Abrechnung richtig zuordnen zu k&#246;nnen gibt es den Werkausschuss, nicht mit dem Wertungsverfahren zu verwechseln! Im zitierten Falle, wo ein gr&#246;sseres Werk eines Komponisten durch die Th&#252;ringische Philharmonie im Erfurter Dom zu beurteilen war, konnten sich Komponist und Werkausschuss nicht einigen, ob es sich dabei um E-Musik handelt. So zog der Komponist vor Gericht. Das siebenteilige Werk wollte der Werkausschuss als U-Musik eingeordnet wissen, ein Gegengutachten im Auftrag des Komponisten kam zu einem anderen Schluss. Noch bevor es richtig vor Gericht losging, erkl&#228;rte der GEMA-Werkausschuss das St&#252;ck pl&#246;tzlich nachtr&#228;glich zu E-Musik, womit das Verfahren eingestellt wurde. Bei der Kostenentscheidung ging das Kammergericht Berlin von einem vorhersehbaren Prozessgewinn des Komponisten aus und sprach bez&#252;glich des durch den GEMA-Werkausschuss eingesetzten Ermessens von einer Ermessensreduzierung gegen Null. Das ist der nasseste Waschlappen, den man bei Beurteilungen von falschen Ermessen ins Gesicht geschlagen bekommen kann. Leider schweigt sich Hertin &#252;ber das genaue Werk aus. Denn dann k&#246;nnte man den vom Gericht unterstellten Ermessensfehlgebrauch des Werkausschusses erst &#252;berpr&#252;fen. Nur soviel: wenn ein Komponist seine wichtigsten mit den U-Musik-&#252;blichen Worten \u201eSong\u201c und \u201eMusical\u201c versieht, diese gattungsanzeigenden Worte eher erf&#252;llt als kunstmusikalisch kreativ umschifft, kann man schon auf die Idee kommen, dass ein siebenteiliges St&#252;ck, das im Zusammenhang mit einem Werk eines britischen mehr als erfolgreichen Musicall&#246;wen uraufgerf&#252;hrt wurde, eine starke Tendenz zur Popularmusik hat. Nach L&#228;nge und Besetzung, hier wohl Soli, Chor und Orchester, k&#246;nnte man es f&#252;r E-Musik halten, was aber ja noch nichts &#252;ber den Gehalt aussagt. Zur &#228;sthetischen Tods&#252;nde wird es dann, wenn das von Hertin auch nicht namentlich genannte Gutachten des klagenden Komponisten anerkannte Kunstmusik-Komponisten \u201eHindemith &#252;ber Prokofjew zu Br&#252;ten (!, wohl Britten) und Ligeti\u201c und ihre Verwendung von Popularmusik als Begr&#252;ndung heranzieht, um wohl mehrheitliche Popularmusik zu Kunstmusik zu erkl&#228;ren. <\/p>\n<p>Vollkommen schr&#228;g wird es im Gutachten, wenn Paul Hertin Mozart bem&#252;ht: nat&#252;rlich k&#246;nnte man mit heutigen Massst&#228;ben dessen klassische Musik mal U, mal E, mal nichts zuordnen. Dennoch entwickelte sich ja gerade in Mozart selbst das Bewusstsein zwischen unterhaltenden und schnell Musik ausspuckenden Paradiesvogel und hart arbeitenden Streichquartett- und Sinfonie-Komponisten. Alle sp&#228;ten Werke dieser Gattung ben&#246;tigten mehrere Monate, um vor dem Anspruch Mozarts standzuhalten. Mozart als Massstab f&#252;r die Aufhebung aller Grenzen gelingt eben auch nicht. Nat&#252;rlich &#246;ffnet sich Kunstmusik gerne zum Popularen, heute mehr denn je, sind Komponisten in den beiden und noch mehr Sparten unterwegs. Dennoch wird kaum jemand sich wirklich zu einem Komponisten von Nicht-Kunstmusik degradieren lassen wollen. Letztlich entscheidet die Sch&#246;pfungsh&#246;he, was den Anspruch erheben kann, Kunst oder Kunstgewerbe zu sein. Als komponierende Einzelperson wehrt man sich erstmal strikt gegen Kategorisierungen und tritt auch mal aus der Neuen Musik aus, ohne deren Foren zu verlassen. Und nat&#252;rlich schwingt man Pl&#228;doyers f&#252;r eine genrefreie Musik. Ist man aber auch bereit die absoluten Konsequenzen zu tragen? Sich letztlich nicht mit Beethoven, Berg und Barrett messen zu m&#252;ssen, sondern am Einkommen eines Bohlen quantitativ zu Grunde gerichtet zu werden? Begibt man sich als Kunstmusiker in die Gefilde der Popularmusik, pickt man sich Versatzst&#252;cke aus dieser heraus, so m&#246;chte man doch sehr wohl Musik schaffen, die &#252;ber den Horizont der verwendeten St&#252;cke herauskommt, so sehr diese nat&#252;rlich auch durchaus den ihren haben k&#246;nnen. Hertin f&#252;hrt als musikspartenspezifische Unterscheidungsmerkmale die Einteilungen der Musikindustrie Pop, Jazz und Klassik an. Unter Klassik findet sich diese selbst, wie alte Musik, Romantik und zeitgen&#246;ssische Musik. Das st&#246;sst nat&#252;rlich vielen unter uns auf, wie sich ein Rockkomponist nicht im Pop wiederfinden m&#246;chte. Und Hertin benutzt dies nat&#252;rlich, um f&#252;r sich zu best&#228;tigen, dass weder Musiklabels, noch Musikwissenschaft oder gar die Komponisten selbst richtige Zuordnungen treffen k&#246;nnen. Genauso zieht er in Zweifel, dass sich das Recht hierzulande seit Mozarts Zeiten eben so ausdifferenzierte, wie es jetzt ist. So ver&#228;nderbar das heute wieder ist, sein muss, so gibt es wohl doch sowas wie einen anthropologischen Fortschritt der Vernunft in Musik wie Recht und allen anderen Lebensbereichen: wie man heute niemand mehr guillotiniert so wendet man eben das Urheberrecht an, was es zu Mozarts Zeiten nur in Ans&#228;tzen gab. Nichts ist in Stein gemeisselt, aber auch Herrn Hertins Ansichten nicht! Denn auch Recht ist nur die Meinung eines Menschen. Wie man eben sich gerne zu anderen Sparten &#246;ffnen, rechnen m&#246;chte, dennoch ganz in seiner Pers&#246;nlichkeit aber der K&#252;nstler ist, der aus den Stilen austritt und sich doch in k&#252;nstlerischen Linien sieht, eben eher bei Spahlinger als Lloyd-Webber studierte. <\/p>\n<p>Was bleibt nun? Die Autonomie der Urheber muss erhalten werden, zu bestimmen, was Kunstmusik ist, was nicht. Der Vorschlag Hertins, kulturelle und soziale Kriterien auf direkte staatliche F&#246;rderung und Unterst&#252;tzung durch Private zu verschieben ist fadenscheinig, neo-liberal. Wo es zu helfen und zu st&#252;tzen gilt, ist das Geldverdienen nach der Werksch&#246;pfung. Nat&#252;rlich klingt es im Moment besser, das Ende von Betriebsrenten zu fordern und gleichzeitig auf die eigene Absicherung f&#252;rs Alter zu verweisen. Aber was ist die GEMA anderes, als ein komplexes Gebilde, mit dem sich durch gesetzlichen Auftrag eben gerade Urheber absichern, dies unter sich aus machen? Da gibt es garantiert noch einiges zu tun. Was aber nicht im Einstampfen der Kunstmusik enden kann, nur dass andere noch mehr in ihren gierigen Schlund bekommen! Vielmehr hat man den Eindruck, dass lieber fr&#252;her als sp&#228;ter andere Autorenverwertungsgesellschaften eher dem Modell GEMA nachstreben als umgekehrt. Vielleicht muss man &#252;ber weitere Bemessungsgrundlagen als Besetzung und L&#228;nge nachdenken, vielleicht ein flexibleres als  ein 10%-Aufschlagsystem f&#252;r Kunstmusik auch f&#252;r Kunstmusik-n&#228;here Werke kreieren. Das Heil liegt aber nicht darin, den Urhebern ihre Autonomie zu nehmen, wie es so oft von Aussen gefordert wird, wenn allzu gern &#252;bersehen wird, dass die GEMA eine vor allem autorenbestimmte Gesellschaft ist denn eine durch Musiklabel gesteuerte wie im angels&#228;chsischen Raum. Eine M&#246;glichkeit liegt eher darin, Aussch&#252;sse wie Wertungs- und Werkaussch&#252;sse besser zu beraten, die Mittel feiner werden zu lassen. Nur einfacher werden sie nicht, genauso wie das Verh&#228;ltnis Kunstmusik zu Popularmusik immer ein durchdringendes und sich absetzendes bleiben wird. Denn die eine kann ohne die andere nicht. Das erfordert Solidarit&#228;t &#8211; und die ist heute noch fl&#252;chtiger als die Errungenschaften des Urheberrechts!<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Vom%20Winde%20verweht%20%E2%80%93%20droht%20das%20Ende%20der%20E-Musik%3F https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2014%2F01%2F26%2Fvom-winde-verweht-droht-das-ende-der-e-musik%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Vom%20Winde%20verweht%20%E2%80%93%20droht%20das%20Ende%20der%20E-Musik%3F https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2014%2F01%2F26%2Fvom-winde-verweht-droht-das-ende-der-e-musik%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2014%2F01%2F26%2Fvom-winde-verweht-droht-das-ende-der-e-musik%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Vom%20Winde%20verweht%20%E2%80%93%20droht%20das%20Ende%20der%20E-Musik%3F%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2014%2F01%2F26%2Fvom-winde-verweht-droht-das-ende-der-e-musik%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2014%2F01%2F26%2Fvom-winde-verweht-droht-das-ende-der-e-musik%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Wie sich die Winde drehen: Der Nachfolger Paul W. Hertin ist das totale Gegenteil des Namensgeber der ehemaligen Urheberrechtskanzlei Wilhelm Nordemann, in die er vor vielen Jahren eintrat und nun mit ihr gegen die GEMA antritt. Sein Vorg&#228;nger Nordemann dagegen ist ein Protagonist eines Urheberrechts, das die Bed&#252;rfnisse der einzelnen&#46;&#46;&#46;<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Vom%20Winde%20verweht%20%E2%80%93%20droht%20das%20Ende%20der%20E-Musik%3F https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2014%2F01%2F26%2Fvom-winde-verweht-droht-das-ende-der-e-musik%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Vom%20Winde%20verweht%20%E2%80%93%20droht%20das%20Ende%20der%20E-Musik%3F https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2014%2F01%2F26%2Fvom-winde-verweht-droht-das-ende-der-e-musik%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2014%2F01%2F26%2Fvom-winde-verweht-droht-das-ende-der-e-musik%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Vom%20Winde%20verweht%20%E2%80%93%20droht%20das%20Ende%20der%20E-Musik%3F%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2014%2F01%2F26%2Fvom-winde-verweht-droht-das-ende-der-e-musik%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2014%2F01%2F26%2Fvom-winde-verweht-droht-das-ende-der-e-musik%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"author":31,"featured_media":10681,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[14657,2892,8381],"tags":[],"class_list":["post-9898","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert","category-deutsch","category-sprache"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vom Winde verweht \u2013 droht das Ende der E-Musik? &#8211; Bad Blog Of Musick - nmz Klassik-Blog<\/title>\n<meta name=\"description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.nmz.de\/badblog\/2014\/01\/26\/vom-winde-verweht-droht-das-ende-der-e-musik\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vom Winde verweht \u2013 droht das Ende der E-Musik? &#8211; Bad Blog Of Musick - nmz Klassik-Blog\" \/>\n<meta property=\"og:description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.nmz.de\/badblog\/2014\/01\/26\/vom-winde-verweht-droht-das-ende-der-e-musik\/\" \/>\n<meta property=\"og:site_name\" content=\"Bad Blog Of Musick\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/musikzeitung\" \/>\n<meta property=\"article:published_time\" content=\"2014-01-26T18:12:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-01-20T17:58:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2014\/07\/badboy_gaelic.jpg?fit=640%2C480&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alexander Strauch\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@musikzeitung\" \/>\n<meta name=\"twitter:site\" content=\"@musikzeitung\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexander Strauch\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2014\\\/01\\\/26\\\/vom-winde-verweht-droht-das-ende-der-e-musik\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2014\\\/01\\\/26\\\/vom-winde-verweht-droht-das-ende-der-e-musik\\\/\"},\"author\":{\"name\":\"Alexander Strauch\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/73d6c9ef0d58ae670a7d6f9affe7259c\"},\"headline\":\"Vom Winde verweht \u2013 droht das Ende der E-Musik?\",\"datePublished\":\"2014-01-26T18:12:14+00:00\",\"dateModified\":\"2018-01-20T17:58:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2014\\\/01\\\/26\\\/vom-winde-verweht-droht-das-ende-der-e-musik\\\/\"},\"wordCount\":1629,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2014\\\/01\\\/26\\\/vom-winde-verweht-droht-das-ende-der-e-musik\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2014\\\/07\\\/badboy_gaelic.jpg?fit=640%2C480&ssl=1\",\"articleSection\":{\"1\":\"Deutsch\",\"2\":\"Sprache\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2014\\\/01\\\/26\\\/vom-winde-verweht-droht-das-ende-der-e-musik\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2014\\\/01\\\/26\\\/vom-winde-verweht-droht-das-ende-der-e-musik\\\/\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2014\\\/01\\\/26\\\/vom-winde-verweht-droht-das-ende-der-e-musik\\\/\",\"name\":\"Vom Winde verweht \u2013 droht das Ende der E-Musik? &#8211; Bad Blog Of Musick - nmz Klassik-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2014\\\/01\\\/26\\\/vom-winde-verweht-droht-das-ende-der-e-musik\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2014\\\/01\\\/26\\\/vom-winde-verweht-droht-das-ende-der-e-musik\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2014\\\/07\\\/badboy_gaelic.jpg?fit=640%2C480&ssl=1\",\"datePublished\":\"2014-01-26T18:12:14+00:00\",\"dateModified\":\"2018-01-20T17:58:21+00:00\",\"description\":\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2014\\\/01\\\/26\\\/vom-winde-verweht-droht-das-ende-der-e-musik\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2014\\\/01\\\/26\\\/vom-winde-verweht-droht-das-ende-der-e-musik\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2014\\\/01\\\/26\\\/vom-winde-verweht-droht-das-ende-der-e-musik\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2014\\\/07\\\/badboy_gaelic.jpg?fit=640%2C480&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2014\\\/07\\\/badboy_gaelic.jpg?fit=640%2C480&ssl=1\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2014\\\/01\\\/26\\\/vom-winde-verweht-droht-das-ende-der-e-musik\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vom Winde verweht \u2013 droht das Ende der E-Musik?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"name\":\"Bad Blog Of Musick\",\"description\":\"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\",\"name\":\"Bad Blog Of Musick\",\"alternateName\":\"Ein Klassik-Blog zur Musik\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"width\":512,\"height\":512,\"caption\":\"Bad Blog Of Musick\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/musikzeitung\",\"https:\\\/\\\/x.com\\\/musikzeitung\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/73d6c9ef0d58ae670a7d6f9affe7259c\",\"name\":\"Alexander Strauch\",\"description\":\"Komponist*in\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/author\\\/querstand\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vom Winde verweht \u2013 droht das Ende der E-Musik? &#8211; Bad Blog Of Musick - nmz Klassik-Blog","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.nmz.de\/badblog\/2014\/01\/26\/vom-winde-verweht-droht-das-ende-der-e-musik\/","og_locale":"de_DE","og_type":"article","og_title":"Vom Winde verweht \u2013 droht das Ende der E-Musik? &#8211; Bad Blog Of Musick - nmz Klassik-Blog","og_description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","og_url":"https:\/\/blogs.nmz.de\/badblog\/2014\/01\/26\/vom-winde-verweht-droht-das-ende-der-e-musik\/","og_site_name":"Bad Blog Of Musick","article_publisher":"https:\/\/www.facebook.com\/musikzeitung","article_published_time":"2014-01-26T18:12:14+00:00","article_modified_time":"2018-01-20T17:58:21+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2014\/07\/badboy_gaelic.jpg?fit=640%2C480&ssl=1","type":"image\/jpeg"}],"author":"Alexander Strauch","twitter_card":"summary_large_image","twitter_creator":"@musikzeitung","twitter_site":"@musikzeitung","twitter_misc":{"Verfasst von":"Alexander Strauch","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.nmz.de\/badblog\/2014\/01\/26\/vom-winde-verweht-droht-das-ende-der-e-musik\/#article","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2014\/01\/26\/vom-winde-verweht-droht-das-ende-der-e-musik\/"},"author":{"name":"Alexander Strauch","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/73d6c9ef0d58ae670a7d6f9affe7259c"},"headline":"Vom Winde verweht \u2013 droht das Ende der E-Musik?","datePublished":"2014-01-26T18:12:14+00:00","dateModified":"2018-01-20T17:58:21+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2014\/01\/26\/vom-winde-verweht-droht-das-ende-der-e-musik\/"},"wordCount":1629,"commentCount":2,"publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2014\/01\/26\/vom-winde-verweht-droht-das-ende-der-e-musik\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2014\/07\/badboy_gaelic.jpg?fit=640%2C480&ssl=1","articleSection":{"1":"Deutsch","2":"Sprache"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.nmz.de\/badblog\/2014\/01\/26\/vom-winde-verweht-droht-das-ende-der-e-musik\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.nmz.de\/badblog\/2014\/01\/26\/vom-winde-verweht-droht-das-ende-der-e-musik\/","url":"https:\/\/blogs.nmz.de\/badblog\/2014\/01\/26\/vom-winde-verweht-droht-das-ende-der-e-musik\/","name":"Vom Winde verweht \u2013 droht das Ende der E-Musik? &#8211; Bad Blog Of Musick - nmz Klassik-Blog","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2014\/01\/26\/vom-winde-verweht-droht-das-ende-der-e-musik\/#primaryimage"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2014\/01\/26\/vom-winde-verweht-droht-das-ende-der-e-musik\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2014\/07\/badboy_gaelic.jpg?fit=640%2C480&ssl=1","datePublished":"2014-01-26T18:12:14+00:00","dateModified":"2018-01-20T17:58:21+00:00","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","breadcrumb":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2014\/01\/26\/vom-winde-verweht-droht-das-ende-der-e-musik\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.nmz.de\/badblog\/2014\/01\/26\/vom-winde-verweht-droht-das-ende-der-e-musik\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/2014\/01\/26\/vom-winde-verweht-droht-das-ende-der-e-musik\/#primaryimage","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2014\/07\/badboy_gaelic.jpg?fit=640%2C480&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2014\/07\/badboy_gaelic.jpg?fit=640%2C480&ssl=1","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.nmz.de\/badblog\/2014\/01\/26\/vom-winde-verweht-droht-das-ende-der-e-musik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blogs.nmz.de\/badblog\/"},{"@type":"ListItem","position":2,"name":"Vom Winde verweht \u2013 droht das Ende der E-Musik?"}]},{"@type":"WebSite","@id":"https:\/\/blogs.nmz.de\/badblog\/#website","url":"https:\/\/blogs.nmz.de\/badblog\/","name":"Bad Blog Of Musick","description":"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur","publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.nmz.de\/badblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blogs.nmz.de\/badblog\/#organization","name":"Bad Blog Of Musick","alternateName":"Ein Klassik-Blog zur Musik","url":"https:\/\/blogs.nmz.de\/badblog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","width":512,"height":512,"caption":"Bad Blog Of Musick"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/musikzeitung","https:\/\/x.com\/musikzeitung"]},{"@type":"Person","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/73d6c9ef0d58ae670a7d6f9affe7259c","name":"Alexander Strauch","description":"Komponist*in","url":"https:\/\/blogs.nmz.de\/badblog\/author\/querstand\/"}]}},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2014\/07\/badboy_gaelic.jpg?fit=640%2C480&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/9898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/comments?post=9898"}],"version-history":[{"count":10,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/9898\/revisions"}],"predecessor-version":[{"id":10983,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/9898\/revisions\/10983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/media\/10681"}],"wp:attachment":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/media?parent=9898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/categories?post=9898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/tags?post=9898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}