{"id":783,"date":"2009-09-12T14:07:58","date_gmt":"2009-09-12T12:07:58","guid":{"rendered":"http:\/\/blogs.nmz.de\/badblog\/?p=783"},"modified":"2009-09-13T11:40:46","modified_gmt":"2009-09-13T09:40:46","slug":"martern-aller-arten-in-marzahn","status":"publish","type":"post","link":"https:\/\/blogs.nmz.de\/badblog\/2009\/09\/12\/martern-aller-arten-in-marzahn\/","title":{"rendered":"Martern aller Arten in Marzahn"},"content":{"rendered":"<p>Liebe Baddies,<br \/>\nEs ist an der Zeit mal wieder &#252;ber Kulturpolitik anstatt &#252;ber Kultur&#228;sthetik zu reden. Gerade erhielt ich beunruhigende Nachrichten aus Berlin, die Zukunft der Musikschule Marzahn-Hellersdorf (seit kurzem &#8222;Hans Werner Henze &#8211; Musikschule&#8220; genannt) und ihres gro&#223;en Jugendorchesters &#8211; das in jahrelanger aufopferungsvoller Arbeit vom Dirigenten Jobst Liebrecht aufgebaut wurde &#8211; betreffend.<\/p>\n<p>Hier wird die Bedrohung geschildert:<\/p>\n<blockquote><p>In einer heutigen Pressekonferenz und zuvor in einem Gespr&#228;ch gaben<br \/>\nder zust&#228;ndige Stadtrat Stephan Richter (SPD) und die zust&#228;ndige<br \/>\nAmtsleiterin Esther Drusche (SPD) bekannt, da&#223;<\/p>\n<p>&#8211; das Organisationsteam des Orchesters ver&#228;ndert werden m&#252;sse<\/p>\n<p>&#8211; das im Budget des Orchesters  K&#252;rzungen n&#246;tig sind<\/p>\n<p>&#8211; das man in der Musikschule &#8222;weg von Veranstaltungen, hin zum Unterricht&#8220;<br \/>\nkommen m&#252;sse<\/p>\n<p>&#8211; das die zuk&#252;nftigen Projekte des Jugendorchesters reduziert und von der<br \/>\nAmtsleitung genehmigt werden m&#252;ssen<\/p>\n<p>Es zeichnet sich ab, da&#223; die Musikschulleitung, die das Jugendorchester<br \/>\nmitgegr&#252;ndet hat, &#252;berhaupt abgel&#246;st werden soll.<\/p><\/blockquote>\n<p>Es ist kein Geheimnis, dass ich der Hans Werner Henze &#8211; Musikschule als Pianist wie Komponist engstens seit der Gr&#252;ndung des Jugendorchesters verbunden bin. Unter der liebevollen Betreuung des Teams der Musikschule (allen voran Martina und Rainer Feldmann) und Jobst Liebrecht ist hier im Laufe der Jahre ein fantastisches Orchester entstanden, das aufw&#228;ndige und ungew&#246;hnliche Projekte realisiert. Gleich das erste Gro&#223;projekt in Marzahn &#8211; die Kompletteinspielung von Henzes Kinderoper &#8222;Pollicino&#8220; &#8211; war ein vielbeachteter Erfolg, der mit dem Echo-Klassikpreis belohnt wurde (man mu&#223; sich das auf der Zunge zergehen lassen: ein Jugendorchester aus einer kleinen Musikschule in Marzahn-Hellersdorf erh&#228;lt diesen international begehrten Preis!). Seitdem ist dieses Orchester unerm&#252;dlich aktiv &#8211; sich gleicherma&#223;en f&#252;r klassische, popul&#228;re wie auch zeitgen&#246;ssische Musik einsetzend &#8211; so gab es vor kurzem die vielbeachtete erstmalige Wiederauff&#252;hrung des &#8222;Pl&#246;ner Musiktages&#8220; von Hindemith, zusammen mit mehreren Auftragswerken von zeitgen&#246;ssischen Komponisten, auch dies eine enorme Leistung, die manche &#8222;Profi&#8220;-Hochschule nicht gestemmt h&#228;tte. Aber in Marzahn ist das m&#246;glich, was ein Wunder ist. Jetzt soll diese m&#252;hsame Aufbauarbeit wieder zerst&#246;rt werden, die Musikschule soll wieder auf ein &#8222;unauff&#228;lliges&#8220; Niveau zurechtgestutzt werden &#8211; schon jetzt ist Rainer Feldmann gek&#252;ndigt worden, auch die weitere Arbeit des ganzen Musikschulteams inklusive Martina Feldmann und Jobst Liebrecht ist fraglich, nach den Ferien wurde zudem allen Honorarlehrern die K&#252;ndigung angedroht.<\/p>\n<div style=\"width: 273px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.schott-musik.de\/cms\/resources\/122149270264a7911f183a987d114d3c40b4b37ad6\/BildJSOMarzahn-Hellersdorf3.jpg?resize=263%2C176\" alt=\"Das Orchester \" width=\"263\" height=\"176\" \/><p class=\"wp-caption-text\">Das Orchester <\/p><\/div>\n<p>Wie man sich vorstellen kann, ist die Betreibung eines solchen Unterfangens in Marzahn-Hellersdorf enorm aufreibend, aber eben auch enorm wichtig in einem Bezirk von Berlin, der ganz sicherlich nicht ohne soziale Schwierigkeiten ist und in dem es Kindern und  Jugendlichen generell an Perspektiven und Entfaltungsm&#246;glichkeiten fehlt.  Nun soll eines der wenigen erfolgreichen Projekte, bei denen man sich ganz bewu&#223;t an wirtschaftlich weniger gut gestellte Kinder und Jugendliche wendet, und bei dem alle Beteiligten ohnehin schon mit einem Minimum an Finanzierung &#220;bermenschliches leisten, demontiert, kastriert und damit letztlich auch eingestampft werden. Das ist tats&#228;chlich ein Skandal.<\/p>\n<p>Im Grunde geht es hier um einen allgemeinen Meinungsstreit, der unsere Kulturpolitik seit einiger Zeit durchzieht, n&#228;mlich ob man &#8222;Breitenf&#246;rderung&#8220; oder &#8222;Elitenf&#246;rderung&#8220; betreibt (was man dabei immer wieder &#252;bersieht ist, dass beides gleicherma&#223;en wichtig ist, und nicht das eine gegen das andere ausgespielt werden mu&#223;, aber das nur nebenbei).<br \/>\nBei manchem Konzert des venezuelanischen Jugendorchesters unter seinem charismatischen Leiter Gustavo Dudamel sitzt so mancher vertr&#228;umt und ein Tr&#228;nchen verdr&#252;ckend ob so viel Einsatzes f&#252;r sozial unterbemittelte Jugendliche im fernen Venezuela. Was dabei vergessen wird ist, dass auch im vermeintlich so satten Deutschland solche Basisarbeit genauso engagiert und erfolgreich geleistet werden- nur dass eben nicht so viel dar&#252;ber berichtet wird.<\/p>\n<p>Deutschland steuert im Moment immer mehr auf eine &#8222;Vorzeigekultur&#8220; hin &#8211; immer weniger etablierte Opernh&#228;user, Orchester und Bildungsinstitute werden mit F&#246;rdermitteln bedacht, was zunehmend auf Kosten der sogenannten &#8222;Provinz&#8220; (siehe auch mein Artikel &#252;ber Hoyerswerda und G&#246;rlitz) oder sozial schw&#228;cher gestellten Schichten geht.<br \/>\nDas ist auch ein Problem f&#252;r die Neue Musik &#8211; wir hatten hier schon einige Beitr&#228;ge, in denen berichtet wird, wie kleine Festivals und Initiativen gerade im Osten der Republik mit immer gr&#246;sseren Schwierigkeiten zu k&#228;mpfen haben. Insofern ist das Schicksal der Hans Werner Henze &#8211; Musikschule nur symptomatisch f&#252;r eine gesamtdeutsche Entwicklung, unter deren Folgen wir zunehmend leiden m&#252;ssen.<\/p>\n<p>Daher: helft uns im Kampf f&#252;r den Fortbestand des Marzahner Jugendorchesters!<\/p>\n<p>Ich bitte das Team der NMZ herzlich, sich dieser Geschichte anzunehmen &#8211; viel zu selten wird im Feuilleton der SZ oder FAZ &#252;ber Initiativen wie diese berichtet, daher sollten wir dies unbedingt leisten. Es ist nocht nicht zu sp&#228;t, etwas zu tun. Meiner Ansicht nach sind gerade Bezirkspolitiker sehr schnell zum Einlenken  zu bewegen, wenn sie merken, dass sich gegen ihre Entscheidungen &#252;berregionaler Unmut regt.<br \/>\nEs w&#228;re toll, Anschreiben an diese Adresse zu richten:<\/p>\n<blockquote><p>BITTE RICHTET ANSCHREIBEN AN<\/p>\n<p>Stadtrat Stephan Richter<br \/>\nBezirksamt Marzahn-Hellersdorf<br \/>\nPremnitzer Str. 11<br \/>\n12681 Berlin<\/p>\n<p>&#8222;buero@stephan.richter@ba-mh.verwalt-berlin.de&#8220;\n<\/p><\/blockquote>\n<p>Ich denke, dass jedes Schreiben hilft. Am Besten keine Brandbriefe oder Drohungen, sondern Briefe, die die Wichtigkeit der Orchesterarbeit herausstellen. Wenn mal wieder ein Rundfunkorchester geschlossen werden soll, gibt es gleich tausende Unterschriften dagegen &#8211; es w&#228;re doch eine Schande, wenn dies nicht auch bei der Hans Werner Henze &#8211; Musikschule Marzahn-Hellersdorf m&#246;glich w&#228;re. In gewisser Weise ist n&#228;mlich deren Arbeit NOCH wichtiger als die der Rundfunkorchester.<\/p>\n<p>Ich hoffe auf Eure Hilfe, bitte verlinkt diesen Artikel und kommentiert ihn, damit wir viel Aufmerksamkeit erzeugen k&#246;nnen.<br \/>\nVielen Dank<br \/>\nEuer Bad Boy<br \/>\nMoritz Eggert<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/i0.wp.com\/www.marzahn-hellersdorf-musikschule.de\/Musikschule\/images\/titel.jpg?resize=300%2C215\" alt=\"\" width=\"300\" height=\"215\" \/><\/p>\n<p><img decoding=\"async\" src=\"http:\/\/vg03.met.vgwort.de\/na\/69bf17544ee9a0d8f6adf6b9624376\" width=\"1\"\/> <\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Martern%20aller%20Arten%20in%20Marzahn https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2009%2F09%2F12%2Fmartern-aller-arten-in-marzahn%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Martern%20aller%20Arten%20in%20Marzahn https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2009%2F09%2F12%2Fmartern-aller-arten-in-marzahn%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2009%2F09%2F12%2Fmartern-aller-arten-in-marzahn%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Martern%20aller%20Arten%20in%20Marzahn%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2009%2F09%2F12%2Fmartern-aller-arten-in-marzahn%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2009%2F09%2F12%2Fmartern-aller-arten-in-marzahn%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Es ist an der Zeit mal wieder &#252;ber Kulturpolitik anstatt &#252;ber Kultur&#228;sthetik zu reden. Gerade erhielt ich beunruhigende Nachrichten aus Berlin, die Zukunft der Musikschule Marzahn-Hellersdorf (seit kurzem &#8222;Hans Werner Henze &#8211; Musikschule&#8220; genannt) und ihres gro&#223;en Jugendorchesters &#8211; das in jahrelanger aufopferungsvoller Arbeit vom Dirigenten Jobst Liebrecht aufgebaut wurde &#8211; betreffend.<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Martern%20aller%20Arten%20in%20Marzahn https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2009%2F09%2F12%2Fmartern-aller-arten-in-marzahn%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Martern%20aller%20Arten%20in%20Marzahn https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2009%2F09%2F12%2Fmartern-aller-arten-in-marzahn%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2009%2F09%2F12%2Fmartern-aller-arten-in-marzahn%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Martern%20aller%20Arten%20in%20Marzahn%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2009%2F09%2F12%2Fmartern-aller-arten-in-marzahn%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2009%2F09%2F12%2Fmartern-aller-arten-in-marzahn%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[14657],"tags":[79,467,468,471,470,465,266,469,466,464,472],"class_list":["post-783","post","type-post","status-publish","format-standard","hentry","category-nicht-kategorisiert","tag-basisarbeit","tag-berlin","tag-dudamel","tag-elitenfoerderung","tag-feldmann","tag-hans-werner-henze","tag-kulturpolitik","tag-liebrecht","tag-marzahn-hellersdorf","tag-musikschule","tag-skandal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Martern aller Arten in Marzahn &#8211; Bad Blog Of Musick - nmz Klassik-Blog<\/title>\n<meta name=\"description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.nmz.de\/badblog\/2009\/09\/12\/martern-aller-arten-in-marzahn\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Martern aller Arten in Marzahn &#8211; Bad Blog Of Musick - nmz Klassik-Blog\" \/>\n<meta property=\"og:description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.nmz.de\/badblog\/2009\/09\/12\/martern-aller-arten-in-marzahn\/\" \/>\n<meta property=\"og:site_name\" content=\"Bad Blog Of Musick\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/musikzeitung\" \/>\n<meta property=\"article:author\" content=\"moritz.eggert.79\" \/>\n<meta property=\"article:published_time\" content=\"2009-09-12T12:07:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2009-09-13T09:40:46+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.schott-musik.de\/cms\/resources\/122149270264a7911f183a987d114d3c40b4b37ad6\/BildJSOMarzahn-Hellersdorf3.jpg\" \/>\n<meta name=\"author\" content=\"Moritz Eggert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MoritzEggert\" \/>\n<meta name=\"twitter:site\" content=\"@musikzeitung\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Moritz Eggert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2009\\\/09\\\/12\\\/martern-aller-arten-in-marzahn\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2009\\\/09\\\/12\\\/martern-aller-arten-in-marzahn\\\/\"},\"author\":{\"name\":\"Moritz Eggert\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/ce88a756dea34f64ceab78df990e3dd4\"},\"headline\":\"Martern aller Arten in Marzahn\",\"datePublished\":\"2009-09-12T12:07:58+00:00\",\"dateModified\":\"2009-09-13T09:40:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2009\\\/09\\\/12\\\/martern-aller-arten-in-marzahn\\\/\"},\"wordCount\":941,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2009\\\/09\\\/12\\\/martern-aller-arten-in-marzahn\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.schott-musik.de\\\/cms\\\/resources\\\/122149270264a7911f183a987d114d3c40b4b37ad6\\\/BildJSOMarzahn-Hellersdorf3.jpg\",\"keywords\":[\"Basisarbeit\",\"Berlin\",\"Dudamel\",\"Elitenf\u00f6rderung\",\"Feldmann\",\"Hans Werner Henze\",\"kulturpolitik\",\"Liebrecht\",\"Marzahn-Hellersdorf\",\"Musikschule\",\"Skandal\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2009\\\/09\\\/12\\\/martern-aller-arten-in-marzahn\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2009\\\/09\\\/12\\\/martern-aller-arten-in-marzahn\\\/\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2009\\\/09\\\/12\\\/martern-aller-arten-in-marzahn\\\/\",\"name\":\"Martern aller Arten in Marzahn &#8211; Bad Blog Of Musick - nmz Klassik-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2009\\\/09\\\/12\\\/martern-aller-arten-in-marzahn\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2009\\\/09\\\/12\\\/martern-aller-arten-in-marzahn\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.schott-musik.de\\\/cms\\\/resources\\\/122149270264a7911f183a987d114d3c40b4b37ad6\\\/BildJSOMarzahn-Hellersdorf3.jpg\",\"datePublished\":\"2009-09-12T12:07:58+00:00\",\"dateModified\":\"2009-09-13T09:40:46+00:00\",\"description\":\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2009\\\/09\\\/12\\\/martern-aller-arten-in-marzahn\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2009\\\/09\\\/12\\\/martern-aller-arten-in-marzahn\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2009\\\/09\\\/12\\\/martern-aller-arten-in-marzahn\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.schott-musik.de\\\/cms\\\/resources\\\/122149270264a7911f183a987d114d3c40b4b37ad6\\\/BildJSOMarzahn-Hellersdorf3.jpg\",\"contentUrl\":\"http:\\\/\\\/www.schott-musik.de\\\/cms\\\/resources\\\/122149270264a7911f183a987d114d3c40b4b37ad6\\\/BildJSOMarzahn-Hellersdorf3.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2009\\\/09\\\/12\\\/martern-aller-arten-in-marzahn\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Martern aller Arten in Marzahn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"name\":\"Bad Blog Of Musick\",\"description\":\"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\",\"name\":\"Bad Blog Of Musick\",\"alternateName\":\"Ein Klassik-Blog zur Musik\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"width\":512,\"height\":512,\"caption\":\"Bad Blog Of Musick\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/musikzeitung\",\"https:\\\/\\\/x.com\\\/musikzeitung\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/ce88a756dea34f64ceab78df990e3dd4\",\"name\":\"Moritz Eggert\",\"description\":\"Komponist\",\"sameAs\":[\"http:\\\/\\\/www.moritz-eggert.de\",\"moritz.eggert.79\",\"https:\\\/\\\/x.com\\\/MoritzEggert\"],\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/author\\\/moritzeggert\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Martern aller Arten in Marzahn &#8211; Bad Blog Of Musick - nmz Klassik-Blog","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.nmz.de\/badblog\/2009\/09\/12\/martern-aller-arten-in-marzahn\/","og_locale":"de_DE","og_type":"article","og_title":"Martern aller Arten in Marzahn &#8211; Bad Blog Of Musick - nmz Klassik-Blog","og_description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","og_url":"https:\/\/blogs.nmz.de\/badblog\/2009\/09\/12\/martern-aller-arten-in-marzahn\/","og_site_name":"Bad Blog Of Musick","article_publisher":"https:\/\/www.facebook.com\/musikzeitung","article_author":"moritz.eggert.79","article_published_time":"2009-09-12T12:07:58+00:00","article_modified_time":"2009-09-13T09:40:46+00:00","og_image":[{"url":"http:\/\/www.schott-musik.de\/cms\/resources\/122149270264a7911f183a987d114d3c40b4b37ad6\/BildJSOMarzahn-Hellersdorf3.jpg","type":"","width":"","height":""}],"author":"Moritz Eggert","twitter_card":"summary_large_image","twitter_creator":"@MoritzEggert","twitter_site":"@musikzeitung","twitter_misc":{"Verfasst von":"Moritz Eggert","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.nmz.de\/badblog\/2009\/09\/12\/martern-aller-arten-in-marzahn\/#article","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2009\/09\/12\/martern-aller-arten-in-marzahn\/"},"author":{"name":"Moritz Eggert","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/ce88a756dea34f64ceab78df990e3dd4"},"headline":"Martern aller Arten in Marzahn","datePublished":"2009-09-12T12:07:58+00:00","dateModified":"2009-09-13T09:40:46+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2009\/09\/12\/martern-aller-arten-in-marzahn\/"},"wordCount":941,"commentCount":3,"publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2009\/09\/12\/martern-aller-arten-in-marzahn\/#primaryimage"},"thumbnailUrl":"http:\/\/www.schott-musik.de\/cms\/resources\/122149270264a7911f183a987d114d3c40b4b37ad6\/BildJSOMarzahn-Hellersdorf3.jpg","keywords":["Basisarbeit","Berlin","Dudamel","Elitenf\u00f6rderung","Feldmann","Hans Werner Henze","kulturpolitik","Liebrecht","Marzahn-Hellersdorf","Musikschule","Skandal"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.nmz.de\/badblog\/2009\/09\/12\/martern-aller-arten-in-marzahn\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.nmz.de\/badblog\/2009\/09\/12\/martern-aller-arten-in-marzahn\/","url":"https:\/\/blogs.nmz.de\/badblog\/2009\/09\/12\/martern-aller-arten-in-marzahn\/","name":"Martern aller Arten in Marzahn &#8211; Bad Blog Of Musick - nmz Klassik-Blog","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2009\/09\/12\/martern-aller-arten-in-marzahn\/#primaryimage"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2009\/09\/12\/martern-aller-arten-in-marzahn\/#primaryimage"},"thumbnailUrl":"http:\/\/www.schott-musik.de\/cms\/resources\/122149270264a7911f183a987d114d3c40b4b37ad6\/BildJSOMarzahn-Hellersdorf3.jpg","datePublished":"2009-09-12T12:07:58+00:00","dateModified":"2009-09-13T09:40:46+00:00","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","breadcrumb":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2009\/09\/12\/martern-aller-arten-in-marzahn\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.nmz.de\/badblog\/2009\/09\/12\/martern-aller-arten-in-marzahn\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/2009\/09\/12\/martern-aller-arten-in-marzahn\/#primaryimage","url":"http:\/\/www.schott-musik.de\/cms\/resources\/122149270264a7911f183a987d114d3c40b4b37ad6\/BildJSOMarzahn-Hellersdorf3.jpg","contentUrl":"http:\/\/www.schott-musik.de\/cms\/resources\/122149270264a7911f183a987d114d3c40b4b37ad6\/BildJSOMarzahn-Hellersdorf3.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.nmz.de\/badblog\/2009\/09\/12\/martern-aller-arten-in-marzahn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blogs.nmz.de\/badblog\/"},{"@type":"ListItem","position":2,"name":"Martern aller Arten in Marzahn"}]},{"@type":"WebSite","@id":"https:\/\/blogs.nmz.de\/badblog\/#website","url":"https:\/\/blogs.nmz.de\/badblog\/","name":"Bad Blog Of Musick","description":"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur","publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.nmz.de\/badblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blogs.nmz.de\/badblog\/#organization","name":"Bad Blog Of Musick","alternateName":"Ein Klassik-Blog zur Musik","url":"https:\/\/blogs.nmz.de\/badblog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","width":512,"height":512,"caption":"Bad Blog Of Musick"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/musikzeitung","https:\/\/x.com\/musikzeitung"]},{"@type":"Person","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/ce88a756dea34f64ceab78df990e3dd4","name":"Moritz Eggert","description":"Komponist","sameAs":["http:\/\/www.moritz-eggert.de","moritz.eggert.79","https:\/\/x.com\/MoritzEggert"],"url":"https:\/\/blogs.nmz.de\/badblog\/author\/moritzeggert\/"}]}},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","jetpack_featured_media_url":"","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/comments?post=783"}],"version-history":[{"count":9,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/783\/revisions"}],"predecessor-version":[{"id":803,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/783\/revisions\/803"}],"wp:attachment":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/media?parent=783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/categories?post=783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/tags?post=783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}