{"id":7170,"date":"2012-10-07T23:50:03","date_gmt":"2012-10-07T22:50:03","guid":{"rendered":"http:\/\/blogs.nmz.de\/badblog\/?p=7170"},"modified":"2018-01-20T19:01:55","modified_gmt":"2018-01-20T18:01:55","slug":"mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik","status":"publish","type":"post","link":"https:\/\/blogs.nmz.de\/badblog\/2012\/10\/07\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\/","title":{"rendered":"Mensch oder Maschine und Wahrnehmung \u2013 wer oder was macht die Musik?"},"content":{"rendered":"<p style=\"text-align: center\"><a href=\"https:\/\/blogs.nmz.de\/badblog\/2012\/10\/07\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\/mgnm-verspielte-maschinen\/\" rel=\"attachment wp-att-7174\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2012\/10\/mgnm-verspielte-maschinen.jpg?resize=141%2C300&#038;ssl=1\" alt=\"\" width=\"141\" height=\"300\" \/><\/a><\/p>\n<p style=\"text-align: left\">Mensch oder Maschine \u2013 wer oder was macht die Musik? Das war meine Frage an mich nach dem kleinen Festival \u201eVerspielte Maschinen\u201c der <a href=\"http:\/\/www.mgnm.de\/\">M&#252;nchener Gesellschaft f&#252;r Neue Musik<\/a> im Deutschen Museum. Problematisch f&#252;r meine Objektivit&#228;t ist, dass ich die meisten der K&#252;nstler pers&#246;nlich kenne. So spreche ich hier zwar &#252;ber ihre St&#252;cke, ihre Arbeit. Mir geht es hier aber v.a. um mein eigenes Wahrnehmen, ist die hier eine narzisstische Selbstbeobachtung. Immerhin ist dies ja &#8222;nur&#8220; ein Blog und kein Kritikorgan der Pressewelt.<!--more--><\/p>\n<p style=\"text-align: left\">Ich sah mir nur die beiden Abschlussveranstaltungen am Samstagabend an. Am Abend zuvor ging es in einem Vortrag um \u201eMensch und Materie \u2013 Philosophische Betrachtungen zu m&#246;glichen oder unm&#246;glichen Identit&#228;ten und Differenzen\u201c sowie samstags am Nachmittag um \u201everspielt\/unspielbar\u201c in Bezug auf Iannis Xenakis. Man sehe es mir nach, mich fixte beides nicht an. Ich sage es mal masslos &#252;berzogen: Schwebt die Drohne &#252;ber einem, vielleicht nur durch einen selbstentscheidenden Algorithmus gesteuert, hilft weder beten noch philosophieren. So auch im Moment der konkreten Betrachtung und Anh&#246;rung von Musikautomaten. Und zur Unspielbarkeit: manchmal macht es mir Spass, f&#252;r mich viel zu schwierige Musik vor mich her zu klimpern, meist ist es nicht mein vorrangiges kompositorisches Ziel, Interpreten das Leben all zu schwer zu machen. Auch wenn ich dann in Form meines Notentextes wie jene hirnlose Drohen erscheinen mag. Man sieht allein an den letzten S&#228;tzen, wie nah sich \u201espielbar\u201c, \u201eunspielbar\u201c, das 0 oder 1 der Auff&#252;hrbarkeit, bei nur von Menschenhand gespielter Musik sind, greifen in freier Beschreibung dessen der adjektivische Gebrauch der reine Technik beschreibenden Begriffe: \u201emechanisch\u201c, \u201etechnizistisch\u201c, \u201eautomatisch\u201c, \u201emaschinell\u201c etc. Wie oft allein verwenden wir diese Worte f&#252;r Musiker aus Ostasien, um deren uns befremdlichen Zugriff auf \u201eunsere Musiktradition\u201c zu umschreiben.<\/p>\n<p>Im Prinzip brachte es der f&#252;r die Technik verantwortliche Kompagnon\u00a0<a href=\"http:\/\/ablinger.mur.at\/\">Peter Ablingers<\/a> auf den Punkt, wenn ich es richtig wiedergebe: Peter Ritsch (was f&#252;r ein wundervoller Nachname, der sofort an musique concr\u00e8te denken l&#228;sst, elektronisch oder instrumental) sagte, letztlich sei in Bezug auf Musik, ob durch Mensch oder Automat produziert, ihre geistige, denkerische oder ungefilterte Wahrnehmung durch den H&#246;rer, Zuseher entscheidend. Ganz fantastisch zu sehen an Peter Ablingers inzwischen weiten Kreisen bekanntem \u201e<a href=\"http:\/\/www.youtube.com\/watch?v=BzcBusxDThM\">Deus cantando<\/a>\u201c: Ein Junge verliest die UN-Deklaration f&#252;r den Internationalen Umweltgerichtshof. Die Formanten der Rede des Sprechers werden gemessen und in unendlicher Differenzierung von Ritschs Anschlagsmaschine in Tonh&#246;he und Lautst&#228;rke wie Dauer auf einen Fl&#252;gel &#252;bertragen, der dies in vielen der Sprachmelodie nahen Clustern wiedergibt. H&#246;rt man dies erst ohne Verfolgen des Textes, registriert man als Unge&#252;bter v.a. jene Cluster. Wird der Texte parallel eingeblendet, versteht man Alles. Ritsch sprach davon, wie gewohnt ihm dies inzwischen sei, dass er ohne Projektion zurechtk&#228;me. Ich k&#246;nnte mir das sogar so weitgehend vorstellen, dass man dies besser wahrnimmt als mittelpr&#228;chtig artikulierende Operns&#228;nger, die oft genug im Singen nur undeutliche Worte hervorpressen. &#196;hnlich faszinierend Ablingers Analyse, filternde Zersetzung und durch immer feinere Raster wieder deutlicher werdende Umsetzung des \u201eZeit im Bild\u201c-Openers der ORF Nachrichtensendung. Bemerkenswert in beiden F&#228;llen, wie Ritsch seine eigene Apparatur baute, sehr wohl auf Bestehendem zur&#252;ckgreifend, um den Fl&#252;gel zu traktieren. Das entscheidende an Ablingers und Ritschs &#196;sthetik ist die Verwandlung des Klaviers in ein anderes Medium, in eine sprechende Maschine, die ber&#252;hrt wie die netten Momente mit HAL in Kubricks \u201e2001: A Space Odyssey\u201c.<\/p>\n<p>Ein weiterer Versuch, ein Klavier durch elektrische Anregung, Steuerung, zum spielerlosen Klingen zu bringen ist das <a href=\"http:\/\/de.wikipedia.org\/wiki\/Disklavier\">Disklavier<\/a>. Daf&#252;r arbeiteten die meisten K&#252;nstler des Abends. Das Klavier in seiner Tradition als DAS Virtuosen- und Komponierinstrument des 19. wie doch auch 20. Jahrhunderts, ist durch den Versuch, die Anschlagsmechanik so zu verfeinern, als bet&#228;tige die menschliche Hand direkt die Anregung der Saite, absurderweise selbst zu einem Fast-Apparat, ja als urspr&#252;nglicher Streicher kann ich das Fast weglassen, zu einer Maschine geworden. Das alte Welte-Mignon-Klavier mit Lochkartenrollen ging diesen Schritt dann in letzter Konsequenz. Das Disklavier mag baulich eine andere Sache sein. Dennoch empfinde ich es eher als Weiterentwicklung des &#228;lteren Verfahrens denn als vollkommen neuartige Entwicklung. Im Endergebnis wird ein Klavier von Geisterhand bet&#228;tigt. Interessanterweise inspirierte dies jene damit arbeitenden Komponisten des Abends v.a. zur Auseinandersetzung mit Virtuosit&#228;t, mal komponierter, mal improvisierter gespielt wirkend, immer &#252;berbordend und alle Register ziehend, die Tastatur hinauf- und herabrasend. Das &#220;berzeugendste der Disklavierst&#252;cke waren \u00a0<a href=\"http:\/\/www.clockboxx.de\/\">Volker Nickels<\/a>\u00a0&#8222;Sechs Et&#252;den&#8220;, die dem Ger&#228;t einen an dessen strenge Zeitlichkeit des Disklaviers gefesselten Akkordeonisten gegen&#252;ber setzten, der den Notentext des schwirrenden Tastenapparates atmend reliefartig konterkarierte, begleitete. Insgesamt in virtuoser Machart war der Moment im Gegenspiel non Mensch und Maschine am spannendsten, als der Akkordensolist echt ins Schwitzen kam, weil er seinen Notenberg kaum Umbl&#228;ttern konnte und aus seinem konzentriertem Spielen kam, um doch schnell wieder den Faden der eleganten Komposition zu ergreifen.<\/p>\n<p>Die besten humanen Momente in Bezug auf unerbittliche Technik sind immer die angestrengten Reaktionen der menschlichen Ausl&#246;ser, Spieler, Beherrscher der Apparaturen. Zwei St&#252;cke arbeiteten so z.B. mit wirklich eigens gebauten Instrumenten, mechanischen nat&#252;rlich, des Soundart-K&#252;nstlers <a href=\"http:\/\/martinriches.de\/\">Martin Riches<\/a>: Schn&#252;re werden als Tonleiter durch ein R&#228;dchen gestrichen, einen Hebel geszupft, weitere abgegriffen, durch eine Art Holzhorn der Schall nach aussen verst&#228;rkt. Zwei dieser Maschinen traten in diesen Kompositionen je aufeinander abgestimmt in Interaktion. Das k&#252;rzere St&#252;ck war interessant, das l&#228;ngere nervte, strapazierte arg die H&#246;rlust. Man erwartet auch hier bei angek&#252;ndigter Kompositionskunst gestaltete Zeit. Wurde auch das Spiel aller Ger&#228;te, Riches Instrumente, das Disklavier, Ritschs Apparatur und mehr filmisch live projiziert, sprang mich die damit produzierte Musik immer an, wenn sie entweder kurz war und menschliche Themen anriss, wie Ablingers Musik. Pr&#228;sentierte sie sich im \u201eGeisterhand-Modus\u201c, stellte sie nicht beinahe schulisch direkt ihr Material, den beabsichtigten Prozess vor, war es gef&#228;hrlich &#246;de.<\/p>\n<p>Dem wirkte <a href=\"http:\/\/www.swr.de\/swr2\/festivals\/donaueschingen\/komponisten\/-\/id=3500652\/nid=3500652\/did=3329642\/174m3fr\/index.html\">Zoro Babel<\/a> mit seinen mechanisch, computergesteuerten Steinplatten-Bagatellen entgegen, der dazu selbst musikantische Spannung als Schlagzeuger einsetzte, auch wunderbar immer wieder auf seine Maschine wartend. Ber&#252;hrend, das richtige Mass zwischen Konstruktion, Komposition und &#252;berm&#228;chtiger Anstrengung des spielenden Menschen, zeigte auch\u00a0<a href=\"http:\/\/www.tomsora.de\/\">Tom Sora<\/a> mit seinen beiden St&#252;cken f&#252;r Lochkarten und von Hand gekurbelter Spieluhr. Nah an Nancarrow dran, genauso das Material, den Prozess vorstellend. Aber eben im Gegensatz zu den allein spielenden mechanischen Klavieren des Urvaters hier der schwitzende Mensch!<\/p>\n<p>Und in anderen St&#252;cken, der auf den richtigen Moment wartende Mensch: Dies widerfuhr auch <a href=\"http:\/\/www.pianoklang.de\/musiker\/experimentell\/838\">Alexis Pope<\/a> mit seiner Popophonie 1.0. Er pr&#228;sentierte seinen Prototyp: Er goss Wasser in ein Infusionssystem, liess es in einen Wasserkocher tropfen, nahm dies wie das sp&#228;tere Kochen mit einem Kontaktmikrofon ab, liess den Sound durch ein mit sich selbst r&#252;ckgekoppeltes Mischpult laufen und drehte an den Reglern, immer wieder einen angestrengten Blick auf den Wasserfluss riskierend, um rechtzeitig den Wasserkocher schliessen und starten zu k&#246;nnen. Auch hier die Anr&#252;hrung durch die Reaktion des Menschen auf seine Apparatur, nicht die Maschine selbst.<\/p>\n<p>Konsequent erlebte dies auch <a href=\"http:\/\/www.christophreiserer.net\/\">Christoph Reiserer<\/a> mit \u201emeeting\u201c: Er hatte zwischen Disklavier und E-Gitarre, letztere von Elektromotoren angerissen, eine Installation errichtet, die beide Instrumente per MaxMsp-Programmierung aufeinander \u201eh&#246;rend\u201c reagieren liess: Auf die Gitarrenakkorde versuchte das Klavier melodische T&#246;ne, reagierte darauf die Gitarre. Da dies frisch direkt aus der Werkstatt kam, sprang Reiserer selbst zwischen dem Disklavier und seiner Steuerung und der E-Gitarre und ihrer Computeranregung Lautst&#228;rke ausgleichend hin und her, so dass sich das menschliche Element seiner Reaktion deutlich zeigte. Mancher mag das skeptisch betrachtet haben, mich ber&#252;hrte dies.<\/p>\n<p>Die wahre kindliche Freude im Bestaunen einer mechanischen Konstruktion, als sei es ein elektrisches Krippenspiel oder eine Modelleisenbahnlandschaft, l&#246;ste auch <a href=\"http:\/\/www.eigenklang.de\/\">Karl F. Gerbers<\/a> Installation, Komposition \u2013 man kann das nicht immer so richtig scharf trennen \u2013 \u201eAnregungen f&#252;r neu konstruierten experimentellen Violinautomaten\u201c aus. Eine Violine wurde direkt sichtbar durch einen kleinen, an einem Stab befestigten Minibogen gestrichen. Dessen Kratzen wurde durch einen zerbrechlichen Anzieh- und R&#252;ckstossmechanismus bet&#228;tigt. Die T&#246;ne wurden durch kolbenartig gesteuerte Elemente gegriffen und gezupft. Beim \u201eGriffbretttupfen\u201c war dies so m&#228;chtig, dass der gesamte Korpus der traktierten Geige fast zerst&#246;rerisch durchgedr&#252;ckt wurde, so dass ich mich fragte, ob der zusehende Bratscher Klaus-Peter Werani jetzt Angst um das Instrument bekam oder neidisch auf die unglaubliche Druckkraft wurde.<\/p>\n<p>Ich gebe hier nur meine Eindr&#252;cke wieder, ist das Gesagte zu den Kompositionen eigentlich unwichtig. Spannend bleibt, was macht der Mensch w&#228;hrend solcher Musik, solcher Installation. Als reine Soundart n&#228;hert man sich wie ein Ausstellungsbesucher und gestaltet Anfang und Ende selbst. Als Konzert-Zuh&#246;rer f&#252;hlt man sich ausgeliefert, wenn die St&#252;cke zu untertourig vor sich hertr&#246;pfeln und weit und breit keinem Spieler seine Reaktionen auf die Stirn geschrieben abzulesen sind. Ist die Musik total undramatisch, aber streng konzeptionell macht die Musikerferne wieder Sinn, ja sogar Spass. Wird das Kompositorische betont, sind die Wartereien der Spieler das Anregendste oder auch die kompositorische Struktur, wenn sie variantenreich genug ist. Die Virtuosit&#228;t ist dabei das Uninteressanteste. Bekommt man Zeit, Geh&#246;rtes und zu Sehendes zusammen, ist es egal, wie die Musik gestaltet ist, ja ber&#252;hren Inhalte besonders, wie bei Ablinger das Konzept wie Christi Wundmale offen zeigen oder dieses kindliche Staunen wie beim Betrachten elektrischen Krippenspielen eintritt. Die Musik macht ja niemals der Komponist oder der Musiker, nein \u2013 der H&#246;rer ist letztlich selbst verantwortlich, was er erlebt oder nicht. Instrumente und Automaten, Komposition und Interpretation sind nur Angebote. Zwar will sich der Zuh&#246;rer gerne steuern lassen. Er ist aber sein eigener Kapit&#228;n, wir K&#252;nstler und Konstrukteure nur Obermaat und Steuermann\/-frau.<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Mensch%20oder%20Maschine%20und%20Wahrnehmung%20%E2%80%93%20wer%20oder%20was%20macht%20die%20Musik%3F https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2012%2F10%2F07%2Fmensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Mensch%20oder%20Maschine%20und%20Wahrnehmung%20%E2%80%93%20wer%20oder%20was%20macht%20die%20Musik%3F https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2012%2F10%2F07%2Fmensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2012%2F10%2F07%2Fmensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Mensch%20oder%20Maschine%20und%20Wahrnehmung%20%E2%80%93%20wer%20oder%20was%20macht%20die%20Musik%3F%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2012%2F10%2F07%2Fmensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2012%2F10%2F07%2Fmensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Mensch oder Maschine \u2013 wer oder was macht die Musik? Das war meine Frage an mich nach dem kleinen Festival \u201eVerspielte Maschinen\u201c der M&#252;nchener Gesellschaft f&#252;r Neue Musik im Deutschen Museum. Problematisch f&#252;r meine Objektivit&#228;t ist, dass ich die meisten der K&#252;nstler pers&#246;nlich kenne. So spreche ich hier zwar &#252;ber&#46;&#46;&#46;<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Mensch%20oder%20Maschine%20und%20Wahrnehmung%20%E2%80%93%20wer%20oder%20was%20macht%20die%20Musik%3F https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2012%2F10%2F07%2Fmensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Mensch%20oder%20Maschine%20und%20Wahrnehmung%20%E2%80%93%20wer%20oder%20was%20macht%20die%20Musik%3F https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2012%2F10%2F07%2Fmensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2012%2F10%2F07%2Fmensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Mensch%20oder%20Maschine%20und%20Wahrnehmung%20%E2%80%93%20wer%20oder%20was%20macht%20die%20Musik%3F%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2012%2F10%2F07%2Fmensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2012%2F10%2F07%2Fmensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"author":31,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[14657,2892],"tags":[9694,8683,9692,8783,9682,9685,9683,9697,9696,9688,9695,7403,9690,9681,9689,9693,9691,8233,9687,9686,9684,9698],"class_list":["post-7170","post","type-post","status-publish","format-standard","hentry","category-nicht-kategorisiert","category-deutsch","tag-alexis-pope","tag-christoph-reiserer","tag-conlon-nancarrow","tag-deutsches-museum","tag-disklavier","tag-drohne","tag-hal","tag-horer","tag-karl-f-gerber","tag-martin-riches","tag-maxmsp","tag-mgnm","tag-musikautomat","tag-peter-ablinger","tag-peter-ritsch","tag-soundart","tag-tom-sora","tag-volker-nickel","tag-welte-mignon","tag-zeit-im-bild","tag-zoror-babel","tag-zuschauer"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mensch oder Maschine und Wahrnehmung \u2013 wer oder was macht die Musik? &#8211; Bad Blog Of Musick - nmz Klassik-Blog<\/title>\n<meta name=\"description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.nmz.de\/badblog\/2012\/10\/07\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mensch oder Maschine und Wahrnehmung \u2013 wer oder was macht die Musik? &#8211; Bad Blog Of Musick - nmz Klassik-Blog\" \/>\n<meta property=\"og:description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.nmz.de\/badblog\/2012\/10\/07\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\/\" \/>\n<meta property=\"og:site_name\" content=\"Bad Blog Of Musick\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/musikzeitung\" \/>\n<meta property=\"article:published_time\" content=\"2012-10-07T22:50:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-01-20T18:01:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.nmz.de\/badblog\/files\/2012\/10\/mgnm-verspielte-maschinen-141x300.jpg\" \/>\n<meta name=\"author\" content=\"Alexander Strauch\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@musikzeitung\" \/>\n<meta name=\"twitter:site\" content=\"@musikzeitung\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexander Strauch\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2012\\\/10\\\/07\\\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2012\\\/10\\\/07\\\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\\\/\"},\"author\":{\"name\":\"Alexander Strauch\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/73d6c9ef0d58ae670a7d6f9affe7259c\"},\"headline\":\"Mensch oder Maschine und Wahrnehmung \u2013 wer oder was macht die Musik?\",\"datePublished\":\"2012-10-07T22:50:03+00:00\",\"dateModified\":\"2018-01-20T18:01:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2012\\\/10\\\/07\\\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\\\/\"},\"wordCount\":1611,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2012\\\/10\\\/07\\\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2012\\\/10\\\/mgnm-verspielte-maschinen-141x300.jpg\",\"keywords\":[\"Alexis Pope\",\"Christoph Reiserer\",\"Conlon Nancarrow\",\"Deutsches Museum\",\"Disklavier\",\"Drohne\",\"HAL\",\"H\u00f6rer\",\"Karl F. Gerber\",\"Martin Riches\",\"MaxMsp\",\"mgnm\",\"Musikautomat\",\"Peter Ablinger\",\"Peter Ritsch\",\"Soundart\",\"Tom Sora\",\"Volker Nickel\",\"Welte-Mignon\",\"Zeit im Bild\",\"Zoror Babel\",\"Zuschauer\"],\"articleSection\":{\"1\":\"Deutsch\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2012\\\/10\\\/07\\\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2012\\\/10\\\/07\\\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\\\/\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2012\\\/10\\\/07\\\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\\\/\",\"name\":\"Mensch oder Maschine und Wahrnehmung \u2013 wer oder was macht die Musik? &#8211; Bad Blog Of Musick - nmz Klassik-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2012\\\/10\\\/07\\\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2012\\\/10\\\/07\\\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2012\\\/10\\\/mgnm-verspielte-maschinen-141x300.jpg\",\"datePublished\":\"2012-10-07T22:50:03+00:00\",\"dateModified\":\"2018-01-20T18:01:55+00:00\",\"description\":\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2012\\\/10\\\/07\\\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2012\\\/10\\\/07\\\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2012\\\/10\\\/07\\\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2012\\\/10\\\/mgnm-verspielte-maschinen.jpg?fit=272%2C576&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2012\\\/10\\\/mgnm-verspielte-maschinen.jpg?fit=272%2C576&ssl=1\",\"width\":\"272\",\"height\":\"576\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2012\\\/10\\\/07\\\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mensch oder Maschine und Wahrnehmung \u2013 wer oder was macht die Musik?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"name\":\"Bad Blog Of Musick\",\"description\":\"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\",\"name\":\"Bad Blog Of Musick\",\"alternateName\":\"Ein Klassik-Blog zur Musik\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"width\":512,\"height\":512,\"caption\":\"Bad Blog Of Musick\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/musikzeitung\",\"https:\\\/\\\/x.com\\\/musikzeitung\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/73d6c9ef0d58ae670a7d6f9affe7259c\",\"name\":\"Alexander Strauch\",\"description\":\"Komponist*in\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/author\\\/querstand\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mensch oder Maschine und Wahrnehmung \u2013 wer oder was macht die Musik? &#8211; Bad Blog Of Musick - nmz Klassik-Blog","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.nmz.de\/badblog\/2012\/10\/07\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\/","og_locale":"de_DE","og_type":"article","og_title":"Mensch oder Maschine und Wahrnehmung \u2013 wer oder was macht die Musik? &#8211; Bad Blog Of Musick - nmz Klassik-Blog","og_description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","og_url":"https:\/\/blogs.nmz.de\/badblog\/2012\/10\/07\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\/","og_site_name":"Bad Blog Of Musick","article_publisher":"https:\/\/www.facebook.com\/musikzeitung","article_published_time":"2012-10-07T22:50:03+00:00","article_modified_time":"2018-01-20T18:01:55+00:00","og_image":[{"url":"https:\/\/blogs.nmz.de\/badblog\/files\/2012\/10\/mgnm-verspielte-maschinen-141x300.jpg","type":"","width":"","height":""}],"author":"Alexander Strauch","twitter_card":"summary_large_image","twitter_creator":"@musikzeitung","twitter_site":"@musikzeitung","twitter_misc":{"Verfasst von":"Alexander Strauch","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.nmz.de\/badblog\/2012\/10\/07\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\/#article","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2012\/10\/07\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\/"},"author":{"name":"Alexander Strauch","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/73d6c9ef0d58ae670a7d6f9affe7259c"},"headline":"Mensch oder Maschine und Wahrnehmung \u2013 wer oder was macht die Musik?","datePublished":"2012-10-07T22:50:03+00:00","dateModified":"2018-01-20T18:01:55+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2012\/10\/07\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\/"},"wordCount":1611,"commentCount":2,"publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2012\/10\/07\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.nmz.de\/badblog\/files\/2012\/10\/mgnm-verspielte-maschinen-141x300.jpg","keywords":["Alexis Pope","Christoph Reiserer","Conlon Nancarrow","Deutsches Museum","Disklavier","Drohne","HAL","H\u00f6rer","Karl F. Gerber","Martin Riches","MaxMsp","mgnm","Musikautomat","Peter Ablinger","Peter Ritsch","Soundart","Tom Sora","Volker Nickel","Welte-Mignon","Zeit im Bild","Zoror Babel","Zuschauer"],"articleSection":{"1":"Deutsch"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.nmz.de\/badblog\/2012\/10\/07\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.nmz.de\/badblog\/2012\/10\/07\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\/","url":"https:\/\/blogs.nmz.de\/badblog\/2012\/10\/07\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\/","name":"Mensch oder Maschine und Wahrnehmung \u2013 wer oder was macht die Musik? &#8211; Bad Blog Of Musick - nmz Klassik-Blog","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2012\/10\/07\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\/#primaryimage"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2012\/10\/07\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.nmz.de\/badblog\/files\/2012\/10\/mgnm-verspielte-maschinen-141x300.jpg","datePublished":"2012-10-07T22:50:03+00:00","dateModified":"2018-01-20T18:01:55+00:00","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","breadcrumb":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2012\/10\/07\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.nmz.de\/badblog\/2012\/10\/07\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/2012\/10\/07\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\/#primaryimage","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2012\/10\/mgnm-verspielte-maschinen.jpg?fit=272%2C576&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2012\/10\/mgnm-verspielte-maschinen.jpg?fit=272%2C576&ssl=1","width":"272","height":"576"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.nmz.de\/badblog\/2012\/10\/07\/mensch-oder-maschine-und-wahrnehmung-wer-oder-was-macht-die-musik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blogs.nmz.de\/badblog\/"},{"@type":"ListItem","position":2,"name":"Mensch oder Maschine und Wahrnehmung \u2013 wer oder was macht die Musik?"}]},{"@type":"WebSite","@id":"https:\/\/blogs.nmz.de\/badblog\/#website","url":"https:\/\/blogs.nmz.de\/badblog\/","name":"Bad Blog Of Musick","description":"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur","publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.nmz.de\/badblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blogs.nmz.de\/badblog\/#organization","name":"Bad Blog Of Musick","alternateName":"Ein Klassik-Blog zur Musik","url":"https:\/\/blogs.nmz.de\/badblog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","width":512,"height":512,"caption":"Bad Blog Of Musick"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/musikzeitung","https:\/\/x.com\/musikzeitung"]},{"@type":"Person","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/73d6c9ef0d58ae670a7d6f9affe7259c","name":"Alexander Strauch","description":"Komponist*in","url":"https:\/\/blogs.nmz.de\/badblog\/author\/querstand\/"}]}},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","jetpack_featured_media_url":"","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/7170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/comments?post=7170"}],"version-history":[{"count":19,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/7170\/revisions"}],"predecessor-version":[{"id":8253,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/7170\/revisions\/8253"}],"wp:attachment":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/media?parent=7170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/categories?post=7170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/tags?post=7170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}