{"id":6778,"date":"2012-07-16T15:15:54","date_gmt":"2012-07-16T14:15:54","guid":{"rendered":"http:\/\/blogs.nmz.de\/badblog\/?p=6778"},"modified":"2012-07-16T15:15:54","modified_gmt":"2012-07-16T14:15:54","slug":"iamus-komponiert-und-ein-dramolett-von-stefan-hetzel","status":"publish","type":"post","link":"https:\/\/blogs.nmz.de\/badblog\/2012\/07\/16\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\/","title":{"rendered":"Iamus komponiert. Und ein Dramolett von Stefan Hetzel."},"content":{"rendered":"<blockquote><p>Es ist eigentlich schon ein Weilchen soweit &#8211; die Computer komponieren ja schon seit einiger Zeit mit, nicht nur erst seit MaxMSP. Doch nun komponieren sie anscheinend so gut, dass Menschen sie nicht mehr als Computerkomponisten erkennen k&#246;nnen, berichtet zumindest <a href=\"http:\/\/www.freitag.de\/autoren\/michael-jaeger\/iamus-scheitert-am-turing-test\">dieser Artikel<\/a>:<\/p>\n<p><a href=\"http:\/\/stefanhetzel.de\/\">Stefan Hetzel<\/a> hat sich davon zu einem Gastartikel anregen lassen. Hier ist er:<\/p><\/blockquote>\n<p>Vor kurzem las ich mit gro&#223;em Interesse, aber ohne rechte Begeisterung in dem B&#228;ndchen &#8222;<a title=\"Wolke Verlag\" href=\"http:\/\/www.wolke-verlag.de\/musik-asthetik-digitalisierung.html\" target=\"_blank\">Musik, &#196;sthetik, Digitalisierung<\/a>&#8220; aus dem Jahr 2010, welches im Wesentlichen eine Debatte zwischen den Komponisten <a title=\"Wikipedia\" href=\"http:\/\/de.wikipedia.org\/wiki\/Claus-Steffen_Mahnkopf\" target=\"_blank\">Claus-Steffen Mahnkopf<\/a> und <a title=\"Wikipedia\" href=\"http:\/\/de.wikipedia.org\/wiki\/Johannes_Kreidler_%28Musiker%29\" target=\"_blank\">Johannes Kreidler<\/a> abbildet. Einige Argumentationen beider Seiten kamen mir merkw&#252;rdig bekannt vor. Schlie&#223;lich kam ich darauf, warum: In mancherlei Hinsicht wiederholt sich hier die Kontroverse zwischen dem &#8222;Humanisten&#8220; und dem &#8222;Technokraten&#8220; &#252;ber das Thema &#8222;K&#252;nstliche Intelligenz und musikalische Komposition&#8220;, die ich in meinem Dramolett &#8222;<a title=\"Homepage S.H.\" href=\"http:\/\/stefanhetzel.de\/interold.html\">Interaktivit&#228;t<\/a>&#8220; bereits 1998 in eine, &#228;h, popul&#228;re, wenn auch nicht populistische Form zu fassen versuchte.<\/p>\n<p>Die Kontrahenten meines damaligen Textes hie&#223;en freilich <a title=\"Wikipedia\" href=\"http:\/\/de.wikipedia.org\/wiki\/Konrad_Boehmer\" target=\"_blank\">Konrad Boehmer<\/a> und <a title=\"Wikipedia\" href=\"http:\/\/de.wikipedia.org\/wiki\/Clarence_Barlow\" target=\"_blank\">Clarence Barlow<\/a>, denen ich die Soziologen J&#252;rgen Habermas und Niklas Luhmann als Sekundanten zur Seite stellte. &#8222;Interaktivit&#228;t&#8220; stellte nichts anderes als eine leicht dramatisierte Collage aus <a title=\"Quelltexte\" href=\"http:\/\/stefanhetzel.de\/interakt.html#Quelltexte\">Originaltexten<\/a> dieser Autoren da.<\/p>\n<p>Ich nahm mir das Dramolett noch einmal vor und aktualisierte es ma&#223;voll als &#8222;<a title=\"Homepage S.H.\" href=\"http:\/\/stefanhetzel.de\/interakt.html\">Interaktivit&#228;t 2.0<\/a>&#8222;. Einige wenige Schl&#252;sselbegriffe aus der Mahnkopf \/ Kreidler-Debatte, die in der Urfassung nicht vorkommen (wie etwa &#8222;das Nicht-Identische&#8220;) wurden eingef&#252;gt. Im Wesentlichen blieben die Argumentationsg&#228;nge jedoch unver&#228;ndert.<\/p>\n<p>Da mir der Text zu lang f&#252;r einen Blog-Artikel erscheint, habe ich ihn in voller L&#228;nge nur auf meiner Homepage publiziert. Im Anschluss jedoch ein kleiner Ausschnitt, der ja evtl. zum Weiterlesen animiert. &#8222;Interaktivit&#228;t 2.0&#8220; in voller L&#228;nge gibt&#8217;s <a title=\"Homepage S.H.\" href=\"http:\/\/stefanhetzel.de\/interakt.html\">hier<\/a>.<br \/>\n<strong>Interaktivit&#228;t 2.0<\/strong><br \/>\n<em>K&#252;nstliche Intelligenz und musikalische Komposition<\/em><br \/>\n<em>Dramolett in vier Szenen<\/em><em>Personen:<br \/>\nH Der Humanist<br \/>\nT Der Technokrat<br \/>\nK Der Kompositionssch&#252;ler<\/em><\/p>\n<p>SZENE 2<\/p>\n<p><em>Mensa der Musikhochschule. Orangefarbenes Plastikgest&#252;hl. Wei&#223;e Resopaltische mit angeschlagenen Ecken. Ein paar Stunden sp&#228;ter.<\/em><\/p>\n<p>K Also ich finde Komponieren am Computer einfach <strong>spannend<\/strong>! Man wei&#223; vorher nie so richtig, was dabei herauskommt. Au&#223;erdem geben einem die vielen Optionen einfach ein gutes Gef&#252;hl. Du stehst dr&#252;ber, du beobachtest, wie das eigenst&#228;ndig l&#228;uft, was du selber programmiert hast, du f&#252;hlst dich wie &#8230; wie &#8230;<\/p>\n<p>H <em>bitter l&#228;chelnd<\/em> &#8230; Gott?<\/p>\n<p>T <em>intervenierend<\/em> &#8230; ja klar, jetzt unterstellen Sie uns nat&#252;rlich gleich mal wieder die &#252;blichen <em>macht Anf&#252;hrungszeichen mit den Fingern<\/em> &#8222;technokratischen Allmachtsfantasien&#8220;! Sehen Sie nicht, dass das ein Totschlagsargument ist, das ich genausogut auf Ihre rousseauistische Gutmenschenp&#228;dagogik anwenden k&#246;nnte? &#8211; Abgesehen davon d&#252;rfen Sie sowieso nicht alles, was mein Sch&#252;ler hier sagt, auf die Goldwaage legen. Er ist zweifellos hochbegabt, aber seine Entwicklung <em>blickt K pr&#252;fend an, dieser blickt besch&#228;mt zu Boden<\/em> ist eben &#8230;<\/p>\n<p>H <em>sarkastisch<\/em> &#8230; noch nicht abgeschlossen, mag sein. Aber unter Ihrer Obhut, da bin ich mir ganz sicher, wird er reifen! <em>zornig, lauter werdend<\/em> Allerdings nicht zum K&#252;nstler, sondern zum &#8230; zum &#8230; Programmiersklaven mit Tunnelblick, zum &#8230; zum Freak!<\/p>\n<p>T <em>ver&#228;rgert<\/em> Ich bitte um ergebenst um Argumente!<\/p>\n<p>H <em>auftrumpfend<\/em> Kybernetische Kunst, wie Sie sie praktizieren und lehren, verk&#246;rpert doch letztlich genau das, was sich der fantasielose Kleinb&#252;rger schon immer unter Moderner Kunst vorgestellt hat: Da bastelt sich halt einer seine Welt &#8211; wie eine Modelleisenbahn! Da hat einer eine Idee, und die wird dann umgesetzt, um jeden Preis, mit dem denkbar gr&#246;&#223;ten technischen Aufwand. Ich nenne das schlicht Materialisierung beschr&#228;nkten Bewusstseins! Und, wissen Sie was, im Grunde ist Ihnen doch klar, dass Sie sich damit Ihr eigenes Grab schaufeln, dass Sie damit an Ihrer Selbstabschaffung als Komponist arbeiten! Ich verstehe einfach nicht, wieso Sie st&#228;ndig so tun, als h&#228;tten Sie dabei auch noch <strong>Spa&#223;<\/strong>! <em>angeekelt<\/em> Das hat etwas geradezu Perverses, etwas von Selbsthass!<\/p>\n<p>K <em>aufbegehren<\/em>d &#196;h, wenn ich &#8230;<\/p>\n<p>T <em>f&#228;hrt K &#252;ber den Mund<\/em> Ist schon gut, aber jetzt lassen Sie <strong>mich<\/strong> mal antworten! <em>H zugewandt, mit gro&#223;er Sanftheit, als spr&#228;che er mit einem Kind<\/em> Ihre eloquente Habermas-Paraphrase in allen Ehren, aber sie k&#228;mpfen hier als Don Quijote gegen Windm&#252;hlen &#8230;<\/p>\n<p>H <em>sarkastisch<\/em> &#8230; <strong>digitale<\/strong> Windm&#252;hlen sozusagen &#8230;<\/p>\n<p>T <em>holt tief Luft<\/em> Lassen Sie mich einfach mal erkl&#228;ren, warum!<\/p>\n<p>H <em>lehnt sich zur&#252;ck. Der Plastikstuhl gibt ein lautes Knarzen von sich.<\/em> Nur zu, ich bin gespannt.<\/p>\n<p>T <em>mit weit ausholender Geb&#228;rde<\/em> Dazu muss ich ein wenig allgemeiner werden und das Terrain der Neuen Musik verlassen. Also &#8211; warum sind Algorithmen, also Rechenvorschriften, in allen <strong>wichtigen<\/strong> gesellschaftlichen Bereichen heutzutage auf dem Vormarsch? Was ist der Grund ihres beispiellosen Erfolgs?<\/p>\n<p>H <em>l&#228;ssig<\/em> Ihre &#8230; Banalit&#228;t?<\/p>\n<p>T <em>sehr ruhig<\/em> Falsch. Die Ursache liegt in der zunehmenden Abl&#246;sung von Interaktion durch Gesellschaft.<\/p>\n<p>H <em>verst&#228;ndnislos<\/em> Ich verstehe nur Bahnhof. Geht&#8217;s auch ein bisschen weniger kryptisch?<\/p>\n<p>T <em>dozierend<\/em> Interaktion, also der herk&#246;mmliche soziale Austausch menschlicher Individuen, spielt doch ganz klar eine immer geringere Rolle bei der L&#246;sung wirklich wichtiger gesellschaftlicher Probleme, oder?<\/p>\n<p>H <em>pl&#246;tzlich gelangweilt, mit deutlich ironischem Unterton<\/em> &#8230; ach so, Sie sprechen vom guten alten Tod des Subjekts! Sehr originell.<\/p>\n<p>T <em>unbeirrt<\/em> In gewisser Weise ja. Allerdings nicht im Sinne des Poststrukturalismus&#8216;!<\/p>\n<p>H <em>sarkastisch abwinkend<\/em> &#8230; nat&#252;rlich nicht &#8230;<\/p>\n<p>T <em>ver&#228;rgert<\/em> Ich bitte Sie doch, mich nicht durch ihre st&#228;ndigen Nebenbemerkungen zu unterbrechen &#8230; wo war ich? Ach ja, sehen Sie, es ist doch so: N&#252;chtern betrachtet, ist es f&#252;r die Evolution einer Gesellschaft doch einfach belanglos, ob die allermeisten dieser menschlichen Interaktionen nun aufh&#246;ren oder weitergehen oder was auch immer, oder?<\/p>\n<p>H <em>fassungslos<\/em> Das ist &#8230; zynisch!<\/p>\n<p>T <em>siegesgewiss<\/em> Das ist nicht zynisch, das ist Luhmann!<\/p>\n<p>H <em>l&#228;sst Luft ab<\/em> Luhmann. Nat&#252;rlich.<\/p>\n<p>T <em>ver&#228;rgert<\/em> Sie halten nichts von Luhmann, das war mir schon klar!<\/p>\n<p>H <em>k&#252;hl<\/em> Ach, mein Gott, &#8230; ein vereinsamter Witwer &#8230; im Reihenhaus &#8230; in Bielefeld &#8230;<\/p>\n<p>T <em>emp&#246;rt<\/em> Na, auf dieses Niveau wollen wir uns doch jetzt bittesch&#246;n nicht begeben! Ich reduziere ja Habermas auch nicht auf seine physiognomischen Besonderheiten!<\/p>\n<p>H <em>einlenkend<\/em> Ok, ja gut, dann lassen wir das, bitte fahren Sie fort!<\/p>\n<p>T <em>wieder Tritt fassend<\/em> Versucht man sich einmal die Gesamtheit aller menschlichen Interaktionen heutzutage vorzustellen, wird einem schnell klar: Hier herrscht eine Art anarchisches Grundrauschen, das lediglich Spielmaterial f&#252;r die Evolution der Gesellschaft liefert.<\/p>\n<p>H <em>ratlos<\/em> Das mag ja alles sein, aber was hat das mit Neuer Musik zu tun &#8211; jetzt kommen Sie doch bittesch&#246;n mal zur Sache zur&#252;ck!<\/p>\n<p>T <em>unbeirrt<\/em> Was ich sagen will, ist: je st&#228;rker sich eine Gesellschaft ausdifferenziert, &#8230;<\/p>\n<p>H <em>verdreht die Augen<\/em> &#8230; dieses Luhmann-Sprech &#8230; <em>angeekelt<\/em> &#8230; <strong>scheu&#223;lich<\/strong>!<\/p>\n<p>T &#8230; desto h&#228;ufiger erscheint uns diese Masse an menschlichen Interaktionen als trivial, weil einfach nicht mehr an relevante gesellschaftliche Bereiche anschlie&#223;bar, &#8230;<\/p>\n<p>H <em>genervt<\/em> Wenn Luhmann doch nur irgendwo mal <strong>definiert<\/strong> h&#228;tte, was er eigentlich unter &#8222;Anschlussf&#228;higkeit&#8220; versteht! So wabert das so undefiniert &#252;berall herum und jeder versteht darunter, was er will!<\/p>\n<p>T &#8230; also spielt es letztlich <strong>gesellschaftlich<\/strong> keine Rolle, ob diese trivialen menschlichen Interaktionen nun weitergehen oder aufh&#246;ren! Sie sind einfach irrelevant!<\/p>\n<p>K <em>bewundernd<\/em> Klingt toll! Aber was bedeutet es? <em>gr&#252;belt eine Weile<\/em> Je komplexer eine Gesellschaft, desto unwichtiger wird die menschliche Interaktion f&#252;r ihren Fortschritt &#8230;<\/p>\n<p>T <em>saugt an seiner Zigarre<\/em> Exakt.<\/p>\n<p>K <em>eifriger werdend<\/em> &#8230; stattdessen werden mehr und mehr Algorithmen entwickelt, die die Chaotik der Interaktion durch quantifizierbare Verfahren ersetzen!<\/p>\n<p>H <em>mit lauter Stimme, gestenreich protestierend<\/em> Aber das ist doch einfach <strong>Technik-Faschismus<\/strong>! Anbetung der Maschine! Und es zeugt von tiefster Menschenverachtung!<\/p>\n<p>T <em>beschwichtigend<\/em> Beruhigen Sie sich. <em>wieder wie zu einem Kind<\/em> Sie stimmen mir doch darin zu, dass sich relevante gesellschaftliche Probleme heutzutage nicht mehr auf Einzelne oder deren Interaktionen zur&#252;ckf&#252;hren lassen, oder?<\/p>\n<p>H <em>immer noch aufgebracht<\/em> Da stimme ich Ihnen <strong>keineswegs<\/strong> zu! Vielmehr bin ich der Meinung, achwas: ich bin der tiefsten &#220;berzeugung, dass eine Gesellschaft <strong>nur<\/strong> durch intensivste Interaktion ihrer Mitglieder <strong>&#252;berhaupt<\/strong> irgendwelche Probleme bew&#228;ltigen kann, seien es nun <em>im Tonfall der Verachtung<\/em> &#8222;relevante&#8220; oder &#8222;irrelevante&#8220;, wer immer diese Unterscheidung treffen darf.<\/p>\n<p>K <em>studentisch frech<\/em> Helmut Kohl sagt auch immer: &#8222;Wir m&#252;ssen die anstehenden Probleme <strong>gemeinsam<\/strong> anbaggen.&#8220; [Anmerkung des Autors: Die Szene spielt im Jahr 1990.]<\/p>\n<p>H <em>indigniert<\/em> Ach seien sie doch einfach mal still, Sie, Sie &#8230; Maschinenbediener!<\/p>\n<p>T <em>entspannter werdend<\/em> Wieso, unser junger Mann hat doch recht! Der permanent wiederkehrende Appell unseres Bundeskanzlers an das &#8222;gesellschaftliche Wir&#8220; ist doch nicht mal mehr als Realsatire unterhaltsam. &#220;berlegen Sie doch mal: Wo ist menschliche Interaktion wichtiger als gesellschaftliche Regeln?<\/p>\n<p>H <em>ersch&#246;pft<\/em> Die Frage ist doch &#8230;<\/p>\n<p>T &#8230; nur in ausgesprochen <strong>primitiven<\/strong> Verh&#228;ltnissen! Soziale Formen werden in diesem Fall nur dann gefunden, wenn sie gerade gebraucht werden, bleiben an bestimme Orte gebunden und m&#252;ssen immer pr&#228;sent sein, um wirken zu k&#246;nnen.<\/p>\n<p>H <em>erstaunt<\/em> Improvisierte Musik w&#228;re demnach primitiv &#8230;<\/p>\n<p>T <em>unbeirrt<\/em> &#8230; und au&#223;erdem entstehen die Regeln der Interaktion sowieso erst durch die Selbstbez&#252;glichkeit der umgebenden Gesellschaft! Es gibt also gar keine freie Interaktion freier Individuen irgendwo in einem Au&#223;erhalb der Gesellschaft, ganz einfach, weil es au&#223;erhalb der Gesellschaft nichts gibt!<\/p>\n<p>H <em>verwirrt<\/em> Ich war immer daf&#252;r, Musik und Gesellschaft zusammenzudenken &#8211; ich sage nur Adorno &#8211; aber was sie da pr&#228;sentieren &#8230;<\/p>\n<p>T <em>auftrumpfend<\/em> &#8230; ist, mit Verlaub, ebenfalls Musiksoziologie &#8230;<\/p>\n<p>K <em>kichernd<\/em> &#8230; die allerdings zu, &#228;h, anderen Ergebnissen als Adorno kommt!<\/p>\n<p>H <em>in pl&#246;tzlicher Theatralik<\/em> <strong>Aber wo bleibt das Subjekt? Wo bleibt die Vermittlung von Sinnlichkeit durch &#228;sthetische Konstrukte? Wo bleibt: &#8211; das Leben?<\/strong><\/p>\n<div id=\"attachment_6780\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2012\/07\/bad-blog.jpeg?ssl=1\" class=\"thickbox no_icon\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-6780\" data-attachment-id=\"6780\" data-permalink=\"https:\/\/blogs.nmz.de\/badblog\/2012\/07\/16\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\/bad-blog\/\" data-orig-file=\"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2012\/07\/bad-blog.jpeg?fit=445%2C282&amp;ssl=1\" data-orig-size=\"445,282\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"bad blog\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Iamus. Besser als Boulez?&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2012\/07\/bad-blog.jpeg?fit=445%2C282&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2012\/07\/bad-blog-300x190.jpg?resize=300%2C190&#038;ssl=1\" alt=\"\" width=\"300\" height=\"190\" class=\"size-medium wp-image-6780\" srcset=\"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2012\/07\/bad-blog.jpeg?resize=300%2C190&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2012\/07\/bad-blog.jpeg?resize=150%2C95&amp;ssl=1 150w, https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2012\/07\/bad-blog.jpeg?resize=400%2C253&amp;ssl=1 400w, https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2012\/07\/bad-blog.jpeg?w=445&amp;ssl=1 445w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-6780\" class=\"wp-caption-text\">Iamus. Besser als Boulez?<\/p><\/div>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Iamus%20komponiert.%20Und%20ein%20Dramolett%20von%20Stefan%20Hetzel. https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2012%2F07%2F16%2Fiamus-komponiert-und-ein-dramolett-von-stefan-hetzel%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Iamus%20komponiert.%20Und%20ein%20Dramolett%20von%20Stefan%20Hetzel. https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2012%2F07%2F16%2Fiamus-komponiert-und-ein-dramolett-von-stefan-hetzel%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2012%2F07%2F16%2Fiamus-komponiert-und-ein-dramolett-von-stefan-hetzel%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Iamus%20komponiert.%20Und%20ein%20Dramolett%20von%20Stefan%20Hetzel.%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2012%2F07%2F16%2Fiamus-komponiert-und-ein-dramolett-von-stefan-hetzel%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2012%2F07%2F16%2Fiamus-komponiert-und-ein-dramolett-von-stefan-hetzel%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Es ist eigentlich schon ein Weilchen soweit &#8211; die Computer komponieren ja schon seit einiger Zeit mit, nicht nur erst seit MaxMSP. Doch nun komponieren sie anscheinend so gut, dass Menschen sie nicht mehr als Computerkomponisten erkennen k&#246;nnen, berichtet zumindest&#8230;<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Iamus%20komponiert.%20Und%20ein%20Dramolett%20von%20Stefan%20Hetzel. https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2012%2F07%2F16%2Fiamus-komponiert-und-ein-dramolett-von-stefan-hetzel%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Iamus%20komponiert.%20Und%20ein%20Dramolett%20von%20Stefan%20Hetzel. https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2012%2F07%2F16%2Fiamus-komponiert-und-ein-dramolett-von-stefan-hetzel%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2012%2F07%2F16%2Fiamus-komponiert-und-ein-dramolett-von-stefan-hetzel%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Iamus%20komponiert.%20Und%20ein%20Dramolett%20von%20Stefan%20Hetzel.%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2012%2F07%2F16%2Fiamus-komponiert-und-ein-dramolett-von-stefan-hetzel%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2012%2F07%2F16%2Fiamus-komponiert-und-ein-dramolett-von-stefan-hetzel%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[14657],"tags":[8995,1080,8991,658,8994,8989,893,8992,8990,59,8993,7110],"class_list":["post-6778","post","type-post","status-publish","format-standard","hentry","category-nicht-kategorisiert","tag-algorithmus","tag-bielefeld","tag-clarence-barlow","tag-claus-steffen-mahnkopf","tag-freak","tag-iamus","tag-johannes-kreidler","tag-jurgen-habermas","tag-konrad-boehmer","tag-neue-musik","tag-niklas-luhmann","tag-stefan-hetzel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Iamus komponiert. Und ein Dramolett von Stefan Hetzel. &#8211; Bad Blog Of Musick - nmz Klassik-Blog<\/title>\n<meta name=\"description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.nmz.de\/badblog\/2012\/07\/16\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Iamus komponiert. Und ein Dramolett von Stefan Hetzel. &#8211; Bad Blog Of Musick - nmz Klassik-Blog\" \/>\n<meta property=\"og:description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.nmz.de\/badblog\/2012\/07\/16\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\/\" \/>\n<meta property=\"og:site_name\" content=\"Bad Blog Of Musick\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/musikzeitung\" \/>\n<meta property=\"article:author\" content=\"moritz.eggert.79\" \/>\n<meta property=\"article:published_time\" content=\"2012-07-16T14:15:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.nmz.de\/badblog\/files\/2012\/07\/bad-blog-300x190.jpg\" \/>\n<meta name=\"author\" content=\"Moritz Eggert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MoritzEggert\" \/>\n<meta name=\"twitter:site\" content=\"@musikzeitung\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Moritz Eggert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2012\\\/07\\\/16\\\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2012\\\/07\\\/16\\\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\\\/\"},\"author\":{\"name\":\"Moritz Eggert\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/ce88a756dea34f64ceab78df990e3dd4\"},\"headline\":\"Iamus komponiert. Und ein Dramolett von Stefan Hetzel.\",\"datePublished\":\"2012-07-16T14:15:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2012\\\/07\\\/16\\\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\\\/\"},\"wordCount\":1590,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2012\\\/07\\\/16\\\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2012\\\/07\\\/bad-blog-300x190.jpg\",\"keywords\":[\"Algorithmus\",\"Bielefeld\",\"Clarence Barlow\",\"Claus-Steffen Mahnkopf\",\"Freak\",\"iamus\",\"Johannes Kreidler\",\"J\u00fcrgen Habermas\",\"Konrad Boehmer\",\"Neue Musik\",\"Niklas Luhmann\",\"Stefan Hetzel\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2012\\\/07\\\/16\\\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2012\\\/07\\\/16\\\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\\\/\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2012\\\/07\\\/16\\\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\\\/\",\"name\":\"Iamus komponiert. Und ein Dramolett von Stefan Hetzel. &#8211; Bad Blog Of Musick - nmz Klassik-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2012\\\/07\\\/16\\\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2012\\\/07\\\/16\\\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2012\\\/07\\\/bad-blog-300x190.jpg\",\"datePublished\":\"2012-07-16T14:15:54+00:00\",\"description\":\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2012\\\/07\\\/16\\\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2012\\\/07\\\/16\\\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2012\\\/07\\\/16\\\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2012\\\/07\\\/bad-blog-300x190.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2012\\\/07\\\/bad-blog-300x190.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2012\\\/07\\\/16\\\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Iamus komponiert. Und ein Dramolett von Stefan Hetzel.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"name\":\"Bad Blog Of Musick\",\"description\":\"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\",\"name\":\"Bad Blog Of Musick\",\"alternateName\":\"Ein Klassik-Blog zur Musik\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"width\":512,\"height\":512,\"caption\":\"Bad Blog Of Musick\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/musikzeitung\",\"https:\\\/\\\/x.com\\\/musikzeitung\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/ce88a756dea34f64ceab78df990e3dd4\",\"name\":\"Moritz Eggert\",\"description\":\"Komponist\",\"sameAs\":[\"http:\\\/\\\/www.moritz-eggert.de\",\"moritz.eggert.79\",\"https:\\\/\\\/x.com\\\/MoritzEggert\"],\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/author\\\/moritzeggert\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Iamus komponiert. Und ein Dramolett von Stefan Hetzel. &#8211; Bad Blog Of Musick - nmz Klassik-Blog","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.nmz.de\/badblog\/2012\/07\/16\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\/","og_locale":"de_DE","og_type":"article","og_title":"Iamus komponiert. Und ein Dramolett von Stefan Hetzel. &#8211; Bad Blog Of Musick - nmz Klassik-Blog","og_description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","og_url":"https:\/\/blogs.nmz.de\/badblog\/2012\/07\/16\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\/","og_site_name":"Bad Blog Of Musick","article_publisher":"https:\/\/www.facebook.com\/musikzeitung","article_author":"moritz.eggert.79","article_published_time":"2012-07-16T14:15:54+00:00","og_image":[{"url":"https:\/\/blogs.nmz.de\/badblog\/files\/2012\/07\/bad-blog-300x190.jpg","type":"","width":"","height":""}],"author":"Moritz Eggert","twitter_card":"summary_large_image","twitter_creator":"@MoritzEggert","twitter_site":"@musikzeitung","twitter_misc":{"Verfasst von":"Moritz Eggert","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.nmz.de\/badblog\/2012\/07\/16\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\/#article","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2012\/07\/16\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\/"},"author":{"name":"Moritz Eggert","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/ce88a756dea34f64ceab78df990e3dd4"},"headline":"Iamus komponiert. Und ein Dramolett von Stefan Hetzel.","datePublished":"2012-07-16T14:15:54+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2012\/07\/16\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\/"},"wordCount":1590,"commentCount":1,"publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2012\/07\/16\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.nmz.de\/badblog\/files\/2012\/07\/bad-blog-300x190.jpg","keywords":["Algorithmus","Bielefeld","Clarence Barlow","Claus-Steffen Mahnkopf","Freak","iamus","Johannes Kreidler","J\u00fcrgen Habermas","Konrad Boehmer","Neue Musik","Niklas Luhmann","Stefan Hetzel"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.nmz.de\/badblog\/2012\/07\/16\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.nmz.de\/badblog\/2012\/07\/16\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\/","url":"https:\/\/blogs.nmz.de\/badblog\/2012\/07\/16\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\/","name":"Iamus komponiert. Und ein Dramolett von Stefan Hetzel. &#8211; Bad Blog Of Musick - nmz Klassik-Blog","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2012\/07\/16\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\/#primaryimage"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2012\/07\/16\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.nmz.de\/badblog\/files\/2012\/07\/bad-blog-300x190.jpg","datePublished":"2012-07-16T14:15:54+00:00","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","breadcrumb":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2012\/07\/16\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.nmz.de\/badblog\/2012\/07\/16\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/2012\/07\/16\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\/#primaryimage","url":"https:\/\/blogs.nmz.de\/badblog\/files\/2012\/07\/bad-blog-300x190.jpg","contentUrl":"https:\/\/blogs.nmz.de\/badblog\/files\/2012\/07\/bad-blog-300x190.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.nmz.de\/badblog\/2012\/07\/16\/iamus-komponiert-und-ein-dramolett-von-stefan-hetzel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blogs.nmz.de\/badblog\/"},{"@type":"ListItem","position":2,"name":"Iamus komponiert. Und ein Dramolett von Stefan Hetzel."}]},{"@type":"WebSite","@id":"https:\/\/blogs.nmz.de\/badblog\/#website","url":"https:\/\/blogs.nmz.de\/badblog\/","name":"Bad Blog Of Musick","description":"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur","publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.nmz.de\/badblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blogs.nmz.de\/badblog\/#organization","name":"Bad Blog Of Musick","alternateName":"Ein Klassik-Blog zur Musik","url":"https:\/\/blogs.nmz.de\/badblog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","width":512,"height":512,"caption":"Bad Blog Of Musick"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/musikzeitung","https:\/\/x.com\/musikzeitung"]},{"@type":"Person","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/ce88a756dea34f64ceab78df990e3dd4","name":"Moritz Eggert","description":"Komponist","sameAs":["http:\/\/www.moritz-eggert.de","moritz.eggert.79","https:\/\/x.com\/MoritzEggert"],"url":"https:\/\/blogs.nmz.de\/badblog\/author\/moritzeggert\/"}]}},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","jetpack_featured_media_url":"","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/6778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/comments?post=6778"}],"version-history":[{"count":2,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/6778\/revisions"}],"predecessor-version":[{"id":6781,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/6778\/revisions\/6781"}],"wp:attachment":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/media?parent=6778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/categories?post=6778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/tags?post=6778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}