{"id":4678,"date":"2011-08-10T11:12:52","date_gmt":"2011-08-10T10:12:52","guid":{"rendered":"http:\/\/blogs.nmz.de\/badblog\/?p=4678"},"modified":"2011-08-10T11:12:52","modified_gmt":"2011-08-10T10:12:52","slug":"neue-musik-wozu","status":"publish","type":"post","link":"https:\/\/blogs.nmz.de\/badblog\/2011\/08\/10\/neue-musik-wozu\/","title":{"rendered":"Neue Musik &#8211; wozu?"},"content":{"rendered":"<p>Diese Ausschreibung macht gerade die Runde:<\/p>\n<blockquote><p>Sehr geehrte Damen und Herren,<br \/>\n\u00bbNeue Musik wozu? \u2013 Interventionen bei den Donaueschinger Musiktagen 2011\u00ab<br \/>\nUnter diesem Titel flankiert die 1922 gegr&#252;ndete Gesellschaft f&#252;r Neue Musik das Festival mit flammenden Pl&#228;doyers, Statements, Mini-Manifesten f&#252;r das aktuelle Musikschaffen und f&#252;r eine lebendige Neue-Musik-Szene. Gedacht ist daran, Sinn und Zweck der Neuen Musik stichhaltig zu untermauern &#8211; und damit f&#252;r die unverbr&#252;chliche Notwendigkeit ihres Weiterbestehens einzutreten. Es soll hierbei nicht um Kompositionsweisen und Stile, Gebr&#228;uche und Rezeptionstopoi der Neuen Musik gehen.<br \/>\nWir laden Sie herzlich ein, sich mit einem 2- bis 4-min&#252;tigen Vortrag an diesem Vorhaben zu beteiligen. (Bei normaler Formatierung und einer 12-Punkt-Type dauert eine getippte Textseite im Vortrag etwa 2 \u00bd-Minuten.)<br \/>\nRedezeit wird gegeben am Samstag und Sonntag jeweils zwischen 14.00 und 15.00 Uhr. Als Redeorte stehen in der Karlstra&#223;e in Donaueschingen f&#252;nf Spots zur Verf&#252;gung: zum Beispiel vor dem Caf\u00e9 Hengstler, gegen&#252;ber vom Kulturamt, vor der Linde, vor dem Rathaus \u2026<br \/>\n&#220;ber Ihre Mitwirkung w&#252;rden wir uns freuen! Wenn Sie verbindlich teilnehmen m&#246;chten, bitten wir um R&#252;ckmeldung bis zum 10. September, damit wir die Reihenfolge der Redner\/innen und die Verteilung auf die Orte organisieren k&#246;nnen.<br \/>\nBitte teilen Sie uns auch mit, ob Ihnen Samstag oder Sonntag lieber w&#228;re oder ob Sie an beiden Tagen k&#246;nnen.<br \/>\nHerzliche Gr&#252;&#223;e<br \/>\nJens Cording, Julia Cloot, Stefan Fricke<\/p><\/blockquote>\n<p>Lieber Jens, liebe Julia, Lieber Stefan,<br \/>\nIch habe mir &#252;ber euer Anliegen Gedanken gemacht. Daher widme ich euch dieses kleine Theaterst&#252;ck, dass ihr &#8211; wenn ihr wollt &#8211; in Donaueschingen auff&#252;hren lassen k&#246;nnt, zu obigem Anlass. <\/p>\n<p>Das ist der Text:<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2011\/08\/SpeakersCorner.jpg?ssl=1\" class=\"thickbox no_icon\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2011\/08\/SpeakersCorner-300x240.jpg?resize=300%2C240&#038;ssl=1\" alt=\"SpeakersCorner\" title=\"SpeakersCorner\" width=\"300\" height=\"240\" class=\"aligncenter size-medium wp-image-4679\" \/><\/a><\/p>\n<p><strong>Gek&#252;rztes Manifest der Pr&#228;senz<\/strong><\/p>\n<p>Zu lesen in Donaueschingen 2011 vor dem Caf\u00e9 Hengstler, um 14 Uhr<\/p>\n<p><em>(Ein Redner tritt auf, holt umst&#228;ndlich zwei beschriebene Seiten hervor, entfaltet sie. Eine kleine Menge Neugieriger versammelt sich)<\/em><\/p>\n<p>Redner: Meine Damen und Herren, ich bitte um ihre Aufmerksamkeit.<br \/>\nWir wissen nichts, und das ist gut so. Es gibt nichts Fruchtbareres als die Situation der Verwirrung, in der wir uns gerade befinden. Wenn man nicht wei&#223;, wo man sich befindet, probiert man viele Wege aus, wenn man genau wei&#223;, wo man sich befindet, verl&#228;sst man den vorgesehenen Pfad nicht.<br \/>\nIch w&#252;nsche mir eine pr&#228;sentere Musik. Eine Musik, die nicht etwas darstellen muss, die sich nicht profilieren muss, die sich nicht entschuldigen muss. Eine Musik, die frei ist, weil sie zuallererst einmal nur Musik ist. Eine Musik, die wirklich frei ist, kann uns von dieser Freiheit erz&#228;hlen. Das Paradoxe ist, dass es dazu eine Sprache braucht, die wir zumindest ann&#228;hernd verstehen k&#246;nnen, daher muss diese Musik den Willen haben, zu uns zu sprechen. Und dazu geh&#246;rt wiederum eine gewisse Disziplin, die die Selbstgef&#228;lligkeit, also zum Beispiel das Sprechen nur um des Sprechens willen, ausschlie&#223;t. <\/p>\n<p><em>(Zwischenruf: \u201eJawohl\u201c. Gel&#228;chter.)<\/em><\/p>\n<p>Redner: Die Formulierung der Freiheit kann also nicht in v&#246;lliger Freiheit entstehen. Aus diesem Widerspruch der Strenge zu der Vision der Freiheit entsteht pr&#228;sente Musik.  Wir hatten genug Musik, die behauptet, notwendig zu sein, aber wir hatten nur wenig Musik, die wirklich notwendig ist. Die freie Musik, die pr&#228;sente Musik, gibt nicht vor notwendig zu sein, aber wenn Musik wirklich pr&#228;sent ist, ist ihr Vorhandensein ebenso Kritik unserer Lebenssituation, wie es sogenannte \u201esozialkritische\u201c oder \u201epolitische\u201c Musik ist, eben weil die Artikulation der Freiheit etwas zutiefst beunruhigendes ist.<br \/>\nIn der Musik hat alles Platz, wof&#252;r auch in unserem Leben Platz ist: das Raffinierte lockt das Banale hervor, das Opulente verlangt nach dem Kargen, das Ernste kippt um in L&#228;cherliches&#8230;und umgekehrt. Auch nur eines dieser Elemente auszuschlie&#223;en, ist so, als ob man das Leben selbst ausschlie&#223;t. Das Leben will nie ausschlie&#223;lich einen Zustand, sondern ein Gleichgewicht m&#246;glichst vieler Zust&#228;nde, die sich gegenseitig in ihrer Wirkung verst&#228;rken. Nat&#252;rlich gibt es das wirkliche Verst&#228;ndnis des Ernsten &#252;berhaupt erst nur durch das wirkliche Verst&#228;ndnis des Banalen. <\/p>\n<p><em>(Zwischenruf: \u201eH&#228;h&#228;, er hat \u201aanal\u2018 gesagt!\u201c. Nochmal Gel&#228;chter.)<\/em><\/p>\n<p>Redner: Pr&#228;sente Musik will daher ebenso lebendig, abwechslungsreich, farbig, kontrastreich und &#252;berraschend sein wie das Leben.<br \/>\nSich hinter einer kompositorischen Methode oder einem System oder einer Philosophie zu verschanzen hei&#223;t, sich eine Maske aufzusetzen. Die Komponisten die viele Worte gebrauchen, um ihrer Musik ein theoretisches Fundament zu geben, die Angst haben, ihre Musik k&#246;nnte ohne dieses Fundament nicht alleine auf zwei Beinen stehen, sind sie nicht wie Paviane, die sich gegenseitig zeigen, wer den gr&#246;&#223;eren Hintern hat? W&#228;ren sie nicht besser beraten, ihre Musik so anzulegen, dass sie von alleine stehen kann?<br \/>\n<em><br \/>\n(Zwischenruf: \u201eMir steht er auch, h&#246;h&#246;!\u201c. Inzwischen sind einige Zuschauer wieder gegangen. Eine alte Dame stochert im Caf\u00e9 Hengstler in einem K&#228;sekuchen. \u201eWas sagt der dicke Mann da?\u201c fragt sie ihre Nachbarin. \u201eWas ist los in Afrika?\u201c fragt ihre schwerh&#246;rige Nachbarin.)<\/em><\/p>\n<p>Redner: Musik ist in vielem Sprache &#228;hnlich. Die Sprache ver&#228;ndert sich st&#228;ndig, weil die Welt sich st&#228;ndig ver&#228;ndert. Die Sprache wird dabei nie etwas anderes als Sprache sein. Musik ist niemals etwas anderes als Musik. Pr&#228;sente Musik ist wie Sprache: sie ist nicht unverst&#228;ndlich, weil ihr sonst niemand folgen kann \u2013 die pr&#228;sente Musik will ausdr&#252;cklich, da&#223; man ihr folgen kann. Gleichzeitig ist sie auch unverst&#228;ndlich, denn auch Sprache ist niemals vollkommen verst&#228;ndlich, wir suchen best&#228;ndig nach Worten, die etwas ausdr&#252;cken, wof&#252;r es noch keine Worte gibt. Man k&#246;nnte auch sagen: Pr&#228;sente Musik will das Geheimnis, aber nicht das Mysterium, denn das Mysterium zelebriert, anstatt zu reflektieren.<br \/>\nIm Grunde geht es nur um das Jetzt. Was interessiert uns die Nachwelt? Wer sind wir, an diesem bestimmten Punkt in der Zeit wirklich zu wissen, was die Nachwelt an uns noch interessieren wird? Es geht also&#8230; Es geht also vor allem um eine m&#246;glichst genaue Wahrnehmung der Gegenwart. Auch das ist Pr&#228;senz: Pr&#228;sens&#8230;.<br \/>\nNicht zu sp&#252;ren wie die Zeit vergeht, ist einer der gr&#246;&#223;ten Gl&#252;ckszust&#228;nde. <\/p>\n<p><em>(Zwischenruf: \u201eJetzt mach mal zu, Alter!\u201c)<\/em><\/p>\n<p>Man ist am gl&#252;cklichsten, wenn man ganz und gar im Jetzt ist. Langeweile ist, wenn das Verflie&#223;en der Zeit zur einzigen Wahrnehmung wird. Pr&#228;sente Musik ist sich der Gefahr bewusst, dass nichts langweiliger f&#252;r den Zuh&#246;rer ist, als einen Plan, eine Idee, eine Ideologie vor ihm auszubreiten, die mit ihm, mit seiner Wirklichkeit, mit seiner Existenz nichts zu tun hat. Was interessiert es den H&#246;rer, wie komplex etwas ist, wie viel Arbeit es gekostet hat, wie durchdacht es ist? Wir k&#246;nnen aber diese Barriere umgehen, wenn wir den H&#246;rer direkt ansprechen, wenn wir ihn als Partner unserer Musik verstehen. Nur durch den H&#246;renden existiert die Musik. Wir m&#252;ssen mit dem H&#246;rer sprechen.<br \/>\nDas Problem mit der Musik ist, dass sie entweder zu ernst genommen wird, oder aber auch nicht ernst genug\u2026(Rest ist unverst&#228;ndlich)<\/p>\n<p><em>(Das Publikum ist inzwischen so laut geworden, dass der Redner immer schwerer zu verstehen ist.  Ein Motorrad f&#228;hrt laut knatternd vorbei).<\/em><\/p>\n<p>Redner: &#8230;noch einmal auf das Gl&#252;ck zur&#252;ckzukommen: was ist denn gegen Musik einzuwenden, die gl&#252;cklich macht? Wir kennen unterschiedliche Formen des Gl&#252;cks. Jeder kann den grunds&#228;tzlichen Unterschied zwischen einer Bratwurst von der Stra&#223;enbude und einem sorgf&#228;ltig zubereiteten Mahl, an das man sich noch lange erinnert, verstehen. Beides stillt den Hunger, doch niemand von uns will immer Bratwurst essen. <\/p>\n<p><em>(Lautes ungehaltenes Gemurmel, das Publikum wird aggressiv. \u201eIch mag Bratwurst, Arschloch!\u201c)<\/em><\/p>\n<p>Render: \u2026Fehler ist es jedoch, dass die sogenannte ernste Musik sich heute der Befriedigung eines Bed&#252;rfnisses verweigert, das die Pop-Musik nun allein erf&#252;llen muss: der schnelle Wunsch nach ein bisschen Gl&#252;ckseligkeit \u2013 was ist so verwerflich daran? K&#246;nnte es nicht die Aufgabe\u2026(Rest ist unverst&#228;ndlich)<\/p>\n<p><em>(\u201eBuuuh\u201c, \u201eAufh&#246;ren, Knallkopp\u201c, \u201eWas willst Du hier, Du Sau?\u201c)<\/em><\/p>\n<p>Redner: (unverst&#228;ndlich)\u2026.Musik sein\u2026(unverst&#228;ndlich)<br \/>\n<em><br \/>\n(\u201eWichser! Verpiss Dich! Scheiss-Intellektueller!\u201c) <\/em><\/p>\n<p>Redner: (unverst&#228;ndlich)\u2026.aber das ist noch nicht die letzte L&#246;sung, nat&#252;rlich nicht. Pr&#228;sente Musik kann genauso wenig zur Pop-Musik werden, wie Pop-Musik zur pr&#228;senten Musik, denn pr&#228;sente Musik will mehr sein als die Bratwurst von der\u2026.<br \/>\n<em><br \/>\n(Tumultartige Zust&#228;nde. Zwei Skinheads sind aus der Menge hervor getreten und packen den Redner an den Armen) <\/em><\/p>\n<p>Redner: \u2026nicht ignorieren, dass es ein \u2026<\/p>\n<p><em>(Sie ziehen ihn weg, seine F&#252;&#223;e schleifen &#252;ber den Boden, aber der Redner redet weiter)<\/em><\/p>\n<p>Redner: \u2026pr&#228;sente Musik will dieses Dilemma nicht ignorieren, daher muss aber\u2026<br \/>\n<em><br \/>\n(Die zwei Skinheads haben den Redner in eine kleine Gasse gezogen und schlagen auf ihn ein)<\/em><\/p>\n<p>Redner: (zwischendurch wegen der empfangenen Schl&#228;ge aufst&#246;hnend) \u2026.nicht (ugh) so ist also die vornehmlichste Aufgabe der Pr&#228;senz-Bewegung, eine Schule des Komponierens, aber auch des H&#246;rens  (ugh) Pr&#228;senz&#8230;&#8230;&#8230;(ugh)&#8230;&#8230;&#8230;&#8230;&#8230;..mehr&#8230;&#8230;&#8230;&#8230;.(ugh)&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;.Pr&#228;senz!!!!!!!!!!!<\/p>\n<p><em>(Die Menge hat sich aufgel&#246;st. Die Menschen gehen wieder nach Hause. Die beiden Skinheads haben ihre Arbeit verrichtet und lassen den Redner liegen. Nun ist er ganz still.)<\/em><\/p>\n<p>ENDE<\/p>\n<p>Moritz Eggert<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Neue%20Musik%20%E2%80%93%20wozu%3F https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2011%2F08%2F10%2Fneue-musik-wozu%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Neue%20Musik%20%E2%80%93%20wozu%3F https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2011%2F08%2F10%2Fneue-musik-wozu%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2011%2F08%2F10%2Fneue-musik-wozu%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Neue%20Musik%20%E2%80%93%20wozu%3F%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2011%2F08%2F10%2Fneue-musik-wozu%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2011%2F08%2F10%2Fneue-musik-wozu%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Lieber Jens Cording, liebe Julia Cloot, Lieber Stefan Fricke,<br \/>\nIch habe mir &#252;ber euer Anliegen Gedanken gemacht. Daher widme ich euch dieses kleine Theaterst&#252;ck, dass ihr &#8211; wenn ihr wollt &#8211; in Donaueschingen auff&#252;hren lassen k&#246;nnt, zu obigem Anlass. <\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Neue%20Musik%20%E2%80%93%20wozu%3F https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2011%2F08%2F10%2Fneue-musik-wozu%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Neue%20Musik%20%E2%80%93%20wozu%3F https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2011%2F08%2F10%2Fneue-musik-wozu%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2011%2F08%2F10%2Fneue-musik-wozu%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Neue%20Musik%20%E2%80%93%20wozu%3F%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2011%2F08%2F10%2Fneue-musik-wozu%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2011%2F08%2F10%2Fneue-musik-wozu%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[14657],"tags":[3122,3121,527,3118,3117,59,3120,1471,3119],"class_list":["post-4678","post","type-post","status-publish","format-standard","hentry","category-nicht-kategorisiert","tag-athanasio-khyrsh","tag-auf-der-suche-nach-dem-klanng","tag-donaueschingen","tag-jens-cording","tag-julia-cloot","tag-neue-musik","tag-rede","tag-stefan-fricke","tag-vortrag"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neue Musik - wozu? &#8211; Bad Blog Of Musick - nmz Klassik-Blog<\/title>\n<meta name=\"description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.nmz.de\/badblog\/2011\/08\/10\/neue-musik-wozu\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neue Musik - wozu? &#8211; Bad Blog Of Musick - nmz Klassik-Blog\" \/>\n<meta property=\"og:description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.nmz.de\/badblog\/2011\/08\/10\/neue-musik-wozu\/\" \/>\n<meta property=\"og:site_name\" content=\"Bad Blog Of Musick\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/musikzeitung\" \/>\n<meta property=\"article:author\" content=\"moritz.eggert.79\" \/>\n<meta property=\"article:published_time\" content=\"2011-08-10T10:12:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.nmz.de\/badblog\/files\/2011\/08\/SpeakersCorner-300x240.jpg\" \/>\n<meta name=\"author\" content=\"Moritz Eggert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MoritzEggert\" \/>\n<meta name=\"twitter:site\" content=\"@musikzeitung\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Moritz Eggert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2011\\\/08\\\/10\\\/neue-musik-wozu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2011\\\/08\\\/10\\\/neue-musik-wozu\\\/\"},\"author\":{\"name\":\"Moritz Eggert\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/ce88a756dea34f64ceab78df990e3dd4\"},\"headline\":\"Neue Musik &#8211; wozu?\",\"datePublished\":\"2011-08-10T10:12:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2011\\\/08\\\/10\\\/neue-musik-wozu\\\/\"},\"wordCount\":1513,\"commentCount\":9,\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2011\\\/08\\\/10\\\/neue-musik-wozu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2011\\\/08\\\/SpeakersCorner-300x240.jpg\",\"keywords\":[\"Athanasio Khyrsh\",\"Auf der Suche nach dem Klanng\",\"donaueschingen\",\"Jens Cording\",\"Julia Cloot\",\"Neue Musik\",\"Rede\",\"Stefan Fricke\",\"Vortrag\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2011\\\/08\\\/10\\\/neue-musik-wozu\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2011\\\/08\\\/10\\\/neue-musik-wozu\\\/\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2011\\\/08\\\/10\\\/neue-musik-wozu\\\/\",\"name\":\"Neue Musik - wozu? &#8211; Bad Blog Of Musick - nmz Klassik-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2011\\\/08\\\/10\\\/neue-musik-wozu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2011\\\/08\\\/10\\\/neue-musik-wozu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2011\\\/08\\\/SpeakersCorner-300x240.jpg\",\"datePublished\":\"2011-08-10T10:12:52+00:00\",\"description\":\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2011\\\/08\\\/10\\\/neue-musik-wozu\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2011\\\/08\\\/10\\\/neue-musik-wozu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2011\\\/08\\\/10\\\/neue-musik-wozu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2011\\\/08\\\/SpeakersCorner-300x240.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2011\\\/08\\\/SpeakersCorner-300x240.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2011\\\/08\\\/10\\\/neue-musik-wozu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neue Musik &#8211; wozu?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"name\":\"Bad Blog Of Musick\",\"description\":\"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\",\"name\":\"Bad Blog Of Musick\",\"alternateName\":\"Ein Klassik-Blog zur Musik\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"width\":512,\"height\":512,\"caption\":\"Bad Blog Of Musick\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/musikzeitung\",\"https:\\\/\\\/x.com\\\/musikzeitung\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/ce88a756dea34f64ceab78df990e3dd4\",\"name\":\"Moritz Eggert\",\"description\":\"Komponist\",\"sameAs\":[\"http:\\\/\\\/www.moritz-eggert.de\",\"moritz.eggert.79\",\"https:\\\/\\\/x.com\\\/MoritzEggert\"],\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/author\\\/moritzeggert\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neue Musik - wozu? &#8211; Bad Blog Of Musick - nmz Klassik-Blog","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.nmz.de\/badblog\/2011\/08\/10\/neue-musik-wozu\/","og_locale":"de_DE","og_type":"article","og_title":"Neue Musik - wozu? &#8211; Bad Blog Of Musick - nmz Klassik-Blog","og_description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","og_url":"https:\/\/blogs.nmz.de\/badblog\/2011\/08\/10\/neue-musik-wozu\/","og_site_name":"Bad Blog Of Musick","article_publisher":"https:\/\/www.facebook.com\/musikzeitung","article_author":"moritz.eggert.79","article_published_time":"2011-08-10T10:12:52+00:00","og_image":[{"url":"https:\/\/blogs.nmz.de\/badblog\/files\/2011\/08\/SpeakersCorner-300x240.jpg","type":"","width":"","height":""}],"author":"Moritz Eggert","twitter_card":"summary_large_image","twitter_creator":"@MoritzEggert","twitter_site":"@musikzeitung","twitter_misc":{"Verfasst von":"Moritz Eggert","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.nmz.de\/badblog\/2011\/08\/10\/neue-musik-wozu\/#article","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2011\/08\/10\/neue-musik-wozu\/"},"author":{"name":"Moritz Eggert","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/ce88a756dea34f64ceab78df990e3dd4"},"headline":"Neue Musik &#8211; wozu?","datePublished":"2011-08-10T10:12:52+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2011\/08\/10\/neue-musik-wozu\/"},"wordCount":1513,"commentCount":9,"publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2011\/08\/10\/neue-musik-wozu\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.nmz.de\/badblog\/files\/2011\/08\/SpeakersCorner-300x240.jpg","keywords":["Athanasio Khyrsh","Auf der Suche nach dem Klanng","donaueschingen","Jens Cording","Julia Cloot","Neue Musik","Rede","Stefan Fricke","Vortrag"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.nmz.de\/badblog\/2011\/08\/10\/neue-musik-wozu\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.nmz.de\/badblog\/2011\/08\/10\/neue-musik-wozu\/","url":"https:\/\/blogs.nmz.de\/badblog\/2011\/08\/10\/neue-musik-wozu\/","name":"Neue Musik - wozu? &#8211; Bad Blog Of Musick - nmz Klassik-Blog","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2011\/08\/10\/neue-musik-wozu\/#primaryimage"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2011\/08\/10\/neue-musik-wozu\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.nmz.de\/badblog\/files\/2011\/08\/SpeakersCorner-300x240.jpg","datePublished":"2011-08-10T10:12:52+00:00","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","breadcrumb":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2011\/08\/10\/neue-musik-wozu\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.nmz.de\/badblog\/2011\/08\/10\/neue-musik-wozu\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/2011\/08\/10\/neue-musik-wozu\/#primaryimage","url":"https:\/\/blogs.nmz.de\/badblog\/files\/2011\/08\/SpeakersCorner-300x240.jpg","contentUrl":"https:\/\/blogs.nmz.de\/badblog\/files\/2011\/08\/SpeakersCorner-300x240.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.nmz.de\/badblog\/2011\/08\/10\/neue-musik-wozu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blogs.nmz.de\/badblog\/"},{"@type":"ListItem","position":2,"name":"Neue Musik &#8211; wozu?"}]},{"@type":"WebSite","@id":"https:\/\/blogs.nmz.de\/badblog\/#website","url":"https:\/\/blogs.nmz.de\/badblog\/","name":"Bad Blog Of Musick","description":"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur","publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.nmz.de\/badblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blogs.nmz.de\/badblog\/#organization","name":"Bad Blog Of Musick","alternateName":"Ein Klassik-Blog zur Musik","url":"https:\/\/blogs.nmz.de\/badblog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","width":512,"height":512,"caption":"Bad Blog Of Musick"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/musikzeitung","https:\/\/x.com\/musikzeitung"]},{"@type":"Person","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/ce88a756dea34f64ceab78df990e3dd4","name":"Moritz Eggert","description":"Komponist","sameAs":["http:\/\/www.moritz-eggert.de","moritz.eggert.79","https:\/\/x.com\/MoritzEggert"],"url":"https:\/\/blogs.nmz.de\/badblog\/author\/moritzeggert\/"}]}},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","jetpack_featured_media_url":"","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/4678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/comments?post=4678"}],"version-history":[{"count":2,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/4678\/revisions"}],"predecessor-version":[{"id":4681,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/4678\/revisions\/4681"}],"wp:attachment":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/media?parent=4678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/categories?post=4678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/tags?post=4678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}