{"id":4182,"date":"2011-05-05T21:13:04","date_gmt":"2011-05-05T20:13:04","guid":{"rendered":"http:\/\/blogs.nmz.de\/badblog\/?p=4182"},"modified":"2011-05-05T21:13:04","modified_gmt":"2011-05-05T20:13:04","slug":"in-der-fremde-3a-sandeep-bhagwati-in-montreal","status":"publish","type":"post","link":"https:\/\/blogs.nmz.de\/badblog\/2011\/05\/05\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\/","title":{"rendered":"In der Fremde (3a): Sandeep Bhagwati in Montr\u00e9al"},"content":{"rendered":"<blockquote><p>Sandeep Bhagwati &#8211; ein von mir hochgesch&#228;tzter Kollege und Freund, mit dem ich vor vielen, vielen Jahren, als noch S&#228;belzahntiger die germanischen Steppen durchstrichen, gemeinsam bei Wilhelm Killmayer studiert habe &#8211; war erst sehr widerstrebend, meine Fragen f&#252;r eine Reihe mit Portr&#228;ts deutscher Komponisten im Ausland zu beantworten. Das liegt daran, dass Sandeep sich nicht wirklich als Deutscher f&#252;hlt: Als Sohn eines indischen Vaters und einer Deutschen Mutter, aufgewachsen in Bombay (heute Mumbai) war er schon fr&#252;h notgedrungenerma&#223;en &#8222;heimatlos&#8220; und stets und mit Leidenschaft &#8222;in der Fremde&#8220;. Sicherlich auch ein Grund f&#252;r seine lebenslange und auch sehr kritische Besch&#228;ftigung mit dem Thema &#8222;Exotik in der Musik&#8220; &#8211; eine Diskussion die seiner Ansicht nach oft viel zu oberfl&#228;chlich gef&#252;hrt wird. Nicht nur hierzu hat sich Sandeep h&#228;ufig auch als Autor und Vortragender zu Wort gemeldet, denn er geh&#246;rt zu der seltenen Gattung von Komponisten, deren kreative Arbeit auch aus einem st&#228;ndigen Nachdenken &#252;ber ein weites Feld von soziokulturellen Fragen resultiert.<br \/>\nEine ausf&#252;hrliche Biographie Sandeeps ist <a href=\"http:\/\/matralab.hexagram.ca\/matrapeople\/sandeep-bhagwati\">hier <\/a>zu finden, es sei auf jeden Fall erw&#228;hnt, dass sein Schaffen eine immense Bandbreite hat und von Kammermusik, Vokal- wie Orchestermusik bis zu elektronischer Musik reicht (u.a. resultierend aus einem fast schon obligatorischem Studium am IRCAM und Arbeit am ZKM in Karlsruhe), mit einer gro&#223;en Konzentration auf experimentelle wie musiktheatralische Auff&#252;hrungsformen wie auch gro&#223;e Opern (z.B. &#8222;Ramanujan&#8220; f&#252;r die M&#252;nchener Biennale). In den letzten Jahren entwickelte Sandeep vor allem seine Idee der &#8222;Komprovisation&#8220;, einer sehr detaillierten Notationsform zur Erzeugung von &#8222;durchkomponierten&#8220; Improvisationen, die weit &#252;ber das hinaus geht, was sonst in Neuer Musik &#252;blich ist. Er ist auch indirekt schon in der Reihe &#252;ber Komponisten in der Fremde aufgetaucht, als Lehrer von Stefan Pohlit (siehe Teil 1 von &#8222;In der Fremde&#8220;).<br \/>\nSandeep auf sein momentanes Aufenthaltsland &#8211; Kanada &#8211; festzulegen, ist fast eine S&#252;nde, denn er hat schon in vielen Teilen dieser Welt gewirkt und gearbeitet. Seine sehr detaillierte Bestandsaufnahme der kanadischen Musikszene und ihrer Finanzierungsmechanismen ist aber hochspannend zu lesen und genau richtig f&#252;r diese Reihe.<br \/>\nSeine Antworten sind sehr ausf&#252;hrlich ausgefallen, daher teile ich sein Interview zu Montr\u00e9al in 2 Teile (Teil 2 ist hier in 3 Tagen zu lesen).<br \/>\nMoritz Eggert\n <\/p><\/blockquote>\n<p><a href=\"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2011\/05\/Sandeep-Bhagwati.jpg?ssl=1\" class=\"thickbox no_icon\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2011\/05\/Sandeep-Bhagwati.jpg?resize=243%2C208&#038;ssl=1\" alt=\"Sandeep Bhagwati\" title=\"Sandeep Bhagwati\" width=\"243\" height=\"208\" class=\"aligncenter size-full wp-image-4183\" \/><\/a><\/p>\n<p><em>1)\tWas hat Dich damals bewogen, nach Kanada zu gehen? Waren es musikalische oder private Gr&#252;nde, oder einfach nur Neugier auf eine andere Kultur<\/em><\/p>\n<p>Ich sah 2005 in Deutschland keine richtige Perspektive mehr f&#252;r meine Arbeiten \u2013 weder in finanzieller Hinsicht noch in der Art wie das Musikleben eingerichtet war. Meine Werkideen erforderten zunehmend lange Forschungsphasen, in denen ich mit Musikern meine speziellen Arbeitsmethoden der Komprovisation erarbeiten, neue Software Patches und andere Raumsituationen ausprobieren oder in langj&#228;hrige interdisziplin&#228;re und interkulturelle sch&#246;pferische Dialoge eintreten konnte.<br \/>\nMir wurde immer deutlicher, dass deutsche Ensembles und Veranstalter genau diese Art von intensiver Recherche nicht mit ihren herk&#246;mmlichen Finanzierungsinstrumenten in den Griff kriegen k&#246;nnen: alle meine Projekte von 2000 an waren verglichen mit einem konventionell als Streichquartett komponierten Werk (und zur Konvention z&#228;hlen inzwischen ja auch Lachenmann&#8217;sche Techniken oder Kagel&#8217;sche Inszenierungen) oder einem normal konzertant aufzuf&#252;hrenden Ensemblewerk immer extrem teuer, weil sie lange Probenvorl&#228;ufe oder Entwicklungphasen verlangten. Wenn ich das \u2013 wie oft &#8211; von meinem Kompositionshonorar zahlte, blieb mir weniger als nichts &#8211; und wenn ich es den Veranstaltern aufhalste, wurde ich als fordernd verschrien. <\/p>\n<p>Mir war ab 2004 klar, dass ich eine Institution im R&#252;cken brauchen w&#252;rde, die einen Teil der Kosten f&#252;r Forschung auffangen w&#252;rde \u2013 am besten eine Uni. Da aber in Deutschland die Musikhochschulen kaum Zugang zu Forschungsgeldern haben (sie werden mit Recht eben nicht als Orte der Wissenschaft wahrgenommen) und weil k&#252;nstlerische Forschung in Deutschland bis heute nicht als universit&#228;re Kategorie existiert, richtete ich meinen Blick ins Angels&#228;chsische, wo ich von solchen Ans&#228;tzen wusste. <\/p>\n<p>Ich bewarb mich in Winnipeg (Kanada), Lancaster (UK) und anderswo, aber die beste und am besten ausgestattete (und mit am wenigsten Lehre und\/oder Verwaltungskram befrachtete) Stelle war der Canada Research Chair for Inter-X Art an der Concordia University Montr\u00e9al. Der Ruf erfolgte auf eine internationale Ausschreibung hin &#8211; und durch eine internationale Jury, deren Mitglieder schriftlich versichern mussten, mit mir noch nie zusammengearbeitet zu haben und keine pers&#246;nlichen Beziehungen zu mir zu haben (da kann sich der deutsche Hochschul-Besetzungs-Kl&#252;ngel noch eine Scheibe abschneiden). Hier gelte ich also seit 2006 als Spitzenforscher, kann mich um Forschungsgelder in Millionenh&#246;he bewerben, und bekam quasi als Antrittsgeschenk ein Privatlabor &#8211; meine eigene, technisch voll ausgestattete Black Box (8 Kanal Audio, 3 Kanal Video) &#8211; und besch&#228;ftige dort 10 Assistenten, die an meinen Projekten in verschiedenen Rollen mitarbeiten \u2013 von der Softwareentwicklung &#252;ber die technische Direktion, von der Videodokumentation bis hin zur B&#252;roverwaltung.<\/p>\n<p>Was muss ich daf&#252;r tun? Vor allem Kunst schaffen \u2013 wie bei anderen Professoren Artikel und B&#252;cher, werden von mir Kompositionen und Theaterwerke, Performance- und Videoarbeiten etc erwartet. (Ich habe zwar den Stallgeruch des diplomierten Komponisten, war aber immer auch in den erw&#228;hnten anderen Kunstformen aktiv).<br \/>\nIch lehre also nicht eigentlich Komposition \u2013 wenn ich &#252;berhaupt etwas lehre (ich muss nicht unbedingt lehren), so sind das Seminare, die ich mir selber ausdenke, wie z.B. &#8222;Interdisziplin&#228;re Komprovisation f&#252;r T&#228;nzer, Schauspieler, Musiker, Designer und Informatiker&#8220; oder &#8222;Nicht-Visuelles Theater (f&#252;r Publikum mit verbundenen Augen)&#8220;, &#8222;Konzerte kuratieren &#8211; von der Analyse zur Auff&#252;hrung&#8220; oder &#8222;Musik als Orale Tradition&#8220;. Diese Kurse enthalten oft sowohl traditionell akademische Elemente (theoretische Texte lesen und argumentativ schreiben) wie auch k&#252;nstlerisch-kreative. Und ich habe nat&#252;rlich Master-Studenten, Doktoranden und Post-Docs in Komposition, Neuer Musik, Performance-Kunst, Theater und interdisziplin&#228;rer Kunst \u2013 einige davon sind &#228;lter als ich.<br \/>\nVon Kanada&#8217;s und speziell Qu\u00e9bec&#8217;s Kultur wusste ich, als ich hier landete, nur sehr wenig &#8211; ausser den Klischees: dass elektroakustische Musik hier eine zentrale Rolle im Musikleben einnimmt, und dass einige der besten Tanzcompagnien weltweit aus Montr\u00e9al kommen. Das aber war es sicher nicht, was mich hierher lockte.<\/p>\n<p><em>2)      Was w&#252;rdest Du als die gravierendsten Unterschiede zwischen der deutschen und kanadischen zeitgen&#246;ssischen Musik(szene) beschreiben? Welche Probleme gibt es \/ was ist besser (in Kanada)?<\/em><\/p>\n<p>Wenn meine oben beschriebenen Arbeitsbedingungen dem einen oder anderen paradiesisch erscheinen m&#246;gen, so muss man dazu aber auch wissen, dass dies nur f&#252;r die reine Forschung gilt. Dieses Forschungsgeld darf z.B. bestimmungsgem&#228;ss nicht dazu verwendet werden, Musikerhonorare, Saalmieten, Promotion, Leihgeb&#252;hren, Kompositionsauftr&#228;ge, GEMA &#8211; kurz: alles, was mit einem Konzert verbunden ist &#8211; zu bezahlen.<br \/>\nDer &#8222;reine&#8220; Musikbetrieb hierzulande ist aber finanziell viel weniger reich ausgestattet als in Deutschland und hat &#252;berdies ein ganz anderes Finanzierungsmodell: W&#228;hrend Deutschland vor allem Institutionen (Rundfunk, Opernh&#228;user, Sinfonieorchester, Festivals etc.) f&#246;rdert, die dann im Wettbewerb miteinander ihr Programm gestalten &#8211; und dabei dann K&#252;nstler mit Auftr&#228;gen bedenken (oder auch nicht), werden in Kanada Institutionen  nur soweit gef&#246;rdert, dass sie ihren Betrieb decken k&#246;nnen (Geb&#228;ude, Mitarbeiter etc.), aber kein Geld haben, um das Programm selber zu finanzieren. Und auch diese F&#246;rderung wird nicht per individueller Subvention vergeben, sondern per allj&#228;hrlichem Wettbewerb. Es gibt deshalb keinen Automatismus, bei dem z.B. einem Konzerthaus eine gewisse j&#228;hrliche Subvention zusteht, die dann aktiv gek&#252;rzt werden w&#252;rde, sondern wenn ein anderes Konzerthaus einen besseren Antrag stellt und\/oder einen geschickteren Manager hat, dann spricht halt die Wettbewerbsjury dem letzteren die Subvention zu.<br \/>\nWenn die Regierung etwas streicht oder k&#252;rzt, dann sind es nur die Gesamtsummen, die solchen Programmen zur Verf&#252;gung stehen \u2013 die Jury (die immer aus K&#252;nstlern und Kollegen besteht) kann dann entscheiden, ob sie allen, die sie f&#252;r f&#246;rderungsw&#252;rdig h&#228;lt, etwas gleichm&#228;ssig wegk&#252;rzt \u2013 oder ob sie einzelne &#8222;Leuchtt&#252;rme&#8220; f&#246;rdert, die anderen aber nicht.<\/p>\n<p>Und die Musiker\/Komponisten, wie kommen die an Geld ? Auf dieselbe Weise: K&#252;nstler\/Ensembles werden individuell per Projektwettbewerb gef&#246;rdert. Wenn sie allerdings die leiseste Chance haben, mit Auff&#252;hrungen &#8222;echtes&#8220; Geld zu verdienen (z.B. ein klassischer Musiker im konventionellen Klassikbetrieb), dann f&#246;rdert das Jurysystem sie eher nicht, hier gilt der Markt: deshalb sind Klassik- Tickets immer teuer, klassische Musik live h&#246;ren gilt aufgrund dessen noch mehr als in Deutschland nur als Zeitvertreib der Wohlsituierten.<br \/>\nNahezu jede Opernauff&#252;hrung hat Bayreuther oder Salzburger Preise, und Regiekonzept-Auff&#252;hrungen gibt es da so gut wie gar nicht: meist nur gut gemachte Konvention mit detailfreudigen &#8222;authentischen&#8220; Kost&#252;men und B&#252;hnenbildern \u2013 der Historienfilm aus Hollywood ist die bildnerische Messlatte. Die Oper Montr\u00e9al z.B. hat kein eigenes Haus, und macht 5 Inszenierungen pro Jahr, spielt jede ensuite f&#252;r etwa eine Woche, Opern vor &#8222;Entf&#252;hrung aus dem Serail&#8220; und nach &#8222;Turandot&#8220; kommen im Spielplan praktisch nicht vor.<\/p>\n<p>Musiker jedoch, vor allem Ensembles und Compagnien, die nicht im Mainstream arbeiten, k&#246;nnen sich um Jahresf&#246;rderungen bewerben. In deren Projektantr&#228;gen (die z.B. Pl&#228;ne f&#252;r Konzertreihen und Tourneen beinhalten, aber auch im Detail die Verwaltungsstruktur und das Management offenlegen) wird ein Budget erwartet, das auch ausdr&#252;cklich realistische Lebenshaltungskosten f&#252;r die Ensemblemitglieder ausweist. Viele Komponisten gr&#252;nden selber Ensembles, um so vielleicht in den Genuss eines prek&#228;ren, aber immerhin f&#252;r Miete und Essen ausreichenden &#8222;Gehaltes&#8220; zu kommen.<br \/>\nZus&#228;tzlich kann sich jedes Ensemble um Auftragshonorare bewerben, die sie dann an Komponisten vergeben k&#246;nnen. So entsteht f&#252;r jedes gef&#246;rderte Ensemble (etwa 50% der Antragsteller) eine komplette Saison mit UAs und Tourneen, die komplett vorfinanziert sind (auf niedrigerem Niveau als in Deutschland, aber immerhin). Daf&#252;r muss jedes gef&#246;rderte Ensemble eine Reihe von Konzerten &#8222;umsonst&#8220; d.h. ohne Honorare und Spesen geben.<br \/>\nHier schliesst sich dann der Kreis: H&#228;user, die kein Geld f&#252;r Honorare haben und Ensembles, die f&#252;r einige Ihrer Konzerte kein Honorar verlangen d&#252;rfen, erg&#228;nzen sich \u2013 und so entsteht per Zufallsgenerator das Programm eines Konzertsaales. Damit entgeht man jeder aesthetischen Positionierung \u2013 denn aesthetisch-ideologische Kriterien d&#252;rfen auch ausdr&#252;cklich nicht Basis der Juryentscheidungen &#252;ber F&#246;rderungen sein, nur die Einsch&#228;tzung, ob die Musiker die n&#246;tige k&#252;nstlerische Erfahrung, konzeptuelle Klarheit und finanzielle Seriosit&#228;t mitbringen, um das angepeilte Jahresprogramm zu stemmen.<br \/>\nUnd als &#8222;Haus&#8220; muss man im Grunde froh sein &#252;ber jeden, der einem seine Gratis-Konzerte anbietet \u2013 die Veranstalter werden den Teufel tun und hier aesthetische Positionen durchsetzen wollen. So sind auch die grossen Festivals f&#252;r Neue Musik (die es durchaus gibt) konzipiert \u2013 ins Festival kommen bis auf ein oder zwei thematische Abende nur Projekte, die ihre Finanzierung komplett mitbringen: das Festival ist lediglich eine Art Selbst-Kooperative f&#252;r Medienarbeit, Kartenverkauf und Publikumsaufmerksamkeit. Niemand streitet, weder davor noch danach, &#252;ber Inhalte &#8211; oder ist gar kuratorisch verantwortlich.<\/p>\n<p>Der grosse Vorteil dieses Systems: Einheimische K&#252;nstler jeder Couleur werden lebenslang immer wieder gef&#246;rdert, man kann, wie in Deutschland, von Komposition fast einen halben Lebensunterhalt bestreiten. Dazu kommt, dass jeder Empf&#228;nger von Subventionen auch turnusm&#228;ssig mal in der Jury sitzen muss. Dieses Verfahren verhindert Ideologismus, und f&#246;rdert extreme H&#246;flichkeit: schliesslich weiss man nie, ob der, den man gerade gerne in aestheticis angegriffen h&#228;tte, nicht schon morgen &#252;ber den eigenen F&#246;rderantrag befindet\u2026 Andererseits f&#246;rdert es ein enggewobenes Milieu, in dem man sich gut gegenseitig mit Geld bedenken \u2013 und von jedem &#228;usseren Einfluss abschotten kann.<br \/>\nDas ganze System erschwert n&#228;mlich ein zentrales belebendes Element der deutschen Kulturlandschaft: dass ausl&#228;ndische K&#252;nstler und Ensembles regelm&#228;ssig auch dann eingeladen werden k&#246;nnen, wenn sie nicht mit Mainstream-Kultur selber zum Profit ihrer Reise beitragen. Veranstalter, die ausl&#228;ndische K&#252;nstler nach Kanada einladen wollen, m&#252;ssen nicht selten durch pers&#246;nliche Bankkredite haften \u2013 oder Firmensponsoren finden: man kann sich vorstellen, dass so jede riskante Kunst ausgeklammert wird.<br \/>\nDas heisst auch, dass die hiesigen Ensembles nur selten &#8222;ausl&#228;ndische Neue Musik&#8220; spielen \u2013 ihre Komponistenkollegen in der Jury k&#246;nnten solche Programme ja als Affront empfinden und vielleicht den Jahresf&#246;rderungshahn abdrehen\u2026Jede Initiative zur Rezeption nicht-kanadischer Komponisten und Musiker erfordert entweder eine starke Uni im R&#252;cken (auch wenn die kanadische Neue Musik Szene zum Gl&#252;ck viel weniger akademisch ist als die us-amerikanische) oder den vierfachen Einsatz und das vierfache Risiko vom Veranstalter.<\/p>\n<p>Mit anderen Worten: Kanada ist f&#252;r K&#252;nstler ein gutes Land zum &#220;berleben, aber nicht so reich wie Deutschland, wenn es um Kulturimport geht. Aesthetische Debatten sind in der Musikszene nahezu unbekannt (ausser auf ganz basalem Niveau, also wenn summarisch dar&#252;ber gestritten wird, ob neu komponierte Musik publikumsnah oder im weistesten Sinne &#8222;experimentell&#8220; sein soll). Das allerdings f&#246;rdert eine in Deutschland unbekannte Egalit&#228;t verschiedenster Zug&#228;nge zur Musik: so hat Montr\u00e9al eine starke &#8218;musique actuelle&#8216; Szene \u2013 neue experimentelle Musik, die in Bars und Clubs genauso zuhause ist wie in Konservatorien und Theatern, die Improvisation und Weltmusik ganz nat&#252;rlich neben Ferneyhough&#8217;scher Schreib-Komplexit&#228;t [ent]stehen l&#228;sst, in der akusmatische Komponisten auch mal Turntables anwerfen und mit Free-Jazzern jammen, und in der Improvisationsorchester gerne mit Streichquartetten zusammenarbeiten, deren Repertoire von James Tenney bis Walter Zimmermann, von John Cage bis Steve Reich, von Linda Bouchard bis Christopher Butterfield reicht. Das ist f&#252;r mich stets sehr erfrischend \u2013 und die Hauptprotagonisten dieser Szene (Jean D\u00e9rome, Lori Freedman, Joane H\u00e9tu, Pierre Tanguay, Malcolm Goldstein, Quatuor Bozzini, Michel Gonneville, Kiya Tabassian, DB Boyko, Coat Cooke, D. Andrew Stewart, Michal Seta, Clemens Merkel) sind meine wohl engsten musikalischen Arbeits- und Gespr&#228;chspartner hier geworden.<\/p>\n<p>(Teil 2 folgt in K&#252;rze)<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=In%20der%20Fremde%20%283a%29%3A%20Sandeep%20Bhagwati%20in%20Montr%C3%A9al https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2011%2F05%2F05%2Fin-der-fremde-3a-sandeep-bhagwati-in-montreal%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=In%20der%20Fremde%20%283a%29%3A%20Sandeep%20Bhagwati%20in%20Montr%C3%A9al https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2011%2F05%2F05%2Fin-der-fremde-3a-sandeep-bhagwati-in-montreal%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2011%2F05%2F05%2Fin-der-fremde-3a-sandeep-bhagwati-in-montreal%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=In%20der%20Fremde%20%283a%29%3A%20Sandeep%20Bhagwati%20in%20Montr%C3%A9al%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2011%2F05%2F05%2Fin-der-fremde-3a-sandeep-bhagwati-in-montreal%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2011%2F05%2F05%2Fin-der-fremde-3a-sandeep-bhagwati-in-montreal%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Sandeep Bhagwati &#8211; ein von mir hochgesch&#228;tzter Kollege und Freund, mit dem ich vor vielen, vielen Jahren, als noch S&#228;belzahntiger die germanischen Steppen durchstrichen, gemeinsam bei Wilhelm Killmayer studiert habe &#8211; war erst sehr widerstrebend, meine Fragen f&#252;r eine Reihe mit Portr&#228;ts deutscher Komponisten im Ausland zu beantworten. Das liegt daran, dass Sandeep sich nicht wirklich als Deutscher f&#252;hlt: Als Sohn eines indischen Vaters und einer Deutschen Mutter, aufgewachsen in Bombay (heute Mumbai) war er schon fr&#252;h notgedrungenerma&#223;en &#8222;heimatlos&#8220; und stets und mit Leidenschaft &#8222;in der Fremde&#8220;. <\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=In%20der%20Fremde%20%283a%29%3A%20Sandeep%20Bhagwati%20in%20Montr%C3%A9al https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2011%2F05%2F05%2Fin-der-fremde-3a-sandeep-bhagwati-in-montreal%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=In%20der%20Fremde%20%283a%29%3A%20Sandeep%20Bhagwati%20in%20Montr%C3%A9al https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2011%2F05%2F05%2Fin-der-fremde-3a-sandeep-bhagwati-in-montreal%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2011%2F05%2F05%2Fin-der-fremde-3a-sandeep-bhagwati-in-montreal%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=In%20der%20Fremde%20%283a%29%3A%20Sandeep%20Bhagwati%20in%20Montr%C3%A9al%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2011%2F05%2F05%2Fin-der-fremde-3a-sandeep-bhagwati-in-montreal%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2011%2F05%2F05%2Fin-der-fremde-3a-sandeep-bhagwati-in-montreal%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[14657],"tags":[2701,2710,2722,2719,2706,2720,2718,2703,25,2707,2711,2713,1378,948,2717,2704,2709,2712,2715,2721,2716,828,2702,1232,2714,967,1389,2705,947,2435,1324,2708],"class_list":["post-4182","post","type-post","status-publish","format-standard","hentry","category-nicht-kategorisiert","tag-bombay","tag-christopher-butterfield","tag-clemens-merke","tag-coat-cooke","tag-concordia-university","tag-d-andrew-stewart","tag-db-boyko","tag-exotik","tag-gema","tag-james-tenney","tag-jean-derome","tag-joane-hetu","tag-john-cage","tag-kanada","tag-kiya-tabassian","tag-komprovisation","tag-linda-bouchard","tag-lori-freedman","tag-malcolm-goldstein","tag-michal-seta","tag-michel-gonneville","tag-montreal","tag-mumbai","tag-muenchener-biennale","tag-pierre-tangueay","tag-quatuor-diotima","tag-quebec","tag-ramanujan","tag-sandeep-bhagwati","tag-stefan-pohlit","tag-steve-reich","tag-walter-zimmermann"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>In der Fremde (3a): Sandeep Bhagwati in Montr\u00e9al &#8211; Bad Blog Of Musick - nmz Klassik-Blog<\/title>\n<meta name=\"description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.nmz.de\/badblog\/2011\/05\/05\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"In der Fremde (3a): Sandeep Bhagwati in Montr\u00e9al &#8211; Bad Blog Of Musick - nmz Klassik-Blog\" \/>\n<meta property=\"og:description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.nmz.de\/badblog\/2011\/05\/05\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\/\" \/>\n<meta property=\"og:site_name\" content=\"Bad Blog Of Musick\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/musikzeitung\" \/>\n<meta property=\"article:author\" content=\"moritz.eggert.79\" \/>\n<meta property=\"article:published_time\" content=\"2011-05-05T20:13:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.nmz.de\/badblog\/files\/2011\/05\/Sandeep-Bhagwati.jpg\" \/>\n<meta name=\"author\" content=\"Moritz Eggert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MoritzEggert\" \/>\n<meta name=\"twitter:site\" content=\"@musikzeitung\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Moritz Eggert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2011\\\/05\\\/05\\\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2011\\\/05\\\/05\\\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\\\/\"},\"author\":{\"name\":\"Moritz Eggert\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/ce88a756dea34f64ceab78df990e3dd4\"},\"headline\":\"In der Fremde (3a): Sandeep Bhagwati in Montr\u00e9al\",\"datePublished\":\"2011-05-05T20:13:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2011\\\/05\\\/05\\\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\\\/\"},\"wordCount\":2264,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2011\\\/05\\\/05\\\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2011\\\/05\\\/Sandeep-Bhagwati.jpg\",\"keywords\":[\"Bombay\",\"Christopher Butterfield\",\"Clemens Merke\",\"Coat Cooke\",\"Concordia University\",\"D. Andrew Stewart\",\"DB Boyko\",\"Exotik\",\"GEMA\",\"James Tenney\",\"Jean D\u00e9rome\",\"Joane H\u00e9tu\",\"John Cage\",\"Kanada\",\"Kiya Tabassian\",\"Komprovisation\",\"Linda Bouchard\",\"Lori Freedman\",\"Malcolm Goldstein\",\"Michal Seta\",\"Michel Gonneville\",\"Montr\u00e9al\",\"Mumbai\",\"M\u00fcnchener Biennale\",\"Pierre Tangueay\",\"quatuor diotima\",\"Quebec\",\"Ramanujan\",\"Sandeep Bhagwati\",\"Stefan Pohlit\",\"Steve Reich\",\"Walter Zimmermann\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2011\\\/05\\\/05\\\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2011\\\/05\\\/05\\\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\\\/\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2011\\\/05\\\/05\\\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\\\/\",\"name\":\"In der Fremde (3a): Sandeep Bhagwati in Montr\u00e9al &#8211; Bad Blog Of Musick - nmz Klassik-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2011\\\/05\\\/05\\\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2011\\\/05\\\/05\\\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2011\\\/05\\\/Sandeep-Bhagwati.jpg\",\"datePublished\":\"2011-05-05T20:13:04+00:00\",\"description\":\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2011\\\/05\\\/05\\\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2011\\\/05\\\/05\\\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2011\\\/05\\\/05\\\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2011\\\/05\\\/Sandeep-Bhagwati.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2011\\\/05\\\/Sandeep-Bhagwati.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2011\\\/05\\\/05\\\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"In der Fremde (3a): Sandeep Bhagwati in Montr\u00e9al\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"name\":\"Bad Blog Of Musick\",\"description\":\"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\",\"name\":\"Bad Blog Of Musick\",\"alternateName\":\"Ein Klassik-Blog zur Musik\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"width\":512,\"height\":512,\"caption\":\"Bad Blog Of Musick\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/musikzeitung\",\"https:\\\/\\\/x.com\\\/musikzeitung\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/ce88a756dea34f64ceab78df990e3dd4\",\"name\":\"Moritz Eggert\",\"description\":\"Komponist\",\"sameAs\":[\"http:\\\/\\\/www.moritz-eggert.de\",\"moritz.eggert.79\",\"https:\\\/\\\/x.com\\\/MoritzEggert\"],\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/author\\\/moritzeggert\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"In der Fremde (3a): Sandeep Bhagwati in Montr\u00e9al &#8211; Bad Blog Of Musick - nmz Klassik-Blog","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.nmz.de\/badblog\/2011\/05\/05\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\/","og_locale":"de_DE","og_type":"article","og_title":"In der Fremde (3a): Sandeep Bhagwati in Montr\u00e9al &#8211; Bad Blog Of Musick - nmz Klassik-Blog","og_description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","og_url":"https:\/\/blogs.nmz.de\/badblog\/2011\/05\/05\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\/","og_site_name":"Bad Blog Of Musick","article_publisher":"https:\/\/www.facebook.com\/musikzeitung","article_author":"moritz.eggert.79","article_published_time":"2011-05-05T20:13:04+00:00","og_image":[{"url":"https:\/\/blogs.nmz.de\/badblog\/files\/2011\/05\/Sandeep-Bhagwati.jpg","type":"","width":"","height":""}],"author":"Moritz Eggert","twitter_card":"summary_large_image","twitter_creator":"@MoritzEggert","twitter_site":"@musikzeitung","twitter_misc":{"Verfasst von":"Moritz Eggert","Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.nmz.de\/badblog\/2011\/05\/05\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\/#article","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2011\/05\/05\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\/"},"author":{"name":"Moritz Eggert","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/ce88a756dea34f64ceab78df990e3dd4"},"headline":"In der Fremde (3a): Sandeep Bhagwati in Montr\u00e9al","datePublished":"2011-05-05T20:13:04+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2011\/05\/05\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\/"},"wordCount":2264,"commentCount":1,"publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2011\/05\/05\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.nmz.de\/badblog\/files\/2011\/05\/Sandeep-Bhagwati.jpg","keywords":["Bombay","Christopher Butterfield","Clemens Merke","Coat Cooke","Concordia University","D. Andrew Stewart","DB Boyko","Exotik","GEMA","James Tenney","Jean D\u00e9rome","Joane H\u00e9tu","John Cage","Kanada","Kiya Tabassian","Komprovisation","Linda Bouchard","Lori Freedman","Malcolm Goldstein","Michal Seta","Michel Gonneville","Montr\u00e9al","Mumbai","M\u00fcnchener Biennale","Pierre Tangueay","quatuor diotima","Quebec","Ramanujan","Sandeep Bhagwati","Stefan Pohlit","Steve Reich","Walter Zimmermann"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.nmz.de\/badblog\/2011\/05\/05\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.nmz.de\/badblog\/2011\/05\/05\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\/","url":"https:\/\/blogs.nmz.de\/badblog\/2011\/05\/05\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\/","name":"In der Fremde (3a): Sandeep Bhagwati in Montr\u00e9al &#8211; Bad Blog Of Musick - nmz Klassik-Blog","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2011\/05\/05\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\/#primaryimage"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2011\/05\/05\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.nmz.de\/badblog\/files\/2011\/05\/Sandeep-Bhagwati.jpg","datePublished":"2011-05-05T20:13:04+00:00","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","breadcrumb":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2011\/05\/05\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.nmz.de\/badblog\/2011\/05\/05\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/2011\/05\/05\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\/#primaryimage","url":"https:\/\/blogs.nmz.de\/badblog\/files\/2011\/05\/Sandeep-Bhagwati.jpg","contentUrl":"https:\/\/blogs.nmz.de\/badblog\/files\/2011\/05\/Sandeep-Bhagwati.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.nmz.de\/badblog\/2011\/05\/05\/in-der-fremde-3a-sandeep-bhagwati-in-montreal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blogs.nmz.de\/badblog\/"},{"@type":"ListItem","position":2,"name":"In der Fremde (3a): Sandeep Bhagwati in Montr\u00e9al"}]},{"@type":"WebSite","@id":"https:\/\/blogs.nmz.de\/badblog\/#website","url":"https:\/\/blogs.nmz.de\/badblog\/","name":"Bad Blog Of Musick","description":"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur","publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.nmz.de\/badblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blogs.nmz.de\/badblog\/#organization","name":"Bad Blog Of Musick","alternateName":"Ein Klassik-Blog zur Musik","url":"https:\/\/blogs.nmz.de\/badblog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","width":512,"height":512,"caption":"Bad Blog Of Musick"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/musikzeitung","https:\/\/x.com\/musikzeitung"]},{"@type":"Person","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/ce88a756dea34f64ceab78df990e3dd4","name":"Moritz Eggert","description":"Komponist","sameAs":["http:\/\/www.moritz-eggert.de","moritz.eggert.79","https:\/\/x.com\/MoritzEggert"],"url":"https:\/\/blogs.nmz.de\/badblog\/author\/moritzeggert\/"}]}},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","jetpack_featured_media_url":"","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/4182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/comments?post=4182"}],"version-history":[{"count":2,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/4182\/revisions"}],"predecessor-version":[{"id":4185,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/4182\/revisions\/4185"}],"wp:attachment":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/media?parent=4182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/categories?post=4182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/tags?post=4182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}