{"id":28624,"date":"2024-05-10T18:30:46","date_gmt":"2024-05-10T16:30:46","guid":{"rendered":"https:\/\/blogs.nmz.de\/badblog\/?p=28624"},"modified":"2024-05-10T18:30:46","modified_gmt":"2024-05-10T16:30:46","slug":"der-ernste-zustand-der-e-musik","status":"publish","type":"post","link":"https:\/\/blogs.nmz.de\/badblog\/2024\/05\/10\/der-ernste-zustand-der-e-musik\/","title":{"rendered":"Der ernste Zustand der E-Musik"},"content":{"rendered":"<p><strong>Der ernste Zustand der E-Musik<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Dass die einst von den GEMA-Gr&#252;ndern benutzten Begriffe heute anachronistisch wirken, muss ich nicht erw&#228;hnen. \u201eErnste Musik\u201c ist nicht notwendigerweise ohne Humor und Ironie, und Unterhaltungsmusik ist nicht nur da, um ein bisschen zu am&#252;sieren. Beide Genres kennen Tiefe und hohe Qualit&#228;t. Wenn wir aber &#252;ber die Gr&#252;nde f&#252;r diese Trennung innerhalb der GEMA nachdenken, wird schnell klar, dass ein Verst&#228;ndnis der sehr unterschiedlichen Entstehungsumst&#228;nde eine modifizierte Betrachtung auch bei der Verwertung rechtfertigen. Zum Beispiel kann die Komposition eines gro&#223;en Orchesterwerks mit einer aufwendigen Partitur und zahllosen Einzelstimmen nicht wirklich mit einem im Studio produzierten Song verglichen werden, ohne dass eine solche Feststellung irgendetwas &#252;ber die Berechtigung oder Qualit&#228;t dieser beiden Ausdrucksformen aussagt. Es gibt sehr erfolgreiche E-Komponist:innen mit zahllosen Auff&#252;hrungen, aber selbst diese werden mit ihrer Arbeit nur einen Bruchteil der Ums&#228;tze erreichen, die in vornehmlich kommerzieller Musik theoretisch m&#246;glich sind. Allein dies unterscheidet die beiden Welten grunds&#228;tzlich \u2013 die eine orientiert sich in irgendeiner Form an einem Markt, die andere existiert in einem freien und \u201ewilden\u201c Raum, in dem es eher um hohes k&#252;nstlerisches Risiko, Experiment und den Versuch, m&#246;glichst neue k&#252;nstlerische Wege zu beschreiten geht.<\/p>\n<p>Was aber oft nicht beachtet wird: U-Musik und E-Musik sind keineswegs \u201ekontr&#228;re\u201c oder \u201everfeindete\u201c Konzepte, sie erg&#228;nzen sich, <strong>gerade weil sie sich unterscheiden<\/strong>. Unser Vorstandsmitglied <a href=\"https:\/\/micki-meuser.com\/\">Micki Meuser<\/a> (DKV) \u2013 seines Zeichens Filmkomponist \u2013 hat es sch&#246;n ausgedr&#252;ckt: \u201eWir sind froh, dass es euch E-Komponisten gibt, denn ihr probiert die Sachen zum ersten Mal aus, die uns bei unseren n&#228;chsten Filmmusiken inspirieren k&#246;nnen\u201c. Umgekehrt gibt es zahllose Beispiele, in denen E-Musik durch U-Musik inspiriert wurde \u2013 so versuchte ein Komponist wie Thomas Ad\u00e8s Elemente von Clubmusik in Orchestermusik neu zu interpretieren, Komponisten wie Philip Glass oder David Lang lie&#223;en sich von der Filmmusik eines Bernard Herrmann inspirieren. Popul&#228;r- und Hochkultur haben sich schon immer wechselseitig erg&#228;nzt und inspiriert, das zieht sich durch die gesamte Musikgeschichte, nicht erst seit Mozart.<\/p>\n<p>In einer idealen Welt helfen sich beide Seiten mit gegenseitigem Respekt \u2013 die erfolgreichsten Komponierenden kommerzieller Musik unterst&#252;tzen die \u201eHexenk&#252;che\u201c der Neuen Musik als kreative Werkstatt, die \u201eNeue Musik\u201c-Freaks arbeiten wiederum an neuen und verr&#252;ckten Ideen, die irgendwann auch ein gro&#223;es Publikum begeistern k&#246;nnen. Es w&#228;re so sch&#246;n, aber leider ist es nicht so einfach \u2013 es gibt Kr&#228;fte, die auf die in den GEMA-Statuten festgelegten Unterst&#252;tzungen der E-Musik schielen, weil sie jeden Cent ihrer Tantiemen wollen. Aber es gibt auch leider viel zu viele E-Komponierenden, die sich wenig f&#252;r eine Mitgliedschaft im DKV oder ein Engagement in der GEMA interessieren, weil sie sich daf&#252;r irgendwie zu fein sind oder sich darauf verlassen, dass ihr kleines E-Territorium ewig auf festen F&#252;&#223;en steht. Nein, das tut es nicht, <strong>denn wie und wohin Geld in der GEMA verteilt wird, ist stets verhandelbar und gemeinsame Entscheidung einer Kurie, die bei den Mitgliederversammlungen anwesend ist und sich einbringt<\/strong>. Geschieht dies nicht, werden die Entscheidungen ohne die Personen getroffen, die davon betroffen sein werden.<\/p>\n<p>Es gibt einen gro&#223;en Unterschied zwischen E und U, der mir zunehmend vor allem in Deutschland auff&#228;llt, und das betrifft die grunds&#228;tzliche Solidarit&#228;t untereinander.<\/p>\n<p>Weder in der U noch in der E-Musik finden sich alle gleicherma&#223;en dufte. In der U-Musik zum Beispiel h&#246;ren ganz sicher nicht alle Schlager-Fans gerne auch Heavy Metal. Wer Reinhard Mey und anspruchsvolle Chansons liebt, ist vielleicht nicht die typische Rammstein-H&#246;rerin und Anh&#228;nger von Grunge und Punk werden an Nils Frahm wenig finden. Aber im Grunde macht das &#252;berhaupt nichts, denn in dem riesigen Bereich von auf ganz unterschiedliche Weise popul&#228;rer Musik nehmen z.B. Schlagers&#228;ngerinnen den Heavy Metal \u2013 Bands nichts weg, da sie ein vollkommen unterschiedliches Publikum ansprechen. Man kann wunderbar nebeneinander in gro&#223;er Vielfalt existieren, Konkurrenz gibt es allenfalls dort, wo man exakt dasselbe macht.<\/p>\n<p>Ist es auch so in der E-Musik? Nicht wirklich. Kennerinnen der Neue-Musik-Szene wissen, dass es da genauso viele Unterschiede gibt, wie in der popul&#228;ren Musik. Zum Teil tuen sich tiefste &#228;sthetische Gr&#228;ben auf zwischen New Complexity und Minimalismus, zwischen Spektralmusik und Konzeptmusik. Das kann alles komplett unterschiedlich klingen, ist dennoch ambitionierte Musik von heute. Das Problem ist nur: das Zielpublikum all dieser Aktivit&#228;ten ist mehr oder weniger dasselbe, daher wird der Kampf um die Deutungshoheit wesentlich erbitterter gef&#252;hrt als in der U-Musik, in der eher eine vom Publikum getriebene nat&#252;rliche Selektion herrscht. Oder anders gesagt: je kleiner der Acker ist, desto erbitterter wird der Kampf um die wenigen Furchen gef&#252;hrt.<\/p>\n<p>Immer noch werden schlaue B&#252;cher ver&#246;ffentlicht, in denen diskutiert wird, was gerade \u201erelevant\u201c oder nicht ist, Komponisten wie Pierre Boulez oder Musikphilosophen wie Adorno haben historisch Abgrenzungsprozesse bef&#246;rdert, die die Neue Musik in immer kleinere Parzellen unterteilt hat, in denen bestimmte Stile dann pl&#246;tzlich keinen Platz mehr fanden. Die schlimmsten Grabenk&#228;mpfe der 80er Jahre m&#246;gen Vergangenheit sein, wenn ich aber mit jungen Komponierenden spreche, h&#246;re ich von ihnen nach wie vor eine gro&#223;e Frustration dar&#252;ber, dass sie sich hier und dort mit ihrer Musik ausgegrenzt oder nicht f&#252;r voll genommen f&#252;hlen, oder von bestimmten Festivals aus rein &#228;sthetischen Gr&#252;nden nicht gespielt werden, weil es nicht zu der spezifischen \u201eSzene\u201c passt, die dort vertreten wird.<\/p>\n<p>Das sind alles Ph&#228;nomene, die man sicher auch aus der U-Musik kennt, aber es f&#228;llt schon auf, dass die E-Musik-Szene sich durch unendliche interne Revierabgrenzungen <em>viel kleiner macht, als sie eigentlich ist<\/em>. Und je kleiner man sich macht, desto empfindlicher wird man, desto geringer ist das Selbstbewusstsein.<\/p>\n<p>Auch vergangene Jahrhunderte kannten leidenschaftliche Diskussionen dar&#252;ber, was damals \u201eneue Musik\u201c war. Tschaikowsky fand Brahms \u201elangweilig\u201c, Debussy arbeitete sich an Richard Wagner ab. Der Unterschied aber war, dass man sich grunds&#228;tzlich gegenseitig als Komponierende anerkannte. Tschaikowsky sprach Brahms nicht das Recht zum Komponieren ab. Genau das geschieht aber sehr oft in der E-Musik-Szene aus einer seltsamen Form des D&#252;nkels heraus, wenn z.B. manch akademisch fest im Sattel sitzende Kollege seinen Studierenden sagt, dass man so und so komponieren \u201em&#252;sse\u201c, weil man sonst kein Komponist sei, oder bei einem Meisterkurs eine Partitur desinteressiert bis angeekelt weggelegt wird, weil sie nicht der &#196;sthetik der jeweiligen Lehrperson entspricht.<\/p>\n<p>Dieser grunds&#228;tzliche Geist ist leider noch sehr lebendig, ergibt aber immer weniger Sinn. Warum kann die E-Musik nicht solidarischer auftreten? Nichts w&#228;re in diesen Zeiten der Verteilungsk&#228;mpfe (mit KI wird alles noch schlimmer werden) jetzt wichtiger.<\/p>\n<p>Ich sage es deutlich: <strong>es m&#252;ssen mehr E-Komponierende dem DKV beitreten, zu den GEMA-Versammlungen kommen, aktiv an den notwendigen Reformen der Verteilungspl&#228;ne mitwirken.<\/strong> Immer noch schlummert ein Gro&#223;teil der E-Musik-Szene vor sich hin, vereinzelt, in zahllosen kleinen und zum Teil sogar nur lokal aktiven Szenen, ein eigenes S&#252;ppchen kochend und sich abgrenzend.<\/p>\n<p>Ich meine damit nicht, dass man dort &#252;berall langweilige Musik schreibt, ganz im Gegenteil. Aber wo bleibt das Gemeinschaftsgef&#252;hl, das gerade in schwierigen Zeiten (und diese schwierigen Zeiten sind JETZT) notwendig ist?<\/p>\n<p>Je mehr die E-Musik geschlossen auftritt (bei gleichzeitig gr&#246;&#223;tm&#246;glicher Akzeptanz einer Vielzahl von Stilen und musikalischen Ausdrucksformen, von denen viele im Moment gar nicht f&#252;r alle als \u201eE\u201c gelten, was absurd ist), desto mehr k&#246;nnen wir auch unsere k&#252;nstlerischen wie auch finanziellen Anliegen vermitteln. <strong>Die harte Realit&#228;t ist, dass nur eine Handvoll von E-Komponierenden in Deutschland allein vom Komponieren leben k&#246;nnen.<\/strong> Aber auch die, die nicht allein vom Komponieren leben, profitieren von z.B. der \u201eWertung\u201c bei der GEMA, die ambitionierte und nichtkommerzielle Musik grunds&#228;tzlich als f&#246;rderungsw&#252;rdig erachtet. Manchen sichert das gar ihr &#220;berleben. Der Kreis dieser Musik muss einerseits gr&#246;&#223;er werden, andererseits darf der Erfolg mit E-Musik nicht nur in kleinen Fachpubliken oder dem Feuilleton gesucht werden, sondern muss sich auch ernsthaft um Vermittlung bei Menschen bem&#252;hen, die nicht Fachexperten sind. Auch Orffs Carmina Burana ist letztlich E (und aus GEMA-Perspektive muss man sagen: gottseidank!)<\/p>\n<p>Musik, die nur um ein sehr spezielles Fachwissen oder avancierte und esoterische \u201eMaterialdiskussionen\u201c kreist, darf nicht das einzige Ziel von E-Musik sein. Grunds&#228;tzliche Verst&#228;ndlichkeit hei&#223;t nicht automatisch, dass man billigen Ausverkauf betreibt. Aber auch das Avancierte hat seinen gerechtfertigten Platz. Warum darf es nicht beide Varianten in \u201eE\u201c geben?<\/p>\n<p>Wie oft ist mir in meiner eigenen Karriere unglaublicher D&#252;nkel entgegengekommen. Ein Kollege versuchte zum Beispiel j&#252;ngst, Ver&#246;ffentlichungen von mir bei einem CD-Label zu verhindern allein aus dem Grund, dass ihm meine &#196;sthetik nicht passte. Mein Kompositionslehrer Wilhelm Killmayer wurde jahrzehntelang verlacht und verh&#246;hnt von der \u201eSzene\u201c, nur weil seine Musik nicht den damaligen Ma&#223;st&#228;ben entsprach. Wie oft h&#246;rte ich bei Meisterkursen die Worte \u201edas macht man heute nicht mehr\u201c. Gegenseitige Kritik ist nicht problematisch, wenn aber die grunds&#228;tzliche Existenzberechtigung einer bestimmten &#196;sthetik abgesprochen wird, wird es unertr&#228;glich, denn das werden zuk&#252;nftige Ohren ohnehin ganz anders entscheiden, als man es erwartet.<\/p>\n<p>Der Komponist Hummel galt zu Beethovens Zeit in der auch schon damals existierenden \u201eFachwelt\u201c als der wesentlich gr&#246;&#223;ere und begabtere Komponist, heute kennt man ihn einzig als Urheber eines gelegentlich gespielten Trompetenkonzerts, wenn &#252;berhaupt. Die Musikgeschichte ist voll von solchen Irrt&#252;mern, wir sollten uns nicht anma&#223;en, hier genau schon jetzt &#252;ber die Zukunft Bescheid zu wissen. <strong>Unser Ziel sollte es sein, m&#246;glichst viel musikalische Gegenwart zu erm&#246;glichen,<\/strong> hierzu braucht es auch F&#246;rderung. Wir zahlen einen Rundfunkbeitrag, weil wir auch ein Spartenradio und Kulturradio w&#252;nschen, &#228;hnlich agiert die GEMA mit ihrer Trennung von zwei Konzepten wie E und U. Ob diese Konzepte in Zukunft so hei&#223;en, ob es vielleicht bessere und zeitgem&#228;&#223;e Konzepte gibt &#8211; diese Diskussion wird bei der diesj&#228;hrigen GEMA-Versammlung im Jahre 2024 er&#246;ffnet werden. <strong>Wenn wir als E-Komponierende nicht dabei sind, sollten wir uns danach nicht beschweren, wenn wir mit dem Ergebnis dieser Diskussion nicht einverstanden sind.<\/strong><\/p>\n<p>Was wir aber immer brauchen werden \u2013 vor allem in Zeiten von KI \u2013 ist m&#246;glichst freie menschliche Kreativit&#228;t. Wir werden immer neue Ideen brauchen, neue &#228;sthetische Ans&#228;tze, die vielleicht erst einmal ungewohnt und verr&#252;ckt sind. <strong>Notierte Musik sollte dabei eine wichtige Rolle spielen, <\/strong>weil dort bestimmte Dinge m&#246;glich sind, die in rein elektronisch produzierter oder polyphoner Musik nie m&#246;glich sein werden, zum Beispiel wenn es in Richtung komplexer Polyphonie geht. Ein 40-stimmiges (vierzig unabh&#228;ngig agierende Einzelstimmen in fantastischem Kontrapunkt!) Chorwerk wie \u201eSpem in Alium\u201c von Thomas Tallis kann man nicht eben mal improvisieren, es <em>muss<\/em> aufgeschrieben werden. Diese Musik ist nicht \u201ebesser\u201c als nicht notierte oder improvisierte Musik, <strong>sie stellt nur eine ganz spezielle Art von Musik dar, die nur mit musikalischer Notation &#8211; einer der historisch einzigartigsten Errungenschaften des Abendlandes &#8211; m&#246;glich ist.<\/strong><\/p>\n<p>All das ist \u2013 irgendwie &#8211; E-Musik. Und nat&#252;rlich noch viel mehr als das. <strong>Aber wir werden den Fortbestand der sogenannten \u201eKunstmusik\u201c nur dann sichern, wenn wir dezidiert solidarisch auftreten und uns auch dort engagieren, wo es um Realit&#228;ten unseres Berufs geht, zum Beispiel in der GEMA oder im DKV. <\/strong><\/p>\n<p>Meinen gesch&#228;tzten und geliebten E-Kolleginnen und Kollegen sage ich daher: werdet Mitglied beim DKV, werbt neue Mitglieder! Engagiert euch bei der GEMA, vor allem dann, wenn ihr es bisher noch nicht getan habt!<\/p>\n<p>Ihr seid dort nur so fremd, wie ihr euch f&#252;hlt. Mit gegenseitigem Respekt (auch \u2013 und das ist ganz wichtig \u2013 vor den Kolleginnen und Kollegen der U-Musik) geht alles leichter.<\/p>\n<p>Eure Musik wird damit keineswegs unfreier, ganz im Gegenteil. Vielleicht wird sie gerade dann besonders relevant.<\/p>\n<p>Dann, wenn ihr nicht mehr so tut, als ob euch das alles nichts angeht.<\/p>\n<p>&nbsp;<\/p>\n<p>Moritz Eggert<\/p>\n<p>&nbsp;<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"28625\" data-permalink=\"https:\/\/blogs.nmz.de\/badblog\/2024\/05\/10\/der-ernste-zustand-der-e-musik\/j_e_blanche_le_groupe_des_six_1922\/\" data-orig-file=\"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2024\/05\/J_E_Blanche_le_groupe_des_six_1922-e1715358632598.jpg?fit=641%2C754&amp;ssl=1\" data-orig-size=\"641,754\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"J_E_Blanche_le_groupe_des_six_1922\" data-image-description=\"&lt;p&gt;Le Groupe des Six (Bild von J.E. Blanche)&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2024\/05\/J_E_Blanche_le_groupe_des_six_1922-e1715358632598.jpg?fit=592%2C1024&amp;ssl=1\" class=\"alignnone size-medium wp-image-28625\" src=\"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2024\/05\/J_E_Blanche_le_groupe_des_six_1922.jpg?resize=277%2C480&#038;ssl=1\" alt=\"\" width=\"277\" height=\"480\" \/><\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Der%20ernste%20Zustand%20der%20E-Musik https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2024%2F05%2F10%2Fder-ernste-zustand-der-e-musik%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Der%20ernste%20Zustand%20der%20E-Musik https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2024%2F05%2F10%2Fder-ernste-zustand-der-e-musik%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2024%2F05%2F10%2Fder-ernste-zustand-der-e-musik%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Der%20ernste%20Zustand%20der%20E-Musik%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2024%2F05%2F10%2Fder-ernste-zustand-der-e-musik%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2024%2F05%2F10%2Fder-ernste-zustand-der-e-musik%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Der ernste Zustand der E-Musik &nbsp; Dass die einst von den GEMA-Gr&#252;ndern benutzten Begriffe heute anachronistisch wirken, muss ich nicht erw&#228;hnen. \u201eErnste Musik\u201c ist nicht notwendigerweise ohne Humor und Ironie, und Unterhaltungsmusik ist nicht nur da, um ein bisschen zu am&#252;sieren. Beide Genres kennen Tiefe und hohe Qualit&#228;t. Wenn wir&#46;&#46;&#46;<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Der%20ernste%20Zustand%20der%20E-Musik https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2024%2F05%2F10%2Fder-ernste-zustand-der-e-musik%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Der%20ernste%20Zustand%20der%20E-Musik https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2024%2F05%2F10%2Fder-ernste-zustand-der-e-musik%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2024%2F05%2F10%2Fder-ernste-zustand-der-e-musik%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Der%20ernste%20Zustand%20der%20E-Musik%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2024%2F05%2F10%2Fder-ernste-zustand-der-e-musik%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2024%2F05%2F10%2Fder-ernste-zustand-der-e-musik%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"author":8,"featured_media":28625,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[14657,11372,37],"tags":[413,9499,2762,584,10245,7097,249,25,24729,3101,9530,1947,2682,2424,2835,327,103],"class_list":["post-28624","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert","category-featured","category-marketing","tag-beethoven","tag-bernard-herrmann","tag-brahms","tag-david-lang","tag-debussy","tag-dkv","tag-e-musik","tag-gema","tag-hummel","tag-killmayer","tag-micki-meuser","tag-philip-glass","tag-tallis","tag-thomas-ades","tag-tschaikowsky","tag-u-musik","tag-wagner"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Der ernste Zustand der E-Musik &#8211; Bad Blog Of Musick - nmz Klassik-Blog<\/title>\n<meta name=\"description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/05\/10\/der-ernste-zustand-der-e-musik\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der ernste Zustand der E-Musik &#8211; Bad Blog Of Musick - nmz Klassik-Blog\" \/>\n<meta property=\"og:description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.nmz.de\/badblog\/2024\/05\/10\/der-ernste-zustand-der-e-musik\/\" \/>\n<meta property=\"og:site_name\" content=\"Bad Blog Of Musick\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/musikzeitung\" \/>\n<meta property=\"article:author\" content=\"moritz.eggert.79\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-10T16:30:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.nmz.de\/badblog\/files\/2024\/05\/J_E_Blanche_le_groupe_des_six_1922-e1715358632598.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"641\" \/>\n\t<meta property=\"og:image:height\" content=\"754\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Moritz Eggert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MoritzEggert\" \/>\n<meta name=\"twitter:site\" content=\"@musikzeitung\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Moritz Eggert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2024\\\/05\\\/10\\\/der-ernste-zustand-der-e-musik\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2024\\\/05\\\/10\\\/der-ernste-zustand-der-e-musik\\\/\"},\"author\":{\"name\":\"Moritz Eggert\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/ce88a756dea34f64ceab78df990e3dd4\"},\"headline\":\"Der ernste Zustand der E-Musik\",\"datePublished\":\"2024-05-10T16:30:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2024\\\/05\\\/10\\\/der-ernste-zustand-der-e-musik\\\/\"},\"wordCount\":1972,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2024\\\/05\\\/10\\\/der-ernste-zustand-der-e-musik\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2024\\\/05\\\/J_E_Blanche_le_groupe_des_six_1922-e1715358632598.jpg?fit=641%2C754&ssl=1\",\"keywords\":[\"Beethoven\",\"Bernard Herrmann\",\"Brahms\",\"David Lang\",\"Debussy\",\"DKV\",\"E-Musik\",\"GEMA\",\"Hummel\",\"Killmayer\",\"Micki Meuser\",\"Philip Glass\",\"Tallis\",\"Thomas Ad\u00e8s\",\"Tschaikowsky\",\"U-Musik\",\"Wagner\"],\"articleSection\":{\"1\":\"Featured\",\"2\":\"Marketing\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2024\\\/05\\\/10\\\/der-ernste-zustand-der-e-musik\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2024\\\/05\\\/10\\\/der-ernste-zustand-der-e-musik\\\/\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2024\\\/05\\\/10\\\/der-ernste-zustand-der-e-musik\\\/\",\"name\":\"Der ernste Zustand der E-Musik &#8211; Bad Blog Of Musick - nmz Klassik-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2024\\\/05\\\/10\\\/der-ernste-zustand-der-e-musik\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2024\\\/05\\\/10\\\/der-ernste-zustand-der-e-musik\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2024\\\/05\\\/J_E_Blanche_le_groupe_des_six_1922-e1715358632598.jpg?fit=641%2C754&ssl=1\",\"datePublished\":\"2024-05-10T16:30:46+00:00\",\"description\":\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2024\\\/05\\\/10\\\/der-ernste-zustand-der-e-musik\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2024\\\/05\\\/10\\\/der-ernste-zustand-der-e-musik\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2024\\\/05\\\/10\\\/der-ernste-zustand-der-e-musik\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2024\\\/05\\\/J_E_Blanche_le_groupe_des_six_1922-e1715358632598.jpg?fit=641%2C754&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2024\\\/05\\\/J_E_Blanche_le_groupe_des_six_1922-e1715358632598.jpg?fit=641%2C754&ssl=1\",\"width\":641,\"height\":754},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2024\\\/05\\\/10\\\/der-ernste-zustand-der-e-musik\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Der ernste Zustand der E-Musik\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"name\":\"Bad Blog Of Musick\",\"description\":\"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\",\"name\":\"Bad Blog Of Musick\",\"alternateName\":\"Ein Klassik-Blog zur Musik\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"width\":512,\"height\":512,\"caption\":\"Bad Blog Of Musick\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/musikzeitung\",\"https:\\\/\\\/x.com\\\/musikzeitung\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/ce88a756dea34f64ceab78df990e3dd4\",\"name\":\"Moritz Eggert\",\"description\":\"Komponist\",\"sameAs\":[\"http:\\\/\\\/www.moritz-eggert.de\",\"moritz.eggert.79\",\"https:\\\/\\\/x.com\\\/MoritzEggert\"],\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/author\\\/moritzeggert\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Der ernste Zustand der E-Musik &#8211; Bad Blog Of Musick - nmz Klassik-Blog","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.nmz.de\/badblog\/2024\/05\/10\/der-ernste-zustand-der-e-musik\/","og_locale":"de_DE","og_type":"article","og_title":"Der ernste Zustand der E-Musik &#8211; Bad Blog Of Musick - nmz Klassik-Blog","og_description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","og_url":"https:\/\/blogs.nmz.de\/badblog\/2024\/05\/10\/der-ernste-zustand-der-e-musik\/","og_site_name":"Bad Blog Of Musick","article_publisher":"https:\/\/www.facebook.com\/musikzeitung","article_author":"moritz.eggert.79","article_published_time":"2024-05-10T16:30:46+00:00","og_image":[{"width":641,"height":754,"url":"https:\/\/blogs.nmz.de\/badblog\/files\/2024\/05\/J_E_Blanche_le_groupe_des_six_1922-e1715358632598.jpg","type":"image\/jpeg"}],"author":"Moritz Eggert","twitter_card":"summary_large_image","twitter_creator":"@MoritzEggert","twitter_site":"@musikzeitung","twitter_misc":{"Verfasst von":"Moritz Eggert","Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.nmz.de\/badblog\/2024\/05\/10\/der-ernste-zustand-der-e-musik\/#article","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2024\/05\/10\/der-ernste-zustand-der-e-musik\/"},"author":{"name":"Moritz Eggert","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/ce88a756dea34f64ceab78df990e3dd4"},"headline":"Der ernste Zustand der E-Musik","datePublished":"2024-05-10T16:30:46+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2024\/05\/10\/der-ernste-zustand-der-e-musik\/"},"wordCount":1972,"commentCount":0,"publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2024\/05\/10\/der-ernste-zustand-der-e-musik\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2024\/05\/J_E_Blanche_le_groupe_des_six_1922-e1715358632598.jpg?fit=641%2C754&ssl=1","keywords":["Beethoven","Bernard Herrmann","Brahms","David Lang","Debussy","DKV","E-Musik","GEMA","Hummel","Killmayer","Micki Meuser","Philip Glass","Tallis","Thomas Ad\u00e8s","Tschaikowsky","U-Musik","Wagner"],"articleSection":{"1":"Featured","2":"Marketing"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.nmz.de\/badblog\/2024\/05\/10\/der-ernste-zustand-der-e-musik\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.nmz.de\/badblog\/2024\/05\/10\/der-ernste-zustand-der-e-musik\/","url":"https:\/\/blogs.nmz.de\/badblog\/2024\/05\/10\/der-ernste-zustand-der-e-musik\/","name":"Der ernste Zustand der E-Musik &#8211; Bad Blog Of Musick - nmz Klassik-Blog","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2024\/05\/10\/der-ernste-zustand-der-e-musik\/#primaryimage"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2024\/05\/10\/der-ernste-zustand-der-e-musik\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2024\/05\/J_E_Blanche_le_groupe_des_six_1922-e1715358632598.jpg?fit=641%2C754&ssl=1","datePublished":"2024-05-10T16:30:46+00:00","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","breadcrumb":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2024\/05\/10\/der-ernste-zustand-der-e-musik\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.nmz.de\/badblog\/2024\/05\/10\/der-ernste-zustand-der-e-musik\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/2024\/05\/10\/der-ernste-zustand-der-e-musik\/#primaryimage","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2024\/05\/J_E_Blanche_le_groupe_des_six_1922-e1715358632598.jpg?fit=641%2C754&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2024\/05\/J_E_Blanche_le_groupe_des_six_1922-e1715358632598.jpg?fit=641%2C754&ssl=1","width":641,"height":754},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.nmz.de\/badblog\/2024\/05\/10\/der-ernste-zustand-der-e-musik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blogs.nmz.de\/badblog\/"},{"@type":"ListItem","position":2,"name":"Der ernste Zustand der E-Musik"}]},{"@type":"WebSite","@id":"https:\/\/blogs.nmz.de\/badblog\/#website","url":"https:\/\/blogs.nmz.de\/badblog\/","name":"Bad Blog Of Musick","description":"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur","publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.nmz.de\/badblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blogs.nmz.de\/badblog\/#organization","name":"Bad Blog Of Musick","alternateName":"Ein Klassik-Blog zur Musik","url":"https:\/\/blogs.nmz.de\/badblog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","width":512,"height":512,"caption":"Bad Blog Of Musick"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/musikzeitung","https:\/\/x.com\/musikzeitung"]},{"@type":"Person","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/ce88a756dea34f64ceab78df990e3dd4","name":"Moritz Eggert","description":"Komponist","sameAs":["http:\/\/www.moritz-eggert.de","moritz.eggert.79","https:\/\/x.com\/MoritzEggert"],"url":"https:\/\/blogs.nmz.de\/badblog\/author\/moritzeggert\/"}]}},"wp-worthy-pixel":{"ignored":false,"public":"177618f5617046d18dff8ea5903f1ac0","server":"vg05.met.vgwort.de","url":"https:\/\/vg05.met.vgwort.de\/na\/177618f5617046d18dff8ea5903f1ac0"},"wp-worthy-type":"normal","jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2024\/05\/J_E_Blanche_le_groupe_des_six_1922-e1715358632598.jpg?fit=641%2C754&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/28624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/comments?post=28624"}],"version-history":[{"count":1,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/28624\/revisions"}],"predecessor-version":[{"id":28626,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/28624\/revisions\/28626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/media\/28625"}],"wp:attachment":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/media?parent=28624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/categories?post=28624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/tags?post=28624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}