{"id":28597,"date":"2024-04-28T14:00:47","date_gmt":"2024-04-28T12:00:47","guid":{"rendered":"https:\/\/blogs.nmz.de\/badblog\/?p=28597"},"modified":"2024-04-24T16:27:46","modified_gmt":"2024-04-24T14:27:46","slug":"die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024","status":"publish","type":"post","link":"https:\/\/blogs.nmz.de\/badblog\/2024\/04\/28\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\/","title":{"rendered":"Die erweiterte Radiowoche vom 29.04.2024 bis 05.05.2024"},"content":{"rendered":"<p>Ein kleiner Blick in die Radiowoche 18. Die &#220;bersicht zum <a href=\"https:\/\/service.conbrio.de\/service\/download\/278\/\">Download als PDF<\/a><span style=\"text-decoration: line-through;\">.<\/span> Alle Angaben ohne Gew&#228;hr. Hier eine Auswahl. Die vollst&#228;ndige &#220;bersicht gibt es unter <a href=\"https:\/\/www.jazzzeitung.de\/cms\/2024\/04\/die-erweiterte-jazz-radiowoche-vom-29-04-2024-bis-05-05-2024\/\">JazzZeitung.de <\/a><\/p>\n<hr \/>\n<h2><a name=\"_Toc164855364\"><\/a>mo \u2013 29.04.2024<\/h2>\n<hr \/>\n<p>19:30:00 Uhr +++ &#214;1<br \/>\n<strong>S&#228;nger-Gitarrist Vieux Farka Tour\u00e9 und Band bei den INNt&#246;nen 2023<\/strong><\/p>\n<p>23:03 bis 24:00 Uhr +++ &#214;1<br \/>\n<strong>Musik, Mitspielerin des Theaters \u2013 Aktuelle Theatermusik aus &#214;sterreich<\/strong><\/p>\n<p>23:05 bis 00:00 +++ BR-KLASSIK<br \/>\n<strong>BR-KLASSIK \u2013 Jazztime: Zum 125. Geburtstag von Duke Ellington \u2013 Ein Portr&#228;t<\/strong><\/p>\n<p>23:30 bis 00:00 +++ NDR Kultur<br \/>\n<strong>Round Midnight: Jazz und Militanz: Peter Kemper \u201eThe Sound of Rebellion\u201c (1\/2)<\/strong><\/p>\n<hr \/>\n<h2><a name=\"_Toc164855365\"><\/a>di \u2013 30.04.2024<\/h2>\n<hr \/>\n<p>00:05 bis 01:00 +++ Deutschlandfunk Kultur<br \/>\n<strong>Neue Musik: \u201eMit meiner Musik schaffe ich einen bildnerischen Raum\u201c \u2013 Der Klangk&#252;nstler Rolf Julius (1939 \u2013 2011)<\/strong><\/p>\n<p>13:00 bis 14:00 +++ NDR Kultur<br \/>\n<strong>Starke St&#252;cke: Werkvergleich Concierto de Aranjuez: Xavier de Masitre (Klassik) &amp; Jim Hall (Jazz)<\/strong><\/p>\n<p>17:09:00 Uhr +++ &#214;1<br \/>\n<strong>Gitarrist Peter Rom und Theremin-Virtuosin Pamelia Stickney live im &#214;1 Haus am Wiener K&#252;niglberg<\/strong><\/p>\n<p>19:15 bis 20:00 +++ Deutschlandfunk<br \/>\n<strong>Zersetzung 2.0: Opfer von DDR-Unrecht werden zweimal bestraft<\/strong><\/p>\n<p style=\"padding-left: 40px;\">Von Alexa Hennings. Regie: Claudia Kattanek. Produktion: Deutschlandfunk 2024. Seit 2019 k&#246;nnen erstmals die Opfer von \u201eZersetzung\u201c durch die Stasi eine einmalige Entsch&#228;digung von 1.500 Euro beantragen. Doch es hagelt Absagen von den Gerichten. So setzt sich altes Unrecht bis heute fort.<\/p>\n<p style=\"padding-left: 40px;\">Wenn die Stasi das perfide Ziel der \u201eZersetzung\u201c verfolgte, bedeutete dies berufliche und private Diskreditierung, Destabilisierung der Pers&#246;nlichkeit, Zerst&#246;rung von Beziehungen. Doch selbst Betroffene, die dies anhand ihrer Stasi-Akte oder anderer Belege nachweisen k&#246;nnen, haben oft keinen Erfolg. Viele f&#252;hlen sich zum R&#252;ckzug gen&#246;tigt \u2013 wenn sie nicht klagen wollen oder es sich nicht leisten k&#246;nnen. Auch jene, die wegen politisch motivierter Verfolgung in Haft waren: Sie bekommen zwar eine Rehabilitierung zugesprochen, doch wer soziale Ausgleichsleistungen beantragt, scheitert meist. Kleine Renten und dauerhafte Gesundheitssch&#228;den machen f&#252;r viele Betroffene den Alltag schwer. Bei den Versorgungs&#228;mtern k&#246;nnen sie Unterst&#252;tzung \u2013 etwa in Form einer kleinen Rente \u2013 bekommen. Doch nur zehn Prozent aller Antr&#228;ge von \u2013 gerichtlich bereits anerkannten \u2013 DDR-Opfern werden genehmigt. Ein Skandal \u2013 sagen Opferanw&#228;lte, Historikerinnen, Wissenschaftler. Eine Dem&#252;tigung mehr, sagen die Betroffenen, eine \u201eZersetzung 2.0\u201c.<\/p>\n<p>20:00 bis 21:00 +++ NDR Kultur<br \/>\n<strong>An der Leine. Der Hund in der Literatur und unterm Schreibtisch<\/strong><\/p>\n<p style=\"padding-left: 40px;\">Von Manuela Reichart. DLF 2021. Ob Homer, Thomas Mann, Ernst Jandl, Monika Maron oder Sigrid Nunez \u2013 seitdem es Literatur gibt, schreiben Schriftsteller und Schriftstellerinnen &#252;ber Hunde. Dabei wird er zum Liebesobjekt und Stimmungsbarometer, Gef&#228;hrten, Besch&#252;tzer oder auch Angstmacher. Zu wohl keinem anderen Tier hat der Mensch ein so enges Verh&#228;ltnis wie zum Hund. Das ist bei einem Spaziergang durch den Park ebenso zu sehen wie in der Literatur. Die Deutsche Dogge ist viel zu gro&#223; f&#252;r das Appartement im Roman \u201eDer Freund\u201c von Sigrid Nunez, die struppige Mischlingsh&#252;ndin hingegen viel zu klein in der Erz&#228;hlung \u201eBonnie Propeller\u201c von Monika Maron. Ist dem Menschen ewig denn nichts recht?<\/p>\n<p>21:00 bis 22:00 +++ NDR Kultur<br \/>\n<strong>neue musik: Musique contemporaine parlante<\/strong><\/p>\n<p style=\"padding-left: 40px;\">Von Helmut Peters. Die franz&#246;sische Pianistin Florence Millet forscht im ersten Teil ihres gerade ver&#246;ffentlichten Zyklus \u201eKeywords \u2013 Piano parlando\u201c nach dem Umgang der Neuen Musik mit der Sprache. Von Georges Aperghis\u2019 \u201eConversation X\u201c mit st&#246;hnenden Och-Lauten und harten Interruptionen eines pr&#228;parierten Klaviers bis hin zu Peter Ablingers \u201eVoices and Piano\u201c mit zugespielten Originalaufnahmen von Hanna Schygulla reicht die St&#252;ckauswahl der in K&#246;ln lehrenden Professorin, &#252;ber die das Pariser IRCAM 2024 einen Film &#252;ber Musik und Elektronik ver&#246;ffentlichen wird.<\/p>\n<p>21:03 bis 22:00 +++ SWR Kultur<br \/>\n<strong>JetztMusik: Zwischen Analogtechnik und Wellenfeldsynthese \u2013 Das Institut f&#252;r Sonologie in Den Haag<\/strong><\/p>\n<p style=\"padding-left: 40px;\">Von Hubert Steins. \u201eIn der Musik ist der Raum das Medium der Verwandlung\u201c. So verstand es Gottfried Michael Koenig, der Gr&#252;nder des urspr&#252;nglich in Utrecht beheimateten Instituts f&#252;r Sonologie. 1960 wurde es mit den technischen Hinterlassenschaften des legend&#228;ren Philips Forschungslabors gegr&#252;ndet und profilierte sich im Bereich der automatisierten und computergest&#252;tzten Komposition. 1986 wurde es in das K&#246;nigliche Konservatorium in den Haag eingegliedert. Im Juli 2021 zog das Ausbildungs- und Forschungszentrum in neue R&#228;ume des Kulturzentrum AMARE um, die optimal auf die eigenen Bed&#252;rfnisse zugeschnitten sind.<\/p>\n<p>22:05 bis 23:00 +++ BR-KLASSIK<br \/>\n<strong>Horizonte: Erinnerung h&#246;rbar machen \u2013 Die Komponistin Elnaz Seyedi<\/strong><\/p>\n<p>23:00 bis 00:00 +++ radio3<br \/>\n<strong>Musik der Gegenwart: Das Ensemble LUX:NM Berlin<\/strong><\/p>\n<p>23:03 bis 24:00 Uhr +++ &#214;1<br \/>\n<strong>Studio Dan \u2013 Ein Ensemble, das keine Grenzz&#228;une kennt \u2013 Studio Dan im Zeit-Ton Portrait<\/strong><\/p>\n<p>23:30 bis 00:00 +++ NDR Kultur<br \/>\n<strong>Round Midnight: Jazz und Militanz: Peter Kemper \u201eThe Sound of Rebellion\u201c (2\/2)<\/strong><\/p>\n<hr \/>\n<h2><a name=\"_Toc164855366\"><\/a>mi \u2013 01.05.2024<\/h2>\n<hr \/>\n<p>00:05 bis 06:00 +++ Deutschlandfunk<br \/>\n<strong>Deutschlandfunk Radionacht: Jazz \u2013 \u201eL\u2019heure bleue\u201c \u2013 Die Farbe Blau im Jazz<\/strong><\/p>\n<p>12:10 bis 13:00 +++ Deutschlandfunk<br \/>\n<strong>An der p&#228;dagogischen Front \u2013 Ostdeutsche Lehrer in den Umbr&#252;chen der Wende<\/strong><\/p>\n<p style=\"padding-left: 40px;\">Von Holger Siemann. Regie: Claudia Kattanek. Produktion: Deutschlandfunk 2019. Jutta Hoffmann stieg von der DDR-Schulleiterin zur Hauptschullehrerin ab. Siglinde Schaub klagte gegen den Rausschmiss aus dem Direktorenamt und landete im Berliner Abgeordnetenhaus. Alexander Lubawinski fand sich nach der Wende als Vorgesetzter der beiden Kolleginnen wieder. Alle drei lieben ihren Beruf immer noch. Alle drei sind &#252;berzeugte P&#228;dagogen geblieben. Ihre Vorwendeerfahrungen haben ihnen geholfen, die Umbr&#252;che ihres Lebens zu meistern. Mit einer gewissen Genugtuung stellen sie fest, dass das deutsche Bildungswesen 30 Jahre sp&#228;ter wieder an Punkte gelangt, die die DDR-P&#228;dagogen verlassen mussten: die Gemeinschaftsschule. Das Fach \u201ePraktische Arbeit\u201c. Die fr&#252;hkindliche Bildung. Siglinde Schaub und Alexander Lubawinski haben im politischen Raum daf&#252;r gek&#228;mpft. Und Jutta Hoffmann in der Schule, die ihr kein Burn-out bescherte. Im Gegenteil, sie war der Ort, eine private Katastrophe zu verarbeiten.<\/p>\n<p>17:10:00 +++ &#214;1<br \/>\n<strong>Zum 1. Todestag von Gordon Lightfoot<\/strong><\/p>\n<p>19:05 bis 20:00 +++ Bayern 2<br \/>\n<strong>Bayern 2 Z&#252;ndfunk: Zum 30. Geburtstag von Rap-Queen Little Simz<\/strong><\/p>\n<p>23:30 bis 00:00 +++ NDR Kultur<br \/>\n<strong>Jazz: Lady Liberty #40: Shirley Horn<\/strong><\/p>\n<p>23:30 bis 23:57 +++ Deutschlandfunk<br \/>\n<strong>Jazz Live: jazzahead! <\/strong><strong>2023 \u2013 Jazz mit Pop-Appeal<\/strong><\/p>\n<p style=\"padding-left: 40px;\">LIUN &amp; The Science Fiction Orchestra. Aufnahme vom 28.4.2023 beim jazzahead!-Festival, Bremen<\/p>\n<hr \/>\n<h2><a name=\"_Toc164855367\"><\/a>do \u2013 02.05.2024<\/h2>\n<hr \/>\n<p>00:05 bis 01:00 +++ Deutschlandfunk Kultur<br \/>\n<strong>Neue Musik: Kompositionen von Erhard Grosskopf<\/strong><\/p>\n<p style=\"padding-left: 40px;\">Vorgestellt von Carolin Naujocks. Im M&#228;rz wurde Erhard Grosskopf 90 Jahre alt. Der Berliner Komponist verbindet avancierte Techniken mit seinem Faible f&#252;r eine kultivierte &#196;sthetik.<\/p>\n<p>18:00 bis 19:00 +++ MDR Kultur<br \/>\n<strong>D&#252;rre in Europa: Doku &#252;ber nachhaltige Landwirtschaft in der Klimakrise \/ Von Brigitte Kramer<\/strong><\/p>\n<p style=\"padding-left: 40px;\">Die andalusischen Erdbeeren, die f&#252;r wenige Euro im Supermarktregal liegen, fordern an andere Stelle einen hohen Preis: Sie gedeihen mit Wasser aus Europas gr&#246;&#223;tem Feuchtgebiet Do\u00f1ana \u2013 einem Schutzgebiet f&#252;r Zugv&#246;gel und zahlreiche gef&#228;hrdete Tierarten \u2013 das immer schneller austrocknet.<\/p>\n<p style=\"padding-left: 40px;\">Rund 80 Prozent aller spanischen Wasserressourcen werden f&#252;r Bew&#228;sserung von Feldern verbraucht. Das Problem ist aber auch ein gesamteurop&#228;isches: Durch den Klimawandel werden agrarische D&#252;rren auch in Deutschland und in weiten Teilen Europas l&#228;nger dauern und mehr Fl&#228;chen betreffen. Der D&#252;rremonitor des Helmholtz-Instituts publiziert beunruhigende Perspektiven: Zwischen 1971-2000 gab es in Deutschland durchschnittlich zwei D&#252;rremonate pro Jahr. Bei einer globalen Erw&#228;rmung von 3 \u00b0C steigt diese Zahl bundesweit um &#252;ber 50 Prozent.<\/p>\n<p style=\"padding-left: 40px;\">Die Ernteausf&#228;lle haben Auswirkungen auf die Nahrungsmittelsicherheit und Lebenshaltungskosten. Was kommt auf Europas Landwirte und Verbraucher zu? Und welche L&#246;sungsans&#228;tze gibt es?<\/p>\n<p style=\"padding-left: 40px;\">Autorin Brigitte Kramer hat Projekte in Europa besucht, die m&#246;gliche Wege in die Zukunft aufzeigen: In Brandenburg wird mit dem Agroforstsystem experimentiert: Hier gedeihen Getreide, Gem&#252;se oder H&#252;hner im schattigen, feuchten Wald.<\/p>\n<p style=\"padding-left: 40px;\">In &#214;sterreich forschen Wissenschaftler*innen an der Bodenbeschaffenheit, um resilienter gegen Extremwetterlagen zu werden. Intelligente Bew&#228;sserungssysteme in Spanien k&#246;nnen den Wasserverbrauch um zwei Drittel reduzieren. Und in Valencia werden gentechnisch ver&#228;nderte Tomaten gez&#252;chtet, die bis zu zehn Tage ohne Wasser auskommen.<\/p>\n<p style=\"padding-left: 40px;\">Brigitte Kramer, geboren in M&#252;nchen, Absolventin der Deutschen Journalistenschule. Lebt und arbeitet in Spanien. Autorin diverser Feature und Wissenssendungen. Themenschwerpunkte: Natur und Umwelt. Produktion: HR 2024<\/p>\n<p>20:05 bis 21:30 Uhr +++ BR-KLASSIK<br \/>\n<strong>Thema Musik Live aus dem Bergson Kunstkraftwerk \u2013 Ein ungleiches Paar!? Chancen und Herausforderungen f&#252;r &#246;ffentliche und private Veranstalter<\/strong><\/p>\n<p style=\"padding-left: 40px;\">Kann Kultur beides? Das Publikum inspirieren, anspruchsvoll sein, den K&#252;nstlerinnen und K&#252;nstlern Engagements bieten und sich zugleich rechnen? Staatliche Opernh&#228;user geh&#246;ren zu den kulturellen Leuchtt&#252;rmen dieses Landes, mit vielen Festangestellten und einem gro&#223;en Repertoire. Was leisten sie, was andere nicht k&#246;nnen und wie werden sie finanziert? Private und &#246;ffentliche Kulturveranstalter haben sicher am Ende das gleiche, ideelle Ziel: Sie wollen mit ihren Programmen Menschen nachhaltig ber&#252;hren \u2013 sie unterhalten, zum Nachdenken bringen, begeistern. Die Wege dahin sind aber verschieden, auch die Konzepte und M&#246;glichkeiten, die dem zugrunde liegen. Worin bestehen diese Unterschiede und was sind deren Folgen? Und wie k&#246;nnen sich beide Seiten, die &#246;ffentliche und die private, bestm&#246;glich erg&#228;nzen, um ein vielf&#228;ltiges, nachhaltiges Kulturangebot zu erm&#246;glichen? Diese und weitere Fragen diskutieren aus verschiedenen Perspektiven Laura Berman (Intendantin der Staatsoper Hannover), Wolfgang Heubisch (Bayerischer Staatsminister a. D.), Anna Kleeblatt (Coach und Beraterin f&#252;r Kulturbetriebe) und Maximilian Maier (Programmdirektor Bergson Kunstkraftwerk). Live-Musik von den Bergson Artists aus dem Fr&#252;hlingsalbum \u201eLichtdurchflutet\u201d sorgt f&#252;r weitere Energie in der Debatte. Moderation: Sylvia Schreiber<\/p>\n<p>22:05 bis 23:00 Uhr +++ BR-KLASSIK<br \/>\n<strong>Horizonte: Zum 85. Geburtstag von Jonathan Harvey<\/strong><\/p>\n<p style=\"padding-left: 40px;\">Jonathan Harvey: \u201eI love the Lord\u201c (Choir of St John\u2019s College); \u201e\u2026towards a pure land\u201c (Symphonieorchester des Bayerischen Rundfunks: Matthias Pintscher); \u201eMortuos plango, vivos voco\u201c (Dominique Harvey, Knabensopran; Jonathan Harvey, Stanley Haynes, Technische Realisation); \u201eBody mandala\u201c (BBC Scottish Symphony Orchestra: Ilan Volkov); \u201eLaus Deo\u201c (Edward Picton-Turbervill, Orgel)<\/p>\n<h2><a name=\"_Toc164855368\"><\/a><\/h2>\n<hr \/>\n<h2>fr \u2013 03.05.2024<\/h2>\n<hr \/>\n<p>14:05:00 +++ &#214;1<br \/>\n<strong>Das Jan Garbarek Quartett mit Bobo Stenson, Palle Danielsson und Jon Christensen im Juli 1974 in Graz<\/strong><\/p>\n<p>18:00 bis 19:00 +++ NDR Kultur<br \/>\n<strong>Musica: Viktoria Tolstoy bei der JazzBaltica<\/strong><\/p>\n<p>20:04 bis 23:00 +++ WDR 3<br \/>\n<strong>WDR 3 Konzert live: Wittener Tage f&#252;r neue Kammermusik 2024<\/strong><\/p>\n<p style=\"padding-left: 40px;\">Milica Djordjevi&#196;?: Neues Werk f&#252;r 8 Blechbl&#228;ser; The Monochrome Project \/ Sergej Maingardt \/ Anna Konjetzky: Songs of Absence feat. Witten Resonance f&#252;r Schlagzeug, T&#228;nzer, Elektronische Musik und Performer; Sergej Maingardt, Elektronik; Anna Konjetzky, Choreographie; Brian Archinal, Schlagzeug; Ensemble Resonanz. &#220;bertragung aus dem Foyer<\/p>\n<p style=\"padding-left: 40px;\">Ab ca. 20.30 Uhr:<br \/>\nHannes Seidl: Unfinished Circles f&#252;r verst&#228;rktes Streichquartett in Vitrinen; Arditti String Quartet. &#220;bertragung aus dem Theatersaal<\/p>\n<p style=\"padding-left: 40px;\">Ab ca. 21.30 Uhr:<br \/>\nAndreas Dohmen: FPP I (le\u00e7ons du mardi) f&#252;r E-Gitarre; Yaron Deutsch, E-Gitarre; Christopher Trapani Patch, Implementation \/ Francesca Verunelli: In margine f&#252;r Streichorchester; Ensemble Resonanz, Leitung: Friederike Scheunchen. &#220;bertragung aus dem Festsaal des Saalbaus<\/p>\n<p>22:30:00 +++ &#214;1<br \/>\n<strong>Fats Waller zum 120. Geburtstag<\/strong><\/p>\n<h2><a name=\"_Toc164855369\"><\/a><\/h2>\n<hr \/>\n<h2>sa \u2013 04.05.2024<\/h2>\n<hr \/>\n<p>00:05:00 +++ &#214;1<br \/>\n<strong>(Fortsetzung). Fats Waller zum 120. Geburtstag<\/strong><\/p>\n<p>08:05 bis 09:00 +++ Bayern 2<br \/>\n<strong>Bayern 2 Bayerisches Feuilleton: Zum 100. Geburtstag von Otto Gr&#252;nmandl \u2013 Die Tiroler Antiautorit&#228;t<\/strong><\/p>\n<p>18:05 bis 19:00 +++ Deutschlandfunk Kultur<br \/>\n<strong>\u201eDie Sprache geht verloren, die Seele bleibt!\u201c \u2013 Der Sound von Dersim \u2013 Von Fritz Sch&#252;tte<\/strong><\/p>\n<p style=\"padding-left: 40px;\">Regie: Iris Dr&#246;gekamp. Mit: Tim Seyfi und Ilknur Bahad\u00fdr. Ton und Technik: Boris Kellenbenz und Claudia Peycke. Produktion: SWR 2023. L&#228;nge: 52\u201945<\/p>\n<p style=\"padding-left: 40px;\">Dersim ist auf keiner Landkarte mehr zu finden. Schon 1937 hat man die Region umbenannt. Der Sound lebt weiter \u2212 in der Diaspora. Eine Spurensuche von Fritz Sch&#252;tte. Alles schwingt, alles ist heilig, sagen Einwohner &#252;ber die Landschaft von Dersim in der T&#252;rkei. Die t&#252;rkische Provinz z&#228;hlt zu den bev&#246;lkerungs&#228;rmsten des Landes, die meisten Einwohner sind ins Exil gegangen, fahren nur noch zu Besuch hin. Allein in Deutschland sollen 300.000 von ihnen leben. Mitgenommen haben sie die naturverbundene Weltsicht der Aleviten, die kurdische Sprache und ihre Musik: uralte Melodien und Instrumente, neuzeitliche Adaptionen. Fritz Sch&#252;tte hat sich auf die Suche nach dem \u201eDersim-Sound\u201c gemacht: bei kurdischen Musikern, aber auch in einem Kreuzberger Zeitschriftenladen, wo ein junger Mann die ganze musikalische Bandbreite Dersims auf CDs verkauft, und im Gespr&#228;ch mit dem Musikwissenschaftler Martin Greve. Die behutsame Begegnung des Autors mit einem Netzwerk aus Musik und Kultur, Sprache und Religion, Geschichte und Politik l&#228;sst schlie&#223;lich auch die Frage nach einem eigenen kurdischen Staat nicht aus \u2212 \u201eund umfasse er nur einen kleinen Stein\u201c, wie der Musiker Ali Baran aus Karlsruhe anmerkt. Bis dahin bieten ihm seine ann&#228;hernd 1.000 Kassetten ein St&#252;ck Heimat.<\/p>\n<p style=\"padding-left: 40px;\">Empfehlung: In ihrem St&#252;ck \u201eDas ist meine Geschichte. Uns gibt es!\u201c untersucht die kurdisch-deutsch-schwedische Filmemacherin G&#252;lseren Sengezer das kollektive Sprachtrauma vieler Kurdinnen und Kurden, die gezwungen sind, ihre Sprache und Identit&#228;t zu leugnen.<\/p>\n<p style=\"padding-left: 40px;\">Fritz Sch&#252;tte, 1958 in Hamburg geboren, hat Romanistik und Journalismus an der Universit&#228;t M&#252;nchen studiert. Seit 1993 lebt er als freier Rundfunkautor in Berlin. Zuletzt hat er f&#252;r Deutschlandfunk Kultur in der Sendung \u201eNachspiel\u201c die Features \u201eBreakdance wird olympisch\u201c (2023) und \u201eTanz den Balkan\u201c (2023) produziert.<\/p>\n<p>18:20 \u2013 19:00 UHR +++ SWR Kultur Jazz<br \/>\n<strong>Piep, Piep, Piep \u2013 V&#246;gel inspirieren den Jazz<\/strong><\/p>\n<p>23:00 bis 00:00 +++ hr2-kultur<br \/>\n<strong>The Artist\u2019s Corner | Peter E&#246;tv&#246;s in Darmstadt<\/strong><\/p>\n<p style=\"padding-left: 40px;\">Eine Sendung von J&#252;rgen Otten. Der ungarische Komponist und Dirigent Peter E&#246;tv&#246;s ist tot. Am 24. M&#228;rz starb er, der intensiv mit der Musikszene in Deutschland verbunden war, im Alter von 80 Jahren in Budapest. Aus diesem traurigen Anlass erinnert hr2-kultur in seinem Programm mit der Wiederholung einer hr2-Sendung zur Pr&#228;senz E&#246;tv&#246;s\u2019 bei den Darmst&#228;dter Ferienkursen.<\/p>\n<hr \/>\n<h2><a name=\"_Toc164855370\"><\/a>so \u2013 05.05.2024<\/h2>\n<hr \/>\n<p>14:00 bis 15:05 +++ hr2-kultur<br \/>\n<strong>H&#246;rspiel | \u201eDas Labyrinth\u201c von Ingeborg Drewitz \u2013 Flucht aus der DDR durch die Kanalisation<\/strong><\/p>\n<p style=\"padding-left: 40px;\">Ein Ingenieur und das M&#228;dchen Ulrike, die der gemeinsame Wille zur Flucht aus der DDR zusammengef&#252;hrt hat, nehmen das Wagnis auf sich, durch die Kanalisation den Weg in die Freiheit zu suchen.<\/p>\n<p style=\"padding-left: 40px;\">Auf den Mann warten dr&#252;ben Frau und Kinder, das M&#228;dchen m&#246;chte sich den Schinkanen entziehen, denen es als Pfarrerstochter in einer Ost-Berliner Fabrik ausgesetzt ist. Aber selbst an der unterirdischen Grenze finden die beiden den Weg in die Freiheit durch ein Stacheldrahtverhau gesperrt. Schon ist die Volkspolizei ihnen auf der Spur und bewacht die Kanalisation, die beiden Fl&#252;chtlinge aber irren durch das Labyrinth, das sie gefangen h&#228;lt.<\/p>\n<p>17:10:00 +++ &#214;1<br \/>\n<strong>Jazzpianistin und S&#228;ngerin Shirley Horn<\/strong><\/p>\n<p>22:03 \u2013 22:00 UHR +++ SWR Kultur Jazztime<br \/>\n<strong>Low Down Groove \u2013 Die Tuba im Jazz<\/strong><\/p>\n<p>23:00 bis 00:00 +++ radio3<br \/>\n<strong>Late Night Jazz: Jazzahead: Tobias Meinhart \u2013 The Painter<\/strong><\/p>\n<p>23:03 bis 00:00 +++ Bayern 2<br \/>\n<strong>Bayern 2 Nachtmix: Popcast \u2013 Neue Musik aus Deutschland<\/strong><\/p>\n<p style=\"padding-left: 40px;\">Mit Mit Ralf Summer. Rock, Pop, Hip-Hop, Electro: jeder Monat beginnt mit einem Schlaglicht auf die Studios und Clubs zwischen Kiel und Weilheim. Der Z&#252;ndfunk und das Goethe-Institut pr&#228;sentieren gemeinsam Neues abseits der Charts. Qualit&#228;ts-Pop made in Germany.<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Die%20erweiterte%20Radiowoche%20vom%2029.04.2024%20bis%2005.05.2024 https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2024%2F04%2F28%2Fdie-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Die%20erweiterte%20Radiowoche%20vom%2029.04.2024%20bis%2005.05.2024 https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2024%2F04%2F28%2Fdie-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2024%2F04%2F28%2Fdie-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Die%20erweiterte%20Radiowoche%20vom%2029.04.2024%20bis%2005.05.2024%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2024%2F04%2F28%2Fdie-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2024%2F04%2F28%2Fdie-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Ein kleiner Blick in die Radiowoche 18. Die &#220;bersicht zum Download als PDF. Alle Angaben ohne Gew&#228;hr. Hier eine Auswahl. Die vollst&#228;ndige &#220;bersicht gibt es unter JazzZeitung.de mo \u2013 29.04.2024 19:30:00 Uhr +++ &#214;1 S&#228;nger-Gitarrist Vieux Farka Tour\u00e9 und Band bei den INNt&#246;nen 2023 23:03 bis 24:00 Uhr +++ &#214;1&#46;&#46;&#46;<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Die%20erweiterte%20Radiowoche%20vom%2029.04.2024%20bis%2005.05.2024 https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2024%2F04%2F28%2Fdie-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Die%20erweiterte%20Radiowoche%20vom%2029.04.2024%20bis%2005.05.2024 https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2024%2F04%2F28%2Fdie-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2024%2F04%2F28%2Fdie-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Die%20erweiterte%20Radiowoche%20vom%2029.04.2024%20bis%2005.05.2024%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2024%2F04%2F28%2Fdie-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2024%2F04%2F28%2Fdie-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"author":1,"featured_media":24784,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[14853],"tags":[],"class_list":["post-28597","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-radiomedien"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die erweiterte Radiowoche vom 29.04.2024 bis 05.05.2024 &#8211; Bad Blog Of Musick - nmz Klassik-Blog<\/title>\n<meta name=\"description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/04\/28\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die erweiterte Radiowoche vom 29.04.2024 bis 05.05.2024 &#8211; Bad Blog Of Musick - nmz Klassik-Blog\" \/>\n<meta property=\"og:description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.nmz.de\/badblog\/2024\/04\/28\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Bad Blog Of Musick\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/musikzeitung\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/hufner\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-28T12:00:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2021\/09\/radiowoche2021_gesamt.jpg?fit=2200%2C1458&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"2200\" \/>\n\t<meta property=\"og:image:height\" content=\"1458\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Martin Hufner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@huflaikhan\" \/>\n<meta name=\"twitter:site\" content=\"@musikzeitung\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin Hufner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"13\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2024\\\/04\\\/28\\\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2024\\\/04\\\/28\\\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\\\/\"},\"author\":{\"name\":\"Martin Hufner\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/488a80049cf0bbc4cce99951ae91c3b9\"},\"headline\":\"Die erweiterte Radiowoche vom 29.04.2024 bis 05.05.2024\",\"datePublished\":\"2024-04-28T12:00:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2024\\\/04\\\/28\\\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\\\/\"},\"wordCount\":2265,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2024\\\/04\\\/28\\\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2021\\\/09\\\/radiowoche2021_gesamt.jpg?fit=2200%2C1458&ssl=1\",\"articleSection\":[\"Radio\\\/Medien\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2024\\\/04\\\/28\\\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2024\\\/04\\\/28\\\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\\\/\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2024\\\/04\\\/28\\\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\\\/\",\"name\":\"Die erweiterte Radiowoche vom 29.04.2024 bis 05.05.2024 &#8211; Bad Blog Of Musick - nmz Klassik-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2024\\\/04\\\/28\\\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2024\\\/04\\\/28\\\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2021\\\/09\\\/radiowoche2021_gesamt.jpg?fit=2200%2C1458&ssl=1\",\"datePublished\":\"2024-04-28T12:00:47+00:00\",\"description\":\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2024\\\/04\\\/28\\\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2024\\\/04\\\/28\\\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2024\\\/04\\\/28\\\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2021\\\/09\\\/radiowoche2021_gesamt.jpg?fit=2200%2C1458&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2021\\\/09\\\/radiowoche2021_gesamt.jpg?fit=2200%2C1458&ssl=1\",\"width\":2200,\"height\":1458,\"caption\":\"Im Radio. Foto: Hufner\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2024\\\/04\\\/28\\\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die erweiterte Radiowoche vom 29.04.2024 bis 05.05.2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"name\":\"Bad Blog Of Musick\",\"description\":\"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\",\"name\":\"Bad Blog Of Musick\",\"alternateName\":\"Ein Klassik-Blog zur Musik\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"width\":512,\"height\":512,\"caption\":\"Bad Blog Of Musick\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/musikzeitung\",\"https:\\\/\\\/x.com\\\/musikzeitung\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/488a80049cf0bbc4cce99951ae91c3b9\",\"name\":\"Martin Hufner\",\"description\":\"seit 1997 chef\u00f6konom der kritischen masse und netzbabysitter der nmz.\",\"sameAs\":[\"https:\\\/\\\/www.musikkritik.org\",\"http:\\\/\\\/www.facebook.com\\\/hufner\",\"https:\\\/\\\/www.linkedin.com\\\/profile\\\/view?id=48050869&trk=spm_pic\",\"https:\\\/\\\/x.com\\\/huflaikhan\"],\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die erweiterte Radiowoche vom 29.04.2024 bis 05.05.2024 &#8211; Bad Blog Of Musick - nmz Klassik-Blog","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.nmz.de\/badblog\/2024\/04\/28\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\/","og_locale":"de_DE","og_type":"article","og_title":"Die erweiterte Radiowoche vom 29.04.2024 bis 05.05.2024 &#8211; Bad Blog Of Musick - nmz Klassik-Blog","og_description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","og_url":"https:\/\/blogs.nmz.de\/badblog\/2024\/04\/28\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\/","og_site_name":"Bad Blog Of Musick","article_publisher":"https:\/\/www.facebook.com\/musikzeitung","article_author":"http:\/\/www.facebook.com\/hufner","article_published_time":"2024-04-28T12:00:47+00:00","og_image":[{"width":2200,"height":1458,"url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2021\/09\/radiowoche2021_gesamt.jpg?fit=2200%2C1458&ssl=1","type":"image\/jpeg"}],"author":"Martin Hufner","twitter_card":"summary_large_image","twitter_creator":"@huflaikhan","twitter_site":"@musikzeitung","twitter_misc":{"Verfasst von":"Martin Hufner","Gesch\u00e4tzte Lesezeit":"13\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.nmz.de\/badblog\/2024\/04\/28\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\/#article","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2024\/04\/28\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\/"},"author":{"name":"Martin Hufner","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/488a80049cf0bbc4cce99951ae91c3b9"},"headline":"Die erweiterte Radiowoche vom 29.04.2024 bis 05.05.2024","datePublished":"2024-04-28T12:00:47+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2024\/04\/28\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\/"},"wordCount":2265,"commentCount":0,"publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2024\/04\/28\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2021\/09\/radiowoche2021_gesamt.jpg?fit=2200%2C1458&ssl=1","articleSection":["Radio\/Medien"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.nmz.de\/badblog\/2024\/04\/28\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.nmz.de\/badblog\/2024\/04\/28\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\/","url":"https:\/\/blogs.nmz.de\/badblog\/2024\/04\/28\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\/","name":"Die erweiterte Radiowoche vom 29.04.2024 bis 05.05.2024 &#8211; Bad Blog Of Musick - nmz Klassik-Blog","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2024\/04\/28\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\/#primaryimage"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2024\/04\/28\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2021\/09\/radiowoche2021_gesamt.jpg?fit=2200%2C1458&ssl=1","datePublished":"2024-04-28T12:00:47+00:00","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","breadcrumb":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2024\/04\/28\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.nmz.de\/badblog\/2024\/04\/28\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/2024\/04\/28\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\/#primaryimage","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2021\/09\/radiowoche2021_gesamt.jpg?fit=2200%2C1458&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2021\/09\/radiowoche2021_gesamt.jpg?fit=2200%2C1458&ssl=1","width":2200,"height":1458,"caption":"Im Radio. Foto: Hufner"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.nmz.de\/badblog\/2024\/04\/28\/die-erweiterte-radiowoche-vom-29-04-2024-bis-05-05-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blogs.nmz.de\/badblog\/"},{"@type":"ListItem","position":2,"name":"Die erweiterte Radiowoche vom 29.04.2024 bis 05.05.2024"}]},{"@type":"WebSite","@id":"https:\/\/blogs.nmz.de\/badblog\/#website","url":"https:\/\/blogs.nmz.de\/badblog\/","name":"Bad Blog Of Musick","description":"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur","publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.nmz.de\/badblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blogs.nmz.de\/badblog\/#organization","name":"Bad Blog Of Musick","alternateName":"Ein Klassik-Blog zur Musik","url":"https:\/\/blogs.nmz.de\/badblog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","width":512,"height":512,"caption":"Bad Blog Of Musick"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/musikzeitung","https:\/\/x.com\/musikzeitung"]},{"@type":"Person","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/488a80049cf0bbc4cce99951ae91c3b9","name":"Martin Hufner","description":"seit 1997 chef\u00f6konom der kritischen masse und netzbabysitter der nmz.","sameAs":["https:\/\/www.musikkritik.org","http:\/\/www.facebook.com\/hufner","https:\/\/www.linkedin.com\/profile\/view?id=48050869&trk=spm_pic","https:\/\/x.com\/huflaikhan"],"url":"https:\/\/blogs.nmz.de\/badblog\/author\/admin\/"}]}},"wp-worthy-pixel":{"ignored":true,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2021\/09\/radiowoche2021_gesamt.jpg?fit=2200%2C1458&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/28597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/comments?post=28597"}],"version-history":[{"count":4,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/28597\/revisions"}],"predecessor-version":[{"id":28601,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/28597\/revisions\/28601"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/media\/24784"}],"wp:attachment":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/media?parent=28597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/categories?post=28597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/tags?post=28597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}