{"id":26834,"date":"2023-04-04T16:53:03","date_gmt":"2023-04-04T14:53:03","guid":{"rendered":"https:\/\/blogs.nmz.de\/badblog\/?p=26834"},"modified":"2023-04-04T16:53:03","modified_gmt":"2023-04-04T14:53:03","slug":"kis-und-die-grauen-herren","status":"publish","type":"post","link":"https:\/\/blogs.nmz.de\/badblog\/2023\/04\/04\/kis-und-die-grauen-herren\/","title":{"rendered":"KIs und die grauen Herren"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>KIs und die grauen Herren<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&#220;ber das Thema KI wird jetzt viel geschrieben, und das ist erst der Anfang. Wir befinden uns in einer &#228;hnlichen Situation wie am Anfang des Internets: Damals wurde langsam klar, dass eine riesige Ver&#228;nderung auf uns zukommt. Die Ver&#228;nderungen unseres Alltags durch das Internet wurden erst untersch&#228;tzt (\u201eich brauche doch gar kein Internet\u201c), dann &#252;bersch&#228;tzt (Dotcom-Blase), nun ist es mit all seinen Chancen und Problemen ein unausl&#246;schlicher Teil unseres Alltags geworden. Wir k&#246;nnen uns keine Welt ohne Internet mehr vorstellen. Sehr &#228;hnlich wird es beim Sprung zu k&#252;nstlichen Intelligenzen sein, die uns bei kreativer Arbeit unterst&#252;tzen sollen.<\/p>\n<p>&nbsp;<\/p>\n<p>Dass der Einsatz k&#252;nstlicher Intelligenzen zahllose Jobs nicht nur (aber vor allem) in der Kreativbranche ausl&#246;schen wird, ist ein Thema, das immer mehr in den Fokus r&#252;ckt. Es gibt aber einen Aspekt, &#252;ber den bisher noch nicht geschrieben wird, und das ist der Aspekt, dass mit der Verwendung von KIs bei k&#252;nstlerischer Arbeit ein historisch noch nie dagewesener Paradigmenwechsel stattfindet, dessen Auswirkung auf die menschliche Gesellschaft viel schwieriger einzusch&#228;tzen ist als die reale Gefahr von zunehmender Arbeitslosigkeit durch KIs.<\/p>\n<p>&nbsp;<\/p>\n<p>Kultur und Sprache sind menschliche Errungenschaften, die quasi in der \u201eFreizeit\u201c der ersten menschlichen Gemeinschaften entwickelt wurden, n&#228;mlich in der Zeit, die man nicht mit der Nahrungssuche oder dem nackten &#220;berleben verbrachte. Je besser wir unser &#220;berleben sichern konnten &#8211; zum Beispiel mit Ackerbau und den ersten menschlichen Siedlungen &#8211; desto weniger \u201eZeit\u201c hatten wir aber, obwohl uns jede neue technische Erfindung eigentlich versprach, uns nun Arbeit abzunehmen. Gesellschaften von J&#228;gern und Sammlern haben relativ viel freie Zeit, was unser romantisches Ideal vom \u201eNaturvolk\u201c befeuert. Aber mit der Komplexit&#228;t einer Gesellschaft und des eigenen Anspruchs wachsen auch die Anforderungen, die sie an uns stellt. Eine eigene Wohnung zu haben, dauerhaften Besitz anzuh&#228;ufen, den eigenen Nahrungsvorrat zu verwalten sowie mit Geld zu handeln, hat unser Leben keineswegs einfacher gemacht.<\/p>\n<p>&nbsp;<\/p>\n<p>Anfang des letzten Jahrhunderts war die W&#228;sche von Kleidungsst&#252;cken, das Reinigen der Wohnung oder dass Geschirrsp&#252;len ein extrem zeitaufreibender Prozess, dem viele Stunden am Tag gewidmet werden mussten. Man k&#246;nnte nun meinen, dass Geschirrsp&#252;ler, Waschmaschine und Staubsauger all diese Aufgaben so effizient erf&#252;llen, dass man nun \u201emehr Freizeit\u201c hat. Tats&#228;chlich wurde aber nichts gewonnen, denn trotz dieser technischen Entwicklungen ist das Leben keineswegs weniger stressig geworden, denn mit jeder Erleichterung des Alltags sind neue Herausforderungen hinzugekommen.<\/p>\n<p>&nbsp;<\/p>\n<p>Dennoch kann man eindeutig sagen, dass der Hauptgrund f&#252;r Erfindungen wie Geschirrsp&#252;ler eine <em>Vereinfachung unseres Alltags<\/em> ist. Wir erfinden solche Maschinen und Systeme, weil wir Arbeit abgeben und delegieren wollen, oder weil die dazu ben&#246;tigte Macht (zum Beispiel hunderte von Menschen mit einem Flugzeug tausende von Kilometern in gro&#223;er Geschwindigkeit zu bewegen) unsere menschlichen M&#246;glichkeiten &#252;bersteigt.<\/p>\n<p>&nbsp;<\/p>\n<p>Bisher haben wir also Maschinen vor allem deswegen benutzt, <em>um l&#228;stige oder uns unm&#246;gliche Aufgaben zu erf&#252;llen<\/em>. Das ist \u2013 neben angestrebter milit&#228;rischer &#220;berlegenheit &#8211; der Hauptgrund f&#252;r jede technische Revolution in der Geschichte der Menschheit.<\/p>\n<p>&nbsp;<\/p>\n<p>Oberfl&#228;chlich betrachtet machen KIs &#228;hnliches. Schon lange helfen sie bei der Verkehrssteuerung oder sind als Autopiloten im Einsatz. Und niemand w&#252;rde sich beschweren, wenn sie beim Ausf&#252;llen von l&#228;stigen Steuererkl&#228;rungen oder langweiliger Formulare behilflich sein werden. Doch KI-Anwendungen wie ChatGPT oder DALL-E ersetzen keine l&#228;stigen Arbeit, sondern Arbeit, die urspr&#252;nglich aus einem rein spielerischen k&#252;nstlerischen Impuls entstand: <em>kreative<\/em> Arbeit. Und das ist neu.<\/p>\n<p>&nbsp;<\/p>\n<p>Ja, es gibt eine \u201eKreativbranche\u201c, es gibt Werbetexterinnen und Jinglekomponisten. Kreativit&#228;t wird oft als Dienstleistung beschrieben, und das ist auch wichtig, um zum Beispiel das Urheberrecht zu begr&#252;nden und das &#220;berleben von Urheber:innen zu sichern.<\/p>\n<p>Und ja, k&#252;nstlerische Arbeit ist nicht immer spa&#223;ig und fr&#246;hlich. Sie kann hart und schwei&#223;treibend sein.<\/p>\n<p>&nbsp;<\/p>\n<p>Dennoch kann mir niemand erz&#228;hlen, dass er mit der Pistole gezwungen werden musste, \u201eKomponist\u201c zu werden, genauso wenig wie man Kinder dazu zwingen muss, \u201ekreativ\u201c zu sein. Alle Kinder tragen Kreativit&#228;t als urmenschliche F&#228;higkeit in sich. Sie malen, zeichnen und singen von sich aus, <em>weil es ihnen Spa&#223; macht. <\/em>Menschliche Kreativit&#228;t macht unser Leben lebenswert. Mit Kunst und Kultur erschaffen wir Lebenswert. Mit den Geschichten, die wir erfinden, den Bildern, die wir malen und der Musik, die wir spielen, f&#252;llen wir unsere Freizeit mit Inhalt und k&#246;nnen auf einmalige Weise unsere Existenz kontemplieren oder miteinander kommunizieren. Auch wenn nicht alle Menschen eine k&#252;nstlerische Laufbahn einschlagen: In uns allen schlummert die F&#228;higkeit, sich z.B. eine Geschichte oder einen Witz auszudenken. Und selbst wenn wir dies nicht beruflich tun \u2013 sp&#228;testens bei der n&#228;chsten Hochzeit von Freunden werden wir ein selbstverfasstes Gedicht vortragen oder ein albernes Lied singen. <em>Weil es uns Spa&#223; macht, und weil es anderen Spa&#223; macht.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>Als Musiker geben wir Konzerte nicht nur, weil wir ber&#252;hmt werden und bewundert sein wollen. <em>Es macht uns Spa&#223;.<\/em> Und selbst wenn manche Komponierende von E-Musik gerne zur Schau stellen, wie wahnsinnig sie bei der Produktion ihrer St&#252;cke leiden \u2013 h&#228;tten sie diesen Beruf je ergriffen, wenn ihnen das Komponieren <em>keinen Spa&#223; machen w&#252;rde<\/em>? Ganz sicher nicht.<\/p>\n<p>Und das ist das, was ich vorher mit dem Begriff \u201eParadigmenwechsel\u201c meinte. Zum ersten Mal in der Geschichte lassen wir uns etwas abnehmen, das keineswegs eine l&#228;stige Arbeit ist, sondern etwas, das wir <em>gerne<\/em> betreiben und eine essenzielle menschliche Ausdrucksform ist: das Erfinden von Dingen.<\/p>\n<p>Es ist ein gigantischer Unterschied, ob ich ein Notenprogramm z.B. dazu benutze, den Prozess des Notenschreibens (eher l&#228;stig und eine Arbeit, da immer langsamer als die Erfindung selbst) zu vereinfachen. Oder ein Textprogramm, um das Verfassen eines Textes zu beschleunigen. Erfinden muss immer noch ich.<\/p>\n<p>Wenn ich aber nun eine KI damit beauftrage, sich etwas auszudenken, gebe ich quasi das als Arbeit ab, was mein Kerngesch&#228;ft ist, das Allersch&#246;nste und Wunderbarste daran: <em>das Erfinden selbst.<\/em><\/p>\n<p>Nun werden sicherlich einige mit Recht argumentieren, dass ja auch das menschliche Erfinden eine Art algorithmischer Prozess ist, den unser Gehirn vollf&#252;hrt. Hierbei spielen sicherlich auch zuf&#228;llige Assoziationen wie auch unvollst&#228;ndige Erinnerungen eine Rolle. Aber jede kreative Arbeit ist \u2013 und das wei&#223; jeder, der regelm&#228;&#223;ig erfindet \u2013 immer auch ein Selbstfindungsprozess, eine Suche nach der \u201eeigenen\u201c Stimme. Immer wieder wird man dabei von sich selbst &#252;berrascht oder gewinnt neue Erkenntnisse. Die sch&#246;nsten \u201eFlow\u201c-Momente der kreativen Arbeit sind genau solche: wenn man von den eigenen Ideen so &#252;berw&#228;ltigt wird, dass man das Gef&#252;hl hat, dass sich z.B. das St&#252;ck fast \u201evon selbst\u201c schreibt.<\/p>\n<p>Und ausgerechnet diesen Prozess soll ich einer KI anvertrauen? Die Versuchung wird gro&#223; sein. Wie standhaft werden wir sein, wenn eine Deadline droht und uns nichts \u201eeinf&#228;llt\u201c? Wie lange noch, bis man bei Kompositionswettbewerben die St&#252;cke m&#252;hsam heraussuchen muss, die komplett ohne menschliches Zutun entstanden sind, einfach weil die KIs immer perfekter werden, bestehende Stile zu kopieren?<\/p>\n<p>Sicherlich wird es auch interessante Nutzungen geben, bei denen man KIs zur Erweiterung kompositorischer Konzepte verwendet. Einer der Gr&#252;nde, warum ein Ligeti nicht endlos St&#252;cke wie zum Beispiel \u201eLontano\u201c schrieb ist simple Schreibarbeit \u2013 die komplexe Mikropolyphonie war beim Komponieren extrem zeitraubend und ich kann mir vorstellen, dass ihn diese Prozesse irgendwann langweilten. Was w&#228;re nun, wenn mir polyphone Klangwolken quasi auf Knopfdruck endlos zur Verf&#252;gung st&#252;nden? In der zeitgen&#246;ssischen Musik drohen uns daher sicherlich zunehmend \u201eKonzeptst&#252;cke\u201c, die nur noch aus Ideen bestehen, die dann von KIs realisiert werden, ohne dass ein einziger Ton selbst gefunden werden muss. Das Sch&#246;ne beim Finden von T&#246;nen ist aber, dass es wie beim Pilzesuchen im Wald ist: man stolpert dabei, findet Unvorhergesehenes oder verl&#228;uft sich. Genau das ist das Sch&#246;ne daran, nicht die Perfektion der Umsetzung einer einzelnen Idee. Eine gute Komposition besteht aus mehreren Ideen und Konzepten, und wir folgen einer interessanten Pers&#246;nlichkeit, die damit jongliert.<\/p>\n<p>Werden wir irgendwann zu faul werden, kreativ zu sein? Werden wir uns damit zufrieden geben, dass uns KIs Schlaflieder f&#252;r unsere Kinder erfinden oder immer und &#252;berall zur Stelle sind, wenn wir einen Text, eine Musik oder ein Bild brauchen? F&#252;r was benutzen wir dann die \u201egewonnene\u201c Zeit? Oder sind wir wie die grauen Herren in Michael Endes \u201eMomo\u201c dazu verdammt, immer mehr zu Sklaven unserer eigenen Sehnsucht nach Zeitersparnis zu werden? Und ausgerechnet auf den Akt verzichten, der unser Leben lebenswert macht: n&#228;mlich die F&#228;higkeit, sich etwas Beliebiges auszudenken, zu tr&#228;umen oder einfach nur mit eigenen Ideen zu spielen?<\/p>\n<p>Diese Fragen werden uns in den kommenden Jahrzehnten auf jeden Fall besch&#228;ftigen, so viel ist sicher.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Moritz Eggert<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=KIs%20und%20die%20grauen%20Herren https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2023%2F04%2F04%2Fkis-und-die-grauen-herren%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=KIs%20und%20die%20grauen%20Herren https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2023%2F04%2F04%2Fkis-und-die-grauen-herren%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2023%2F04%2F04%2Fkis-und-die-grauen-herren%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=KIs%20und%20die%20grauen%20Herren%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2023%2F04%2F04%2Fkis-und-die-grauen-herren%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2023%2F04%2F04%2Fkis-und-die-grauen-herren%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>&nbsp; KIs und die grauen Herren &nbsp; &#220;ber das Thema KI wird jetzt viel geschrieben, und das ist erst der Anfang. Wir befinden uns in einer &#228;hnlichen Situation wie am Anfang des Internets: Damals wurde langsam klar, dass eine riesige Ver&#228;nderung auf uns zukommt. Die Ver&#228;nderungen unseres Alltags durch das&#46;&#46;&#46;<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=KIs%20und%20die%20grauen%20Herren https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2023%2F04%2F04%2Fkis-und-die-grauen-herren%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=KIs%20und%20die%20grauen%20Herren https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2023%2F04%2F04%2Fkis-und-die-grauen-herren%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2023%2F04%2F04%2Fkis-und-die-grauen-herren%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=KIs%20und%20die%20grauen%20Herren%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2023%2F04%2F04%2Fkis-und-die-grauen-herren%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2023%2F04%2F04%2Fkis-und-die-grauen-herren%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"author":8,"featured_media":26835,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[14657,29,11372,37],"tags":[8995,24429,24511,24514,249,25,769,14764,480,24513,7331,24512,24515],"class_list":["post-26834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert","category-aesthetik","category-featured","category-marketing","tag-algorithmus","tag-chatgpt","tag-dalle","tag-dotcom-blase","tag-e-musik","tag-gema","tag-internet","tag-ki","tag-komponieren","tag-kreativbranche","tag-kreativitat","tag-kulturgeschichte","tag-kuenstliche-intelligenz"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>KIs und die grauen Herren &#8211; Bad Blog Of Musick - nmz Klassik-Blog<\/title>\n<meta name=\"description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.nmz.de\/badblog\/2023\/04\/04\/kis-und-die-grauen-herren\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KIs und die grauen Herren &#8211; Bad Blog Of Musick - nmz Klassik-Blog\" \/>\n<meta property=\"og:description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.nmz.de\/badblog\/2023\/04\/04\/kis-und-die-grauen-herren\/\" \/>\n<meta property=\"og:site_name\" content=\"Bad Blog Of Musick\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/musikzeitung\" \/>\n<meta property=\"article:author\" content=\"moritz.eggert.79\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-04T14:53:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.nmz.de\/badblog\/files\/2023\/04\/Screenshot-2023-04-04-at-16-51-12-Robot-Pulp-History-in-24-Covers-Dark-Worlds-Quarterly.png\" \/>\n\t<meta property=\"og:image:width\" content=\"816\" \/>\n\t<meta property=\"og:image:height\" content=\"776\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Moritz Eggert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MoritzEggert\" \/>\n<meta name=\"twitter:site\" content=\"@musikzeitung\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Moritz Eggert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2023\\\/04\\\/04\\\/kis-und-die-grauen-herren\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2023\\\/04\\\/04\\\/kis-und-die-grauen-herren\\\/\"},\"author\":{\"name\":\"Moritz Eggert\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/ce88a756dea34f64ceab78df990e3dd4\"},\"headline\":\"KIs und die grauen Herren\",\"datePublished\":\"2023-04-04T14:53:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2023\\\/04\\\/04\\\/kis-und-die-grauen-herren\\\/\"},\"wordCount\":1468,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2023\\\/04\\\/04\\\/kis-und-die-grauen-herren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2023\\\/04\\\/Screenshot-2023-04-04-at-16-51-12-Robot-Pulp-History-in-24-Covers-Dark-Worlds-Quarterly.png?fit=816%2C776&ssl=1\",\"keywords\":[\"Algorithmus\",\"ChatGPT\",\"DallE\",\"Dotcom-Blase\",\"E-Musik\",\"GEMA\",\"internet\",\"KI\",\"Komponieren\",\"Kreativbranche\",\"Kreativit\u00e4t\",\"Kulturgeschichte\",\"K\u00fcnstliche Intelligenz\"],\"articleSection\":{\"1\":\"\u00c4sthetik\",\"2\":\"Featured\",\"3\":\"Marketing\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2023\\\/04\\\/04\\\/kis-und-die-grauen-herren\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2023\\\/04\\\/04\\\/kis-und-die-grauen-herren\\\/\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2023\\\/04\\\/04\\\/kis-und-die-grauen-herren\\\/\",\"name\":\"KIs und die grauen Herren &#8211; Bad Blog Of Musick - nmz Klassik-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2023\\\/04\\\/04\\\/kis-und-die-grauen-herren\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2023\\\/04\\\/04\\\/kis-und-die-grauen-herren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2023\\\/04\\\/Screenshot-2023-04-04-at-16-51-12-Robot-Pulp-History-in-24-Covers-Dark-Worlds-Quarterly.png?fit=816%2C776&ssl=1\",\"datePublished\":\"2023-04-04T14:53:03+00:00\",\"description\":\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2023\\\/04\\\/04\\\/kis-und-die-grauen-herren\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2023\\\/04\\\/04\\\/kis-und-die-grauen-herren\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2023\\\/04\\\/04\\\/kis-und-die-grauen-herren\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2023\\\/04\\\/Screenshot-2023-04-04-at-16-51-12-Robot-Pulp-History-in-24-Covers-Dark-Worlds-Quarterly.png?fit=816%2C776&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2023\\\/04\\\/Screenshot-2023-04-04-at-16-51-12-Robot-Pulp-History-in-24-Covers-Dark-Worlds-Quarterly.png?fit=816%2C776&ssl=1\",\"width\":816,\"height\":776},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2023\\\/04\\\/04\\\/kis-und-die-grauen-herren\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KIs und die grauen Herren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"name\":\"Bad Blog Of Musick\",\"description\":\"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\",\"name\":\"Bad Blog Of Musick\",\"alternateName\":\"Ein Klassik-Blog zur Musik\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"width\":512,\"height\":512,\"caption\":\"Bad Blog Of Musick\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/musikzeitung\",\"https:\\\/\\\/x.com\\\/musikzeitung\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/ce88a756dea34f64ceab78df990e3dd4\",\"name\":\"Moritz Eggert\",\"description\":\"Komponist\",\"sameAs\":[\"http:\\\/\\\/www.moritz-eggert.de\",\"moritz.eggert.79\",\"https:\\\/\\\/x.com\\\/MoritzEggert\"],\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/author\\\/moritzeggert\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KIs und die grauen Herren &#8211; Bad Blog Of Musick - nmz Klassik-Blog","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.nmz.de\/badblog\/2023\/04\/04\/kis-und-die-grauen-herren\/","og_locale":"de_DE","og_type":"article","og_title":"KIs und die grauen Herren &#8211; Bad Blog Of Musick - nmz Klassik-Blog","og_description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","og_url":"https:\/\/blogs.nmz.de\/badblog\/2023\/04\/04\/kis-und-die-grauen-herren\/","og_site_name":"Bad Blog Of Musick","article_publisher":"https:\/\/www.facebook.com\/musikzeitung","article_author":"moritz.eggert.79","article_published_time":"2023-04-04T14:53:03+00:00","og_image":[{"width":816,"height":776,"url":"https:\/\/blogs.nmz.de\/badblog\/files\/2023\/04\/Screenshot-2023-04-04-at-16-51-12-Robot-Pulp-History-in-24-Covers-Dark-Worlds-Quarterly.png","type":"image\/png"}],"author":"Moritz Eggert","twitter_card":"summary_large_image","twitter_creator":"@MoritzEggert","twitter_site":"@musikzeitung","twitter_misc":{"Verfasst von":"Moritz Eggert","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.nmz.de\/badblog\/2023\/04\/04\/kis-und-die-grauen-herren\/#article","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2023\/04\/04\/kis-und-die-grauen-herren\/"},"author":{"name":"Moritz Eggert","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/ce88a756dea34f64ceab78df990e3dd4"},"headline":"KIs und die grauen Herren","datePublished":"2023-04-04T14:53:03+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2023\/04\/04\/kis-und-die-grauen-herren\/"},"wordCount":1468,"commentCount":1,"publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2023\/04\/04\/kis-und-die-grauen-herren\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2023\/04\/Screenshot-2023-04-04-at-16-51-12-Robot-Pulp-History-in-24-Covers-Dark-Worlds-Quarterly.png?fit=816%2C776&ssl=1","keywords":["Algorithmus","ChatGPT","DallE","Dotcom-Blase","E-Musik","GEMA","internet","KI","Komponieren","Kreativbranche","Kreativit\u00e4t","Kulturgeschichte","K\u00fcnstliche Intelligenz"],"articleSection":{"1":"\u00c4sthetik","2":"Featured","3":"Marketing"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.nmz.de\/badblog\/2023\/04\/04\/kis-und-die-grauen-herren\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.nmz.de\/badblog\/2023\/04\/04\/kis-und-die-grauen-herren\/","url":"https:\/\/blogs.nmz.de\/badblog\/2023\/04\/04\/kis-und-die-grauen-herren\/","name":"KIs und die grauen Herren &#8211; Bad Blog Of Musick - nmz Klassik-Blog","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2023\/04\/04\/kis-und-die-grauen-herren\/#primaryimage"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2023\/04\/04\/kis-und-die-grauen-herren\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2023\/04\/Screenshot-2023-04-04-at-16-51-12-Robot-Pulp-History-in-24-Covers-Dark-Worlds-Quarterly.png?fit=816%2C776&ssl=1","datePublished":"2023-04-04T14:53:03+00:00","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","breadcrumb":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2023\/04\/04\/kis-und-die-grauen-herren\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.nmz.de\/badblog\/2023\/04\/04\/kis-und-die-grauen-herren\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/2023\/04\/04\/kis-und-die-grauen-herren\/#primaryimage","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2023\/04\/Screenshot-2023-04-04-at-16-51-12-Robot-Pulp-History-in-24-Covers-Dark-Worlds-Quarterly.png?fit=816%2C776&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2023\/04\/Screenshot-2023-04-04-at-16-51-12-Robot-Pulp-History-in-24-Covers-Dark-Worlds-Quarterly.png?fit=816%2C776&ssl=1","width":816,"height":776},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.nmz.de\/badblog\/2023\/04\/04\/kis-und-die-grauen-herren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blogs.nmz.de\/badblog\/"},{"@type":"ListItem","position":2,"name":"KIs und die grauen Herren"}]},{"@type":"WebSite","@id":"https:\/\/blogs.nmz.de\/badblog\/#website","url":"https:\/\/blogs.nmz.de\/badblog\/","name":"Bad Blog Of Musick","description":"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur","publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.nmz.de\/badblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blogs.nmz.de\/badblog\/#organization","name":"Bad Blog Of Musick","alternateName":"Ein Klassik-Blog zur Musik","url":"https:\/\/blogs.nmz.de\/badblog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","width":512,"height":512,"caption":"Bad Blog Of Musick"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/musikzeitung","https:\/\/x.com\/musikzeitung"]},{"@type":"Person","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/ce88a756dea34f64ceab78df990e3dd4","name":"Moritz Eggert","description":"Komponist","sameAs":["http:\/\/www.moritz-eggert.de","moritz.eggert.79","https:\/\/x.com\/MoritzEggert"],"url":"https:\/\/blogs.nmz.de\/badblog\/author\/moritzeggert\/"}]}},"wp-worthy-pixel":{"ignored":false,"public":"384d7cbef10948af933a4b7113741747","server":"vg04.met.vgwort.de","url":"https:\/\/vg04.met.vgwort.de\/na\/384d7cbef10948af933a4b7113741747"},"wp-worthy-type":"normal","jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2023\/04\/Screenshot-2023-04-04-at-16-51-12-Robot-Pulp-History-in-24-Covers-Dark-Worlds-Quarterly.png?fit=816%2C776&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/26834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/comments?post=26834"}],"version-history":[{"count":1,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/26834\/revisions"}],"predecessor-version":[{"id":26836,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/26834\/revisions\/26836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/media\/26835"}],"wp:attachment":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/media?parent=26834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/categories?post=26834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/tags?post=26834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}