{"id":25419,"date":"2022-03-28T15:28:56","date_gmt":"2022-03-28T13:28:56","guid":{"rendered":"https:\/\/blogs.nmz.de\/badblog\/?p=25419"},"modified":"2022-03-28T15:28:56","modified_gmt":"2022-03-28T13:28:56","slug":"brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr","status":"publish","type":"post","link":"https:\/\/blogs.nmz.de\/badblog\/2022\/03\/28\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\/","title":{"rendered":"BRSO braucht sehr wohl ein gut ausgestattetes Konzerthaus, aber auch nicht mehr"},"content":{"rendered":"<p>Die Diskussion um das Konzerthaus f&#252;r das Sinfonieorchester des Bayerischen Rundfunks (BRSO) geht nun in seine n&#228;chste Wahlkampf-Phase. Zur letzten Landtagswahl vor 4 Jahren sollte es erst per Wei&#223;wurstessen zwischen dem damaligen Ministerpr&#228;sident Horst Seehofer und dem M&#252;nchener Oberb&#252;rgermeister Dieter Reiter zu s&#252;&#223;en Senf eingestampft werden. Dann rutschte es aus dem Fokus der Innenstadtlage ins Werksviertel am Ostbahnhof, analog inspiriert zur Randlage der neuen Pariser Philharmonie. Alle waren happy und Seehofers Nachfolger S&#246;der verlor nicht all zu viele BR-Klassik H&#246;rer:innen an andere Parteien. Dazu klebte ein Architekt einen Plastikzapfen auf einen Karton und man hatte das gr&#246;&#223;te Glashaus der bayerischen Hemisph&#228;re in Aussicht gestellt. Das Problem: \u201eaufregende\u201c Architektur. In Sachen Akustik und Finanzierung nur Unbekanntes. Als Gegenst&#252;ck nun die akustisch passable, nicht ganz geeignete, enge Isarphilharmonie, immerhin spottbillig.<\/p>\n<p>Jetzt ist im Gegensatz zum letzten Wahlkampf \u201eSparkurs\u201c en vogue, nachdem man am Anfang der Pandemie den \u201eKeingeldkurs\u201c f&#252;r die Kulturszene, insbesondere die Freie Szene gefahren ist und dann urpl&#246;tzlich doch auch die Wahlklientel \u201eK&#252;nstler:innen\u201c entdeckte und ihre n&#246;rgelnde Multiplikatoren-Eigenschaft mit dann ordentlich viel Geld neutralisieren konnte. Jetzt redet man davon, dass mit einem aufgeschobenem Konzerthaus-Projekt der Kunstszene noch mehr geholfen w&#228;re. Autsch!<\/p>\n<p>Auf der anderen Seite der Bayerische Rundfunk. Der fordert seit Jahren das neue Konzerthaus. Und wird wohl allein bei der Grundsteinlegung vielleicht einen Euro f&#252;r die Grundsteinkapsel ausgeben statt die Spendeneinsammelbauchl&#228;den samt Werbetrommel sich umzuh&#228;ngen. Dann haben wir Stars wie Anne Sophie Mutter, die von Wohnzimmer und Sofa in Bezug auf das Konzerthaus-Projekt spricht. Alles ein wenig nebul&#246;s und eher kein ermunterndes Zeichen, S&#246;der ernsthaft zu widersprechen.<\/p>\n<p>Die L&#246;sung ist nun angeblich eine \u201emodifizierte Isarphilharmonie\u201c. Zugegeben: sie h&#228;tte die richtige Gr&#246;&#223;e f&#252;r das Publikum. Allerdings haben wir hier das Problem, dass die jetzt noch sehr brauchbare Ausstattung doch so wirkt, dass sie nach f&#252;nf Jahren ziemlich abgenutzt erscheinen wird. Auch der Charme der industriellen Vornutzung des Areals wird verfliegen, wenn zum hunderttausendsten Male jemand &#252;ber alte Schienen gestolpert sein wird oder von den Rangpl&#228;tzen durch die Drahtgitter auf das Podium geblickt haben wird.<\/p>\n<p>Es bleibt zudem f&#252;r das BRSO beengt, egal ob im Backstage des Herkulessaals oder in der Isarphilharmonie. Und die renovierte Philharmonie am Gasteig wird vorzugsweise Heimst&#228;tte der M&#252;nchener Philharmoniker sein. Wenn wir Gl&#252;ck haben, wird die neue Gasteig-Akustik dann auch f&#252;r Mahler, Bruckner, Sch&#246;nberg, Prokoffief und Co. wirklich geeignet sein. Denn die der Isarphilharmonie ist es nicht! Bei Fortissimo f&#228;ngt es an akustisch verzerrt zu sein und erzeugt die im Forte einer gro&#223;romantischen Riesenbesetzung einen &#220;berdruck auf den Ohren, der durchaus unangenehm wirkt. Bis hin zu einem schlanken Brahms, nicht aufgemotzt bis zu 16 ersten Geigen, ist der Saal allerdings sehr fein.<\/p>\n<p>Eine Modifizierung m&#252;sste daher auch die Akustik betreffen. Zugleich auch den Platz im Backstage -Bereich. Zwar w&#252;rden dann Stadtb&#252;cherei und VHS auch wieder in den Gasteig zur&#252;ckwandern und viel Platz f&#252;r Umbauten frei. Neben der Vergr&#246;&#223;erung der Akustik br&#228;uchte es dann noch ein besseres D&#228;mmungskonzept. Denn man h&#246;rt doch auch ein LKW-Brummen, wenn einer in der N&#228;he seinen Motor laufen l&#228;sst wie zuletzt z.B. beim Auftritt von Manfred Honeck mit Bruckners Achter. Das mag f&#252;r manchen den Charme eines Theatre des Champs-Elysees haben, wenn man die Metro rumpeln h&#246;rt, nun denn. Und wenn die Landeshauptstadt ihren Interim-Gasteig wieder am Gasteig selbst hat, wird die jetzige Verdichtung der provisorischen Verkehrsanbindung in Teilen entfallen.<\/p>\n<p>Das zeigt uns: auch eine modifizierte Isarphilharmonie ist nicht unbedingt der Idealfall, der er sein k&#246;nnte. Der Saal begeistert akustisch, weil er ein Erleben bietet, das wir hier mit der Gasteig-Philharmonie bei \u201eBrahms abw&#228;rts\u201c nicht hatten. Bei \u201eBrahms aufw&#228;rts\u201c war die Gasteig-Philharmonie allerdings bei gro&#223;en Besetzungen ohne Solo-Instrumente sehr gut, abgesehen von den Koordinationsproblemen auf dem Podium. Gasteig wie Werksviertel sind zudem im Gegensatz zur Isarphilharmonie hervorragend an den &#246;ffentlichen Nahverkehr angebunden und lassen die H&#246;rerschaft aus den Landkreisen direkt mit der S-Bahn heimgondeln, derweil man jetzt erst einmal mit U-Bahnen via ca. f&#252;nf Stationen das Stadtzentrum erreichen muss, um dann heimreisen zu k&#246;nnen. Man mu&#223; doch etliches mehr an Zeit investieren, um dort hinzukommen. Das kann man nat&#252;rlich mit Shuttles l&#246;sen bzw. U-Bahn und Busse auch nach der Interimszeit verbessert beibehalten. Doch muss die Akustik und Beengtheit dauerhaft bereinigt werden, ein Nutzungskonzept her, das aber eben auch nach den &#246;rtlichen Gegebenheiten &#252;berhaupt m&#246;glich w&#228;re. Das ist nicht ausgeschlossen, erfordert aber wirklich ernsthaften Willen, den dazu Staat und BR bisher nicht zeigen.<\/p>\n<p>Wenn dann doch im Werksviertel ein Neubau erfolgen w&#252;rde, sieht man an der Isarphilharmonie, wie g&#252;nstig das Eigentliche, eine sehr gute Akustik f&#252;r gewisse Koordinaten zu haben w&#228;re. Wenn man auf alles Spektakul&#228;re an Architektur verzichten w&#252;rde, unn&#246;tige Experimente im Konzertsaal f&#252;r das Publikum und schlicht auf eine \u201eSchuhschachtel\u201c wie den Konzertverein in Wien oder in Luzern setzen w&#252;rde, k&#246;nnte man mit weniger Geld zurechtkommen. Vielleicht sollte man auch weitere Konzepte mit weiteren S&#228;len f&#252;r weitere edukatorische Partner wie die Musikhochschule, die ja auch bei einer weiterbetriebenen Isarphilharmonie und einem neuen Gasteig sowieso mit dabei w&#228;re, einfach sein lassen. Die Konzentration auf das Wesentliche: ein ordentlicher Konzertsaal f&#252;r das BRSO. Nicht mehr, nicht weniger.<\/p>\n<p>Es gilt also abzuw&#228;gen, ob und wie man die Isarphilharmonie wirklich dauerhaft f&#252;r das BRSO und weitere Nutzer:innen anpassen kann. Wie man das mit dem Verkehr, dem Platzbedarf und der Akustik \u201everstetigt\u201c. Wenn das nicht geht, dann w&#228;re ein schlichter Neubau im Werksviertel tats&#228;chlich eine sinnvolle und unbedingt notwendige Ma&#223;nahme. Es bleibt allerdings auch eine weitere Alternative: den Herkulessaal ert&#252;chtigen und das Platzproblem dort angehen mit einem Auszug der Akademie der Wissenschaften, ein Neudenken von versenkten R&#228;umen unter Parkpl&#228;tzen oder Gartenanlagen: was den Parisern mit der Pyramide im Louvre gelang, k&#246;nnte doch auch hier in Verbund von Denkmalschutz und Innovation gelingen. Man m&#252;&#223;te nur wollen, das vielleicht auch gesetzlich anpassen, wenn es nicht anders geht. Denn Kultur ist kein Museum, Kultur ist immer auch Wandel. Hier: endlich ehrlich die Finanzierungen und Perspektiven auf den Tisch legen und nicht nur Wei&#223;wurstessenwahlk&#228;mpfe zu Landtags- oder Kommunalwahlen veranstalten sowie als BR genauso ehrlich die Finanzierung mit angehen. Oder das alte Gel&#228;nde in der Innenstadt nicht weiter verscherbeln wollen, sondern dort den Konzertsaal im Verbund mit Spenden, Stadt und Staat neu errichten. Es ist zu vieles zu unehrlich oder sinnlos ambitioniert: Akustik ist wichtig, Fassadenschnickschnack ist Bullshit.<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=BRSO%20braucht%20sehr%20wohl%20ein%20gut%20ausgestattetes%20Konzerthaus%2C%20aber%20auch%20nicht%20mehr https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2022%2F03%2F28%2Fbrso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=BRSO%20braucht%20sehr%20wohl%20ein%20gut%20ausgestattetes%20Konzerthaus%2C%20aber%20auch%20nicht%20mehr https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2022%2F03%2F28%2Fbrso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2022%2F03%2F28%2Fbrso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=BRSO%20braucht%20sehr%20wohl%20ein%20gut%20ausgestattetes%20Konzerthaus%2C%20aber%20auch%20nicht%20mehr%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2022%2F03%2F28%2Fbrso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2022%2F03%2F28%2Fbrso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Die Diskussion um das Konzerthaus f&#252;r das Sinfonieorchester des Bayerischen Rundfunks (BRSO) geht nun in seine n&#228;chste Wahlkampf-Phase. Zur letzten Landtagswahl vor 4 Jahren sollte es erst per Wei&#223;wurstessen zwischen dem damaligen Ministerpr&#228;sident Horst Seehofer und dem M&#252;nchener Oberb&#252;rgermeister Dieter Reiter zu s&#252;&#223;en Senf eingestampft werden. Dann rutschte es aus&#46;&#46;&#46;<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=BRSO%20braucht%20sehr%20wohl%20ein%20gut%20ausgestattetes%20Konzerthaus%2C%20aber%20auch%20nicht%20mehr https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2022%2F03%2F28%2Fbrso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=BRSO%20braucht%20sehr%20wohl%20ein%20gut%20ausgestattetes%20Konzerthaus%2C%20aber%20auch%20nicht%20mehr https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2022%2F03%2F28%2Fbrso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2022%2F03%2F28%2Fbrso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=BRSO%20braucht%20sehr%20wohl%20ein%20gut%20ausgestattetes%20Konzerthaus%2C%20aber%20auch%20nicht%20mehr%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2022%2F03%2F28%2Fbrso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2022%2F03%2F28%2Fbrso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"author":31,"featured_media":10681,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[14657,29,2892,11372,385,266,8381],"tags":[],"class_list":["post-25419","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert","category-aesthetik","category-deutsch","category-featured","category-kultur","category-kulturpolitik","category-sprache"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BRSO braucht sehr wohl ein gut ausgestattetes Konzerthaus, aber auch nicht mehr &#8211; Bad Blog Of Musick - nmz Klassik-Blog<\/title>\n<meta name=\"description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.nmz.de\/badblog\/2022\/03\/28\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BRSO braucht sehr wohl ein gut ausgestattetes Konzerthaus, aber auch nicht mehr &#8211; Bad Blog Of Musick - nmz Klassik-Blog\" \/>\n<meta property=\"og:description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.nmz.de\/badblog\/2022\/03\/28\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\/\" \/>\n<meta property=\"og:site_name\" content=\"Bad Blog Of Musick\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/musikzeitung\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-28T13:28:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.nmz.de\/badblog\/files\/2014\/07\/badboy_gaelic.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alexander Strauch\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@musikzeitung\" \/>\n<meta name=\"twitter:site\" content=\"@musikzeitung\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexander Strauch\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2022\\\/03\\\/28\\\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2022\\\/03\\\/28\\\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\\\/\"},\"author\":{\"name\":\"Alexander Strauch\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/73d6c9ef0d58ae670a7d6f9affe7259c\"},\"headline\":\"BRSO braucht sehr wohl ein gut ausgestattetes Konzerthaus, aber auch nicht mehr\",\"datePublished\":\"2022-03-28T13:28:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2022\\\/03\\\/28\\\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\\\/\"},\"wordCount\":1128,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2022\\\/03\\\/28\\\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2014\\\/07\\\/badboy_gaelic.jpg?fit=640%2C480&ssl=1\",\"articleSection\":{\"1\":\"\u00c4sthetik\",\"2\":\"Deutsch\",\"3\":\"Featured\",\"4\":\"Kultur\",\"5\":\"kulturpolitik\",\"6\":\"Sprache\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2022\\\/03\\\/28\\\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2022\\\/03\\\/28\\\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\\\/\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2022\\\/03\\\/28\\\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\\\/\",\"name\":\"BRSO braucht sehr wohl ein gut ausgestattetes Konzerthaus, aber auch nicht mehr &#8211; Bad Blog Of Musick - nmz Klassik-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2022\\\/03\\\/28\\\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2022\\\/03\\\/28\\\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2014\\\/07\\\/badboy_gaelic.jpg?fit=640%2C480&ssl=1\",\"datePublished\":\"2022-03-28T13:28:56+00:00\",\"description\":\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2022\\\/03\\\/28\\\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2022\\\/03\\\/28\\\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2022\\\/03\\\/28\\\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2014\\\/07\\\/badboy_gaelic.jpg?fit=640%2C480&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2014\\\/07\\\/badboy_gaelic.jpg?fit=640%2C480&ssl=1\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2022\\\/03\\\/28\\\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BRSO braucht sehr wohl ein gut ausgestattetes Konzerthaus, aber auch nicht mehr\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"name\":\"Bad Blog Of Musick\",\"description\":\"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\",\"name\":\"Bad Blog Of Musick\",\"alternateName\":\"Ein Klassik-Blog zur Musik\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"width\":512,\"height\":512,\"caption\":\"Bad Blog Of Musick\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/musikzeitung\",\"https:\\\/\\\/x.com\\\/musikzeitung\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/73d6c9ef0d58ae670a7d6f9affe7259c\",\"name\":\"Alexander Strauch\",\"description\":\"Komponist*in\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/author\\\/querstand\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BRSO braucht sehr wohl ein gut ausgestattetes Konzerthaus, aber auch nicht mehr &#8211; Bad Blog Of Musick - nmz Klassik-Blog","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.nmz.de\/badblog\/2022\/03\/28\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\/","og_locale":"de_DE","og_type":"article","og_title":"BRSO braucht sehr wohl ein gut ausgestattetes Konzerthaus, aber auch nicht mehr &#8211; Bad Blog Of Musick - nmz Klassik-Blog","og_description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","og_url":"https:\/\/blogs.nmz.de\/badblog\/2022\/03\/28\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\/","og_site_name":"Bad Blog Of Musick","article_publisher":"https:\/\/www.facebook.com\/musikzeitung","article_published_time":"2022-03-28T13:28:56+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/blogs.nmz.de\/badblog\/files\/2014\/07\/badboy_gaelic.jpg","type":"image\/jpeg"}],"author":"Alexander Strauch","twitter_card":"summary_large_image","twitter_creator":"@musikzeitung","twitter_site":"@musikzeitung","twitter_misc":{"Verfasst von":"Alexander Strauch","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.nmz.de\/badblog\/2022\/03\/28\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\/#article","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2022\/03\/28\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\/"},"author":{"name":"Alexander Strauch","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/73d6c9ef0d58ae670a7d6f9affe7259c"},"headline":"BRSO braucht sehr wohl ein gut ausgestattetes Konzerthaus, aber auch nicht mehr","datePublished":"2022-03-28T13:28:56+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2022\/03\/28\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\/"},"wordCount":1128,"commentCount":0,"publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2022\/03\/28\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2014\/07\/badboy_gaelic.jpg?fit=640%2C480&ssl=1","articleSection":{"1":"\u00c4sthetik","2":"Deutsch","3":"Featured","4":"Kultur","5":"kulturpolitik","6":"Sprache"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.nmz.de\/badblog\/2022\/03\/28\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.nmz.de\/badblog\/2022\/03\/28\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\/","url":"https:\/\/blogs.nmz.de\/badblog\/2022\/03\/28\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\/","name":"BRSO braucht sehr wohl ein gut ausgestattetes Konzerthaus, aber auch nicht mehr &#8211; Bad Blog Of Musick - nmz Klassik-Blog","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2022\/03\/28\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\/#primaryimage"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2022\/03\/28\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2014\/07\/badboy_gaelic.jpg?fit=640%2C480&ssl=1","datePublished":"2022-03-28T13:28:56+00:00","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","breadcrumb":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2022\/03\/28\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.nmz.de\/badblog\/2022\/03\/28\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/2022\/03\/28\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\/#primaryimage","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2014\/07\/badboy_gaelic.jpg?fit=640%2C480&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2014\/07\/badboy_gaelic.jpg?fit=640%2C480&ssl=1","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.nmz.de\/badblog\/2022\/03\/28\/brso-braucht-sehr-wohl-ein-gut-ausgestattetes-konzerthaus-aber-auch-nicht-mehr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blogs.nmz.de\/badblog\/"},{"@type":"ListItem","position":2,"name":"BRSO braucht sehr wohl ein gut ausgestattetes Konzerthaus, aber auch nicht mehr"}]},{"@type":"WebSite","@id":"https:\/\/blogs.nmz.de\/badblog\/#website","url":"https:\/\/blogs.nmz.de\/badblog\/","name":"Bad Blog Of Musick","description":"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur","publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.nmz.de\/badblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blogs.nmz.de\/badblog\/#organization","name":"Bad Blog Of Musick","alternateName":"Ein Klassik-Blog zur Musik","url":"https:\/\/blogs.nmz.de\/badblog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","width":512,"height":512,"caption":"Bad Blog Of Musick"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/musikzeitung","https:\/\/x.com\/musikzeitung"]},{"@type":"Person","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/73d6c9ef0d58ae670a7d6f9affe7259c","name":"Alexander Strauch","description":"Komponist*in","url":"https:\/\/blogs.nmz.de\/badblog\/author\/querstand\/"}]}},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2014\/07\/badboy_gaelic.jpg?fit=640%2C480&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/25419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/comments?post=25419"}],"version-history":[{"count":1,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/25419\/revisions"}],"predecessor-version":[{"id":25420,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/25419\/revisions\/25420"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/media\/10681"}],"wp:attachment":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/media?parent=25419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/categories?post=25419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/tags?post=25419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}