{"id":24741,"date":"2022-04-26T11:36:55","date_gmt":"2022-04-26T09:36:55","guid":{"rendered":"https:\/\/blogs.nmz.de\/badblog\/?p=24741"},"modified":"2024-07-31T13:01:04","modified_gmt":"2024-07-31T11:01:04","slug":"die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49","status":"publish","type":"post","link":"https:\/\/blogs.nmz.de\/badblog\/2022\/04\/26\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\/","title":{"rendered":"Die schlechtesten Kunstlied-Interpretationen aller Zeiten (Eine Liebeserkl&#228;rung) \u2013 Folge 49"},"content":{"rendered":"<p><span data-mce-type=\"bookmark\" style=\"width: 0px;overflow: hidden;line-height: 0\" class=\"mce_SELRES_start\"><\/span>Die bisherigen Folgen:<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2018\/05\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-1\">Folge 1<\/a> (Diverse, noch ohne Untertitelung)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2018\/06\/05\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-2\/\">Folge 2<\/a> (Diverse, noch ohne Untertitelung)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-3-2\/\">Folge 3<\/a> (Johannes Brahms: Auf dem Schiffe)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-4-2\/\">Folge 4<\/a> (Robert Schumann: Widmung)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-5\/\">Folge 5<\/a> (Robert Schumann: Du Ring an meinem Finger)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-6-2\/\">Folge 6<\/a> (Wolfgang Amadeus Mozart: An Chloe)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-7-2\/\">Folge 7<\/a> (Gustav Mahler: Liebst du um Sch&#246;nheit)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-8-2\/\">Folge 8<\/a> (Hugo Wolf: Schlafendes Jesuskind)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-9-2\/\">Folge 9<\/a> (Franz Schubert: Auf dem Wasser zu singen)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-10-2\/\">Folge 10<\/a> (Robert Schumann: Helft mir, ihr Schwestern)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-11-2\/\">Folge 11<\/a> (Franz Schubert: Der Zwerg)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-12-2\/\">Folge 12 <\/a> (Wolfgang Amadeus Mozart: Die Verschweigung)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-13-2\/\">Folge 13<\/a> (Wolfgang Amadeus Mozart: Der Zauberer)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-14-2\/\">Folge 14<\/a> (Felix Mendelssohn Bartholdy: Hexenlied)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-15-2\/\">Folge 15<\/a> (Johannes Brahms: D&#228;mmrung senkte sich von oben)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-16-2\/\">Folge 16<\/a> (Robert Schumann: Venetianisches Lied I)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-17-2\/\">Folge 17<\/a> (Johannes Brahms: Wie Melodien zieht es mir)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-18-2\/\">Folge 18<\/a> (Robert Schumann: R&#228;tsel)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-19-2\/\">Folge 19<\/a> (Hugo Wolf: Elfenlied)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-20-2\/\">Folge 20<\/a> (Edvard Grieg: Solveigs Lied)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-21-2\/\">Folge 21<\/a> (Johannes Brahms: Ophelia-Lieder)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-22-2\/\">Folge 22<\/a> (Johannes Brahms: Vergebliches St&#228;ndchen)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-23-2\/\">Folge 23<\/a> (Robert Schumann: Mondnacht)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-24-2\/\">Folge 24<\/a> (Franz Schubert: An Sylvia)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-25-2\/\">Folge 25<\/a> (Franz Schubert: Mein)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-26-2\/\">Folge 26<\/a> (Franz Schubert: An die Laute)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-27-2\/\">Folge 27<\/a> (Franz Schubert: Aufenthalt)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-28-2\/\">Folge 28<\/a> (Robert Schumann: In der Fremde)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-29-2\/\">Folge 29<\/a> (Franz Schubert: An die Nachtigall)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-30-2\/\">Folge 30<\/a> (Robert Schumann: Marienw&#252;rmchen)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-31-2\/\">Folge 31<\/a> (Felix Mendelssohn Bartholdy: Auf den Fl&#252;geln des Gesangs)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-32-2\/\">Folge 32<\/a> (Franz Schubert: Die Blumensprache)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2024\/07\/30\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-33-2\/\">Folge 33<\/a> (Johannes Brahms: Die Mainacht)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2021\/03\/01\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-34\/\">Folge 34<\/a> (Richard Strauss: Allerseelen)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2021\/06\/05\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-35\/\">Folge 35<\/a> (Felix Mendelssohn Bartholdy: An die Entfernte)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2021\/07\/13\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-36\/\">Folge 36<\/a> (Robert Schumann: Mein sch&#246;ner Stern)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2021\/08\/01\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-37\/\">Folge 37<\/a> (Franz Schubert: Der Schmetterling)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2021\/08\/31\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-38\/\">Folge 38<\/a> (Franz Schubert: Lachen und Weinen)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2021\/09\/19\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-39\/\">Folge 39<\/a> (Robert Schumann: Die Stille)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2021\/10\/14\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-40\/ \">Folge 40<\/a> (Franz Schubert: Memnon)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2021\/11\/09\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-41\/\">Folge 41<\/a> (Johannes Brahms: O k&#252;hler Wald)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2021\/12\/22\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-42\/\">Folge 42<\/a> (Felix Mendelssohn Bartholdy: Neue Liebe)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2022\/01\/03\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-43\/\">Folge 43<\/a> (Hugo Wolf: Lebe wohl)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2022\/02\/24\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-44\/\">Folge 44<\/a> (Clara Schumann: Er ist gekommen)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2022\/02\/24\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-45\/\">Folge 45<\/a> (Franz Schubert: Nur wer die Sehnsucht kennt)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2022\/03\/08\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-46\/\">Folge 46<\/a> (Richard Strauss: St&#228;ndchen)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2022\/03\/08\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-47\/\">Folge 47<\/a> (Franz Schubert: Die V&#246;gel)<br \/>\n<a href=\"https:\/\/blogs.nmz.de\/badblog\/2022\/03\/28\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-48\/\">Folge 48<\/a> (Robert Schumann: Du bist wie eine Blume)<\/p>\n<div class=\"video-container\"><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/VNUs7qjnK38?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=de-DE&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/div>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Die%20schlechtesten%20Kunstlied-Interpretationen%20aller%20Zeiten%20%28Eine%20Liebeserkl%C3%A4rung%29%20%E2%80%93%20Folge%2049 https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2022%2F04%2F26%2Fdie-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Die%20schlechtesten%20Kunstlied-Interpretationen%20aller%20Zeiten%20%28Eine%20Liebeserkl%C3%A4rung%29%20%E2%80%93%20Folge%2049 https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2022%2F04%2F26%2Fdie-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2022%2F04%2F26%2Fdie-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Die%20schlechtesten%20Kunstlied-Interpretationen%20aller%20Zeiten%20%28Eine%20Liebeserkl%C3%A4rung%29%20%E2%80%93%20Folge%2049%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2022%2F04%2F26%2Fdie-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2022%2F04%2F26%2Fdie-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Die bisherigen Folgen: Folge 1 (Diverse, noch ohne Untertitelung) Folge 2 (Diverse, noch ohne Untertitelung) Folge 3 (Johannes Brahms: Auf dem Schiffe) Folge 4 (Robert Schumann: Widmung) Folge 5 (Robert Schumann: Du Ring an meinem Finger) Folge 6 (Wolfgang Amadeus Mozart: An Chloe) Folge 7 (Gustav Mahler: Liebst du um&#46;&#46;&#46;<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Die%20schlechtesten%20Kunstlied-Interpretationen%20aller%20Zeiten%20%28Eine%20Liebeserkl%C3%A4rung%29%20%E2%80%93%20Folge%2049 https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2022%2F04%2F26%2Fdie-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Die%20schlechtesten%20Kunstlied-Interpretationen%20aller%20Zeiten%20%28Eine%20Liebeserkl%C3%A4rung%29%20%E2%80%93%20Folge%2049 https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2022%2F04%2F26%2Fdie-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2022%2F04%2F26%2Fdie-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Die%20schlechtesten%20Kunstlied-Interpretationen%20aller%20Zeiten%20%28Eine%20Liebeserkl%C3%A4rung%29%20%E2%80%93%20Folge%2049%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2022%2F04%2F26%2Fdie-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2022%2F04%2F26%2Fdie-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"author":4,"featured_media":24739,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[14657,29,2892,11372],"tags":[24037,10,2909,22977,2267],"class_list":["post-24741","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert","category-aesthetik","category-deutsch","category-featured","tag-fanny-hensel","tag-humor","tag-interpretation","tag-kunstlied","tag-lied"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die schlechtesten Kunstlied-Interpretationen aller Zeiten (Eine Liebeserkl\u00e4rung) \u2013 Folge 49 &#8211; Bad Blog Of Musick - nmz Klassik-Blog<\/title>\n<meta name=\"description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.nmz.de\/badblog\/2022\/04\/26\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die schlechtesten Kunstlied-Interpretationen aller Zeiten (Eine Liebeserkl\u00e4rung) \u2013 Folge 49 &#8211; Bad Blog Of Musick - nmz Klassik-Blog\" \/>\n<meta property=\"og:description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.nmz.de\/badblog\/2022\/04\/26\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\/\" \/>\n<meta property=\"og:site_name\" content=\"Bad Blog Of Musick\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/musikzeitung\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-26T09:36:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-31T11:01:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.nmz.de\/badblog\/files\/2021\/09\/Jetzt-eine-Koenigsdusche.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1191\" \/>\n\t<meta property=\"og:image:height\" content=\"661\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arno L\u00fccker\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@musikzeitung\" \/>\n<meta name=\"twitter:site\" content=\"@musikzeitung\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arno L\u00fccker\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2022\\\/04\\\/26\\\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2022\\\/04\\\/26\\\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\\\/\"},\"author\":{\"name\":\"Arno L\u00fccker\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/006319494c6abac7102be470a5b5c092\"},\"headline\":\"Die schlechtesten Kunstlied-Interpretationen aller Zeiten (Eine Liebeserkl&#228;rung) \u2013 Folge 49\",\"datePublished\":\"2022-04-26T09:36:55+00:00\",\"dateModified\":\"2024-07-31T11:01:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2022\\\/04\\\/26\\\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\\\/\"},\"wordCount\":297,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2022\\\/04\\\/26\\\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2021\\\/09\\\/Jetzt-eine-Koenigsdusche.png?fit=1191%2C661&ssl=1\",\"keywords\":[\"Fanny Hensel\",\"Humor\",\"interpretation\",\"Kunstlied\",\"Lied\"],\"articleSection\":{\"1\":\"\u00c4sthetik\",\"2\":\"Deutsch\",\"3\":\"Featured\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2022\\\/04\\\/26\\\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2022\\\/04\\\/26\\\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\\\/\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2022\\\/04\\\/26\\\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\\\/\",\"name\":\"Die schlechtesten Kunstlied-Interpretationen aller Zeiten (Eine Liebeserkl\u00e4rung) \u2013 Folge 49 &#8211; Bad Blog Of Musick - nmz Klassik-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2022\\\/04\\\/26\\\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2022\\\/04\\\/26\\\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2021\\\/09\\\/Jetzt-eine-Koenigsdusche.png?fit=1191%2C661&ssl=1\",\"datePublished\":\"2022-04-26T09:36:55+00:00\",\"dateModified\":\"2024-07-31T11:01:04+00:00\",\"description\":\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2022\\\/04\\\/26\\\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2022\\\/04\\\/26\\\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2022\\\/04\\\/26\\\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2021\\\/09\\\/Jetzt-eine-Koenigsdusche.png?fit=1191%2C661&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2021\\\/09\\\/Jetzt-eine-Koenigsdusche.png?fit=1191%2C661&ssl=1\",\"width\":1191,\"height\":661},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2022\\\/04\\\/26\\\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die schlechtesten Kunstlied-Interpretationen aller Zeiten (Eine Liebeserkl&#228;rung) \u2013 Folge 49\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"name\":\"Bad Blog Of Musick\",\"description\":\"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\",\"name\":\"Bad Blog Of Musick\",\"alternateName\":\"Ein Klassik-Blog zur Musik\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"width\":512,\"height\":512,\"caption\":\"Bad Blog Of Musick\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/musikzeitung\",\"https:\\\/\\\/x.com\\\/musikzeitung\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/006319494c6abac7102be470a5b5c092\",\"name\":\"Arno L\u00fccker\",\"description\":\"Arno L\u00fccker wuchs in der N\u00e4he von Hannover auf, studierte Musikwissenschaft und Philosophie in Hannover, Freiburg - und Berlin. Er arbeitet als Autor (2020 erschien sein Buch \u00bbop. 111 \u2013 Beethovens letzte Klaviersonate Takt f\u00fcr Takt\u00ab, 2023 sein Buch \u00bb250 Komponistinnen\u00ab), Moderator, Dramaturg, Pianist, Komponist und Musik-Satiriker. Seit 2025 ist er Dramaturg an der Staatsoper Hannover. Seit 2004 erscheinen regelm\u00e4\u00dfig Beitr\u00e4ge von ihm in der TITANIC. Arno L\u00fccker ist Bad-Blog-Autor der ersten Stunde, Fan von Hannover 96 und den Toronto Blue Jays.\",\"sameAs\":[\"http:\\\/\\\/www.arnoluecker.de\\\/\"],\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/author\\\/arno\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die schlechtesten Kunstlied-Interpretationen aller Zeiten (Eine Liebeserkl\u00e4rung) \u2013 Folge 49 &#8211; Bad Blog Of Musick - nmz Klassik-Blog","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.nmz.de\/badblog\/2022\/04\/26\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\/","og_locale":"de_DE","og_type":"article","og_title":"Die schlechtesten Kunstlied-Interpretationen aller Zeiten (Eine Liebeserkl\u00e4rung) \u2013 Folge 49 &#8211; Bad Blog Of Musick - nmz Klassik-Blog","og_description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","og_url":"https:\/\/blogs.nmz.de\/badblog\/2022\/04\/26\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\/","og_site_name":"Bad Blog Of Musick","article_publisher":"https:\/\/www.facebook.com\/musikzeitung","article_published_time":"2022-04-26T09:36:55+00:00","article_modified_time":"2024-07-31T11:01:04+00:00","og_image":[{"width":1191,"height":661,"url":"https:\/\/blogs.nmz.de\/badblog\/files\/2021\/09\/Jetzt-eine-Koenigsdusche.png","type":"image\/png"}],"author":"Arno L\u00fccker","twitter_card":"summary_large_image","twitter_creator":"@musikzeitung","twitter_site":"@musikzeitung","twitter_misc":{"Verfasst von":"Arno L\u00fccker","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.nmz.de\/badblog\/2022\/04\/26\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\/#article","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2022\/04\/26\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\/"},"author":{"name":"Arno L\u00fccker","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/006319494c6abac7102be470a5b5c092"},"headline":"Die schlechtesten Kunstlied-Interpretationen aller Zeiten (Eine Liebeserkl&#228;rung) \u2013 Folge 49","datePublished":"2022-04-26T09:36:55+00:00","dateModified":"2024-07-31T11:01:04+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2022\/04\/26\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\/"},"wordCount":297,"commentCount":0,"publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2022\/04\/26\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2021\/09\/Jetzt-eine-Koenigsdusche.png?fit=1191%2C661&ssl=1","keywords":["Fanny Hensel","Humor","interpretation","Kunstlied","Lied"],"articleSection":{"1":"\u00c4sthetik","2":"Deutsch","3":"Featured"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.nmz.de\/badblog\/2022\/04\/26\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.nmz.de\/badblog\/2022\/04\/26\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\/","url":"https:\/\/blogs.nmz.de\/badblog\/2022\/04\/26\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\/","name":"Die schlechtesten Kunstlied-Interpretationen aller Zeiten (Eine Liebeserkl\u00e4rung) \u2013 Folge 49 &#8211; Bad Blog Of Musick - nmz Klassik-Blog","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2022\/04\/26\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\/#primaryimage"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2022\/04\/26\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2021\/09\/Jetzt-eine-Koenigsdusche.png?fit=1191%2C661&ssl=1","datePublished":"2022-04-26T09:36:55+00:00","dateModified":"2024-07-31T11:01:04+00:00","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","breadcrumb":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2022\/04\/26\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.nmz.de\/badblog\/2022\/04\/26\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/2022\/04\/26\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\/#primaryimage","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2021\/09\/Jetzt-eine-Koenigsdusche.png?fit=1191%2C661&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2021\/09\/Jetzt-eine-Koenigsdusche.png?fit=1191%2C661&ssl=1","width":1191,"height":661},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.nmz.de\/badblog\/2022\/04\/26\/die-schlechtesten-kunstlied-interpretationen-aller-zeiten-eine-liebeserklaerung-folge-49\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blogs.nmz.de\/badblog\/"},{"@type":"ListItem","position":2,"name":"Die schlechtesten Kunstlied-Interpretationen aller Zeiten (Eine Liebeserkl&#228;rung) \u2013 Folge 49"}]},{"@type":"WebSite","@id":"https:\/\/blogs.nmz.de\/badblog\/#website","url":"https:\/\/blogs.nmz.de\/badblog\/","name":"Bad Blog Of Musick","description":"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur","publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.nmz.de\/badblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blogs.nmz.de\/badblog\/#organization","name":"Bad Blog Of Musick","alternateName":"Ein Klassik-Blog zur Musik","url":"https:\/\/blogs.nmz.de\/badblog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","width":512,"height":512,"caption":"Bad Blog Of Musick"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/musikzeitung","https:\/\/x.com\/musikzeitung"]},{"@type":"Person","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/006319494c6abac7102be470a5b5c092","name":"Arno L\u00fccker","description":"Arno L\u00fccker wuchs in der N\u00e4he von Hannover auf, studierte Musikwissenschaft und Philosophie in Hannover, Freiburg - und Berlin. Er arbeitet als Autor (2020 erschien sein Buch \u00bbop. 111 \u2013 Beethovens letzte Klaviersonate Takt f\u00fcr Takt\u00ab, 2023 sein Buch \u00bb250 Komponistinnen\u00ab), Moderator, Dramaturg, Pianist, Komponist und Musik-Satiriker. Seit 2025 ist er Dramaturg an der Staatsoper Hannover. Seit 2004 erscheinen regelm\u00e4\u00dfig Beitr\u00e4ge von ihm in der TITANIC. Arno L\u00fccker ist Bad-Blog-Autor der ersten Stunde, Fan von Hannover 96 und den Toronto Blue Jays.","sameAs":["http:\/\/www.arnoluecker.de\/"],"url":"https:\/\/blogs.nmz.de\/badblog\/author\/arno\/"}]}},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2021\/09\/Jetzt-eine-Koenigsdusche.png?fit=1191%2C661&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/24741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/comments?post=24741"}],"version-history":[{"count":4,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/24741\/revisions"}],"predecessor-version":[{"id":29107,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/24741\/revisions\/29107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/media\/24739"}],"wp:attachment":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/media?parent=24741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/categories?post=24741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/tags?post=24741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}