{"id":20467,"date":"2019-09-25T11:38:05","date_gmt":"2019-09-25T09:38:05","guid":{"rendered":"http:\/\/blogs.nmz.de\/badblog\/?p=20467"},"modified":"2019-09-25T11:38:05","modified_gmt":"2019-09-25T09:38:05","slug":"hinter-tausend-legenden-keine-musik","status":"publish","type":"post","link":"https:\/\/blogs.nmz.de\/badblog\/2019\/09\/25\/hinter-tausend-legenden-keine-musik\/","title":{"rendered":"Hinter tausend Legenden&#8230;keine Musik"},"content":{"rendered":"<p><strong>\u201cHinter tausend Legenden&#8230;keine Musik&#8230;\u201d (Hommage \u00e1 Rilke)<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><em>Kompositionsauftrag der Neuen Musikzeitung, gef&#246;rdert von Mitteln der Theo Gei&#223;ler und Barbara Haack &#8211; Gesellschaft<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>gewidmet Martin Hufner &#8211; in Dankbarkeit<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li>317b<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>komponiert in Detmold, Luzern, Wuppertal, Venedig (Deutsches Studienzentrum), New York, Bielefeld und Tokyo, 13.7.2018 14:37 Uhr bis 14.9.2019 20:23 Uhr (MEZ)<\/p>\n<p>&nbsp;<\/p>\n<p>Die Durchschnittstemperatur bei der Komposition betrug 23 Grad Celsius (1)<\/p>\n<p>&nbsp;<\/p>\n<p>f&#252;r schreibenden und polemisierenden Blogautoren, sowie eine beliebige Anzahl von Lesern, jedoch mindestens einen, bzw. eine. (2)<\/p>\n<p>&nbsp;<\/p>\n<p>L&#228;nge: 11,456332 Minuten (bei genauer Einhaltung der Tempoangaben, siehe Appendix C-G)<\/p>\n<p>&nbsp;<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"20468\" data-permalink=\"https:\/\/blogs.nmz.de\/badblog\/2019\/09\/25\/hinter-tausend-legenden-keine-musik\/227-0\/\" data-orig-file=\"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2019\/09\/227-0.jpg?fit=1024%2C699&amp;ssl=1\" data-orig-size=\"1024,699\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"227-0\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2019\/09\/227-0.jpg?fit=1024%2C699&amp;ssl=1\" class=\"alignnone size-medium wp-image-20468\" src=\"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2019\/09\/227-0.jpg?resize=600%2C410&#038;ssl=1\" alt=\"\" width=\"600\" height=\"410\" srcset=\"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2019\/09\/227-0.jpg?resize=600%2C410&amp;ssl=1 600w, https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2019\/09\/227-0.jpg?resize=768%2C524&amp;ssl=1 768w, https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2019\/09\/227-0.jpg?w=1024&amp;ssl=1 1024w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Vorwort:<\/p>\n<p>&nbsp;<\/p>\n<p>In meinem St&#252;ck \u201eHinter tausend Legenden&#8230;keine Musik\u201c (Hommage \u00e0 Rilke) werfe ich einen kritischen Blick auf die akademische Blase der zeitgen&#246;ssischen aktuellen Partiturproduktion. Schon seit vielen Jahren hat sich ein bestimmter Stil etabliert, der der zur musikalischen Realisierung n&#246;tigen Bestimmung einer umfassenden Zeichensetzung einen immer gr&#246;&#223;eren Raum gibt, all dies im Sinne einer \u201everwirrenden Topologie\u201c (Walter Benjamin: \u201eDie Topologie des modernen Kunstbegriffs als Ph&#228;nomenologie einer Kritik an der Schopenhauerschen Weltsicht\u201c, Seite 24ff.), die sich durch vorget&#228;uschte Tiefe und Komplexit&#228;t eben jener Stilmittel bedient, deren scheinbare Sinnhaftigkeit sich gleichsam in einer &#252;bertriebenen Penibilit&#228;t manifestiert, die letztlich de facto eine Sinnlosigkeit darstellt, so als sei der komplexen Welt der Klangph&#228;nomene (vgl.\u201cDie Welt als Klang\u201c, unvollendeter Aufsatz von T.W.Adorno) nur damit beizukommen, indem man sie ins letzte Detail auslotet und als Ph&#228;nomen damit (nur scheinbar) greifbar machen w&#252;rde h&#228;tte haben sollen geworden sein.<\/p>\n<p>&nbsp;<\/p>\n<p>Typisch f&#252;r diesen Stil sind endlose Partiturvorworte und Legenden, bei denen bestimmte Spieltechniken ausufernd und en detail beschrieben werden, als seien sie in Wirklichkeit terra incognita, ja, als sei der Eintritt in die &#196;sthetik dieser Komponistinnen und Komponisten nur mittels eines ausf&#252;hrlichen Quellenstudiums m&#246;glich, wobei die Quellen praktischerweise von der Komponistin bzw. Komponistin selber bereitgestellt werden, sich dabei auf einen wachsenden Kanon Neue-Musik-&#252;blicher 08\/15-Ausdifferenzierungen berufend, der wie eine Art Doppelte-Rittberger-&#220;bung absolviert werden muss, bevor man &#252;berhaupt zum \u201eEigentlichen\u201c (dem \u201eWerk\u201c) kommen kann. So ist z.B. eine Partitur f&#252;r Holzbl&#228;ser ohne mindestens 3-4 detailliert beschriebene Multiphonics samt Grifftabellen f&#252;r verschiedene Griffsysteme nicht \u201erelevant\u201c, da sie sich den inzwischen &#252;berall g&#228;ngigen Codes der Scheinkomplexit&#228;t verweigern w&#252;rde. Dem Komponisten bzw. der Komponistin scheint der Weg zu den h&#246;heren \u201eWeihen\u201c der Szene auch versperrt zu sein, wenn nicht zumindest eine der verwendeten Spieltechniken so ungew&#246;hnlich und &#252;berdifferenziert ist, dass sie mittels komplizierter Grafiken und Hilfsnotationen seitenlang erkl&#228;rt werden muss, da nur dann der pseudowissenschaftliche Entwurf erf&#252;llt ist, der den im Grunde immer gleichf&#246;rmigeren Partituren den Hauch von Eigenwilligkeit verleihen soll, den diese musikalisch meist vermissen lassen.<\/p>\n<p>&nbsp;<\/p>\n<p>Inzwischen treibt dieser Erkl&#228;rzwang so seltsame Bl&#252;ten, dass Partituren ohne mindestens 10-seitige Vorworte nicht als \u201evollst&#228;ndig\u201c empfunden werden, ja, manche Partituren bestehen fast nur noch (!) \u00a0aus Vorworten und Legenden, die Musik selber kann &#8211; wie ein unn&#246;tiger Wurmfortsatz &#8211; weggelassen werden, denn wenn alles erkl&#228;rt worden ist, bevor auch nur ein Ton erklungen ist, wird das Klingen selbst redundant.<\/p>\n<p>&nbsp;<\/p>\n<p>Mein St&#252;ck setzt sich kritisch mit dieser Praxis auseinander, im Sinne einer zeitlich genau definierten \u201eKlangrede\u201c im Grenzbereich zwischen Performance und Kammermusik.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Legende:<\/p>\n<p>&nbsp;<\/p>\n<p>abcdefg&#8230;.. \u00a0 \u00a0Diese \u201eBuchstaben\u201c ergeben in festgelegten Abfolgen sogenannte \u201eWorte\u201c, die jeweils als eigenst&#228;ndiger Sinnzusammenhang eine Grammatik von Inhalten ergeben. Die genaue Reihenfolge der \u201eWortfolgen\u201c ist hierbei streng festgelegt, und sollte vom Interpreten bzw. Interpretin bzw. der Leserin oder dem Leser ebenso streng beibehalten werden.<\/p>\n<p>&nbsp;<\/p>\n<p>. \u00a0 \u00a0 \u00a0 \u00a0Mit diesem Symbol endet eine spezifische Abfolge. Die Lesepause sollte ca. 5\/100 Sekunden dauern, dann kann im Vortrag fortgefahren werden.<\/p>\n<p>&nbsp;<\/p>\n<p>, \u00a0 \u00a0 \u00a0Mit diesem Symbol wird das Ende eines spezifischen Sinnzusammenhangs gekennzeichnet, allerdings nicht das Ende eines sogenannten \u201eSatzes\u201c<\/p>\n<p>&nbsp;<\/p>\n<p>; \u00a0 \u00a0 Mit diesem sogenannten \u201ePunktkomma\u201c (vulg&#228;rrhaetoromanisch: \u201esemikolon\u201c, oder auch \u201eHalbarschloch\u201c) wird quasi eine Dichotomie des \u201eabschlie&#223;enden\u201c wie auch \u201eweiterf&#252;hrenden\u201c Zustands symbolisiert. In diesem speziellen Zwischenzustand, sind die Gesetze der normalen Lesart quasi au&#223;er Kraft gesetzt, idealerweise entsteht also ein Equilibrium aus \u201eVerharren\u201c und \u201eFortschreiten\u201c, das einer besonderen Spannung bei der Ausf&#252;hrung bedarf.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>fettgedruckt \u00a0 \u00a0 \u00a0<\/strong>Diese \u201eWorte\u201c sollen besonders betont werden. Der Aussprachevorgang kann durch ein leichtes oder auch deutliches Anheben der Stimme unterst&#252;tzt werden, dies ist vor allem dann der Fall, wenn dem fettgedruckten Wort auch ein Ausrufezeichen folgt, wobei dieses sowohl fett- als auch normalgedruckt erscheinen kann. Die Intensit&#228;t der Ausf&#252;hrung unterliegt teilweise der pers&#246;nlichen Einsch&#228;tzung des Interpreten\/der Interpretin, wobei darauf geachtet werden muss, dass diese der Intention des Komponisten nicht zuwider l&#228;uft, denn diese hat auf jeden Fall Vorrang, ihr Motherfuckers.<\/p>\n<p>&nbsp;<\/p>\n<p><em>kursiv \u00a0 \u00a0 \u00a0 \u00a0<\/em>diese \u201eWorte\u201c haben eine Sonderstellung innerhalb der Notation &#8211; sie sind quasi Repr&#228;sentanten einer eigentlichen \u201eBesonderheit\u201c, die sich durch Uneigentlichkeit einer genauen Lokalisierung widersetzen. Wichtig ist hierbei die Deutung des Zeichens als gleichsam \u201eexterritoriales\u201c Ereignis im Sinne einer Stockhausenschen Logik der Gestenrede. Ich wei&#223; auch nicht so richtig, was das jetzt bedeutet, aber es klingt irgendwie gut.<\/p>\n<p>&nbsp;<\/p>\n<p><u>unterstrichen<\/u>\u00a0 \u00a0 leichte Ausdifferenzierung, irgendwo zwischen <strong>fettgedruckt <\/strong>\u00a0und <em>kursiv, <\/em>\u00a0allerdings mit leicht angeschr&#228;gter Bogenhaltung, damit deutlich mehr Obert&#246;ne erklingen als bei normaler Spielweise.<\/p>\n<p>&nbsp;<\/p>\n<p>Wichtig: In diesem St&#252;ck kommen zwar keine Multiphonics vor, aber wenn sie vork&#228;men, dann w&#228;ren sie extrem obskuren Almanachen entnommen, die nur dem Sch&#246;pfer dieser Zeilen und seinem Cousin 4. Grades bekannt w&#228;ren. Nur um es euch zu zeigen, ihr erb&#228;rmlichen Loser!<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fig. I-VIIIIa-x: \u00a0Multiphonics, die in diesem St&#252;ck nicht vorkommen, aber einfach geil aussehen<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>Moritz Eggert: \u201eHinter tausend Legenden&#8230;keine Musik\u201c (Hommage \u00e1 Rilke)<\/u><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Version 1.04<\/p>\n<p>&nbsp;<\/p>\n<p>copyright Breitkopf und H&#228;rtl<\/p>\n<p>&nbsp;<\/p>\n<p><em>Das Kopieren dieser Partitur wird mit dem Tode geahndet, au&#223;er der Kopierende f&#252;hrt die Kacke auf, denn dann gibt es GEMA.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li>( und einziger) Satz<\/li>\n<\/ol>\n<p>Tempo: Viertel gleich 35,7 (Achtel gleich 71,4)<\/p>\n<p>leise schreitend (ohne besondere Hast, jedoch streng im &#8211; nicht zu schnellen &#8211; Zeitma&#223;, pochend, unruhig)<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Wenn ????<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>ihr<\/p>\n<p>&nbsp;<\/p>\n<p><em>so VIELE<\/p>\n<p><\/em><\/p>\n<p><em>&#8230;.<u>\u00a0<\/u><\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em><u>.<\/u><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>\u2014-<\/p>\n<p>&nbsp;<\/p>\n<p>Worte<\/p>\n<p>&nbsp;<\/p>\n<p><strong>braucht<\/strong><\/p>\n<p><strong><\/p>\n<p><\/strong><\/p>\n<p><strong>um eure Musik!!!! \u00a0 \u00a0-.. \u00a0 ?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>zu erkl&#228;ren<strong><\/p>\n<p><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>warum? \u00a0 \u00a0&#8230;<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>seid ihr dann eigentlich&#8230;..<\/p>\n<p>&nbsp;<\/p>\n<p>&#228;h (&#228;h)<\/p>\n<p>&nbsp;<\/p>\n<p>(krks)<\/p>\n<p>&nbsp;<\/p>\n<p><em><u>nicht!<\/u><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em><u>&amp;%\u20ac<\/u><\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em><u>\u20ac<\/u><\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>Schriftsteller geworden ?;:;:;:=====<\/u><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Fine<\/p>\n<p>&nbsp;<\/p>\n<p><em><u>Moritz Eggert, 23.9.2019<\/u><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li>Siehe auch die Umrechnung in Fahrenheit, Appendix A<\/li>\n<li>Ideal w&#228;re eine Mischung aus sowohl weiblichen als auch m&#228;nnlichem Zuh&#246;rerInnen, solange die Auff&#252;hrungssituation nicht f&#252;r einen GEMA-Missbrauch genutzt wird (siehe Appendix B)<\/li>\n<\/ol>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Hinter%20tausend%20Legenden%E2%80%A6keine%20Musik https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2019%2F09%2F25%2Fhinter-tausend-legenden-keine-musik%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Hinter%20tausend%20Legenden%E2%80%A6keine%20Musik https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2019%2F09%2F25%2Fhinter-tausend-legenden-keine-musik%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2019%2F09%2F25%2Fhinter-tausend-legenden-keine-musik%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Hinter%20tausend%20Legenden%E2%80%A6keine%20Musik%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2019%2F09%2F25%2Fhinter-tausend-legenden-keine-musik%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2019%2F09%2F25%2Fhinter-tausend-legenden-keine-musik%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Wichtig ist hierbei die Deutung des Zeichens als gleichsam \u201eexterritoriales\u201c Ereignis im Sinne einer Stockhausenschen Logik der Gestenrede. Ich wei&#223; auch nicht so richtig, was das jetzt bedeutet, aber es klingt irgendwie gut.<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Hinter%20tausend%20Legenden%E2%80%A6keine%20Musik https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2019%2F09%2F25%2Fhinter-tausend-legenden-keine-musik%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Hinter%20tausend%20Legenden%E2%80%A6keine%20Musik https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2019%2F09%2F25%2Fhinter-tausend-legenden-keine-musik%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2019%2F09%2F25%2Fhinter-tausend-legenden-keine-musik%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Hinter%20tausend%20Legenden%E2%80%A6keine%20Musik%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2019%2F09%2F25%2Fhinter-tausend-legenden-keine-musik%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2019%2F09%2F25%2Fhinter-tausend-legenden-keine-musik%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"author":8,"featured_media":20468,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[14657,29,2892,11372,14294],"tags":[805,23420,12749,23419,23418,2536,59,1922,12253,2469],"class_list":["post-20467","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert","category-aesthetik","category-deutsch","category-featured","category-musick","tag-adorno","tag-breitkopf-und-haertl","tag-kanon","tag-legende","tag-multiiphonics-gewichse","tag-multiphonics","tag-neue-musik","tag-partitur","tag-schopenhauer","tag-walter-benjamin"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hinter tausend Legenden...keine Musik &#8211; Bad Blog Of Musick - nmz Klassik-Blog<\/title>\n<meta name=\"description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.nmz.de\/badblog\/2019\/09\/25\/hinter-tausend-legenden-keine-musik\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hinter tausend Legenden...keine Musik &#8211; Bad Blog Of Musick - nmz Klassik-Blog\" \/>\n<meta property=\"og:description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.nmz.de\/badblog\/2019\/09\/25\/hinter-tausend-legenden-keine-musik\/\" \/>\n<meta property=\"og:site_name\" content=\"Bad Blog Of Musick\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/musikzeitung\" \/>\n<meta property=\"article:author\" content=\"moritz.eggert.79\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-25T09:38:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2019\/09\/227-0.jpg?fit=1024%2C699&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"699\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Moritz Eggert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MoritzEggert\" \/>\n<meta name=\"twitter:site\" content=\"@musikzeitung\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Moritz Eggert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2019\\\/09\\\/25\\\/hinter-tausend-legenden-keine-musik\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2019\\\/09\\\/25\\\/hinter-tausend-legenden-keine-musik\\\/\"},\"author\":{\"name\":\"Moritz Eggert\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/ce88a756dea34f64ceab78df990e3dd4\"},\"headline\":\"Hinter tausend Legenden&#8230;keine Musik\",\"datePublished\":\"2019-09-25T09:38:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2019\\\/09\\\/25\\\/hinter-tausend-legenden-keine-musik\\\/\"},\"wordCount\":1091,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2019\\\/09\\\/25\\\/hinter-tausend-legenden-keine-musik\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2019\\\/09\\\/227-0.jpg?fit=1024%2C699&ssl=1\",\"keywords\":[\"Adorno\",\"Breitkopf und H\u00e4rtl\",\"Kanon\",\"Legende\",\"Multiiphonics-Gewichse\",\"Multiphonics\",\"Neue Musik\",\"Partitur\",\"Schopenhauer\",\"Walter Benjamin\"],\"articleSection\":{\"1\":\"\u00c4sthetik\",\"2\":\"Deutsch\",\"3\":\"Featured\",\"4\":\"Musick\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2019\\\/09\\\/25\\\/hinter-tausend-legenden-keine-musik\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2019\\\/09\\\/25\\\/hinter-tausend-legenden-keine-musik\\\/\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2019\\\/09\\\/25\\\/hinter-tausend-legenden-keine-musik\\\/\",\"name\":\"Hinter tausend Legenden...keine Musik &#8211; Bad Blog Of Musick - nmz Klassik-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2019\\\/09\\\/25\\\/hinter-tausend-legenden-keine-musik\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2019\\\/09\\\/25\\\/hinter-tausend-legenden-keine-musik\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2019\\\/09\\\/227-0.jpg?fit=1024%2C699&ssl=1\",\"datePublished\":\"2019-09-25T09:38:05+00:00\",\"description\":\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2019\\\/09\\\/25\\\/hinter-tausend-legenden-keine-musik\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2019\\\/09\\\/25\\\/hinter-tausend-legenden-keine-musik\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2019\\\/09\\\/25\\\/hinter-tausend-legenden-keine-musik\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2019\\\/09\\\/227-0.jpg?fit=1024%2C699&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2019\\\/09\\\/227-0.jpg?fit=1024%2C699&ssl=1\",\"width\":1024,\"height\":699},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2019\\\/09\\\/25\\\/hinter-tausend-legenden-keine-musik\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hinter tausend Legenden&#8230;keine Musik\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"name\":\"Bad Blog Of Musick\",\"description\":\"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\",\"name\":\"Bad Blog Of Musick\",\"alternateName\":\"Ein Klassik-Blog zur Musik\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"width\":512,\"height\":512,\"caption\":\"Bad Blog Of Musick\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/musikzeitung\",\"https:\\\/\\\/x.com\\\/musikzeitung\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/ce88a756dea34f64ceab78df990e3dd4\",\"name\":\"Moritz Eggert\",\"description\":\"Komponist\",\"sameAs\":[\"http:\\\/\\\/www.moritz-eggert.de\",\"moritz.eggert.79\",\"https:\\\/\\\/x.com\\\/MoritzEggert\"],\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/author\\\/moritzeggert\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hinter tausend Legenden...keine Musik &#8211; Bad Blog Of Musick - nmz Klassik-Blog","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.nmz.de\/badblog\/2019\/09\/25\/hinter-tausend-legenden-keine-musik\/","og_locale":"de_DE","og_type":"article","og_title":"Hinter tausend Legenden...keine Musik &#8211; Bad Blog Of Musick - nmz Klassik-Blog","og_description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","og_url":"https:\/\/blogs.nmz.de\/badblog\/2019\/09\/25\/hinter-tausend-legenden-keine-musik\/","og_site_name":"Bad Blog Of Musick","article_publisher":"https:\/\/www.facebook.com\/musikzeitung","article_author":"moritz.eggert.79","article_published_time":"2019-09-25T09:38:05+00:00","og_image":[{"width":1024,"height":699,"url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2019\/09\/227-0.jpg?fit=1024%2C699&ssl=1","type":"image\/jpeg"}],"author":"Moritz Eggert","twitter_card":"summary_large_image","twitter_creator":"@MoritzEggert","twitter_site":"@musikzeitung","twitter_misc":{"Verfasst von":"Moritz Eggert","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.nmz.de\/badblog\/2019\/09\/25\/hinter-tausend-legenden-keine-musik\/#article","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2019\/09\/25\/hinter-tausend-legenden-keine-musik\/"},"author":{"name":"Moritz Eggert","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/ce88a756dea34f64ceab78df990e3dd4"},"headline":"Hinter tausend Legenden&#8230;keine Musik","datePublished":"2019-09-25T09:38:05+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2019\/09\/25\/hinter-tausend-legenden-keine-musik\/"},"wordCount":1091,"commentCount":1,"publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2019\/09\/25\/hinter-tausend-legenden-keine-musik\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2019\/09\/227-0.jpg?fit=1024%2C699&ssl=1","keywords":["Adorno","Breitkopf und H\u00e4rtl","Kanon","Legende","Multiiphonics-Gewichse","Multiphonics","Neue Musik","Partitur","Schopenhauer","Walter Benjamin"],"articleSection":{"1":"\u00c4sthetik","2":"Deutsch","3":"Featured","4":"Musick"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.nmz.de\/badblog\/2019\/09\/25\/hinter-tausend-legenden-keine-musik\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.nmz.de\/badblog\/2019\/09\/25\/hinter-tausend-legenden-keine-musik\/","url":"https:\/\/blogs.nmz.de\/badblog\/2019\/09\/25\/hinter-tausend-legenden-keine-musik\/","name":"Hinter tausend Legenden...keine Musik &#8211; Bad Blog Of Musick - nmz Klassik-Blog","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2019\/09\/25\/hinter-tausend-legenden-keine-musik\/#primaryimage"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2019\/09\/25\/hinter-tausend-legenden-keine-musik\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2019\/09\/227-0.jpg?fit=1024%2C699&ssl=1","datePublished":"2019-09-25T09:38:05+00:00","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","breadcrumb":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2019\/09\/25\/hinter-tausend-legenden-keine-musik\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.nmz.de\/badblog\/2019\/09\/25\/hinter-tausend-legenden-keine-musik\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/2019\/09\/25\/hinter-tausend-legenden-keine-musik\/#primaryimage","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2019\/09\/227-0.jpg?fit=1024%2C699&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2019\/09\/227-0.jpg?fit=1024%2C699&ssl=1","width":1024,"height":699},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.nmz.de\/badblog\/2019\/09\/25\/hinter-tausend-legenden-keine-musik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blogs.nmz.de\/badblog\/"},{"@type":"ListItem","position":2,"name":"Hinter tausend Legenden&#8230;keine Musik"}]},{"@type":"WebSite","@id":"https:\/\/blogs.nmz.de\/badblog\/#website","url":"https:\/\/blogs.nmz.de\/badblog\/","name":"Bad Blog Of Musick","description":"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur","publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.nmz.de\/badblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blogs.nmz.de\/badblog\/#organization","name":"Bad Blog Of Musick","alternateName":"Ein Klassik-Blog zur Musik","url":"https:\/\/blogs.nmz.de\/badblog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","width":512,"height":512,"caption":"Bad Blog Of Musick"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/musikzeitung","https:\/\/x.com\/musikzeitung"]},{"@type":"Person","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/ce88a756dea34f64ceab78df990e3dd4","name":"Moritz Eggert","description":"Komponist","sameAs":["http:\/\/www.moritz-eggert.de","moritz.eggert.79","https:\/\/x.com\/MoritzEggert"],"url":"https:\/\/blogs.nmz.de\/badblog\/author\/moritzeggert\/"}]}},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2019\/09\/227-0.jpg?fit=1024%2C699&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/20467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/comments?post=20467"}],"version-history":[{"count":1,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/20467\/revisions"}],"predecessor-version":[{"id":20469,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/20467\/revisions\/20469"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/media\/20468"}],"wp:attachment":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/media?parent=20467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/categories?post=20467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/tags?post=20467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}