{"id":18011,"date":"2018-09-25T20:10:26","date_gmt":"2018-09-25T18:10:26","guid":{"rendered":"http:\/\/blogs.nmz.de\/badblog\/?p=18011"},"modified":"2018-10-26T14:31:09","modified_gmt":"2018-10-26T12:31:09","slug":"das-podcast-ufo-die-e-musik-transkripte-2","status":"publish","type":"post","link":"https:\/\/blogs.nmz.de\/badblog\/2018\/09\/25\/das-podcast-ufo-die-e-musik-transkripte-2\/","title":{"rendered":"DAS PODCAST UFO &#8211; Die E-Musik-Transkripte 2"},"content":{"rendered":"<p><code><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"17920\" data-permalink=\"https:\/\/blogs.nmz.de\/badblog\/2018\/09\/07\/das-podcast-ufo-die-e-musik-transkripte-1\/podcast-ufo-logo\/\" data-orig-file=\"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2018\/09\/Podcast-Ufo-Logo.jpg?fit=605%2C608&amp;ssl=1\" data-orig-size=\"605,608\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Podcast-Ufo-Logo\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2018\/09\/Podcast-Ufo-Logo.jpg?fit=605%2C608&amp;ssl=1\" class=\"aligncenter size-medium wp-image-17920\" src=\"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2018\/09\/Podcast-Ufo-Logo.jpg?resize=478%2C480&#038;ssl=1\" alt=\"\" width=\"478\" height=\"480\" srcset=\"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2018\/09\/Podcast-Ufo-Logo.jpg?resize=478%2C480&amp;ssl=1 478w, https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2018\/09\/Podcast-Ufo-Logo.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2018\/09\/Podcast-Ufo-Logo.jpg?resize=600%2C603&amp;ssl=1 600w, https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2018\/09\/Podcast-Ufo-Logo.jpg?resize=160%2C160&amp;ssl=1 160w, https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2018\/09\/Podcast-Ufo-Logo.jpg?resize=320%2C320&amp;ssl=1 320w, https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2018\/09\/Podcast-Ufo-Logo.jpg?w=605&amp;ssl=1 605w\" sizes=\"auto, (max-width: 478px) 100vw, 478px\" \/><\/code><\/p>\n<p>In der <a href=\"https:\/\/blogs.nmz.de\/badblog\/2018\/09\/07\/das-podcast-ufo-die-e-musik-transkripte-1\/\">ersten Folge dieser Serie hier<\/a> habe ich die Aufgabe, die zu erledigen ist, beschrieben. Alle Stellen, an denen im besten deutschen Podcast (<a href=\"http:\/\/podcast-ufo.fail\">&#8222;DAS PODCAST UFO&#8220;<\/a>) von klassischer Musik im weitesten Sinne die Rede ist, sollen als Text transkribiert werden. Ohne Besch&#246;nigungen, ohne Auslassungen (lediglich &#8222;&#228;h&#8220;s, Pausen und Satzunterbrechungen werden durch &#8222;&#8230;&#8220; dargestellt.) Aber <em>mit <\/em>fachlichen Korrekturen am Ende.<\/p>\n<p>&nbsp;<\/p>\n<p>Bereits in der Ende 2014 ver&#246;ffentlichten ersten Podcast-Folge (wir sind ja im R&#252;ckstand &#8211; und holen die Transkription jetzt peu a peu auf&#8230;) war von Klassik die Rede. Dann ging es weiter in <a href=\"http:\/\/podcast-ufo.fail\/?p=45\">Folge 8<\/a>&#8230;<\/p>\n<p><a href=\"http:\/\/podcast-ufo.fail\/?p=45\"><strong>Folge 8 (17. Februar 2015)<\/strong><\/a><\/p>\n<p><em>Unmittelbar vor dem hier abgebildeten Dialog sprechen Florentin Will und Stefan Titze unter anderem &#252;ber nicht genutzte Comedy-Momente im allt&#228;glichen Leben, so bei Aufs&#228;tzen in der Schule und &#252;ber Joyce-Ilg-T-Shirts.<\/em><\/p>\n<p>(&#8230;)<\/p>\n<p>[Minute 50.45]<\/p>\n<p>Florentin: Oh, moment, mir f&#228;llt noch ein&#8230; Bei uns gab es einen Running Gag&#8230; &#8230;auch in der Schule, weil bei uns hatte mal jemand eine Musikklausur &#8211; glaube ich &#8211; &#8230;abgegeben. Ein komplett leeres Blatt &#8211; und da waren so verschiedene Fragen, unter anderem zum Beispiel: &#8222;Was ist ein Concerto grosso?&#8220; Und dann hat er hingeschrieben: &#8222;Concerto grosso ist ein gro&#223;es Konzert.&#8220; [lacht] Und das war der einzige Satz. Und hat ihn leer abgegeben. Und seitdem wurden auf relativ random&#8230; &#8230;auch in anderen F&#228;chern&#8230;<\/p>\n<p>Stefan: [lacht mittelm&#228;&#223;ig belustigt]<\/p>\n<p>Florentin: &#8230;der Satz untergebracht: &#8222;Concerto grosso ist ein gro&#223;es Konzert.&#8220;<\/p>\n<p>Stefan: [lacht]<\/p>\n<p>Florentin: Einfach nebenbei. Damit der Lehrer noch etwas lernt nebenbei.<\/p>\n<p>Stefan: Es f&#228;llt mir gerade ein. Ich habe&#8230; &#8230;die einfachste Note, die ich jemals bekommen habe, die einfachste &#8222;1&#8220;, die ich jemals bekommen habe, war in <em>Musik<\/em>. Zw&#246;lftonmusik! [lacht] Zw&#246;lftonmusik, f&#252;r die, die es nicht kennen: Es sind einfach willk&#252;rlich irgendwelche&#8230; &#8230;irgendwelche Noten aneinander gereiht. Es muss schei&#223;e klingen&#8230;<\/p>\n<p>Florentin: [lacht leise]<\/p>\n<p>Stefan: &#8230;aber es m&#252;ssen alle zw&#246;lf&#8230; &#8230;Halbt&#246;ne, die es auf&#8230; &#8230;die es da gibt&#8230; &#8230;auf Keyboards zum Beispiel&#8230; &#8230;m&#252;ssen darin vorkommen. [lachend] Und dann habe ich einfach mich Zuhause an das Keyboard gesetzt und habe einfach jeden Ton irgendwie&#8230;<\/p>\n<p>Florentin: [lacht]<\/p>\n<p>Stefan: &#8230;untergebracht &#8211; und es gab eine &#8222;1+&#8220;. Es gab eine &#8222;1+&#8220;&#8230;<\/p>\n<p>Florentin: [lacht lauter]<\/p>\n<p>Stefan: &#8230;und einen&#8230; ..und einen Smiley &#8211; und dann stand: &#8222;Sehr gut, Stefan!&#8220; [lacht]<\/p>\n<p>Florentin: Ja, das ist das Gute&#8230;<\/p>\n<p>Stefan: [gleichzeitig] [unverst&#228;ndlich] &#8230;modern&#8230;<\/p>\n<p>Florentin: &#8230;an dieser modernen post-post-ideologischen Musik, dass man halt einfach&#8230;<\/p>\n<p>Stefan: [lacht] [gleichzeitig] [unverst&#228;ndlich]<\/p>\n<p>Florentin: &#8230;nicht [unverst&#228;ndlich] bewerten kann, weil <em>alles <\/em>schei&#223;e klingt! [schmunzelnd] Deswegen: &#8222;Ja, gut!&#8220;<\/p>\n<p>Stefan: Es war das h&#228;sslichste&#8230;.<\/p>\n<p>Florentin: [unverst&#228;ndlich, vermutlich:] &#8222;Klingt gut!&#8220;<\/p>\n<p>Stefan: &#8230;Lied der Welt. Es war das h&#228;sslichste&#8230; &#8230;es war eine &#8222;1+&#8220; mit&#8230; &#8230;wo dann sogar noch &#8222;Sehr gut, Stefan!&#8220; dran stand.<\/p>\n<p>Florentin: [nach einem ganz kurzen Moment des Schweigens] Bei uns hat unser Musiklehrer irgendwann komplett aufgegeben. Und hat uns einfach SingStar&#x2122;&#8230;<\/p>\n<p>Stefan: [lacht]<\/p>\n<p>Florentin: &#8230;spielen lassen&#8230;<\/p>\n<p>Stefan: [lachend] Was?<\/p>\n<p>Florentin: &#8230;und hat uns Noten&#8230; &#8230;hat uns Noten [mit kurz &#252;berschlagender Stimme] &#8211; kein Witz&#8230; &#8230;hat uns Noten nach den Punkten bei SingStar&#x2122; gegeben! Das war irgendwie&#8230;<\/p>\n<p>Stefan: [lacht nachdr&#252;cklich]<\/p>\n<p>Florentin: &#8230;zehnte, elfte Klasse oder so, wo man eigentlich nicht mehr singt.<\/p>\n<p>Stefan: [lacht]<\/p>\n<p>Florentin: Knallhart: &#8222;Ja, hier ist die PlayStation, spielt SingStar&#x2122;. Lied k&#246;nnt ihr euch selber aussuchen.&#8220;<\/p>\n<p>Stefan: [lacht]<\/p>\n<p>Florentin: [lacht heiser]<\/p>\n<p>Stefan: [lachend] Nein, ey! Wo da am Ende auch dann diese Symbole standen&#8230;<\/p>\n<p>Florentin: [gleichzeitig, unverst&#228;ndlich, vermutlich:] Nein, doch! Er hat sich&#8230;<\/p>\n<p>Stefan: [gleichzeitig] &#8230;&#8220;Du bist ein&#8230; &#8230;Topstar!&#8220; Oder du bist&#8230;<\/p>\n<p>Florentin: Genau.<\/p>\n<p>Stefan: &#8230;ein Sternchen&#8230;<\/p>\n<p>Florentin: War eine &#8222;1&#8220;. Jaja.<\/p>\n<p>Stefan: [nachdr&#252;cklich] Sternchen? &#8222;1&#8220;! [lacht]<\/p>\n<p>Florentin: [zeitgleich] Genauso ist es&#8230; [unverst&#228;ndlich] &#8230;Sternchen oder so etwas&#8230; [rau und &#252;berraschend] Aaaaah! Aber da hat sich der andere&#8230; &#8230;weil es gab zwei Musiklehrer &#8211; und der eine war so der <a href=\"https:\/\/de.wikipedia.org\/wiki\/Slacker\">Slacker<\/a>, dem alles schei&#223;egal war. Aber auch ein total s&#252;&#223;er Kerl. Und der andere war so der Hardcore-&#8230; &#8230;irgendwie selber komponiert hat und irgendwie in einem Chor in Japan gesungen hat&#8230;<\/p>\n<p>Stefan: [lacht gickernd]<\/p>\n<p>Florentin: &#8230;oder so&#8230; Und der hat sich dann immer &#252;ber den Typen aufgeregt, der immer SingStar&#x2122; gespielt hat: [verstellt seine Stimme etwas] &#8222;Das hat doch mit Musik nichts zu tun!&#8220; Und hier und da, aber im Endef&#8230;<\/p>\n<p>Stefan: [lacht leise]<\/p>\n<p>Florentin: &#8230;Endeffekt hat wahrscheinlich auch der&#8230; &#8230;der&#8230; &#8230;der Rektor gesagt: [am Ende des Satzes lachend] &#8222;Kollege, das ist Musik!&#8220; [gleichzeitig mit Stefan lachend] Das interessiert halt keine Sau [unverst&#228;ndlich]&#8230;<\/p>\n<p>Stefan: Bei uns immer&#8230; &#8230;bei uns war&#8230; &#8230;wir hatten einen sehr&#8230; &#8230;sehr gepflegten Musikraum, wo immer auch&#8230; [kichert] &#8230;sehr viele Kabel waren, f&#252;r die Keyboards und so&#8230; Und irgendwie sind andauernd <em>Kabel <\/em>verschwunden. Also, es haben&#8230; &#8230;es haben Sch&#252;ler wirklich <em>Kabel <\/em>geklaut und so [lacht]&#8230; &#8230;und&#8230; &#8230;einer hat mal versucht, wirklich einen Verst&#228;rker&#8230; [lachend] &#8230;einen Gitarrenverst&#228;rker mitgehen zu lassen&#8230;<\/p>\n<p>Florentin: [lacht laut]<\/p>\n<p>Stefan: &#8230;was dann sehr bl&#246;d aussah. Der hat dann [lacht]&#8230; &#8230;der hat dann wirklich unter seinem Pullover halt einen [lachend]&#8230; &#8230;so&#8230; &#8230;so einen Riesen-Gitarrenverst&#228;rker nach drau&#223;en&#8230;<\/p>\n<p>Florentin: [unterbrechend] Das kann man aber auch einfacher [unverst&#228;ndlich]&#8230;<\/p>\n<p>Stefan: &#8230;ja, h&#228;tte man auch einfacher machen k&#246;nnen, genau. Aber das war [lacht]&#8230; &#8230;es sind immer Kabel verschwunden und irgendwann haben dann die Lehrer eingef&#252;hrt, dass man seinen Schl&#252;ssel abgeben musste &#8211; oder sein Handy, um mal so ein Kabel zu bekommen [lacht]&#8230; &#8230;um dann Keyboard spielen zu k&#246;nnen, also so Kopfh&#246;rer oder so&#8230; &#8230;keine Ahnung&#8230; &#8230;weil&#8230; &#8230;weil halt so viel gest&#8230; &#8230;geklaut wurde. [genuschelt] Und wenn man dann den Kopfh&#246;rer wieder abgegeben hat, [lachend] hat man sein Handy wiederbekommen und konnte dann gehen [lacht].<\/p>\n<p>Florentin: [nach einer kurzen Denkpause] Aber Dinge aus der Schule zu klauen ist mir noch nie gekommen, ehrlich gesagt. In der <em>Uni <\/em>tats&#228;chlich&#8230; &#8230;da waren teilweise auch in komplett leeren Vorlesungss&#228;len, zwischen Vorlesungen, die einfach&#8230; &#8230;stundenlang leerstanden, waren so superkrasse Mikrofone, die man einfach so h&#228;tte mitnehmen k&#246;nnen &#8211; und Boxen und alles&#8230; &#8230;wo ich mich echt gefragt habe, warum das nie jemand klaut, aber&#8230;<\/p>\n<p>Stefan: &#8230;macht dann nicht, ne?<\/p>\n<p>Florentin: Ja, Philosophie-Fakult&#228;t, ne? Die sind alle moralisch gefestigt.<\/p>\n<p>(&#8230;)<\/p>\n<p>Die musikwissenschaftliche Analyse: Stefan hat selbstverst&#228;ndlich recht. Das oberste Gesetz der Zw&#246;lftonmusik hei&#223;t (wie schon Theodor W. Adorno gediegen formulierte): &#8222;Klinge schei&#223;e!&#8220; &#8211; wiewohl Stefan sich in seinem Zw&#246;lftontechnik-Erkl&#228;rungsversuch selbst widerspricht. Zun&#228;chst redet er von &#8222;willk&#252;rlichen&#8220; T&#246;nen (so kann es einem beim ersten H&#246;ren von dodekaphonischer Musik ja durchaus vorkommen), um dann schlie&#223;lich &#8211; nicht unrichtig &#8211; von den zw&#246;lf Halbt&#246;nen (die, das w&#228;re zu erg&#228;nzen, in einem gleichberechtigen Verh&#228;ltnis in dem Sinne zueinander stehen sollen, als dass auf Tonwiederholungen, Harmonie-Bildungen, geh&#228;ufte &#8222;tonale&#8220; Intervalle und harmonie&#228;hnliche Konstellationen verzichtet werden m&#246;ge) zu sprechen, die er &#8211; nehmen wir es nicht &#252;bel! &#8211; auf einem Keyboard gespielt habe.<\/p>\n<p>Doch: Moderne Hurz-Pling-Plong-Frrrrrrrtz-Willk&#252;r oder hehre Zw&#246;lfton-Ordnung? Herr Titze, bitte entscheiden Sie sich!<\/p>\n<p>Im Grunde ist die von Stefan rausgekramte Anekdote jedoch weit weniger witzig als es zun&#228;chst scheint. Eine strenge Zw&#246;lftonkomposition als Hausaufgabe oder Klausur korrekt zu erledigen, erfordert lediglich Notenkenntnis und eben die Kenntnis der strengstm&#246;glich formulierten Zw&#246;lftonregeln. Darin &#228;hnelt es einer mathematischen Aufgabe des kleinen Einmaleins. Das wiederum ist &#8211; in der Tat &#8211; zum Lachen. (Zum Weinen dagegen, dass viele Musikleistungskurs-Sch&#252;ler Schwierigkeiten mit dem Notenlesen haben. Dagegen w&#252;rde niemals toleriert werden, sollte ein Abiturient in Mathematik Probleme beim Erkennen von Zahlen offenbaren.)<\/p>\n<p>Weiter in der Analyse des Gesagten: Ja, viele Musiklehrer scheinen wirklich aufgegeben zu haben. Wurden sie schon fr&#252;her an der Musikhochschule von den angehenden Solisten der Hochschule gemobbt und lassen nun den Frust an ihren Sch&#252;lern aus? Oder haben die weich-eirigen Konzertveranstalter hierzulande mit ihren saudummen, selbstgef&#228;lligen und nur zur Beruhigung und eierschaukligen Bespa&#223;ung von Papa und Opa inszenierten &#8222;Zauberfl&#246;ten-f&#252;r-Kinder&#8220;- und &#8222;Kinder-probieren-nach-dem-Konzert-Instrumente-aus&#8220;-Projekten Schuld an der Misere?<\/p>\n<p>Nun, ein weites Feld. Meiner Meinung nach gibt es jedenfalls bei keinem anderen Schulfach derart gro&#223;e Qualit&#228;tsunterschiede als im Unterrichten von Musik. Es gibt fast kein Mittelma&#223;, sondern nur die, die aufgegeben haben &#8211; oder die, die, sagen wir es mit Stefan Titze, &#8222;in einem Chor in Japan singen&#8220; (was eine s&#252;&#223;e Formulierung aber nun auch absolut kein Qualit&#228;tsmerkmal f&#252;r einen studierten Gymnasialmusiklehrer ist; jeder noch so unmusikalische Mensch kann es &#8222;in einen Chor in Japan&#8220; schaffen; unz&#228;hlige Laiench&#246;re- und Orchester werden regelm&#228;&#223;ig von japanischen Konzertveranstaltern eingeladen, in den gro&#223;en Hallen dort zu spielen; dabei ist es wichtig, aus Deutschland, dem Land von Bach, Beethoven und Brahms, zu kommen; egal, wie es letztlich klingt&#8230; Dort h&#246;rt eh keiner wirklich zu; man erledigt w&#228;hrend des Konzerts gerne noch laut telefonierend Bankgesch&#228;fte am Smartphone&#8230;).<\/p>\n<p>Auf die Anekdote von Stefan hin begeht Florentin den Fehler, von den Vorz&#252;gen (n&#228;mlich denen der musikalischen &#8222;Das-kann-ja-jeder!&#8220;-Willk&#252;r) &#8222;post-post-ideologischer Musik&#8220; zu sprechen. Das ist irgendwie sogar nicht ganz falsch, aber in &#8222;post&#8220;- oder gar &#8222;post-post&#8220;-Begriffen wurde zur Zeit der Entwicklung der Zw&#246;lftonmusik noch nicht gedacht. Im &#220;brigen kann man die Zw&#246;lftontechnik einerseits tats&#228;chlich (siehe Adorno und so) &#8211; das &#8222;post-post&#8220; weglassend &#8211; &#8222;ideologisch&#8220; nennen; andererseits ist diese ja der Versuch, von der &#8222;Ideologie des Sch&#246;nklangs&#8220; (Tonalit&#228;t) loszukommen &#8211; aber eben als neue Ideologie, die &#8211; typisch Ideologie &#8211; Einiges &#8222;verbietet&#8220;. Nun denn. Reicht jetzt auch. Ich muss noch einkaufen.<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=DAS%20PODCAST%20UFO%20%E2%80%93%20Die%20E-Musik-Transkripte%202 https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2018%2F09%2F25%2Fdas-podcast-ufo-die-e-musik-transkripte-2%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=DAS%20PODCAST%20UFO%20%E2%80%93%20Die%20E-Musik-Transkripte%202 https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2018%2F09%2F25%2Fdas-podcast-ufo-die-e-musik-transkripte-2%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2018%2F09%2F25%2Fdas-podcast-ufo-die-e-musik-transkripte-2%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=DAS%20PODCAST%20UFO%20%E2%80%93%20Die%20E-Musik-Transkripte%202%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2018%2F09%2F25%2Fdas-podcast-ufo-die-e-musik-transkripte-2%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2018%2F09%2F25%2Fdas-podcast-ufo-die-e-musik-transkripte-2%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>In der ersten Folge dieser Serie hier habe ich die Aufgabe, die zu erledigen ist, beschrieben. Alle Stellen, an denen im besten deutschen Podcast (&#8222;DAS PODCAST UFO&#8220;) von klassischer Musik im weitesten Sinne die Rede ist, sollen als Text transkribiert werden. Ohne Besch&#246;nigungen, ohne Auslassungen (lediglich &#8222;&#228;h&#8220;s, Pausen und Satzunterbrechungen&#46;&#46;&#46;<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=DAS%20PODCAST%20UFO%20%E2%80%93%20Die%20E-Musik-Transkripte%202 https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2018%2F09%2F25%2Fdas-podcast-ufo-die-e-musik-transkripte-2%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=DAS%20PODCAST%20UFO%20%E2%80%93%20Die%20E-Musik-Transkripte%202 https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2018%2F09%2F25%2Fdas-podcast-ufo-die-e-musik-transkripte-2%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2018%2F09%2F25%2Fdas-podcast-ufo-die-e-musik-transkripte-2%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=DAS%20PODCAST%20UFO%20%E2%80%93%20Die%20E-Musik-Transkripte%202%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2018%2F09%2F25%2Fdas-podcast-ufo-die-e-musik-transkripte-2%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2018%2F09%2F25%2Fdas-podcast-ufo-die-e-musik-transkripte-2%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"author":4,"featured_media":17920,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[11372,14853],"tags":[23083,10,12814],"class_list":["post-18011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured","category-radiomedien","tag-das-podcast-ufo","tag-humor","tag-podcast"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DAS PODCAST UFO - Die E-Musik-Transkripte 2 &#8211; Bad Blog Of Musick - nmz Klassik-Blog<\/title>\n<meta name=\"description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.nmz.de\/badblog\/2018\/09\/25\/das-podcast-ufo-die-e-musik-transkripte-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DAS PODCAST UFO - Die E-Musik-Transkripte 2 &#8211; Bad Blog Of Musick - nmz Klassik-Blog\" \/>\n<meta property=\"og:description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.nmz.de\/badblog\/2018\/09\/25\/das-podcast-ufo-die-e-musik-transkripte-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Bad Blog Of Musick\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/musikzeitung\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-25T18:10:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-26T12:31:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/blogs.nmz.de\/badblog\/files\/2018\/09\/Podcast-Ufo-Logo.jpg?fit=605%2C608&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"605\" \/>\n\t<meta property=\"og:image:height\" content=\"608\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arno L\u00fccker\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@musikzeitung\" \/>\n<meta name=\"twitter:site\" content=\"@musikzeitung\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arno L\u00fccker\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2018\\\/09\\\/25\\\/das-podcast-ufo-die-e-musik-transkripte-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2018\\\/09\\\/25\\\/das-podcast-ufo-die-e-musik-transkripte-2\\\/\"},\"author\":{\"name\":\"Arno L\u00fccker\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/006319494c6abac7102be470a5b5c092\"},\"headline\":\"DAS PODCAST UFO &#8211; Die E-Musik-Transkripte 2\",\"datePublished\":\"2018-09-25T18:10:26+00:00\",\"dateModified\":\"2018-10-26T12:31:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2018\\\/09\\\/25\\\/das-podcast-ufo-die-e-musik-transkripte-2\\\/\"},\"wordCount\":1578,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2018\\\/09\\\/25\\\/das-podcast-ufo-die-e-musik-transkripte-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2018\\\/09\\\/Podcast-Ufo-Logo.jpg?fit=605%2C608&ssl=1\",\"keywords\":[\"Das Podcast Ufo\",\"Humor\",\"Podcast\"],\"articleSection\":[\"Featured\",\"Radio\\\/Medien\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2018\\\/09\\\/25\\\/das-podcast-ufo-die-e-musik-transkripte-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2018\\\/09\\\/25\\\/das-podcast-ufo-die-e-musik-transkripte-2\\\/\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2018\\\/09\\\/25\\\/das-podcast-ufo-die-e-musik-transkripte-2\\\/\",\"name\":\"DAS PODCAST UFO - Die E-Musik-Transkripte 2 &#8211; Bad Blog Of Musick - nmz Klassik-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2018\\\/09\\\/25\\\/das-podcast-ufo-die-e-musik-transkripte-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2018\\\/09\\\/25\\\/das-podcast-ufo-die-e-musik-transkripte-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2018\\\/09\\\/Podcast-Ufo-Logo.jpg?fit=605%2C608&ssl=1\",\"datePublished\":\"2018-09-25T18:10:26+00:00\",\"dateModified\":\"2018-10-26T12:31:09+00:00\",\"description\":\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2018\\\/09\\\/25\\\/das-podcast-ufo-die-e-musik-transkripte-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2018\\\/09\\\/25\\\/das-podcast-ufo-die-e-musik-transkripte-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2018\\\/09\\\/25\\\/das-podcast-ufo-die-e-musik-transkripte-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2018\\\/09\\\/Podcast-Ufo-Logo.jpg?fit=605%2C608&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2018\\\/09\\\/Podcast-Ufo-Logo.jpg?fit=605%2C608&ssl=1\",\"width\":605,\"height\":608},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2018\\\/09\\\/25\\\/das-podcast-ufo-die-e-musik-transkripte-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DAS PODCAST UFO &#8211; Die E-Musik-Transkripte 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"name\":\"Bad Blog Of Musick\",\"description\":\"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\",\"name\":\"Bad Blog Of Musick\",\"alternateName\":\"Ein Klassik-Blog zur Musik\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"width\":512,\"height\":512,\"caption\":\"Bad Blog Of Musick\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/musikzeitung\",\"https:\\\/\\\/x.com\\\/musikzeitung\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/006319494c6abac7102be470a5b5c092\",\"name\":\"Arno L\u00fccker\",\"description\":\"Arno L\u00fccker wuchs in der N\u00e4he von Hannover auf, studierte Musikwissenschaft und Philosophie in Hannover, Freiburg - und Berlin. Er arbeitet als Autor (2020 erschien sein Buch \u00bbop. 111 \u2013 Beethovens letzte Klaviersonate Takt f\u00fcr Takt\u00ab, 2023 sein Buch \u00bb250 Komponistinnen\u00ab), Moderator, Dramaturg, Pianist, Komponist und Musik-Satiriker. Seit 2025 ist er Dramaturg an der Staatsoper Hannover. Seit 2004 erscheinen regelm\u00e4\u00dfig Beitr\u00e4ge von ihm in der TITANIC. Arno L\u00fccker ist Bad-Blog-Autor der ersten Stunde, Fan von Hannover 96 und den Toronto Blue Jays.\",\"sameAs\":[\"http:\\\/\\\/www.arnoluecker.de\\\/\"],\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/author\\\/arno\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DAS PODCAST UFO - Die E-Musik-Transkripte 2 &#8211; Bad Blog Of Musick - nmz Klassik-Blog","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.nmz.de\/badblog\/2018\/09\/25\/das-podcast-ufo-die-e-musik-transkripte-2\/","og_locale":"de_DE","og_type":"article","og_title":"DAS PODCAST UFO - Die E-Musik-Transkripte 2 &#8211; Bad Blog Of Musick - nmz Klassik-Blog","og_description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","og_url":"https:\/\/blogs.nmz.de\/badblog\/2018\/09\/25\/das-podcast-ufo-die-e-musik-transkripte-2\/","og_site_name":"Bad Blog Of Musick","article_publisher":"https:\/\/www.facebook.com\/musikzeitung","article_published_time":"2018-09-25T18:10:26+00:00","article_modified_time":"2018-10-26T12:31:09+00:00","og_image":[{"width":605,"height":608,"url":"https:\/\/i1.wp.com\/blogs.nmz.de\/badblog\/files\/2018\/09\/Podcast-Ufo-Logo.jpg?fit=605%2C608&ssl=1","type":"image\/jpeg"}],"author":"Arno L\u00fccker","twitter_card":"summary_large_image","twitter_creator":"@musikzeitung","twitter_site":"@musikzeitung","twitter_misc":{"Verfasst von":"Arno L\u00fccker","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.nmz.de\/badblog\/2018\/09\/25\/das-podcast-ufo-die-e-musik-transkripte-2\/#article","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2018\/09\/25\/das-podcast-ufo-die-e-musik-transkripte-2\/"},"author":{"name":"Arno L\u00fccker","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/006319494c6abac7102be470a5b5c092"},"headline":"DAS PODCAST UFO &#8211; Die E-Musik-Transkripte 2","datePublished":"2018-09-25T18:10:26+00:00","dateModified":"2018-10-26T12:31:09+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2018\/09\/25\/das-podcast-ufo-die-e-musik-transkripte-2\/"},"wordCount":1578,"commentCount":1,"publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2018\/09\/25\/das-podcast-ufo-die-e-musik-transkripte-2\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2018\/09\/Podcast-Ufo-Logo.jpg?fit=605%2C608&ssl=1","keywords":["Das Podcast Ufo","Humor","Podcast"],"articleSection":["Featured","Radio\/Medien"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.nmz.de\/badblog\/2018\/09\/25\/das-podcast-ufo-die-e-musik-transkripte-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.nmz.de\/badblog\/2018\/09\/25\/das-podcast-ufo-die-e-musik-transkripte-2\/","url":"https:\/\/blogs.nmz.de\/badblog\/2018\/09\/25\/das-podcast-ufo-die-e-musik-transkripte-2\/","name":"DAS PODCAST UFO - Die E-Musik-Transkripte 2 &#8211; Bad Blog Of Musick - nmz Klassik-Blog","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2018\/09\/25\/das-podcast-ufo-die-e-musik-transkripte-2\/#primaryimage"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2018\/09\/25\/das-podcast-ufo-die-e-musik-transkripte-2\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2018\/09\/Podcast-Ufo-Logo.jpg?fit=605%2C608&ssl=1","datePublished":"2018-09-25T18:10:26+00:00","dateModified":"2018-10-26T12:31:09+00:00","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","breadcrumb":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2018\/09\/25\/das-podcast-ufo-die-e-musik-transkripte-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.nmz.de\/badblog\/2018\/09\/25\/das-podcast-ufo-die-e-musik-transkripte-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/2018\/09\/25\/das-podcast-ufo-die-e-musik-transkripte-2\/#primaryimage","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2018\/09\/Podcast-Ufo-Logo.jpg?fit=605%2C608&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2018\/09\/Podcast-Ufo-Logo.jpg?fit=605%2C608&ssl=1","width":605,"height":608},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.nmz.de\/badblog\/2018\/09\/25\/das-podcast-ufo-die-e-musik-transkripte-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blogs.nmz.de\/badblog\/"},{"@type":"ListItem","position":2,"name":"DAS PODCAST UFO &#8211; Die E-Musik-Transkripte 2"}]},{"@type":"WebSite","@id":"https:\/\/blogs.nmz.de\/badblog\/#website","url":"https:\/\/blogs.nmz.de\/badblog\/","name":"Bad Blog Of Musick","description":"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur","publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.nmz.de\/badblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blogs.nmz.de\/badblog\/#organization","name":"Bad Blog Of Musick","alternateName":"Ein Klassik-Blog zur Musik","url":"https:\/\/blogs.nmz.de\/badblog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","width":512,"height":512,"caption":"Bad Blog Of Musick"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/musikzeitung","https:\/\/x.com\/musikzeitung"]},{"@type":"Person","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/006319494c6abac7102be470a5b5c092","name":"Arno L\u00fccker","description":"Arno L\u00fccker wuchs in der N\u00e4he von Hannover auf, studierte Musikwissenschaft und Philosophie in Hannover, Freiburg - und Berlin. Er arbeitet als Autor (2020 erschien sein Buch \u00bbop. 111 \u2013 Beethovens letzte Klaviersonate Takt f\u00fcr Takt\u00ab, 2023 sein Buch \u00bb250 Komponistinnen\u00ab), Moderator, Dramaturg, Pianist, Komponist und Musik-Satiriker. Seit 2025 ist er Dramaturg an der Staatsoper Hannover. Seit 2004 erscheinen regelm\u00e4\u00dfig Beitr\u00e4ge von ihm in der TITANIC. Arno L\u00fccker ist Bad-Blog-Autor der ersten Stunde, Fan von Hannover 96 und den Toronto Blue Jays.","sameAs":["http:\/\/www.arnoluecker.de\/"],"url":"https:\/\/blogs.nmz.de\/badblog\/author\/arno\/"}]}},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2018\/09\/Podcast-Ufo-Logo.jpg?fit=605%2C608&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/18011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/comments?post=18011"}],"version-history":[{"count":12,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/18011\/revisions"}],"predecessor-version":[{"id":18232,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/18011\/revisions\/18232"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/media\/17920"}],"wp:attachment":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/media?parent=18011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/categories?post=18011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/tags?post=18011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}