{"id":11110,"date":"2014-10-16T23:55:10","date_gmt":"2014-10-16T21:55:10","guid":{"rendered":"http:\/\/blogs.nmz.de\/badblog\/?p=11110"},"modified":"2018-01-20T18:56:45","modified_gmt":"2018-01-20T17:56:45","slug":"60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum","status":"publish","type":"post","link":"https:\/\/blogs.nmz.de\/badblog\/2014\/10\/16\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\/","title":{"rendered":"60 Jahre Komponistenverband, diametrales Gestern und Heute in einem Raum"},"content":{"rendered":"<p>Ein bisschen ist es schon her: vor sieben Tagen feierte der Deutsche Komponistenverband (DKV) sein 60-j&#228;hriges Bestehen. Diese seitdem 168 verstrichenen Stunden einer Woche sind im Zeitalter des \u201eSharings\u201c und \u201eLikens\u201c selbst schon eine Ewigkeit, als seien 60 Jahre verstrichen. Was in dieser Zeitspanne an Klingelt&#246;nen, aktuellen Hits und Dauerwerbejingles durch die Z&#228;hler erfasst wurde, k&#246;nnte sich selbst die merkf&#228;higste S&#228;ngerin innerhalb eines Lebens nicht auswenidig lernen. Aber als Komponiste wei&#223; man: Zeit ist relativ. Im merkw&#252;rdigen Verh&#228;ltnis standen manche K&#252;nstlerkarrieren vor einer Woche im gleichen Raum beisammen: anhand des mit der DKV Ehrenplakette f&#252;r sein GEMA-, DKV- und K&#252;nstlerleben ausgezeichneten inzwischen 80 Jahre alten Christian Bruhn erlebte man einen Hauch von Erfolg, wie er in der U- und Filmmusik bis in die 90er Jahre m&#246;glich war, als die Produktionsetats noch riesige waren und die Goldenen Schallplatten echter. Das Verh&#228;ltnis von harter Arbeit, dickem Erfolg und daraus m&#246;glicherweise resultierendem Einkommen stimmte noch, so wie es Heidi- und Kaptain-Future-Soundtracks Christian Bruhn mitunter einbrachten. Im gleichen Raum traf man aber auch den namenlosen Anfangvierziger der Jetztzeit an, der als Komponist wie Interpret E-Musik, U-Musik, Film- und Werbemusik aus&#252;bt, f&#252;r wichtige Theater vielfach erfolgreiche Schauspielmusiken schrieb. So breit aufgestellt hat er das Zeugs, in einem seiner Metiers einen Erfolg zu landen. Vielleicht bot sich ihm nur noch nicht die Gelegenheit, vielleicht ist \u201edas System\u201c heute mit auch nur mit soviel K&#252;nstlerinnen und K&#252;nstlern wie noch nie zu \u201everstopft\u201c. Dazu kommen die heute erheblich verschlechterten bzw. eingefrorenen Produktionshonorare, die zu geringen Beteiligungen an Online-Erfolgen, die hart Arbeitenden zwar eine ausk&#246;mmliche Existenz erm&#246;glichen, sie aber selbst um die Fr&#252;chte ihres Erfolgs bringen, egal ob der bescheiden oder riesig sein mag. Gl&#252;ck hat dabei heute nur der, wer sich rechtzeitig fr&#252;h genug festlegt und der gew&#228;hlten Nische durchstarten kann. Wer allerdings vern&#252;nftig ist, wird sich so breit aufstellen, wie eben fr&#252;her ein Bruhn oder heute dieser namenlose, durchaus real lebende Kollege.<\/p>\n<p>Interessant war dazu die Rede des Berliner Kulturstaatssekret&#228;rs Tim Renner, der U und E f&#252;r sich mit \u201eUnderground\u201c und \u201eExcellence\u201c &#252;bersetzt. Wie soll heute nun noch Exzellenz entstehen k&#246;nnen, wo diese gezwungenermassen im Untergrund agieren muss? Oder verstehe ich da etwas falsch? So wichtig eine Neubewertung der alten Bezahlsparten der GEMA sein mag, muss vor allem das aktuell mehr denn je um sein am Boden &#220;berleben k&#228;mpfende Hochkar&#228;tige wieder in die Lage versetzt werden, ordentlich f&#252;r seine Anstrengung bezahlt zu werden. Es geht da nicht um \u201eEintagsfliegen\u201c oder \u201eHitwunder\u201c, es geht, &#228;hnlich den Universit&#228;ten, um den Mittelbau, der seine Kunst voll und ganz zum Broterwerb einsetzt und immer mehr in die Rolle eines perfekt ausgebildeten Prekariats gedr&#228;ngt wird, dessen Erfolg schnell geteilt und geliebt wird, dessen Einnahmen aber ganz andere einfahren, wie Onlineportale, die nur ihr Regal zur Verf&#252;gung stellen und damit auf Kosten, bildlich gesprochen, der Musikdosenhersteller ihren Reibach einfahren. Wenn nun E, U und Film und noch vieles mehr neu bewertet werden sollen, nachdem sich immer mehr eine Nettoeinzelverrechnungsmentalit&#228;t herauskristallisiert, die nur noch wenige, wie z.B. einzelne Werbemusiker gut verdienen l&#228;sst, sollten die Komponisten, Soundk&#252;nstler und Interpreten wieder mehr zusammenfinden, durchaus durch Eintritte in so etwas Ehrw&#252;rdiges wie einen Komponistenverband, um das Bestehende zu retten und zum Vorteil aller umzubauen. Vielleicht geht der Weg ja sogar tats&#228;chlich dar&#252;ber, E und U und Co. doch nicht gegenseitig aufzuheben, sondern jedem zuzugestehen, sich doch f&#252;r eine Richtung entscheiden zu m&#252;ssen, ohne den Fuss aus den anderen herauszunehmen. Denn nur wenn man wei&#223;, wer man ist, woher man kommt, dann kann man mit voller Kraft zum Erhalt und Ausbau \u201edes Systems\u201c beitragen. Vor lauter Angst in der &#214;ffentlichkeit nicht nur als K&#252;nstlerikone dazustehen, sondern als f&#252;r seine Existenz kulturpolitisch eintretender Mensch verrufen zu sein, werden Abgrenzungen und deutliche Benennungen kaum noch gewagt. Denn das mag einen ins Abseits bringen. Aber eben auch ins denkerische, spirituelle und kreative Aus. M&#246;ge jeder also wissen was er sei und kann. Dann k&#246;nnen andere vielleicht in hoffentlich weniger als 60 Jahren wieder weniger diametrale K&#252;nstlergenerationen in einem Raum erleben!<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=60%20Jahre%20Komponistenverband%2C%20diametrales%20Gestern%20und%20Heute%20in%20einem%20Raum https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2014%2F10%2F16%2F60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=60%20Jahre%20Komponistenverband%2C%20diametrales%20Gestern%20und%20Heute%20in%20einem%20Raum https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2014%2F10%2F16%2F60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2014%2F10%2F16%2F60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=60%20Jahre%20Komponistenverband%2C%20diametrales%20Gestern%20und%20Heute%20in%20einem%20Raum%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2014%2F10%2F16%2F60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2014%2F10%2F16%2F60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Ein bisschen ist es schon her: vor sieben Tagen feierte der Deutsche Komponistenverband (DKV) sein 60-j&#228;hriges Bestehen. Diese seitdem 168 verstrichenen Stunden einer Woche sind im Zeitalter des \u201eSharings\u201c und \u201eLikens\u201c selbst schon eine Ewigkeit, als seien 60 Jahre verstrichen. Was in dieser Zeitspanne an Klingelt&#246;nen, aktuellen Hits und Dauerwerbejingles&#46;&#46;&#46;<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" style=\"display:none\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=60%20Jahre%20Komponistenverband%2C%20diametrales%20Gestern%20und%20Heute%20in%20einem%20Raum https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2014%2F10%2F16%2F60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=60%20Jahre%20Komponistenverband%2C%20diametrales%20Gestern%20und%20Heute%20in%20einem%20Raum https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2014%2F10%2F16%2F60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2014%2F10%2F16%2F60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=60%20Jahre%20Komponistenverband%2C%20diametrales%20Gestern%20und%20Heute%20in%20einem%20Raum%20https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2014%2F10%2F16%2F60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fblogs.nmz.de%2Fbadblog%2F2014%2F10%2F16%2F60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"author":31,"featured_media":10681,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[14657,2892,8381],"tags":[10333,1997,249,12115,12116,11213,327],"class_list":["post-11110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert","category-deutsch","category-sprache","tag-christian-bruhn","tag-deutscher-komponistenverband","tag-e-musik","tag-heidi","tag-kaptain-future","tag-tim-renner","tag-u-musik"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>60 Jahre Komponistenverband, diametrales Gestern und Heute in einem Raum &#8211; Bad Blog Of Musick - nmz Klassik-Blog<\/title>\n<meta name=\"description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.nmz.de\/badblog\/2014\/10\/16\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"60 Jahre Komponistenverband, diametrales Gestern und Heute in einem Raum &#8211; Bad Blog Of Musick - nmz Klassik-Blog\" \/>\n<meta property=\"og:description\" content=\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.nmz.de\/badblog\/2014\/10\/16\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\/\" \/>\n<meta property=\"og:site_name\" content=\"Bad Blog Of Musick\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/musikzeitung\" \/>\n<meta property=\"article:published_time\" content=\"2014-10-16T21:55:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-01-20T17:56:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.nmz.de\/badblog\/files\/2014\/07\/badboy_gaelic.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alexander Strauch\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@musikzeitung\" \/>\n<meta name=\"twitter:site\" content=\"@musikzeitung\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexander Strauch\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2014\\\/10\\\/16\\\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2014\\\/10\\\/16\\\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\\\/\"},\"author\":{\"name\":\"Alexander Strauch\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/73d6c9ef0d58ae670a7d6f9affe7259c\"},\"headline\":\"60 Jahre Komponistenverband, diametrales Gestern und Heute in einem Raum\",\"datePublished\":\"2014-10-16T21:55:10+00:00\",\"dateModified\":\"2018-01-20T17:56:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2014\\\/10\\\/16\\\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\\\/\"},\"wordCount\":713,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2014\\\/10\\\/16\\\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2014\\\/07\\\/badboy_gaelic.jpg?fit=640%2C480&ssl=1\",\"keywords\":[\"Christian Bruhn\",\"Deutscher Komponistenverband\",\"E-Musik\",\"Heidi\",\"Kaptain Future\",\"Tim Renner\",\"U-Musik\"],\"articleSection\":{\"1\":\"Deutsch\",\"2\":\"Sprache\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2014\\\/10\\\/16\\\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2014\\\/10\\\/16\\\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\\\/\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2014\\\/10\\\/16\\\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\\\/\",\"name\":\"60 Jahre Komponistenverband, diametrales Gestern und Heute in einem Raum &#8211; Bad Blog Of Musick - nmz Klassik-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2014\\\/10\\\/16\\\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2014\\\/10\\\/16\\\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2014\\\/07\\\/badboy_gaelic.jpg?fit=640%2C480&ssl=1\",\"datePublished\":\"2014-10-16T21:55:10+00:00\",\"dateModified\":\"2018-01-20T17:56:45+00:00\",\"description\":\"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2014\\\/10\\\/16\\\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2014\\\/10\\\/16\\\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2014\\\/10\\\/16\\\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2014\\\/07\\\/badboy_gaelic.jpg?fit=640%2C480&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2014\\\/07\\\/badboy_gaelic.jpg?fit=640%2C480&ssl=1\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/2014\\\/10\\\/16\\\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"60 Jahre Komponistenverband, diametrales Gestern und Heute in einem Raum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#website\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"name\":\"Bad Blog Of Musick\",\"description\":\"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#organization\",\"name\":\"Bad Blog Of Musick\",\"alternateName\":\"Ein Klassik-Blog zur Musik\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogs.nmz.de\\\/badblog\\\/files\\\/2016\\\/10\\\/badblog-logo1.png?fit=512%2C512&ssl=1\",\"width\":512,\"height\":512,\"caption\":\"Bad Blog Of Musick\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/musikzeitung\",\"https:\\\/\\\/x.com\\\/musikzeitung\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/#\\\/schema\\\/person\\\/73d6c9ef0d58ae670a7d6f9affe7259c\",\"name\":\"Alexander Strauch\",\"description\":\"Komponist*in\",\"url\":\"https:\\\/\\\/blogs.nmz.de\\\/badblog\\\/author\\\/querstand\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"60 Jahre Komponistenverband, diametrales Gestern und Heute in einem Raum &#8211; Bad Blog Of Musick - nmz Klassik-Blog","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.nmz.de\/badblog\/2014\/10\/16\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\/","og_locale":"de_DE","og_type":"article","og_title":"60 Jahre Komponistenverband, diametrales Gestern und Heute in einem Raum &#8211; Bad Blog Of Musick - nmz Klassik-Blog","og_description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","og_url":"https:\/\/blogs.nmz.de\/badblog\/2014\/10\/16\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\/","og_site_name":"Bad Blog Of Musick","article_publisher":"https:\/\/www.facebook.com\/musikzeitung","article_published_time":"2014-10-16T21:55:10+00:00","article_modified_time":"2018-01-20T17:56:45+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/blogs.nmz.de\/badblog\/files\/2014\/07\/badboy_gaelic.jpg","type":"image\/jpeg"}],"author":"Alexander Strauch","twitter_card":"summary_large_image","twitter_creator":"@musikzeitung","twitter_site":"@musikzeitung","twitter_misc":{"Verfasst von":"Alexander Strauch","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.nmz.de\/badblog\/2014\/10\/16\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\/#article","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2014\/10\/16\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\/"},"author":{"name":"Alexander Strauch","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/73d6c9ef0d58ae670a7d6f9affe7259c"},"headline":"60 Jahre Komponistenverband, diametrales Gestern und Heute in einem Raum","datePublished":"2014-10-16T21:55:10+00:00","dateModified":"2018-01-20T17:56:45+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2014\/10\/16\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\/"},"wordCount":713,"commentCount":0,"publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2014\/10\/16\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2014\/07\/badboy_gaelic.jpg?fit=640%2C480&ssl=1","keywords":["Christian Bruhn","Deutscher Komponistenverband","E-Musik","Heidi","Kaptain Future","Tim Renner","U-Musik"],"articleSection":{"1":"Deutsch","2":"Sprache"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.nmz.de\/badblog\/2014\/10\/16\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.nmz.de\/badblog\/2014\/10\/16\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\/","url":"https:\/\/blogs.nmz.de\/badblog\/2014\/10\/16\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\/","name":"60 Jahre Komponistenverband, diametrales Gestern und Heute in einem Raum &#8211; Bad Blog Of Musick - nmz Klassik-Blog","isPartOf":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2014\/10\/16\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\/#primaryimage"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2014\/10\/16\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2014\/07\/badboy_gaelic.jpg?fit=640%2C480&ssl=1","datePublished":"2014-10-16T21:55:10+00:00","dateModified":"2018-01-20T17:56:45+00:00","description":"Bad Blog Of Musick \u2013 Ein Klassik-Blog und das wahrscheinlich bedeutendste Musik-Blog zur zeitgen\u00f6ssischen und klassischen Musikkultur","breadcrumb":{"@id":"https:\/\/blogs.nmz.de\/badblog\/2014\/10\/16\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.nmz.de\/badblog\/2014\/10\/16\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/2014\/10\/16\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\/#primaryimage","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2014\/07\/badboy_gaelic.jpg?fit=640%2C480&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2014\/07\/badboy_gaelic.jpg?fit=640%2C480&ssl=1","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.nmz.de\/badblog\/2014\/10\/16\/60-jahre-komponistenverband-diametrales-gestern-und-heute-in-einem-raum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blogs.nmz.de\/badblog\/"},{"@type":"ListItem","position":2,"name":"60 Jahre Komponistenverband, diametrales Gestern und Heute in einem Raum"}]},{"@type":"WebSite","@id":"https:\/\/blogs.nmz.de\/badblog\/#website","url":"https:\/\/blogs.nmz.de\/badblog\/","name":"Bad Blog Of Musick","description":"Das bedeutendste Blog zur zeitgen\u00f6ssischen Musikkultur","publisher":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.nmz.de\/badblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blogs.nmz.de\/badblog\/#organization","name":"Bad Blog Of Musick","alternateName":"Ein Klassik-Blog zur Musik","url":"https:\/\/blogs.nmz.de\/badblog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2016\/10\/badblog-logo1.png?fit=512%2C512&ssl=1","width":512,"height":512,"caption":"Bad Blog Of Musick"},"image":{"@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/musikzeitung","https:\/\/x.com\/musikzeitung"]},{"@type":"Person","@id":"https:\/\/blogs.nmz.de\/badblog\/#\/schema\/person\/73d6c9ef0d58ae670a7d6f9affe7259c","name":"Alexander Strauch","description":"Komponist*in","url":"https:\/\/blogs.nmz.de\/badblog\/author\/querstand\/"}]}},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogs.nmz.de\/badblog\/files\/2014\/07\/badboy_gaelic.jpg?fit=640%2C480&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/11110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/comments?post=11110"}],"version-history":[{"count":1,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/11110\/revisions"}],"predecessor-version":[{"id":11111,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/posts\/11110\/revisions\/11111"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/media\/10681"}],"wp:attachment":[{"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/media?parent=11110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/categories?post=11110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.nmz.de\/badblog\/wp-json\/wp\/v2\/tags?post=11110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}